{"id":1464276,"date":"2025-07-07T04:03:38","date_gmt":"2025-07-07T11:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/"},"modified":"2025-07-07T04:03:38","modified_gmt":"2025-07-07T11:03:38","slug":"5-cosas-7-julio-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/5-cosas-7-julio-orix\/","title":{"rendered":"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics"},"content":{"rendered":"<p>Aumenta el n\u00famero de muertos por las inundaciones en Texas. Las v\u00edctimas de la tragedia en Texas. Trump se re\u00fane con Netanyahu este lunes en Washington. Se agota el plazo de 90 d\u00edas para evitar nuevos aranceles de EE.UU. Los BRICS rechazan el proteccionismo.<em> Esto es lo que debes saber para comenzar el d\u00eda.<\/em><strong> Primero la verdad.<\/strong><\/p>\n<p><a href=\"https:\/\/www.cnn.com\/newsletters\/5-cosas\">Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo<\/a><\/p>\n<p><a href=\"https:\/\/www.cnn.com\/audio\/podcasts\/5-cosas\">\ud83c\udf99 Escucha las 5 cosas de CNN<\/a><\/p>\n<p>Inundaciones repentinas en el centro de Texas <a href=\"https:\/\/cnnespanol.cnn.com\/eeuu\/live-news\/inundaciones-texas-en-vivo-80-muertos-desaparecidos-trax\">han dejado m\u00e1s de 80 muertos desde el viernes<\/a>, entre ellos 28 menores en un solo condado, seg\u00fan autoridades estatales y locales. Con decenas de personas a\u00fan desaparecidas, el gobernador Greg Abbott advirti\u00f3 que las lluvias intensas previstas podr\u00edan seguir representando un peligro en algunas zonas del estado en los pr\u00f3ximos d\u00edas.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/eeuu\/victimas-inundaciones-texas-trax\">Julian Ryan muri\u00f3 tras salvar a su familia durante las inundaciones <\/a>que arrasaron el condado Kerr, Texas. Entre las decenas de v\u00edctimas hay varias ni\u00f1as del Campamento Mystic, un entrenador de f\u00fatbol y su esposa, una directora del campamento y una psic\u00f3loga. Muchas siguen desaparecidas mientras la comunidad enfrenta el duelo.<\/p>\n<p>Donald Trump se re\u00fane este lunes en Washington con el primer ministro de Israel, Benjamin Netanyahu, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/eeuu\/trump-acuerdo-liberacion-rehenes-gaza-trax\">un encuentro clave<\/a> en medio de los esfuerzos por lograr un acuerdo que permita la liberaci\u00f3n de los rehenes en Gaza y un cese del fuego en el enclave asediado por el hambre y los bombardeos de Israel. El presidente de EE.UU. dijo el domingo que conf\u00eda en que ese acuerdo se concrete esta semana.<\/p>\n<ul>\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/mundo\/ataques-israelies-gaza-negociaciones-alto-fuego-trax\">Ataques israel\u00edes en Gaza dejan decenas de muertos previo al inicio de las negociaciones de alto el fuego<\/a><\/li>\n<\/ul>\n<p>Est\u00e1 a punto de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/eeuu\/pausa-trump-aranceles-reciprocos-trax\">expirar el plazo de 90 d\u00edas<\/a> que el presidente Donald Trump dio a los pa\u00edses para que firmaran acuerdos comerciales con Estados Unidos para evitar aranceles considerablemente m\u00e1s altos. Lo que ocurrir\u00e1 despu\u00e9s de ese plazo, el 9 de julio, es una inc\u00f3gnita.<\/p>\n<p>Los l\u00edderes de los BRICS se reunieron este domingo en R\u00edo de Janeiro y <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/mundo\/resumen-cumbre-brics-rio-de-janeiro-dia-1-efe\">rechazaron el proteccionismo comercial<\/a>, sin confrontar directamente a Trump. La cumbre estuvo marcada por fuertes medidas de seguridad y la ausencia de Xi Jinping y Putin, quien particip\u00f3 de forma remota. Este lunes se llevar\u00e1 a cabo la segunda jornada de la cumbre en Brasil.<\/p>\n<p><strong>\u00bfCon qu\u00e9 banda original se reuni\u00f3 Ozzy Osbourne en su concierto de despedida?<\/strong><\/p>\n<p>A. Los Bukis<\/p>\n<p>B. Oasis<\/p>\n<p>C. Metallica<\/p>\n<p>D. Black Sabbath<\/p>\n<p>\u2b07\ufe0f <em>Conoce la respuesta m\u00e1s abajo.<\/em><\/p>\n<p><strong>M\u00e9xico conquista la Copa Oro tras vencer a EE.UU. <\/strong><\/p>\n<p>La <a href=\"https:\/\/cnnespanol.cnn.com\/deportes\/live-news\/eeuu-mexico-final-copa-oro-en-vivo-resultado-goles-orix\">selecci\u00f3n mexicana de Javier Aguirre se coron\u00f3 campeona de la Copa Oro<\/a> tras vencer 1-2 a Estados Unidos. El equipo mexicano se impuso con autoridad en el campo de juego y logr\u00f3 su d\u00e9cimo t\u00edtulo de la Concacaf.<\/p>\n<p><strong>La Tierra est\u00e1 lo m\u00e1s lejos posible del Sol. Entonces, \u00bfpor qu\u00e9 hace tanto calor? <\/strong><\/p>\n<p>Aunque la Tierra est\u00e1 en su punto m\u00e1s alejado del Sol esta semana \u2014el afelio\u2014, eso no enfr\u00eda el verano en el hemisferio norte. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/05\/ciencia\/tierra-mas-lejos-posible-sol-por-que-hace-tanto-calor-trax\">Las estaciones no dependen de la distancia respecto al Sol<\/a>, sino de la inclinaci\u00f3n del planeta, que en julio hace que el norte reciba luz solar m\u00e1s directa con d\u00edas m\u00e1s largos, lo que genera calor.<\/p>\n<p><strong>Trump inquieta a los l\u00edderes extranjeros con sus encuentros p\u00fablicos y televisados en la Casa Blanca<\/strong><\/p>\n<p>Las visitas de l\u00edderes extranjeros a la Casa Blanca con Trump se han vuelto tensas e impredecibles, como su encuentro con Volodymyr Zelensky. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/eeuu\/trump-reuniones-oficina-oval-inquietado-lideres-extranjeros-trax\">Diplom\u00e1ticos advierten que ahora deber\u00e1n prepararse con cautela<\/a>, evitar contradicciones y apelar al ego de Trump para evitar confrontaciones. Aun as\u00ed, algunos pa\u00edses ven estas reuniones como oportunidades clave para influir directamente en el mandatario.<\/p>\n<p><strong>US$ 147 millones<\/strong><\/p>\n<p>\u201cJurassic World Rebirth\u201d arras\u00f3 en la taquilla del fin de semana del 4 de julio con <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/entretenimiento\/jurassic-world-rebirth-taquilla-estreno-trax\">una recaudaci\u00f3n de US$ 147 millones en cinco d\u00edas<\/a> en Estados Unidos, superando expectativas y acerc\u00e1ndose al \u00e9xito de su predecesora, \u201cDominion\u201d.<\/p>\n<p><strong>\u201cTodo indica que el modelo de globalizaci\u00f3n liberal se est\u00e1 volviendo obsoleto\u201d<\/strong><\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/mundo\/putin-cumbre-brics-globalizacion-agotado-trax\">Lo dijo el presidente de Rusia, Vladimir Putin<\/a>, al asegurar en la cumbre del grupo BRICS que la globalizaci\u00f3n liberal se ha agotado y que el futuro est\u00e1 en los mercados emergentes.<\/p>\n<p><strong>C\u00e1mara r\u00e1pida muestra la velocidad con la que suben las aguas de las inundaciones en Texas<\/strong><\/p>\n<p>Un video captado el viernes <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/eeuu\/video\/timelapse-inundaciones-texas-rio-llano-trax\">muestra la rapidez con la que las aguas crecieron<\/a> a lo largo del r\u00edo Llano en Kingsland, Texas, un pueblo a unos 153 kil\u00f3metros al noreste de Campamento Mystic. El video, que se aceler\u00f3, muestra la entrada y el ascenso del agua a lo largo del r\u00edo en un lapso de 30 minutos.<\/p>\n<p>\ud83d\udc4b Nos vemos ma\u00f1ana.<\/p>\n<p><strong>\ud83e\udde0 La respuesta del quiz: D. <\/strong>Ozzy Osbourne se reuni\u00f3 con los <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/06\/entretenimiento\/ozzy-osbourne-despedida-black-sabbath-concierto-trax\">miembros originales de Black Sabbath<\/a> en su concierto de despedida.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aumenta el n\u00famero de muertos por las inundaciones en Texas. Las v\u00edctimas de la tragedia en Texas. Trump se re\u00fane con Netanyahu este lunes en Washington. Se agota el plazo de 90 d\u00edas para evitar nuevos aranceles de EE.UU. Los BRICS rechazan el proteccionismo. Esto es lo que debes saber para comenzar el d\u00eda. Primero [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464276","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics - Noticias\" \/>\n<meta property=\"og:description\" content=\"Aumenta el n\u00famero de muertos por las inundaciones en Texas. Las v\u00edctimas de la tragedia en Texas. Trump se re\u00fane con Netanyahu este lunes en Washington. Se agota el plazo de 90 d\u00edas para evitar nuevos aranceles de EE.UU. Los BRICS rechazan el proteccionismo. Esto es lo que debes saber para comenzar el d\u00eda. Primero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T11:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics\",\"datePublished\":\"2025-07-07T11:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/\"},\"wordCount\":866,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/\",\"name\":\"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-07T11:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics - Noticias","og_description":"Aumenta el n\u00famero de muertos por las inundaciones en Texas. Las v\u00edctimas de la tragedia en Texas. Trump se re\u00fane con Netanyahu este lunes en Washington. Se agota el plazo de 90 d\u00edas para evitar nuevos aranceles de EE.UU. Los BRICS rechazan el proteccionismo. Esto es lo que debes saber para comenzar el d\u00eda. Primero [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/","og_site_name":"Noticias","article_published_time":"2025-07-07T11:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/"},"author":{"name":"","@id":""},"headline":"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics","datePublished":"2025-07-07T11:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/"},"wordCount":866,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/","url":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/","name":"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-07T11:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/5-cosas-7-julio-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/5-cosas-7-julio-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/5-cosas-7-julio-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/5-cosas-7-julio-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-07T11:03:38Z","datePublished":"2025-07-07T11:03:38Z","dateModified":"2025-07-07T11:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las 5 cosas que debes saber este 7 de julio: Texas, Trump, Gaza, aranceles y Brics\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/07\\\/07\\\/5-cosas-7-julio-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/07\\\/07\\\/5-cosas-7-julio-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-07T11:03:38Z\",\"datePublished\":\"2025-07-07T11:03:38Z\",\"dateModified\":\"2025-07-07T11:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464307,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/08\/5-cosas-8-julio-orix\/","url_meta":{"origin":1464276,"position":0},"title":"Las 5 cosas que debes saber este 8 de julio: Inundaciones en Texas, TPS y aranceles de Trump","author":"","date":"julio 8, 2025","format":false,"excerpt":"El Gobierno de Trump anuncia fin del TPS para nicarag\u00fcenses y hondure\u00f1os. Trump nitifica nuevos aranceles a un n\u00famero creciente de pa\u00edses. Las declaraciones de Lula en la cumbre de los BRICS. La doble vida de una pareja rusa en Buenos Aires. Esto es lo que debes saber para comenzar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456196,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/12\/02\/trump-amenaza-con-aranceles-100-a-brics-si-deciden-crear-moneda-trax\/","url_meta":{"origin":1464276,"position":1},"title":"Trump amenaza con imponer aranceles del 100% a los pa\u00edses BRICS si deciden crear una nueva moneda","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) -- El presidente electo\u00a0 de EE.UU., Donald Trump, dijo que exigir\u00e1 a los pa\u00edses que forman parte de los BRICS \u2014un grupo de econom\u00edas emergentes respaldado por China y Rusia\u2014 que se comprometan a no crear una nueva moneda o enfrentar aranceles del 100% durante su administraci\u00f3n.Ahora puedes seguirnos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459717,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/03\/10\/5-cosas-10-marzo-aranceles-trump-canada-siria-rusia-israel-orix\/","url_meta":{"origin":1464276,"position":2},"title":"Las 5 cosas que debes saber este 10 de marzo: aranceles Trump, Canad\u00e1, Siria, Rusia, Israel corta suministro el\u00e9ctrico","author":"","date":"marzo 10, 2025","format":false,"excerpt":"Acusan al Gobierno de Siria de ejecutar civiles. Rusia avanza en Kursk, amenazando a Ucrania. Israel corta el suministro el\u00e9ctrico a Gaza. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las 5 cosas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464292,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/lula-brics-soberanos-trump-aranceles-efe\/","url_meta":{"origin":1464276,"position":3},"title":"Lula dice que amenaza de Trump de imponer aranceles es &#171;irresponsable&#187; y que los BRICS son soberanos","author":"","date":"julio 7, 2025","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, afirm\u00f3 este lunes que los pa\u00edses de los BRICS son soberanos y que no desean tener un \u201cemperador\u201d, al ser interrogado sobre la amenaza proferida por su hom\u00f3logo de Estados Unidos, Donald Trump, de imponer aranceles adicionales del 10 % a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470366,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/22\/5-cosas-22-enero-orix\/","url_meta":{"origin":1464276,"position":4},"title":"Las 5 cosas que debes saber este 22 de enero","author":"","date":"enero 22, 2026","format":false,"excerpt":"Directriz permite a agentes de ICE entrar en hogares sin orden judicial, seg\u00fan memorando. Venezuela informa que recibi\u00f3 US$ 300 millones por la venta de crudo tras el acuerdo con EE.UU. Ecuador anuncia una \u201ctasa de seguridad\u201d del 30 % a las importaciones de Colombia. Esto es lo que debes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460535,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/03\/28\/5-cosas-28-marzo-parole-humanitario-universidad-tufts-aranceles-orix\/","url_meta":{"origin":1464276,"position":5},"title":"Las 5 cosas que debes saber este 28 de marzo: &#171;Parole&#187; humanitario, estudiante de Universidad Tufts y aranceles a autom\u00f3viles","author":"","date":"marzo 28, 2025","format":false,"excerpt":"Un potente terremoto de magnitud 7,7 sacudi\u00f3 el centro de Myanmar. As\u00ed fue la detenci\u00f3n de una estudiante de la Universidad Tufts. Sheinbaum esperar\u00e1 para responder a aranceles. Niegan libertad condicional a la mujer que mat\u00f3 a Selena Quintanilla. Esto es lo que debes saber para comenzar el d\u00eda. Primero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1464276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1464276"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1464276\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1464276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1464276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1464276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}