{"id":1464280,"date":"2025-07-07T06:03:41","date_gmt":"2025-07-07T13:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/"},"modified":"2025-07-07T06:03:41","modified_gmt":"2025-07-07T13:03:41","slug":"hongos-mujer-australiana-culpable-invitados-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","title":{"rendered":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar"},"content":{"rendered":"<p>Erin Patterson, la mujer australiana <a href=\"https:\/\/www.cnn.com\/2025\/06\/21\/australia\/australia-erin-patterson-mushroom-trial-wrap-intl-hnk\">acusada de matar a tres familiares con<\/a> una comida de hongos horneados en un almuerzo de Beef Wellington, fue declarada culpable de tres cargos de homicidio e intento de homicidio del \u00fanico sobreviviente.<\/p>\n<p>Un jurado de 12 miembros lleg\u00f3 al veredicto tras seis d\u00edas de deliberaci\u00f3n que siguienron al juicio de 10 semanas en Morwell, una peque\u00f1a ciudad a una hora en auto del comedor suburbano en Leongatha, Victoria, donde se sirvi\u00f3 el almuerzo letal en julio de 2023.<\/p>\n<p>Decenas de equipos de medios de comunicaci\u00f3n acudieron al tribunal cuando se anunci\u00f3 que el jurado hab\u00eda llegado a un veredicto en el caso que ha cautivado a las audiencias de todo el mundo y ha generado cuatro podcasts dedicados a analizar la evidencia de cada d\u00eda.<\/p>\n<p>Durante semanas de testimonio, Patterson fue acusada de contaminar deliberadamente la comida del almuerzo con hongos mortales, de una variedad altamente t\u00f3xica que recogi\u00f3 despu\u00e9s de ver su ubicaci\u00f3n publicada en un sitio web p\u00fablico.<\/p>\n<p>D\u00edas despu\u00e9s, sus exsuegros, Don y Gail Patterson, fallecieron junto con la hermana de Gail, Heather Wilkinson. El esposo de Heather, Ian, su pastor local, sobrevivi\u00f3 tras una semana de hospitalizaci\u00f3n.<\/p>\n<p>Sus abogados defensores argumentaron que las muertes fueron un \u201cterrible accidente\u201d que ocurri\u00f3 cuando Patterson intent\u00f3 mejorar el sabor de la comida y que ella minti\u00f3 repetidamente a la Polic\u00eda por p\u00e1nico cuando se dio cuenta de que pudo haber agregado hongos recolectados a la mezcla.<\/p>\n<p>Patterson se sent\u00f3 en la corte, escuchando mientras los fiscales llamaban a testigo tras testigo, cuyo testimonio, alegaron, contaba una historia convincente de un triple asesinato que el jurado finalmente encontr\u00f3 que satisfac\u00eda el est\u00e1ndar legal de m\u00e1s all\u00e1 de toda duda razonable.<\/p>\n<p>Seg\u00fan la ley australiana, ninguno de los jurados puede ser identificado p\u00fablicamente y tienen prohibido revelar las deliberaciones de la sala del jurado incluso despu\u00e9s de finalizado el juicio.<\/p>\n<p>Nunca se sabr\u00e1 qu\u00e9 piezas de evidencia influyeron en la decisi\u00f3n de cada jurado, pero los 12 deb\u00edan estar de acuerdo en el veredicto.<\/p>\n<p>Los hechos acordados fueron que Patterson invit\u00f3 a almorzar a cinco personas el 29 de julio de 2023, incluido su exmarido Simon Patterson, quien se retir\u00f3 el d\u00eda anterior.<\/p>\n<p>A las pocas horas de la comida, los cuatro invitados \u2014los padres de Simon, Don y Gail, y sus t\u00edos, Heather e Ian Wilkinson\u2014 sufrieron v\u00f3mitos y diarrea. Fueron trasladados al hospital, donde les indujeron un coma mientras los m\u00e9dicos intentaban salvarlos.<\/p>\n<p>Gail y Heather fallecieron el 4 de agosto por insuficiencia multiorg\u00e1nica, seguidas por Don el 5 de agosto, tras no responder a un trasplante de h\u00edgado. Ian Wilkinson sobrevivi\u00f3 y finalmente recibi\u00f3 el alta hospitalaria a finales de septiembre, tras casi dos meses de tratamiento intensivo.<\/p>\n<p>Los hongos orejones contienen toxinas de amanita que impiden la producci\u00f3n de prote\u00ednas en las c\u00e9lulas del h\u00edgado, lo que provoca la muerte celular y posible insuficiencia hep\u00e1tica a partir de aproximadamente dos d\u00edas despu\u00e9s de la ingesti\u00f3n.<\/p>\n<p>Estos hongos letales, originarios de Europa, han crecido en varios estados australianos y, en el momento del almuerzo, se los hab\u00eda visto a poca distancia en auto de la casa de Patterson, en la zona rural de Victoria.<\/p>\n<p>Durante el juicio, la fiscal\u00eda argument\u00f3 que Patterson tuvo la oportunidad de recoger hongos letales despu\u00e9s de ver su ubicaci\u00f3n publicada en el sitio web de ciencia ciudadana iNaturalist.<\/p>\n<p>El veredicto de culpabilidad sugiere que el jurado acept\u00f3 el argumento de la fiscal\u00eda de que probablemente viaj\u00f3 a dos sitios en abril y mayo de 2023 y recogi\u00f3 deliberadamente los hongos utilizados en la comida.<\/p>\n<p>La fiscal Nanette Rogers, de la Corte Suprema, aleg\u00f3 que \u201ccuatro enga\u00f1os calculados\u201d fueron la base del caso. \u201cEl primer enga\u00f1o fue la falsa afirmaci\u00f3n de que ten\u00eda c\u00e1ncer que us\u00f3 como pretexto para la invitaci\u00f3n a almorzar\u201d, declar\u00f3.<\/p>\n<p>El segundo enga\u00f1o fueron las dosis letales de veneno que la acusada escondi\u00f3 en las hamburguesas Wellington caseras. El tercer enga\u00f1o fueron sus intentos de hacer creer que tambi\u00e9n sufri\u00f3 intoxicaci\u00f3n por hongos ortiga, y el cuarto enga\u00f1o, el continuo encubrimiento que emprendi\u00f3 para ocultar la verdad.<\/p>\n<p>Patterson admiti\u00f3 que el 28 de abril, el mismo d\u00eda en que las se\u00f1ales de su celular la situaron cerca de hongos mortales, compr\u00f3 un deshidratador que luego tir\u00f3 en un centro de reciclaje de residuos el 2 de agosto, mientras sus invitados estaban en el hospital.<\/p>\n<p>Ten\u00eda sus huellas dactilares y restos de hongos mortales.<\/p>\n<p>La fiscal\u00eda aleg\u00f3 que Patterson fingi\u00f3 estar enferma en los d\u00edas posteriores a servir el almuerzo y trat\u00f3 de ocultar sus huellas desechando el deshidratador y restableciendo sus dispositivos a los valores de f\u00e1brica para eliminar pruebas.<\/p>\n<p>El abogado defensor de Patterson, Colin Mandy SC, acus\u00f3 a la fiscal\u00eda de ser selectiva con las pruebas y de impulsar \u201ccuatro propuestas rid\u00edculas y enrevesadas\u201d.<\/p>\n<p>Lo primero fue que Patterson har\u00eda esto \u201csin ning\u00fan motivo\u201d, dijo Mandy.<\/p>\n<p>Dijo que hab\u00eda varias razones por las que Patterson no querr\u00eda matar a sus invitados. No ten\u00eda problemas econ\u00f3micos, viv\u00eda en una casa grande y ten\u00eda la custodia casi permanente de sus dos hijos peque\u00f1os, quienes eran muy cercanos a sus abuelos, dijo.<\/p>\n<p>La fiscal\u00eda no tuvo que demostrar el motivo.<\/p>\n<p>Rogers acus\u00f3 a Patterson de tener dos caras: una que mostr\u00f3 al mundo y que suger\u00eda que ten\u00eda una buena relaci\u00f3n con los Patterson, y una cara oculta que mostr\u00f3 solo a sus amigos de Facebook y que suger\u00eda que no quer\u00eda \u201ctener nada que ver con ellos\u201d.<\/p>\n<p>En mensajes de Facebook enviados en diciembre de 2022, Patterson hab\u00eda expresado enojo y frustraci\u00f3n por la renuencia de Don y Gail a involucrarse en la ruptura del matrimonio de su hijo.<\/p>\n<p>\u201cEstoy harta de esta mierda, no quiero saber nada de ellos\u201d, escribi\u00f3. \u201cPens\u00e9 que sus padres querr\u00edan que hiciera lo correcto, pero parece que su preocupaci\u00f3n por no sentirse inc\u00f3modo y no involucrarse en los asuntos personales de su hijo est\u00e1 por encima de eso, as\u00ed que que les den\u201d.<\/p>\n<p>Y otro mensaje dec\u00eda: \u201cJuro por esta familia, Dios\u201d.<\/p>\n<p>Durante ocho d\u00edas de testimonio, incluido el interrogatorio, Patterson aleg\u00f3 constantemente su inocencia y afirm\u00f3 que, sin darse cuenta, hab\u00eda a\u00f1adido hongos silvestres a la comida.<\/p>\n<p>En sus instrucciones al jurado, el juez Christopher Beale dijo que la admisi\u00f3n de Patterson de que dijo mentiras y desech\u00f3 pruebas no debe causar prejuicios en su contra.<\/p>\n<p>\u201cEste es un tribunal de justicia, no un tribunal de moral\u201d, afirm\u00f3.<\/p>\n<p>\u201cLa cuesti\u00f3n no es si ella es en alg\u00fan sentido responsable de las tr\u00e1gicas consecuencias del almuerzo, sino si la fiscal\u00eda ha demostrado m\u00e1s all\u00e1 de toda duda razonable que ella es penalmente responsable de esas consecuencias\u201d, dijo.<\/p>\n<p>El jurado concluy\u00f3 que Patterson hab\u00eda tenido la intenci\u00f3n de matar a los cuatro invitados al almuerzo y minti\u00f3 repetidamente en el estrado al afirmar que no lo hab\u00eda hecho.<\/p>\n<p>Patterson ser\u00e1 sentenciada  en una fecha posterior.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erin Patterson, la mujer australiana acusada de matar a tres familiares con una comida de hongos horneados en un almuerzo de Beef Wellington, fue declarada culpable de tres cargos de homicidio e intento de homicidio del \u00fanico sobreviviente. Un jurado de 12 miembros lleg\u00f3 al veredicto tras seis d\u00edas de deliberaci\u00f3n que siguienron al juicio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464280","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar - Noticias\" \/>\n<meta property=\"og:description\" content=\"Erin Patterson, la mujer australiana acusada de matar a tres familiares con una comida de hongos horneados en un almuerzo de Beef Wellington, fue declarada culpable de tres cargos de homicidio e intento de homicidio del \u00fanico sobreviviente. Un jurado de 12 miembros lleg\u00f3 al veredicto tras seis d\u00edas de deliberaci\u00f3n que siguienron al juicio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T13:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar\",\"datePublished\":\"2025-07-07T13:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/\"},\"wordCount\":1262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/\",\"name\":\"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-07T13:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar - Noticias","og_description":"Erin Patterson, la mujer australiana acusada de matar a tres familiares con una comida de hongos horneados en un almuerzo de Beef Wellington, fue declarada culpable de tres cargos de homicidio e intento de homicidio del \u00fanico sobreviviente. Un jurado de 12 miembros lleg\u00f3 al veredicto tras seis d\u00edas de deliberaci\u00f3n que siguienron al juicio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-07T13:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/"},"author":{"name":"","@id":""},"headline":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar","datePublished":"2025-07-07T13:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/"},"wordCount":1262,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","name":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-07T13:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-07T13:03:41Z","datePublished":"2025-07-07T13:03:41Z","dateModified":"2025-07-07T13:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jurado declara culpable de homicidio a mujer australiana que sirvi\\u00f3 hongos t\\u00f3xicos a sus invitados a almorzar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/07\\\/07\\\/hongos-mujer-australiana-culpable-invitados-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/07\\\/07\\\/hongos-mujer-australiana-culpable-invitados-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-07T13:03:41Z\",\"datePublished\":\"2025-07-07T13:03:41Z\",\"dateModified\":\"2025-07-07T13:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461784,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/04\/30\/mujer-asesinato-australia-hongos-venenosos-accidente-trax\/","url_meta":{"origin":1464280,"position":0},"title":"Defensa de mujer australiana acusada de matar a tres personas con hongos venenosos dice que fue un &#171;terrible accidente&#187;","author":"","date":"abril 30, 2025","format":false,"excerpt":"Los abogados de una mujer australiana acusada de envenenar fatalmente a tres miembros de su familia con hongos mortales dijeron al jurado que sus muertes fueron un \u201cterrible accidente\u201d.Erin Patterson est\u00e1 siendo juzgada por las muertes en 2023 de su suegra, Gail Patterson; su suegro, Donald Patterson, y la hermana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446968,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/03\/14\/declaran-culpable-homicidio-involuntario-padre-atacante-michigan-trax\/","url_meta":{"origin":1464280,"position":1},"title":"Declaran culpable de homicidio involuntario a James Crumbley, padre del atacante de Michigan","author":"","date":"marzo 14, 2024","format":false,"excerpt":"(CNN) -- James Crumbley, padre del adolescente que abri\u00f3 fuego en una escuela de Michigan en 2021 y cobr\u00f3 la vida de cuatro estudiantes, fue declarado culpable de homicidio involuntario en el juicio en su contra. Hace un mes, la madre del atacante, Jennifer Crumbley, fue condenada por los mismos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466216,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/09\/06\/mujer-homicidio-exyerno-florida-culpable-trax\/","url_meta":{"origin":1464280,"position":2},"title":"Mujer de Florida en juicio por mandar a matar a su exyerno decidi\u00f3 no testificar. El jurado la declar\u00f3 culpable al otro d\u00eda","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"Un d\u00eda antes de que Donna Adelson fuera condenada por homicidio premeditado por orquestar un complot para matar a su exyerno, la mujer de 75 a\u00f1os se debat\u00eda sobre si deb\u00eda testificar en su defensa en un tribunal de Tallahassee, Florida.Adelson, condenada el jueves tras no declarar, fue acusada inicialmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450224,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/06\/11\/jurado-hunter-biden-cnn-veredicto-culpabilidad-trax\/","url_meta":{"origin":1464280,"position":3},"title":"Miembro del jurado en caso de Hunter Biden explica a CNN c\u00f3mo se produjo el veredicto de culpabilidad","author":"","date":"junio 11, 2024","format":false,"excerpt":"(CNN) -- El jurado en el caso de Hunter Biden por arma de fuego estaba en un punto muerto en una votaci\u00f3n inicial el lunes por la noche sobre si condenar al hijo del presidente, seg\u00fan declar\u00f3 uno de los miembros del jurado a CNN en una entrevista, a\u00f1adiendo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464123,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/01\/jurado-juicio-sean-diddy-combs-veredicto-cargos-trax\/","url_meta":{"origin":1464280,"position":4},"title":"El jurado llega a un veredicto sobre algunos cargos en el juicio de Sean \u2018Diddy\u2019 Combs","author":"","date":"julio 1, 2025","format":false,"excerpt":"Un jurado federal alcanz\u00f3 un veredicto en el juicio por conspiraci\u00f3n de crimen organizado y tr\u00e1fico sexual forzado de Sean \u201cDiddy\u201d Combs, el magnate del hip-hop acusado de operar una empresa criminal que obligaba a mujeres a mantener encuentros sexuales con otros hombres conocidos como \u201cFreak Offs\u201d.El jurado envi\u00f3 una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464307,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/08\/5-cosas-8-julio-orix\/","url_meta":{"origin":1464280,"position":5},"title":"Las 5 cosas que debes saber este 8 de julio: Inundaciones en Texas, TPS y aranceles de Trump","author":"","date":"julio 8, 2025","format":false,"excerpt":"El Gobierno de Trump anuncia fin del TPS para nicarag\u00fcenses y hondure\u00f1os. Trump nitifica nuevos aranceles a un n\u00famero creciente de pa\u00edses. Las declaraciones de Lula en la cumbre de los BRICS. La doble vida de una pareja rusa en Buenos Aires. Esto es lo que debes saber para comenzar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1464280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1464280"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1464280\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1464280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1464280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1464280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}