{"id":1464294,"date":"2025-07-07T14:03:50","date_gmt":"2025-07-07T21:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/"},"modified":"2025-07-07T14:03:50","modified_gmt":"2025-07-07T21:03:50","slug":"jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/","title":{"rendered":"Jeffrey Epstein muri\u00f3 por suicidio y no existe una &#171;lista de clientes&#187;, dice el Departamento de Justicia de EE.UU."},"content":{"rendered":"<p>Tras meses de anunciar la inminente publicaci\u00f3n de nueva informaci\u00f3n sobre el acusado de tr\u00e1fico sexual Jeffrey Epstein, el Departamento de Justicia de EE.UU. (DOJ, por sus siglas en ingl\u00e9s) anunci\u00f3 este lunes en un memorando que no hay pruebas de que \u00e9l tuviera una \u201clista de clientes\u201d ni de que fuera asesinado.<\/p>\n<p>Adem\u00e1s, el Departamento de Justicia no planea publicar nuevos documentos sobre el caso, seg\u00fan inform\u00f3 el lunes.<\/p>\n<p>Esta declaraci\u00f3n contradice las promesas del presidente Donald Trump, quien previamente habl\u00f3 de divulgar m\u00e1s archivos gubernamentales sobre el financista ca\u00eddo en desgracia, y va en contra de las teor\u00edas conspirativas impulsadas por la derecha durante a\u00f1os.<\/p>\n<p>\u201cEsta revisi\u00f3n sistem\u00e1tica no revel\u00f3 ninguna \u2018lista de clientes\u2019 incriminatoria\u201d, se\u00f1ala el memorando sin firma. \u201cTampoco se encontr\u00f3 evidencia cre\u00edble de que Epstein chantajeara a personas prominentes como parte de sus acciones. No descubrimos pruebas que justifiquen una investigaci\u00f3n contra terceros no acusados\u201d.<\/p>\n<p>Axios fue el primer medio en informar detalles de la decisi\u00f3n del DOJ y el FBI.<\/p>\n<p>El departamento tambi\u00e9n difundi\u00f3 10 horas de grabaciones de seguridad de la c\u00e1rcel que muestran que nadie entr\u00f3 a la celda de Epstein el d\u00eda en que muri\u00f3 por suicidio.<\/p>\n<p>Durante a\u00f1os, figuras de los medios de derecha han sugerido que el Gobierno oculta secretos relacionados con Epstein, quien muri\u00f3 por suicidio en 2019 mientras esperaba juicio por cargos federales de tr\u00e1fico sexual. Algunos de ellos impulsaron la teor\u00eda de que Epstein ten\u00eda una \u201clista de clientes\u201d para chantajear a figuras poderosas que habr\u00edan cometido delitos similares.<\/p>\n<p>Tras ser confirmada como secretaria de Justicia a principios de este a\u00f1o, Pam Bondi abraz\u00f3 r\u00e1pidamente esas teor\u00edas, y en una entrevista en Fox News de febrero dijo que una lista de clientes estaba \u201cen su escritorio para revisar\u201d.<\/p>\n<p>Agreg\u00f3: \u201cEso ha sido una directiva del presidente Trump. Lo estoy revisando\u201d.<\/p>\n<p>Poco despu\u00e9s, en conjunto con la Casa Blanca, el Departamento de Justicia public\u00f3 una serie de documentos relacionados con la investigaci\u00f3n de Epstein, casi todos ya disponibles p\u00fablicamente. El Gobierno incluso invit\u00f3 a <em>influencers <\/em>a obtener una \u201cprimicia\u201d sobre los documentos en la Casa Blanca, y fotos del d\u00eda muestran a esos <em>influencers <\/em>saliendo con carpetas blancas etiquetadas como \u201cThe Epstein Files: Phase 1\u201d.<\/p>\n<p>Bondi prometi\u00f3 que habr\u00eda m\u00e1s informaci\u00f3n, y agentes del FBI \u2014muchos asignados a temas de seguridad nacional\u2014 trabajaron d\u00eda y noche para revisar documentos y otras pruebas para su publicaci\u00f3n. Pero pronto el departamento dej\u00f3 de mencionar la publicaci\u00f3n, para disgusto de los seguidores que inundaron las redes sociales del DOJ y el FBI exigiendo nueva informaci\u00f3n.<\/p>\n<p>El director del FBI, Kash Patel, y el subdirector Dan Bongino, ambos cr\u00edticos p\u00fablicos de la investigaci\u00f3n antes de asumir sus cargos, incluso empezaron a decir en entrevistas que no hab\u00eda pruebas de que Epstein hubiera sido asesinado. Bongino, en mayo, dijo que el video de la c\u00e1rcel, ahora publicado en l\u00ednea, es \u201cclaro como el agua\u201d.<\/p>\n<p>\u201cEn l\u00ednea con revelaciones previas, esta revisi\u00f3n confirm\u00f3 que Epstein da\u00f1\u00f3 a m\u00e1s de mil v\u00edctimas\u201d, dice el memorando del lunes. \u201cCada una sufri\u00f3 un trauma \u00fanico. Informaci\u00f3n sensible sobre estas v\u00edctimas est\u00e1 entrelazada en los materiales. Esto incluye detalles como nombres, im\u00e1genes, descripciones f\u00edsicas, lugares de nacimiento, asociados y antecedentes laborales\u201d.<\/p>\n<p>\u201cUna de nuestras m\u00e1s altas prioridades es combatir la explotaci\u00f3n infantil y hacer justicia a las v\u00edctimas. Perpetuar teor\u00edas infundadas sobre Epstein no ayuda a esos fines\u201d, a\u00f1ade.<\/p>\n<p>\u201cPor ello, aunque hemos trabajado para proporcionar al p\u00fablico la m\u00e1xima informaci\u00f3n sobre Epstein y examinado toda la evidencia en posesi\u00f3n del Gobierno, el Departamento de Justicia y el FBI determinan que no ser\u00eda apropiado ni justificado divulgar m\u00e1s informaci\u00f3n\u201d.<\/p>\n<p>Los informes sobre el anuncio generaron indignaci\u00f3n en l\u00ednea, especialmente de Elon Musk, exaliado de Trump, quien public\u00f3 una imagen de un marcador titulado \u201cEl contador oficial de arrestos por pedofilia de Jeffrey Epstein\u201d con el marcador en cero.<\/p>\n<p>\u201c\u00bfQu\u00e9 hora es? Oh, mira, es la hora de que nadie sea arrestado otra vez\u201d, escribi\u00f3 Musk en X.<\/p>\n<p>Hace seis semanas, Musk afirm\u00f3 en X que \u201c@realDonaldTrump est\u00e1 en los archivos de Epstein\u201d, y luego public\u00f3 un video de Trump en una fiesta con Epstein acompa\u00f1ado de un emoji de ceja levantada. Las publicaciones, ya eliminadas, formaron parte de una disputa entre Trump y Musk sobre el reciente proyecto de ley fiscal y de pol\u00edtica interna de Trump.<\/p>\n<p>Otras figuras de la derecha tambi\u00e9n criticaron el anuncio. El activista Jack Posobiec escribi\u00f3 en X \u201csi no hab\u00eda clientes, \u00bfpor qu\u00e9 Ghislaine Maxwell sigue en la c\u00e1rcel?\u201d, refiri\u00e9ndose a la socia de Epstein condenada por cargos relacionados con tr\u00e1fico sexual.<\/p>\n<p>Otro, Robby Starbuck, dijo sobre los comentarios previos de Bondi sobre una lista de clientes: \u201c\u00bfment\u00eda entonces o miente ahora? Merecemos respuestas\u201d.<\/p>\n<p>La secretaria de prensa de la Casa Blanca, Karoline Leavitt, defendi\u00f3 el lunes la \u201cexhaustiva investigaci\u00f3n\u201d del Departamento de Justicia sobre \u201ctodos los archivos relacionados con los cr\u00edmenes y la muerte de Epstein\u201d.<\/p>\n<p>Al ser presionada sobre la lista de clientes mencionada en la entrevista de Fox News en febrero, Leavitt dijo en una rueda de prensa que Bondi se refer\u00eda a \u201cla totalidad de la documentaci\u00f3n\u201d relacionada con Epstein.<\/p>\n<p>\u201cTodos los papeles en relaci\u00f3n con los cr\u00edmenes de Jeffrey Epstein. A eso se refer\u00eda la secretaria de Justicia. Y la dejar\u00e9 hablar por s\u00ed misma. Pero, de nuevo, en cuanto al FBI y el Departamento de Justicia, est\u00e1n m\u00e1s que comprometidos a asegurar que los criminales sean encarcelados\u201d, dijo Leavitt.<\/p>\n<p>El portavoz del DOJ, Chad Gilmartin, tambi\u00e9n dijo a CNN el lunes que, en la entrevista de Fox News, Bondi se refer\u00eda a toda la documentaci\u00f3n de la investigaci\u00f3n de Epstein, como los registros de vuelos, y no a una lista espec\u00edfica de clientes.<\/p>\n<p>Leavitt dijo que parte del material no se public\u00f3 porque era \u201cextremadamente expl\u00edcito y conten\u00eda pornograf\u00eda infantil\u201d.<\/p>\n<p>\u201cEsta administraci\u00f3n quiere que cualquiera que haya cometido un delito rinda cuentas\u2026 y el Gobierno de Trump est\u00e1 comprometido con la verdad y la transparencia\u201d, dijo Leavitt.<\/p>\n<p>\u201cSe comprometieron a una investigaci\u00f3n exhaustiva\u201d, continu\u00f3 Leavitt, refiri\u00e9ndose al Departamento de Justicia. \u201cEso es lo que hicieron, y proporcionaron los resultados. Eso es transparencia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras meses de anunciar la inminente publicaci\u00f3n de nueva informaci\u00f3n sobre el acusado de tr\u00e1fico sexual Jeffrey Epstein, el Departamento de Justicia de EE.UU. (DOJ, por sus siglas en ingl\u00e9s) anunci\u00f3 este lunes en un memorando que no hay pruebas de que \u00e9l tuviera una \u201clista de clientes\u201d ni de que fuera asesinado. Adem\u00e1s, el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1464294","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jeffrey Epstein muri\u00f3 por suicidio y no existe una &quot;lista de clientes&quot;, dice el Departamento de Justicia de EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jeffrey Epstein muri\u00f3 por suicidio y no existe una &quot;lista de clientes&quot;, dice el Departamento de Justicia de EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras meses de anunciar la inminente publicaci\u00f3n de nueva informaci\u00f3n sobre el acusado de tr\u00e1fico sexual Jeffrey Epstein, el Departamento de Justicia de EE.UU. (DOJ, por sus siglas en ingl\u00e9s) anunci\u00f3 este lunes en un memorando que no hay pruebas de que \u00e9l tuviera una \u201clista de clientes\u201d ni de que fuera asesinado. Adem\u00e1s, el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-07T21:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jeffrey Epstein muri\u00f3 por suicidio y no existe una &#171;lista de clientes&#187;, dice el Departamento de Justicia de EE.UU.\",\"datePublished\":\"2025-07-07T21:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/\"},\"wordCount\":1146,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/\",\"name\":\"Jeffrey Epstein muri\u00f3 por suicidio y no existe una \\\"lista de clientes\\\", dice el Departamento de Justicia de EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-07-07T21:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jeffrey Epstein muri\u00f3 por suicidio y no existe una &#171;lista de clientes&#187;, dice el Departamento de Justicia de EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jeffrey Epstein muri\u00f3 por suicidio y no existe una \"lista de clientes\", dice el Departamento de Justicia de EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Jeffrey Epstein muri\u00f3 por suicidio y no existe una \"lista de clientes\", dice el Departamento de Justicia de EE.UU. - Noticias","og_description":"Tras meses de anunciar la inminente publicaci\u00f3n de nueva informaci\u00f3n sobre el acusado de tr\u00e1fico sexual Jeffrey Epstein, el Departamento de Justicia de EE.UU. (DOJ, por sus siglas en ingl\u00e9s) anunci\u00f3 este lunes en un memorando que no hay pruebas de que \u00e9l tuviera una \u201clista de clientes\u201d ni de que fuera asesinado. Adem\u00e1s, el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/","og_site_name":"Noticias","article_published_time":"2025-07-07T21:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/"},"author":{"name":"","@id":""},"headline":"Jeffrey Epstein muri\u00f3 por suicidio y no existe una &#171;lista de clientes&#187;, dice el Departamento de Justicia de EE.UU.","datePublished":"2025-07-07T21:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/"},"wordCount":1146,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/","url":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/","name":"Jeffrey Epstein muri\u00f3 por suicidio y no existe una \"lista de clientes\", dice el Departamento de Justicia de EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-07-07T21:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jeffrey Epstein muri\u00f3 por suicidio y no existe una &#171;lista de clientes&#187;, dice el Departamento de Justicia de EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jeffrey Epstein muri\u00f3 por suicidio y no existe una &#171;lista de clientes&#187;, dice el Departamento de Justicia de EE.UU.","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/07\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-07-07T21:03:50Z","datePublished":"2025-07-07T21:03:50Z","dateModified":"2025-07-07T21:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jeffrey Epstein muri\\u00f3 por suicidio y no existe una &#171;lista de clientes&#187;, dice el Departamento de Justicia de EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/07\\\/07\\\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/07\\\/07\\\/jeffrey-epstein-murio-suicidio-no-existe-lista-clientes-departamento-justicia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-07T21:03:50Z\",\"datePublished\":\"2025-07-07T21:03:50Z\",\"dateModified\":\"2025-07-07T21:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471256,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/02\/15\/departamento-justicia-lista-personas-archivos-epstein-trax\/","url_meta":{"origin":1464294,"position":0},"title":"El Departamento de Justicia env\u00eda al Congreso una lista con cientos de personas destacadas mencionadas en archivos de Epstein","author":"","date":"febrero 15, 2026","format":false,"excerpt":"El Departamento de Justicia envi\u00f3 el s\u00e1bado al Congreso una lista de \u201cpersonas pol\u00edticamente expuestas\u201d que aparecen en los millones de archivos publicados en relaci\u00f3n con sus investigaciones sobre el delincuente sexual condenado Jeffrey Epstein.La carta de seis p\u00e1ginas, de la que CNN obtuvo una copia, incluye los nombres de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470664,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/30\/publican-mas-archivos-caso-jeffrey-epstein-trax\/","url_meta":{"origin":1464294,"position":1},"title":"El Departamento de Justicia publica millones de p\u00e1ginas de documentos en la investigaci\u00f3n de Epstein","author":"","date":"enero 30, 2026","format":false,"excerpt":"El Departamento de Justicia ha completado la revisi\u00f3n de los registros relacionados con Jeffrey Epstein y publicar\u00e1 los documentos a lo largo del viernes, anunci\u00f3 vicesecretario de Justicia Todd Blanche.Los documentos que se publicar\u00e1n hoy incluir\u00e1n m\u00e1s de 3 millones de p\u00e1ginas, 2.000 videos y 180.000 v\u00eddeos.La publicaci\u00f3n pondr\u00e1 fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471117,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/02\/11\/nombres-archivos-epstein-politicos-empresarios-famosos-hollywood-trax\/","url_meta":{"origin":1464294,"position":2},"title":"Pol\u00edticos, empresarios, figuras de Hollywood. Estos son los nombres que aparecen en los archivos de Epstein","author":"","date":"febrero 11, 2026","format":false,"excerpt":"Los archivos relacionados con el fallecido delincuente sexual convicto Jeffrey Epstein se han hecho p\u00fablicos a lo largo del \u00faltimo a\u00f1o en una serie de divulgaciones de documentos. M\u00e1s recientemente y de forma m\u00e1s amplia, el Departamento de Justicia de EE.UU. public\u00f3 millones de documentos (correos electr\u00f3nicos, mensajes de texto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464645,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/18\/trump-bondi-divulgacion-testimonios-epstein-trax\/","url_meta":{"origin":1464294,"position":3},"title":"Trump pide a Bondi que solicite la divulgaci\u00f3n de &#171;todos los testimonios pertinentes&#187; en torno a la investigaci\u00f3n de Epstein","author":"","date":"julio 18, 2025","format":false,"excerpt":"El presidente Donald Trump ha solicitado a la secretaria de Justicia Pam Bondi que presente los testimonios pertinentes relacionados con el presunto traficante sexual Jeffrey Epstein, aparentemente cediendo a la presi\u00f3n para que se publique m\u00e1s material sobre el caso.\u201cCon base en la rid\u00edcula publicidad que se le ha dado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464580,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/16\/trump-partidarios-debiles-bullshit-epstein-trax\/","url_meta":{"origin":1464294,"position":4},"title":"Trump carga contra &#171;d\u00e9biles&#187; que creen en las &#171;estupideces&#187; sobre Epstein en medio de presi\u00f3n para que publique documentos","author":"","date":"julio 16, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump acusa a algunos de sus antiguos partidarios de ser \u201cd\u00e9biles\u201d que est\u00e1n cayendo v\u00edctimas de las \u201cestupideces\u201d dem\u00f3cratas sobre el fallecido delincuente sexual Jeffrey Epstein, concluyendo que ya no quiere su apoyo.Este mensaje fue la se\u00f1al m\u00e1s clara hasta la fecha de las grietas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464759,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/22\/reunion-departamento-justicia-ghislaine-maxwell-caso-epstein-trax\/","url_meta":{"origin":1464294,"position":5},"title":"El Departamento de Justicia contact\u00f3 a Ghislaine Maxwell para una reuni\u00f3n en relaci\u00f3n con el caso Epstein","author":"","date":"julio 22, 2025","format":false,"excerpt":"El Departamento de Justicia dijo el martes que se comunic\u00f3 con la ex asociada de Jeffrey Epstein, Ghislaine Maxwell, para una reuni\u00f3n en medio de las cr\u00edticas por el manejo por parte de la administraci\u00f3n de los archivos relacionados con el acusado de tr\u00e1fico sexual.\u201cLa justicia exige valent\u00eda. Por primera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1464294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1464294"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1464294\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1464294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1464294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1464294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}