{"id":1469114,"date":"2025-12-09T09:03:39","date_gmt":"2025-12-09T17:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/"},"modified":"2025-12-09T09:03:39","modified_gmt":"2025-12-09T17:03:39","slug":"allanan-afa-futbol-clubes-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/","title":{"rendered":"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero"},"content":{"rendered":"<p>Un juez argentino orden\u00f3 el allanamiento de la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) y de m\u00e1s de 30 clubes de f\u00fatbol en forma simult\u00e1nea, confirm\u00f3 a CNN una fuente policial. La orden fue dictada por el juez federal Luis Armella en una causa en la que se investiga el presunto lavado de dinero por parte de la financiera \u201cSur Finanzas\u201d, uno de los principales auspiciantes de la casa rectora del f\u00fatbol argentino.<\/p>\n<p>CNN contact\u00f3 a la AFA, presidida por Claudio \u201cChiqui\u201d Tapia, para pedir comentarios y aun espera una respuesta.<\/p>\n<p>La empresa Sur Finanzas expres\u00f3 d\u00edas atr\u00e1s en un comunicado oficial que todos los servicios que presta se realizan en cumplimiento de la normativa vigente y habl\u00f3 de \u201cacusaciones infundadas\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juez argentino orden\u00f3 el allanamiento de la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) y de m\u00e1s de 30 clubes de f\u00fatbol en forma simult\u00e1nea, confirm\u00f3 a CNN una fuente policial. La orden fue dictada por el juez federal Luis Armella en una causa en la que se investiga el presunto lavado de dinero por parte [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469114","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un juez argentino orden\u00f3 el allanamiento de la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) y de m\u00e1s de 30 clubes de f\u00fatbol en forma simult\u00e1nea, confirm\u00f3 a CNN una fuente policial. La orden fue dictada por el juez federal Luis Armella en una causa en la que se investiga el presunto lavado de dinero por parte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-09T17:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero\",\"datePublished\":\"2025-12-09T17:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/\"},\"wordCount\":162,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/\",\"name\":\"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-09T17:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero - Noticias","og_description":"Un juez argentino orden\u00f3 el allanamiento de la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) y de m\u00e1s de 30 clubes de f\u00fatbol en forma simult\u00e1nea, confirm\u00f3 a CNN una fuente policial. La orden fue dictada por el juez federal Luis Armella en una causa en la que se investiga el presunto lavado de dinero por parte [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-09T17:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/"},"author":{"name":"","@id":""},"headline":"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero","datePublished":"2025-12-09T17:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/"},"wordCount":162,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/","name":"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-09T17:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y 30 clubes en una investigaci\u00f3n por presunto lavado de dinero","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/09\/allanan-afa-futbol-clubes-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-09T17:03:39Z","datePublished":"2025-12-09T17:03:39Z","dateModified":"2025-12-09T17:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Allanan la Asociaci\\u00f3n del F\\u00fatbol Argentino y 30 clubes en una investigaci\\u00f3n por presunto lavado de dinero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/12\\\/09\\\/allanan-afa-futbol-clubes-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/12\\\/09\\\/allanan-afa-futbol-clubes-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-09T17:03:39Z\",\"datePublished\":\"2025-12-09T17:03:39Z\",\"dateModified\":\"2025-12-09T17:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471908,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/05\/huelga-asociacion-futbol-argentino-orix\/","url_meta":{"origin":1469114,"position":0},"title":"La Asociaci\u00f3n de F\u00fatbol Argentino inicia una huelga en medio de su enfrentamiento con el Gobierno y a tres meses del Mundial","author":"","date":"marzo 5, 2026","format":false,"excerpt":"Argentina se quedar\u00e1 sin f\u00fatbol este fin de semana debido a una huelga de la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) que comienza este jueves y afectar\u00e1 a todos los partidos de la novena fecha del torneo local, as\u00ed como todas las divisiones del ascenso y las categor\u00edas juveniles, en protesta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472201,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/14\/nuevo-escandalo-futbol-argentino-meses-antes-mundial-orix\/","url_meta":{"origin":1469114,"position":1},"title":"A menos de tres meses del Mundial, un nuevo esc\u00e1ndalo sacude al f\u00fatbol argentino y su presidente Claudio Tapia","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Entre custodios y periodistas lleg\u00f3 este jueves Claudio Tapia, el presidente de la Asociaci\u00f3n del F\u00fatbol Argentino (AFA), a la sede judicial en la Ciudad de Buenos Aires para presentar declaratoria. El presidente fue el \u00faltimo de la c\u00fapula m\u00e1xima del f\u00fatbol argentino en declarar por la denuncia que present\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469137,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/10\/5-cosas-10-diciembre-orix\/","url_meta":{"origin":1469114,"position":2},"title":"Las 5 cosas que debes saber este 10 de diciembre: plan de Trump para Maduro, Mar\u00eda Corina Machado y Zelensky","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"Informan que Mar\u00eda Corina Machado no estar\u00e1 en la ceremonia de entrega del Nobel de la Paz en Oslo. Trump dice que Rusia tiene \u201cla ventaja\u201d y que Zelensky debe aceptarlo. Allanan la Asociaci\u00f3n del F\u00fatbol Argentino y a 30 clubes. Esto es lo que debes saber para comenzar el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448893,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/05\/05\/muere-cesar-luis-menotti-tecnico-campeon-seleccion-argentina-orix\/","url_meta":{"origin":1469114,"position":3},"title":"Muri\u00f3 C\u00e9sar Luis Menotti, primer t\u00e9cnico campe\u00f3n del mundo que tuvo Argentina, inform\u00f3 la AFA","author":"","date":"mayo 5, 2024","format":false,"excerpt":"(CNN) -- La Asociaci\u00f3n del F\u00fatbol Argentino inform\u00f3 a trav\u00e9s de sus cuentas oficiales sobre la muerte de C\u00e9sar Luis Menotti, quien fung\u00eda como director de Selecciones Nacionales y quien adem\u00e1s se destac\u00f3 por ser el primer director t\u00e9cnico nacional en ganar un campeonato mundial en 1978.En su hoja de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464665,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/19\/publico-visitante-futbol-argentino-orix\/","url_meta":{"origin":1469114,"position":4},"title":"Vuelve el p\u00fablico visitante al f\u00fatbol argentino tras 12 a\u00f1os","author":"","date":"julio 19, 2025","format":false,"excerpt":"Los estadios del f\u00fatbol argentino volver\u00e1n a recibir al p\u00fablico que apoya al equipo visitante, a 12 a\u00f1os de que se suspendiera para evitar actos de violencia. Este s\u00e1bado, el partido entre Lan\u00fas y Rosario Central por el Torneo Clausura de la Primera Divisi\u00f3n ser\u00e1 la primera prueba piloto del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451100,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/07\/14\/scaloni-argentina-como-le-ha-ido-seleccionador-orix\/","url_meta":{"origin":1469114,"position":5},"title":"\u00bfC\u00f3mo le ha ido a Scaloni como seleccionador de Argentina? \u00bfQu\u00e9 ha ganado y qu\u00e9 ha logrado?","author":"","date":"julio 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Desde que asumi\u00f3 la direcci\u00f3n t\u00e9cnica de la selecci\u00f3n de Argentina, Lionel Scaloni ha demostrado que su visi\u00f3n del f\u00fatbol aplicada con los envidiables talentos de los jugadores albicelestes, m\u00e1s la mezcla de juventud y experiencia, son una combinaci\u00f3n peligrosa para cualquier rival.Tras el doloroso fracaso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1469114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1469114"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1469114\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1469114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1469114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1469114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}