{"id":1469154,"date":"2025-12-10T13:03:45","date_gmt":"2025-12-10T21:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/"},"modified":"2025-12-10T13:03:45","modified_gmt":"2025-12-10T21:03:45","slug":"eeuu-incauto-barco-petrolero-venezuela-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/","title":{"rendered":"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela"},"content":{"rendered":"<p>El presidente Donald Trump confirm\u00f3 este mi\u00e9rcoles que EE.UU. ha tomado el control de un barco petrolero frente a la costa de Venezuela.<\/p>\n<p>\u201cComo probablemente saben, acabamos de incautar un petrolero en la costa de Venezuela\u201d, dijo Trump. \u201cUn gran petrolero, muy grande, el m\u00e1s grande jam\u00e1s incautado, de hecho\u201d.<\/p>\n<p>El presidente no ofreci\u00f3 ninguna explicaci\u00f3n inmediata sobre la medida, que probablemente aumente a\u00fan m\u00e1s las tensiones con la naci\u00f3n sudamericana.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump confirm\u00f3 este mi\u00e9rcoles que EE.UU. ha tomado el control de un barco petrolero frente a la costa de Venezuela. \u201cComo probablemente saben, acabamos de incautar un petrolero en la costa de Venezuela\u201d, dijo Trump. \u201cUn gran petrolero, muy grande, el m\u00e1s grande jam\u00e1s incautado, de hecho\u201d. El presidente no ofreci\u00f3 ninguna [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469154","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump confirm\u00f3 este mi\u00e9rcoles que EE.UU. ha tomado el control de un barco petrolero frente a la costa de Venezuela. \u201cComo probablemente saben, acabamos de incautar un petrolero en la costa de Venezuela\u201d, dijo Trump. \u201cUn gran petrolero, muy grande, el m\u00e1s grande jam\u00e1s incautado, de hecho\u201d. El presidente no ofreci\u00f3 ninguna [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-10T21:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela\",\"datePublished\":\"2025-12-10T21:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/\"},\"wordCount\":110,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/\",\"name\":\"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-10T21:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela - Noticias","og_description":"El presidente Donald Trump confirm\u00f3 este mi\u00e9rcoles que EE.UU. ha tomado el control de un barco petrolero frente a la costa de Venezuela. \u201cComo probablemente saben, acabamos de incautar un petrolero en la costa de Venezuela\u201d, dijo Trump. \u201cUn gran petrolero, muy grande, el m\u00e1s grande jam\u00e1s incautado, de hecho\u201d. El presidente no ofreci\u00f3 ninguna [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-10T21:03:45+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/"},"author":{"name":"","@id":""},"headline":"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela","datePublished":"2025-12-10T21:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/"},"wordCount":110,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/","name":"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-10T21:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump dice que EE.UU. incaut\u00f3 un barco petrolero frente a la costa de Venezuela","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/10\/eeuu-incauto-barco-petrolero-venezuela-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-10T21:03:45Z","datePublished":"2025-12-10T21:03:45Z","dateModified":"2025-12-10T21:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump dice que EE.UU. incaut\\u00f3 un barco petrolero frente a la costa de Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/12\\\/10\\\/eeuu-incauto-barco-petrolero-venezuela-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/12\\\/10\\\/eeuu-incauto-barco-petrolero-venezuela-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-10T21:03:45Z\",\"datePublished\":\"2025-12-10T21:03:45Z\",\"dateModified\":\"2025-12-10T21:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469811,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/05\/interceptar-petrolero-venezuela-rusia-trax\/","url_meta":{"origin":1469154,"position":0},"title":"EE.UU. se prepara para interceptar un petrolero vinculado con Venezuela pese a los reclamos de Rusia, seg\u00fan fuentes","author":"","date":"enero 5, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos prepara una operaci\u00f3n para intentar interceptar un petrolero que se ha convertido en el centro de una disputa internacional. Seg\u00fan confirmaron cuatro fuentes familiarizadas con el asunto, la embarcaci\u00f3n es objeto de un reclamo de jurisdicci\u00f3n por parte de Rusia, lo que posiciona este incidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469170,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/11\/5-cosas-11-diciembre-orix\/","url_meta":{"origin":1469154,"position":1},"title":"Las 5 cosas que debes saber este 11 de diciembre: Mar\u00eda Corina Machado, EE.UU. incauta barco petrolero, Ucrania","author":"","date":"diciembre 11, 2025","format":false,"excerpt":"Trump dice que incautaron un barco petrolero frente a la costa de Venezuela. La crisis que mantiene en vilo a Honduras. Ucrania presenta su respuesta al plan de paz de EE.UU. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469431,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/19\/petrolero-sancionado-entra-aguas-venezolanas-bloqueo-trump-trax\/","url_meta":{"origin":1469154,"position":2},"title":"Datos de rastreo muestran que un petrolero sancionado entr\u00f3 en aguas venezolanas, desafiando el bloqueo de Trump","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"Un petrolero y qu\u00edmico sancionado por Estados Unidos ha entrado en aguas venezolanas, seg\u00fan mostraron datos de rastreo de barcos, a pesar de que el presidente de EE.UU., Donald Trump, declar\u00f3 un \u201cbloqueo total y completo\u201d a dichos buques que transitan por el pa\u00eds.El barco con bandera de Gambia, llamado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469470,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/21\/intercepta-buque-venezuela-tercero-trax\/","url_meta":{"origin":1469154,"position":3},"title":"EE.UU. trabaj\u00f3 para interceptar otro buque cerca de Venezuela","author":"","date":"diciembre 21, 2025","format":false,"excerpt":"Personal de EE.UU. trabaj\u00f3 para interceptar este domingo otro buque cerca de Venezuela, dijo un funcionario estadounidense. Se trata del segundo barco intervenido este fin de semana, en medio del aumento de la presi\u00f3n de Washington sobre el presidente Nicol\u00e1s Maduro.A\u00fan no estaba claro el estado del buque ni si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470116,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/15\/cuantos-petroleros-incauto-eeuu-orix\/","url_meta":{"origin":1469154,"position":4},"title":"\u00bfCu\u00e1ntos petroleros vinculados a Venezuela ha incautado EE.UU.? Cronolog\u00eda de las acciones del Gobierno de Trump","author":"","date":"enero 15, 2026","format":false,"excerpt":"Estados Unidos inform\u00f3 este jueves que hab\u00eda incautado un barco petrolero en el mar Caribe, en un anuncio que se ha vuelto casi habitual en las \u00faltimas semanas: desde principios de diciembre, las fuerzas del pa\u00eds norteamericano se han hecho con el control de al menos seis petroleros vinculados de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469506,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/22\/trump-sigue-busqueda-petrolero-venezuela-maduro-trax\/","url_meta":{"origin":1469154,"position":5},"title":"Trump dice que EE.UU. sigue en la b\u00fasqueda de un petrolero y que ser\u00eda &#171;inteligente&#187; que Maduro deje el poder","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"El presidente Donald Trump dijo este lunes que Estados Unidos sigue en la b\u00fasqueda activa de un petrolero frente a las costas de Venezuela, m\u00e1s de 24 horas despu\u00e9s de que comenzara la persecuci\u00f3n, mientras repet\u00eda sus amenazas contra el presidente de Venezuela, Nicol\u00e1s Maduro.\u201cEst\u00e1 avanzando y al final lo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1469154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1469154"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1469154\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1469154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1469154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1469154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}