{"id":1469212,"date":"2025-12-12T08:03:48","date_gmt":"2025-12-12T16:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/"},"modified":"2025-12-12T08:03:48","modified_gmt":"2025-12-12T16:03:48","slug":"trump-indulto-tina-peters-cargos-estatales-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/","title":{"rendered":"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales"},"content":{"rendered":"<p>El presidente Donald Trump anunci\u00f3 el jueves que le otorgar\u00e1 a Tina Peters un indulto federal completo, lo que probablemente aumentar\u00e1 la presi\u00f3n para liberar a la exsecretaria de Colorado de la prisi\u00f3n, a pesar de que no puede anular los cargos estatales.<\/p>\n<p>\u201cTina se encuentra en una prisi\u00f3n de Colorado por el \u2018delito\u2019 de exigir elecciones honestas. Hoy le otorgo un indulto completo por sus intentos de exponer el fraude electoral en las ama\u00f1adas elecciones presidenciales de 2020\u201d, escribi\u00f3 el presidente en Truth Social.<\/p>\n<p>Peters, exsecretaria republicana de Mesa, Colorado, fue declarada culpable el a\u00f1o pasado de cargos estatales por participar en un plan para violar los sistemas de votaci\u00f3n con el fin de probar las falsas afirmaciones de Trump sobre fraude electoral masivo en 2020. Fue sentenciada a nueve a\u00f1os de prisi\u00f3n y cumple su condena en una prisi\u00f3n para mujeres en Pueblo, Colorado.<\/p>\n<p>Peters es actualmente la \u00fanica aliada de Trump en prisi\u00f3n por delitos relacionados con los intentos de anular las elecciones presidenciales de 2020. Ella a\u00fan cree que las elecciones fueron robadas, seg\u00fan declararon recientemente sus abogados a CNN. Sus abogados tambi\u00e9n han expresado su preocupaci\u00f3n por su seguridad f\u00edsica y le han dicho a un juez que su salud se est\u00e1 deteriorando tras las rejas.<\/p>\n<p>El indulto de Trump no tiene impacto legal en su condena ni en su encarcelamiento. Sin embargo, el Gobierno ha estado presionando a las autoridades de Colorado para que la liberen o, al menos, la transfieran a custodia federal, donde podr\u00eda ser trasladada a una instalaci\u00f3n m\u00e1s c\u00f3moda. El Departamento de Justicia incluso intervino para apoyar el intento fallido de Peters de convencer a un juez federal de que la liberara.<\/p>\n<p>Tras meses de audiencias y presentaciones legales, un juez federal en Denver rechaz\u00f3 el lunes su demanda federal solicitando su liberaci\u00f3n, concluyendo que los tribunales estatales son la jurisdicci\u00f3n adecuada para que ella impugne su condena.<\/p>\n<p>El gobernador dem\u00f3crata de Colorado, Jared Polis, defendi\u00f3 en un comunicado la condena de Peters. \u201cNing\u00fan presidente tiene jurisdicci\u00f3n sobre las leyes estatales ni la facultad de indultar a una persona por condenas estatales. Este es un asunto que deben decidir los tribunales, y acataremos sus \u00f3rdenes\u201d, declar\u00f3.<\/p>\n<p>Polis ha declarado previamente que no indultar\u00e1 a Peters como parte de ning\u00fan acuerdo de compensaci\u00f3n.<\/p>\n<p>El fiscal general de Colorado, Phil Weiser, dem\u00f3crata que lucha por confirmar la condena de Peters y mantenerla en prisi\u00f3n, tambi\u00e9n desestim\u00f3 el indulto en un comunicado.<\/p>\n<p>\u201cLa idea de que un presidente pueda indultar a alguien juzgado y condenado en un tribunal estatal no tiene precedentes en el derecho estadounidense, ser\u00eda una desviaci\u00f3n escandalosa de lo que exige nuestra Constituci\u00f3n y no se sostendr\u00e1\u201d, declar\u00f3 Weiser.<\/p>\n<p><em>Con informaci\u00f3n de Kaitlan Collins, de CNN.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump anunci\u00f3 el jueves que le otorgar\u00e1 a Tina Peters un indulto federal completo, lo que probablemente aumentar\u00e1 la presi\u00f3n para liberar a la exsecretaria de Colorado de la prisi\u00f3n, a pesar de que no puede anular los cargos estatales. \u201cTina se encuentra en una prisi\u00f3n de Colorado por el \u2018delito\u2019 de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469212","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump anunci\u00f3 el jueves que le otorgar\u00e1 a Tina Peters un indulto federal completo, lo que probablemente aumentar\u00e1 la presi\u00f3n para liberar a la exsecretaria de Colorado de la prisi\u00f3n, a pesar de que no puede anular los cargos estatales. \u201cTina se encuentra en una prisi\u00f3n de Colorado por el \u2018delito\u2019 de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T16:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales\",\"datePublished\":\"2025-12-12T16:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/\"},\"wordCount\":521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/\",\"name\":\"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-12T16:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales - Noticias","og_description":"El presidente Donald Trump anunci\u00f3 el jueves que le otorgar\u00e1 a Tina Peters un indulto federal completo, lo que probablemente aumentar\u00e1 la presi\u00f3n para liberar a la exsecretaria de Colorado de la prisi\u00f3n, a pesar de que no puede anular los cargos estatales. \u201cTina se encuentra en una prisi\u00f3n de Colorado por el \u2018delito\u2019 de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-12T16:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/"},"author":{"name":"","@id":""},"headline":"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales","datePublished":"2025-12-12T16:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/"},"wordCount":521,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/","name":"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-12T16:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump anuncia indulto para Tina Peters, aumentando la presi\u00f3n para liberarla, aunque no puede anular los cargos estatales","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/12\/trump-indulto-tina-peters-cargos-estatales-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-12T16:03:48Z","datePublished":"2025-12-12T16:03:48Z","dateModified":"2025-12-12T16:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump anuncia indulto para Tina Peters, aumentando la presi\\u00f3n para liberarla, aunque no puede anular los cargos estatales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/12\\\/12\\\/trump-indulto-tina-peters-cargos-estatales-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2025\\\/12\\\/12\\\/trump-indulto-tina-peters-cargos-estatales-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-12T16:03:48Z\",\"datePublished\":\"2025-12-12T16:03:48Z\",\"dateModified\":\"2025-12-12T16:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469691,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/31\/trump-veta-proyectos-ley-bipartidistas-trax\/","url_meta":{"origin":1469212,"position":0},"title":"Trump veta dos proyectos de ley bipartidistas: son los primeros vetos del segundo mandato","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"El presidente Donald Trump emiti\u00f3 este martes los primeros vetos de su segundo mandato, con el objetivo de bloquear dos proyectos de ley bipartidistas relacionados con infraestructura.El presidente argument\u00f3 que frenar ambas medidas era necesario para ahorrar dinero de los contribuyentes.\u201cBasta ya. Mi Gobierno est\u00e1 comprometido a evitar que los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468187,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/11\/10\/trump-indulta-rudy-giuliani-elecciones-2020-trax\/","url_meta":{"origin":1469212,"position":1},"title":"Trump indulta a Rudy Giuliani y a otros implicados en los intentos de anular las elecciones de 2020, seg\u00fan su abogado","author":"","date":"noviembre 10, 2025","format":false,"excerpt":"El presidente Donald Trump indult\u00f3 a una larga lista de sus aliados pol\u00edticos por su apoyo o participaci\u00f3n en supuestos planes para anular las elecciones presidenciales de 2020, seg\u00fan el abogado de indultos del Departamento de Justicia, Ed Martin.Entre las personas enumeradas en una proclamaci\u00f3n que Martin public\u00f3 en X\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456195,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/12\/02\/estos-son-los-indultos-y-conmutaciones-de-alto-perfil-que-trump-ha-otorgado-durante-su-presidencia\/","url_meta":{"origin":1469212,"position":2},"title":"Estos son algunos de los indultos y conmutaciones de alto perfil que Trump otorg\u00f3 durante su presidencia","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) -- El final del mandato de Donald Trump estuvo marcado por un renovado inter\u00e9s en los indultos y conmutaciones, tanto del entonces presidente como de miembros de su c\u00edrculo \u00edntimo que buscaban protecci\u00f3n antes de que el entonces presidente electo Joe Biden asumiera el cargo.Pero incluso desde su llegada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470206,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/18\/doble-indulto-trump-uso-clemencia-trax\/","url_meta":{"origin":1469212,"position":3},"title":"El doble indulto de Trump resalta el uso amplio de la clemencia","author":"","date":"enero 18, 2026","format":false,"excerpt":"El presidente Donald Trump ha hecho un uso mucho m\u00e1s agresivo de sus poderes de clemencia presidencial en su segundo mandato; de hecho, indult\u00f3 a una misma mujer dos veces.Trump concedi\u00f3 una serie de indultos el viernes, incluido uno para Adriana Camberos, quien fue condenada por segunda vez despu\u00e9s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468393,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/11\/16\/trump-nuevos-indultos-insurreccion-6-enero-trax\/","url_meta":{"origin":1469212,"position":4},"title":"Trump emite nuevos indultos para participantes de la insurrecci\u00f3n del 6 de enero, incluyendo al miembro de una milicia","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, emiti\u00f3 un nuevo indulto a un miembro de una milicia involucrado en el asalto al Capitolio del 6 de enero de 2021, que cubre delitos con armas de fuego en Kentucky, que no estaban incluidos en su indulto inicial del d\u00eda de su investidura.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456240,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/12\/03\/trump-indulto-hunter-biden-anular-condena-sobornos-trax\/","url_meta":{"origin":1469212,"position":5},"title":"Trump alude al indulto a Hunter Biden en su \u00faltimo intento legal de anular la condena por pago por silencio","author":"","date":"diciembre 3, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Los abogados defensores del presidente electo Donald Trump est\u00e1n utilizando el indulto del presidente Joe Biden a su hijo Hunter para argumentar que la condena de Trump en su caso de pagos de dinero por silencio en Manhattan deber\u00eda ser desestimada.\u201cAyer, al otorgarle a Hunter Biden un indulto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1469212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1469212"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1469212\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1469212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1469212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1469212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}