{"id":1472224,"date":"2026-03-15T12:03:45","date_gmt":"2026-03-15T19:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/"},"modified":"2026-03-15T12:03:45","modified_gmt":"2026-03-15T19:03:45","slug":"one-battle-after-another-resena-anderson-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/","title":{"rendered":"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson"},"content":{"rendered":"<p>Martin Scorsese y Steven Spielberg ya vieron \u201cOne Battle After Another\u201d y se extendieron en halagos hacia ella. Por su parte, la prensa y los cr\u00edticos han llegado a considerarla no solo \u201cla mejor pel\u00edcula del a\u00f1o\u201d, sino \u201cde la d\u00e9cada\u201d. Con todos estoy de acuerdo, pero me parece que tanta euforia por lo m\u00e1s reciente de Paul Thomas Anderson llega 25 a\u00f1os tarde.<\/p>\n<p>Antes de entrar en materia, quisiera hacer una aclaraci\u00f3n.<\/p>\n<p>Durante estos \u00faltimos 25 a\u00f1os, ante la pregunta de cu\u00e1l es mi director contempor\u00e1neo favorito, mi respuesta siempre es PTA, por las siglas de su nombre y la forma que adopt\u00f3 su p\u00fablico para llamarlo. Y en la categor\u00eda de \u201ctodos los tiempos\u201d, PTA tiene un puesto asegurado entre Stanley Kubrick y Orson Wells, por nombrar solo a un par.<\/p>\n<p>S\u00ed, mi admiraci\u00f3n por este cineasta es infinita. Por eso, me preocupa el hecho de que ahora presenten a \u201cUna batalla tras otra\u201d (su t\u00edtulo en espa\u00f1ol) como la gran sorpresa del a\u00f1o, superando a otras pel\u00edculas que desde Cannes y Venecia ven\u00edan perfil\u00e1ndose como las mejores del 2025, y que solo se trate de un runr\u00fan moment\u00e1neo que injustamente vaya perdiendo fuerza a medida que lleguen nuevos t\u00edtulos a la cartelera.<\/p>\n<p>Ahora enfoqu\u00e9monos propiamente en la pel\u00edcula, que tiene 13 nominaciones a los premios Oscar 2026, incluyendo mejor cinta y mejor director.<\/p>\n<p>Se trata de un revolucionario de vieja data, interpretado por Leonardo DiCaprio, que despu\u00e9s de muchas batallas por la igualdad y la justicia, ahora se solidariza con los inmigrantes que tratan de alcanzar el hoy discutible \u201csue\u00f1o americano\u201d. En el camino, su lucha tambi\u00e9n ser\u00e1 por el bienestar de su hija.<\/p>\n<p>\u201cUna batalla tras otra\u201d toca temas candentes de la actualidad, pese a que est\u00e1 inspirada en la novela \u201cVineland\u201d, del escritor Thomas Pynchon y enmarcada en 1984, a\u00f1o en el que Ronald Reagan, presidente republicano, fue reelegido. Pese a los 40 a\u00f1os de diferencia entre el entonces y el ahora, la pel\u00edcula nos plantea qu\u00e9 tanto seguimos repitiendo nuestra historia o si, en definitiva, nunca aprendemos de nuestros errores.<\/p>\n<p>Durante los primeros minutos de la cinta, vemos las famosas jaulas que desde hace mucho se utilizan para la detenci\u00f3n de inmigrantes indocumentados. M\u00e1s adelante, la c\u00e1mara nos pasea por hogares o negocios de latinos que dan refugio a otros latinos, quienes est\u00e1n obligados a vivir escondidos ante el acecho de las fuerzas de seguridad, representadas por un amenazante pero tambi\u00e9n pat\u00e9tico coronel del Ej\u00e9rcito, encarnado aqu\u00ed por Sean Penn.<\/p>\n<p>La pel\u00edcula se mueve entre diferentes g\u00e9neros y tonos. Hay acci\u00f3n, hay suspenso, hay mucho humor y tambi\u00e9n reflexi\u00f3n. Pero eso lo viene haciendo PTA desde siempre.<\/p>\n<p>En 1999, nos ofreci\u00f3 \u201cMagnolia\u201d, la que hoy sigue siendo mi preferida entre toda su filmograf\u00eda y cuyo \u00edmpetu narrativo pocos han igualado. En 2002, con \u201cPunch-Drunk Love\u201d, se la jug\u00f3 con el lado m\u00e1s vulnerable y menos jocoso de Adam Sandler. Incluso con \u201cBoogie Nights\u201d (1997), una de sus primeras obras, se present\u00f3 como una de las voces m\u00e1s originales y potentes de la cinematograf\u00eda estadounidense.<\/p>\n<p>Volviendo a \u201cOne Battle After Another\u201d, Scorsese dijo, frente a colegas suyos del sindicato de directores de Estados Unidos, que se trata de una pel\u00edcula \u201cfascinante hecha de forma extraordinaria con actuaciones estupendas en general\u201d.<\/p>\n<p>Por su parte, Spielberg, en una charla con PTA, la describi\u00f3 como una \u201clocura de pel\u00edcula\u201d. Adem\u00e1s coment\u00f3: \u201cHay m\u00e1s acci\u00f3n en su primera hora que en cualquier otra pel\u00edcula que hayas dirigido. Todo es realmente incre\u00edble\u201d.<\/p>\n<p>El elenco, en su totalidad, es impresionante.<\/p>\n<p>PTA siempre ha sabido elegir a los actores adecuados para cada personaje, sin importar cu\u00e1n familiar resulte su cara para el espectador.<\/p>\n<p>Vuelvo a \u201cMagnolia\u201d porque mientras con esa pel\u00edcula le regal\u00f3 a Tom Cruise su tercera nominaci\u00f3n al premio Oscar como actor, es dif\u00edcil olvidar la destacada intervenci\u00f3n de un Philip Baker Hall, como conductor de un concurso de televisi\u00f3n, o de la actriz Melora Walters, como una mujer adicta al borde del colapso.<\/p>\n<p>Ese buen ojo y gran sensibilidad que ha demostrado al momento de elegir a sus elencos sale a relucir una vez m\u00e1s con \u201cOne Battle After Another\u201d. Estrellas como Leonardo DiCaprio, Sean Penn y Benicio del Toro interact\u00faan con colegas menos conocidos, pero no menos talentosos, como Teyana Taylor y Chase Infiniti.<\/p>\n<p>Este a\u00f1o, en la entrega del premio Oscar, dos de los principales contendientes a Mejor Pel\u00edcula me remitieron constantemente al trabajo de PTA. Me refiero a \u201cAnora\u201d (la que termin\u00f3 llev\u00e1ndose la estatuilla), de Sean Baker, y a \u201cThe Brutalist\u201d, de Brady Corbet.<\/p>\n<p>Desconozco si para los directores de estas dos cintas, PTA representa una importante influencia, pero en ambas producciones, siendo tan distantes entre s\u00ed, pude notar algunos trazos similares a los de mi director favorito.<\/p>\n<p>Y con esto, llego al tema de la Academia, que si bien ha distinguido a PTA con once nominaciones al Oscar como productor, director y guionista, nunca, repito, nunca le ha dado una sola estatuilla.<\/p>\n<p>Desde hace 25 a\u00f1os ha tenido oportunidades de sobra para hacerlo, pero hasta hoy se sigue negando a ello.<\/p>\n<p>As\u00ed que, por esta raz\u00f3n, espero que el runr\u00fan por su nueva obra maestra no sea pasajero y se materialice con una barrida de premios el pr\u00f3ximo 15 de marzo de 2026, en la entrega n\u00famero 98 de estos galardones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martin Scorsese y Steven Spielberg ya vieron \u201cOne Battle After Another\u201d y se extendieron en halagos hacia ella. Por su parte, la prensa y los cr\u00edticos han llegado a considerarla no solo \u201cla mejor pel\u00edcula del a\u00f1o\u201d, sino \u201cde la d\u00e9cada\u201d. Con todos estoy de acuerdo, pero me parece que tanta euforia por lo m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472224","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;One Battle After Another&quot;: tan magistral como todo lo de Paul Thomas Anderson - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;One Battle After Another&quot;: tan magistral como todo lo de Paul Thomas Anderson - Noticias\" \/>\n<meta property=\"og:description\" content=\"Martin Scorsese y Steven Spielberg ya vieron \u201cOne Battle After Another\u201d y se extendieron en halagos hacia ella. Por su parte, la prensa y los cr\u00edticos han llegado a considerarla no solo \u201cla mejor pel\u00edcula del a\u00f1o\u201d, sino \u201cde la d\u00e9cada\u201d. Con todos estoy de acuerdo, pero me parece que tanta euforia por lo m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-15T19:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson\",\"datePublished\":\"2026-03-15T19:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/\"},\"wordCount\":971,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/\",\"name\":\"\\\"One Battle After Another\\\": tan magistral como todo lo de Paul Thomas Anderson - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-15T19:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"One Battle After Another\": tan magistral como todo lo de Paul Thomas Anderson - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\"One Battle After Another\": tan magistral como todo lo de Paul Thomas Anderson - Noticias","og_description":"Martin Scorsese y Steven Spielberg ya vieron \u201cOne Battle After Another\u201d y se extendieron en halagos hacia ella. Por su parte, la prensa y los cr\u00edticos han llegado a considerarla no solo \u201cla mejor pel\u00edcula del a\u00f1o\u201d, sino \u201cde la d\u00e9cada\u201d. Con todos estoy de acuerdo, pero me parece que tanta euforia por lo m\u00e1s [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-15T19:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/"},"author":{"name":"","@id":""},"headline":"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson","datePublished":"2026-03-15T19:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/"},"wordCount":971,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/","name":"\"One Battle After Another\": tan magistral como todo lo de Paul Thomas Anderson - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-15T19:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/15\/one-battle-after-another-resena-anderson-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-15T19:03:45Z","datePublished":"2026-03-15T19:03:45Z","dateModified":"2026-03-15T19:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/15\\\/one-battle-after-another-resena-anderson-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/15\\\/one-battle-after-another-resena-anderson-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-15T19:03:45Z\",\"datePublished\":\"2026-03-15T19:03:45Z\",\"dateModified\":\"2026-03-15T19:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466768,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/09\/24\/one-battle-after-another-dicaprio-paul-thomas-anderson-orix\/","url_meta":{"origin":1472224,"position":0},"title":"&#171;One Battle After Another&#187;: tan magistral como todo lo de Paul Thomas Anderson","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"Martin Scorsese y Steven Spielberg ya vieron \u201cOne Battle After Another\u201d y se extendieron en halagos hacia ella. Por su parte, la prensa y los cr\u00edticos han llegado a considerarla no solo \u201cla mejor pel\u00edcula del a\u00f1o\u201d, sino \u201cde la d\u00e9cada\u201d. Con todos estoy de acuerdo, pero me parece que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472173,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/13\/sinners-impulso-premios-oscar-2026-orix\/","url_meta":{"origin":1472224,"position":1},"title":"&#171;Sinners&#187; y el impulso de \u00faltimo momento que la llevar\u00eda a la gloria del Oscar","author":"","date":"marzo 13, 2026","format":false,"excerpt":"Para pronosticar los ganadores del Oscar se vale cualquier m\u00e9todo.Tenemos el de la observaci\u00f3n y el descarte, pero tambi\u00e9n el de las matem\u00e1ticas puras, donde se suman y restan los aciertos y desaciertos de cada pel\u00edcula nominada. Y finalmente, est\u00e1 el de las corazonadas porque, en mi caso, el cine\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472192,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/14\/one-battle-after-another-favorita-oscars-orix\/","url_meta":{"origin":1472224,"position":2},"title":"\u00bfPor qu\u00e9 &#171;One Battle After Another&#187; es una de las favoritas para ganar el premio Oscar?","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Desde que su estreno en septiembre de 2025, \u201cOne Battle After Another\u201d fue considerada por la cr\u00edtica como la cinta a la que hab\u00eda que vencer en la carrera por el premio Oscar a mejor pel\u00edcula del a\u00f1o.As\u00ed que ese es el principal atributo de cara a la gala de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468967,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/04\/tarantino-peliculas-favoritas-siglo-xxi-paul-dano-orix\/","url_meta":{"origin":1472224,"position":3},"title":"Quentin Tarantino nombra sus 20 pel\u00edculas favoritas del siglo XXI y critica al actor Paul Dano","author":"","date":"diciembre 4, 2025","format":false,"excerpt":"El director Quentin Tarantino es una figura controversial en Hollywood, no solo por las escenas violentas de sus pel\u00edculas sino por sus comentarios apasionados sobre cintas y estrellas de cine.Esto fue evidente en su participaci\u00f3n el martes en el podcast del escritor Brett Easton Ellis, en el que el director\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469692,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/31\/10-peliculas-2025-orix\/","url_meta":{"origin":1472224,"position":4},"title":"No s\u00e9 si son las mejores, pero son mis favoritas: las 10 pel\u00edculas de 2025","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"En esta \u00e9poca del a\u00f1o, sumado a los nunca bien cumplidos prop\u00f3sitos, suelo escuchar una queja entre algunos malhumorados cin\u00e9filos: \u201ceste a\u00f1o no hubo buenas pel\u00edculas\u201d. Pero esta vez, la queja no se ha sentido.Y es que en el 2025 lo tuvimos todo\u2026 y en grande. Desde el regreso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470595,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/29\/paul-dano-responde-criticas-tarantino-trax\/","url_meta":{"origin":1472224,"position":5},"title":"El actor Paul Dano responde a las cr\u00edticas de Quentin Tarantino hacia \u00e9l","author":"","date":"enero 29, 2026","format":false,"excerpt":"El actor Paul Dano ha roto su silencio sobre las duras cr\u00edticas que Quentin Tarantino hizo sobre \u00e9l.El director de \u201cPulp Fiction\u201d lanz\u00f3 un feroz ataque contra Dano durante una entrevista en \u201cThe Bret Easton Ellis Podcast\u201d en un episodio publicado el mes pasado.Durante la conversaci\u00f3n, Tarantino dijo que su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1472224"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472224\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1472224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1472224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1472224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}