{"id":1472262,"date":"2026-03-16T20:03:49","date_gmt":"2026-03-17T03:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/"},"modified":"2026-03-16T20:03:49","modified_gmt":"2026-03-17T03:03:49","slug":"neymar-afuera-lista-ancelotti-amistosos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/","title":{"rendered":"&#171;Estoy molesto y triste&#187;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026?"},"content":{"rendered":"<p>Carlo Ancelotti, director t\u00e9cnico de la selecci\u00f3n de Brasil, present\u00f3 la lista de 26 futbolistas convocados para la fecha FIFA de finales de marzo, donde destacan las presencias de Alisson Becker, portero del Liverpool, Marquinhos, del Paris Saint-Germain, Casemiro, del Manchester United, Vin\u00edcius Jr. y Raphinha, delanteros del Real Madrid y el Barcelona, entre otros.<\/p>\n<p>Sin embargo, ninguna de esas presencias genera tanto ruido como la ausencia de un gran nombre: Neymar. El delantero que est\u00e1 disputando la Serie A del Brasileirao con el Santos ten\u00eda esperanzas de subirse al avi\u00f3n de la Verdeamarela la semana pr\u00f3xima, en lo que ser\u00e1 la \u00faltima prueba para Ancelotti antes de tener que entregar la lista definitiva para la <a href=\"https:\/\/cnnespanol.cnn.com\/deportes\/mundial-2026\">Copa Mundial de la FIFA<\/a>, que comenzar\u00e1 en junio.<\/p>\n<p>El exfutbolista del FC Barcelona y el PSG habl\u00f3 con MadHouseTV al finalizar un partido en la Kings League y reconoci\u00f3 sentirse \u201cmolesto y triste\u201d. \u201cVoy a hablar porque no puedo quedarme callado, pero la concentraci\u00f3n sigue siendo la misma: d\u00eda tras d\u00eda, entrenamiento tras entrenamiento, partido tras partido\u201d, dijo el delantero, a quien a\u00fan le queda una \u00faltima convocatoria posible antes de la gran cita de mitad de a\u00f1o.<\/p>\n<p>La selecci\u00f3n de Brasil enfrentar\u00e1 a dos rivales de renombre: Francia el 26 de marzo y Croacia el 31 del mismo mes, dos seleccionados que servir\u00e1n para medir el nivel actual de los pentacampeones del mundo y tachar o confirmar nombres en la mente del estratega italiano.<\/p>\n<p>Por eso, su ausencia es una mala se\u00f1al para \u201cNey\u201d, que no se viste de amarillo y azul desde octubre de 2023, cuando se rompi\u00f3 el ligamento cruzado anterior de la rodilla izquierda en un encuentro contra la selecci\u00f3n de Uruguay. Aquella fat\u00eddica tarde marc\u00f3 el principio de un largo periplo para el \u201c10\u201d de la Canarinha, que pas\u00f3 sin pena ni gloria por el f\u00fatbol \u00e1rabe hasta pegar la vuelta a su querido Santos, donde las molestias f\u00edsicas tambi\u00e9n lo han tenido a maltraer.<\/p>\n<p>Sin embargo, la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/03\/deportes\/rodrygo-lesion-mundial-2026-neymar-ancelotti-orix\">grave lesi\u00f3n<\/a>, tambi\u00e9n de rodilla, que sufri\u00f3 hace apenas semanas el delantero del Real Madrid Rodrygo Goes, parec\u00eda abrirle una puerta al regreso del nacido en Sao Paulo hace 34 a\u00f1os. Rodrygo era una fija en la lista de Ancelotti, que ya lo conoce de cuando el italiano guio al Merengue a su \u00faltima Champions League, justamente con Rodrygo y Vin\u00edcius como dupla de atacantes.<\/p>\n<p>El propio Neymar vio abrirse la puerta, o as\u00ed pareci\u00f3 a ra\u00edz de sus <a href=\"https:\/\/www.bing.com\/ck\/a?!&#038;&#038;p=6e65ebd6746d736d41547eb110fe4329ddc37828329ab1626613b3f4be8916faJmltdHM9MTc3MzYxOTIwMA&#038;ptn=3&#038;ver=2&#038;hsh=4&#038;fclid=0e96f89c-bb30-696f-3040-ef81ba0a6810&#038;psq=seleccion+brasil++x&#038;u=a1aHR0cHM6Ly93d3cudHljc3BvcnRzLmNvbS9mdXRib2wtZGUtYnJhc2lsL25leW1hci1zZWxlY2Npb24tYnJhc2lsLW11bmRpYWwtMjAyNi1pZDcxODcxNi5odG1s\">declaraciones<\/a>: \u201cEstoy trabajando para lograrlo. Obviamente, mi deseo es regresar a la selecci\u00f3n nacional y jugar en el Mundial. Pero eso no depende de m\u00ed. La decisi\u00f3n la toma el comit\u00e9. Est\u00e9 o no est\u00e9, siempre apoyar\u00e9 a la selecci\u00f3n nacional\u201d.<\/p>\n<p>El deseo de Neymar ten\u00eda algunos argumentos futbol\u00edsticos, aunque es cierto que apenas jug\u00f3 dos partidos desde que comenz\u00f3 el a\u00f1o, ya que termin\u00f3 el 2025 con una <a href=\"https:\/\/espndeportes.espn.com\/futbol\/brasil\/nota\/_\/id\/16111664\/neymar-operacion-rodilla-promesa-fuerte-mundial-2026\">operaci\u00f3n<\/a> en esa rodilla izquierda. Volvi\u00f3 al campo de juego a mediados de febrero, y desde entonces ha jugado cuatro encuentros, con dos goles y otro par de asistencias.<\/p>\n<p>Sin embargo, en la mente de Ancelotti, hay otros futbolistas por delante de \u00e9l, y parece que son varios. El italiano convoc\u00f3 en total a nueve delanteros para los partidos de marzo. Adem\u00e1s de Vin\u00edcius Jr. y Raphinha, est\u00e1n Gabriel Martinelli, del Arsenal de Inglaterra; Matheus Cunha, del Manchester United; Luiz Enrique, del Zenit de Rusia; Endrick, actualmente en el Olympique Lyon franc\u00e9s; Igor Thiago, del Brentford de Inglaterra; Rayan, del Bournemouth ingl\u00e9s; y Joao Pedro, del Chelsea.<\/p>\n<p>Que Ancelotti piense en algunos nombres con poco rodaje en la selecci\u00f3n, incluso algunos casi desconocidos, antes que en el excapit\u00e1n, muestra lo lejos que el sue\u00f1o de Neymar de participar en otro Mundial est\u00e1 de hacerse realidad.<\/p>\n<p>El italiano no esquiv\u00f3 el tema en una conferencia de prensa que dio este lunes. \u201cEsta es una lista de lo que est\u00e1n bien f\u00edsicamente, porque queremos jugar dos partidos muy importantes, de intensidad, con un par\u00f3n muy corto, incluyendo el viaje. Tomando en cuenta la posici\u00f3n de algunos jugadores que no conozco, como Ib\u00e1\u00f1ez, Bremer, Rayan, Danilo, Gabriel Sara\u2026 es una \u00faltima oportunidad para reunirnos con ellos y hacer una n\u00f3mina final lo m\u00e1s clara posible\u201d, dijo el estratega.<\/p>\n<p>Y dej\u00f3 un \u00faltimo mensaje dirigido directamente al astro: \u201cNeymar puede estar en la Copa del Mundo. \u00bfPor qu\u00e9 no lo he convocado ahora? Porque no est\u00e1 al 100% y, en este momento, necesitamos jugadores que est\u00e9n en perfectas condiciones. La lista final ser\u00e1 otra historia; \u00e9l tiene que seguir trabajando y sumando minutos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carlo Ancelotti, director t\u00e9cnico de la selecci\u00f3n de Brasil, present\u00f3 la lista de 26 futbolistas convocados para la fecha FIFA de finales de marzo, donde destacan las presencias de Alisson Becker, portero del Liverpool, Marquinhos, del Paris Saint-Germain, Casemiro, del Manchester United, Vin\u00edcius Jr. y Raphinha, delanteros del Real Madrid y el Barcelona, entre otros. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472262","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Estoy molesto y triste&quot;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Estoy molesto y triste&quot;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Carlo Ancelotti, director t\u00e9cnico de la selecci\u00f3n de Brasil, present\u00f3 la lista de 26 futbolistas convocados para la fecha FIFA de finales de marzo, donde destacan las presencias de Alisson Becker, portero del Liverpool, Marquinhos, del Paris Saint-Germain, Casemiro, del Manchester United, Vin\u00edcius Jr. y Raphinha, delanteros del Real Madrid y el Barcelona, entre otros. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-17T03:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Estoy molesto y triste&#187;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026?\",\"datePublished\":\"2026-03-17T03:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/\"},\"wordCount\":832,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/\",\"name\":\"\\\"Estoy molesto y triste\\\", dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-17T03:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Estoy molesto y triste&#187;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Estoy molesto y triste\", dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\"Estoy molesto y triste\", dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026? - Noticias","og_description":"Carlo Ancelotti, director t\u00e9cnico de la selecci\u00f3n de Brasil, present\u00f3 la lista de 26 futbolistas convocados para la fecha FIFA de finales de marzo, donde destacan las presencias de Alisson Becker, portero del Liverpool, Marquinhos, del Paris Saint-Germain, Casemiro, del Manchester United, Vin\u00edcius Jr. y Raphinha, delanteros del Real Madrid y el Barcelona, entre otros. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-17T03:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/"},"author":{"name":"","@id":""},"headline":"&#171;Estoy molesto y triste&#187;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026?","datePublished":"2026-03-17T03:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/"},"wordCount":832,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/","name":"\"Estoy molesto y triste\", dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-17T03:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Estoy molesto y triste&#187;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Estoy molesto y triste&#187;, dice Neymar tras quedar afuera de la lista de Ancelotti, \u00bfy tambi\u00e9n del Mundial 2026?","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/16\/neymar-afuera-lista-ancelotti-amistosos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-17T03:03:49Z","datePublished":"2026-03-17T03:03:49Z","dateModified":"2026-03-17T03:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Estoy molesto y triste&#187;, dice Neymar tras quedar afuera de la lista de Ancelotti, \\u00bfy tambi\\u00e9n del Mundial 2026?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/16\\\/neymar-afuera-lista-ancelotti-amistosos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/16\\\/neymar-afuera-lista-ancelotti-amistosos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-17T03:03:49Z\",\"datePublished\":\"2026-03-17T03:03:49Z\",\"dateModified\":\"2026-03-17T03:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462823,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/05\/26\/ancelotti-convocatoria-brasil-neymar-orix\/","url_meta":{"origin":1472262,"position":0},"title":"Sin Neymar, Carlo Ancelotti entreg\u00f3 su primera convocatoria de la selecci\u00f3n brasile\u00f1a de f\u00fatbol","author":"","date":"mayo 26, 2025","format":false,"excerpt":"Carlo Ancelotti oficialmente ejerci\u00f3 su primera tarea como seleccionador de Brasil y lo hizo el mismo d\u00eda de su presentaci\u00f3n: entregar la primera convocatoria de la \u201ccanarinha\u201d de cara a las pr\u00f3ximas dos fechas de las Eliminatorias al Mundial de 2026. La gran novedad de esta convocatoria es la ausencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471839,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/03\/rodrygo-lesion-mundial-2026-neymar-ancelotti-orix\/","url_meta":{"origin":1472262,"position":1},"title":"Rodrygo se perder\u00e1 el Mundial 2026 con Brasil: \u00bfqu\u00e9 lesi\u00f3n tiene y c\u00f3mo puede afectar a Neymar?","author":"","date":"marzo 3, 2026","format":false,"excerpt":"El prometedor ataque de la selecci\u00f3n de Brasil de cara al Mundial 2026 sufri\u00f3 este martes un golpe severo, de enormes proporciones.Rodrygo Goes, uno de los jugadores de confianza del director t\u00e9cnico Carlo Ancelotti, sufri\u00f3 el lunes una grave lesi\u00f3n jugando para el Real Madrid, y este martes el club\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465847,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/08\/25\/neymar-lesion-santos-ancelotti-brasil-orix\/","url_meta":{"origin":1472262,"position":2},"title":"\u00bfQu\u00e9 le pasa a Neymar? Otra lesi\u00f3n en Santos y afuera de la lista de Ancelotti","author":"","date":"agosto 25, 2025","format":false,"excerpt":"Son nuevos tiempos en la carrera de Neymar. Atr\u00e1s quedaron las gambetas en Europa, las vitrinas llenas de trofeos y los elogios. Tambi\u00e9n parece haber quedado atr\u00e1s esa \u201crevoluci\u00f3n\u201d que se gener\u00f3 en su retorno al Santos de Brasil, ese equipo con el que lleg\u00f3 a la cumbre de Am\u00e9rica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472268,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/5-cosas-17-de-marzo-orix\/","url_meta":{"origin":1472262,"position":3},"title":"Las 5 cosas que debes saber este 17 de marzo","author":"","date":"marzo 17, 2026","format":false,"excerpt":"La red el\u00e9ctrica de Cuba colapsa tras semanas de bloqueo petrolero. Tormentas invernales en EE.UU. Los m\u00e1s vulnerables ante la pol\u00edtica inmigratoria de Trump. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las 5\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462249,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/05\/12\/ancelotti-nuevo-seleccionador-brasil-efe\/","url_meta":{"origin":1472262,"position":4},"title":"Carlo Ancelotti es el nuevo seleccionador de Brasil y debutar\u00e1 contra Ecuador en las eliminatorias","author":"","date":"mayo 12, 2025","format":false,"excerpt":"El t\u00e9cnico italiano Carlo Ancelotti, actual entrenador del Real Madrid, ser\u00e1 el pr\u00f3ximo seleccionador nacional de Brasil, con contrato hasta el Mundial de 2026, seg\u00fan anunci\u00f3 este lunes la Confederaci\u00f3n Brasile\u00f1a de F\u00fatbol (CBF).El presidente de la CBF, Ednaldo Rodrigues, afirm\u00f3 que Ancelotti \u201ces el mejor entrenador de la historia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461546,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/04\/23\/copa-del-rey-continuidad-carlo-ancelotti-real-madrid-orix\/","url_meta":{"origin":1472262,"position":5},"title":"\u00bfDefine la Copa del Rey la continuidad de Carlo Ancelotti en el Real Madrid?","author":"","date":"abril 23, 2025","format":false,"excerpt":"Tras la llegada del delantero franc\u00e9s Kylian Mbapp\u00e9 en julio de 2024, el Real Madrid qued\u00f3 a ojos de gran parte del mundo futbol\u00edstico como gran candidato a ganarlo todo.El reto para Carlo Ancelotti, entrenador del cuadro blanco, era el mismo de la temporada anterior: motivar a un plantel que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1472262"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472262\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1472262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1472262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1472262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}