{"id":1472286,"date":"2026-03-17T14:04:03","date_gmt":"2026-03-17T21:04:03","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/"},"modified":"2026-03-17T14:04:03","modified_gmt":"2026-03-17T21:04:03","slug":"presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","title":{"rendered":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein"},"content":{"rendered":"<p>El presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, emiti\u00f3 este martes una citaci\u00f3n a la secretaria de Justicia de Estados Unidos, Pam Bondi, para que comparezca a una declaraci\u00f3n el 14 de abril como parte de la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/21\/eeuu\/que-contienen-archivos-epstein-publicados-trax\">investigaci\u00f3n sobre Jeffrey Epstein.<\/a><\/p>\n<p>Comer escribi\u00f3 en la carta de presentaci\u00f3n de la citaci\u00f3n que su comisi\u00f3n est\u00e1 investigando la \u201cposible mala gesti\u00f3n de la investigaci\u00f3n del Gobierno federal\u201d sobre Epstein y Ghislaine Maxwell.<\/p>\n<p>\u201cLa Comisi\u00f3n tiene preguntas sobre la gesti\u00f3n del Departamento de Justicia de la investigaci\u00f3n sobre Jeffrey Epstein y sus asociados y su cumplimiento de la Ley de Transparencia de los Archivos de Epstein\u201d, escribi\u00f3 Comer, en referencia a la ley aprobada por el Congreso el a\u00f1o pasado que ordena al Departamento de Justicia divulgar los expedientes.<\/p>\n<p>Por separado, la comisi\u00f3n anunci\u00f3 que Bondi y el vicesecretario de Justicia, Todd Blanche, tienen previsto informar a los miembros de la comisi\u00f3n a puerta cerrada el mi\u00e9rcoles. Una fuente familiarizada con el proceso dijo a CNN que el Departamento de Justicia solicit\u00f3 informar a la comisi\u00f3n sobre su investigaci\u00f3n de Epstein y el cumplimiento de la ley para responder con prontitud a las preguntas de los legisladores, dado que programar una declaraci\u00f3n con la comisi\u00f3n llevar\u00e1 tiempo.<\/p>\n<p>Un portavoz del Departamento de Justicia calific\u00f3 la citaci\u00f3n de \u201ccompletamente innecesaria\u201d, pero no dijo si la secretaria de Justicia la acatar\u00eda.<\/p>\n<p>\u201cEsta citaci\u00f3n es completamente innecesaria. Se ha invitado a los legisladores a ver por s\u00ed mismos los archivos sin censuras en el Departamento de Justicia, y la secretaria de Justicia de EE.UU. siempre se ha puesto a disposici\u00f3n para hablar directamente con los miembros del Congreso\u201d, dijo el portavoz.<\/p>\n<p>\u201cElla sigue manteniendo llamadas y reuniones con miembros del Congreso sobre la Ley de Transparencia de los Archivos de Epstein, por lo que el Departamento ofreci\u00f3 informar a la comisi\u00f3n ma\u00f1ana. Como siempre, esperamos seguir proporcionando a los responsables de pol\u00edticas los hechos\u201d, continu\u00f3 el portavoz.<\/p>\n<p>La divulgaci\u00f3n de los archivos por parte del Departamento de Justicia ha provocado quejas de legisladores de ambos partidos, y los cr\u00edticos dicen que creen que los archivos fueron excesivamente censurados y exigen mayor transparencia.<\/p>\n<p>\u201cComo secretaria de Justicia de EE.UU., usted es directamente responsable de supervisar la recopilaci\u00f3n, revisi\u00f3n y decisiones del Departamento respecto de la divulgaci\u00f3n de archivos conforme a la Ley de Transparencia de los Archivos de Epstein, y por lo tanto la Comisi\u00f3n considera que usted posee informaci\u00f3n valiosa sobre estos esfuerzos\u201d, escribi\u00f3 Comer.<\/p>\n<p>La medida se produce despu\u00e9s de que la Comisi\u00f3n, liderada por el Partido Republicano, votara a principios de este mes, de manera bipartidista, citar a Bondi para que testifique sobre su papel en la divulgaci\u00f3n de los archivos.<\/p>\n<p>Esta medida se produce despu\u00e9s de que la comisi\u00f3n, controlada por el Partido Republicano, votara a principios de este mes \u2014con apoyo bipartidista\u2014 a favor de citar a Bondi para que preste declaraci\u00f3n sobre su papel en la divulgaci\u00f3n de los expedientes.<\/p>\n<p>El representante Robert Garc\u00eda, el dem\u00f3crata de mayor rango en el panel, hizo referencia el martes al esfuerzo bipartidista que condujo a la citaci\u00f3n.<\/p>\n<p>\u201cGracias a los dem\u00f3cratas unidos de la Comisi\u00f3n de Supervisi\u00f3n, junto con el apoyo de varios republicanos, el secretario de Justicia de EE.UU. ahora comparecer\u00e1 ante nuestra Comisi\u00f3n bajo juramento. No m\u00e1s mentiras. No m\u00e1s distracciones. Queremos la verdad \u2014y justicia para los sobrevivientes\u201d, dijo Garcia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, emiti\u00f3 este martes una citaci\u00f3n a la secretaria de Justicia de Estados Unidos, Pam Bondi, para que comparezca a una declaraci\u00f3n el 14 de abril como parte de la investigaci\u00f3n sobre Jeffrey Epstein. Comer escribi\u00f3 en la carta de presentaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472286","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, emiti\u00f3 este martes una citaci\u00f3n a la secretaria de Justicia de Estados Unidos, Pam Bondi, para que comparezca a una declaraci\u00f3n el 14 de abril como parte de la investigaci\u00f3n sobre Jeffrey Epstein. Comer escribi\u00f3 en la carta de presentaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-17T21:04:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein\",\"datePublished\":\"2026-03-17T21:04:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/\"},\"wordCount\":660,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/\",\"name\":\"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-17T21:04:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein - Noticias","og_description":"El presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, emiti\u00f3 este martes una citaci\u00f3n a la secretaria de Justicia de Estados Unidos, Pam Bondi, para que comparezca a una declaraci\u00f3n el 14 de abril como parte de la investigaci\u00f3n sobre Jeffrey Epstein. Comer escribi\u00f3 en la carta de presentaci\u00f3n de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-17T21:04:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/"},"author":{"name":"","@id":""},"headline":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein","datePublished":"2026-03-17T21:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/"},"wordCount":660,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","name":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-17T21:04:03+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Presidente de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara cita a Pam Bondi a declarar en la investigaci\u00f3n sobre Epstein","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-17T21:04:03Z","datePublished":"2026-03-17T21:04:03Z","dateModified":"2026-03-17T21:04:03Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Presidente de la Comisi\\u00f3n de Supervisi\\u00f3n de la C\\u00e1mara cita a Pam Bondi a declarar en la investigaci\\u00f3n sobre Epstein\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/17\\\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/17\\\/presidente-comision-camara-cita-pam-bondi-declarar-epstein-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-17T21:04:03Z\",\"datePublished\":\"2026-03-17T21:04:03Z\",\"dateModified\":\"2026-03-17T21:04:03Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472972,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/04\/08\/departamento-justicia-bondi-comparencia-caso-epstein-trax\/","url_meta":{"origin":1472286,"position":0},"title":"Bondi ya no est\u00e1 obligada a declarar sobre el caso Epstein, dice el Departamento de Justicia","author":"","date":"abril 8, 2026","format":false,"excerpt":"El Departamento de Justicia dijo el mi\u00e9rcoles que Pam Bondi no comparecer\u00e1 en su pr\u00f3xima declaraci\u00f3n en la investigaci\u00f3n de Jeffrey Epstein de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara, dado que ya no se desempe\u00f1a como secretaria de Justicia de Estados Unidos.Esto marca el m\u00e1s reciente obst\u00e1culo en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473647,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/04\/29\/bondi-testificara-investigacion-camara-jeffrey-epstein-trax\/","url_meta":{"origin":1472286,"position":1},"title":"Bondi testificar\u00e1 en la investigaci\u00f3n de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes sobre Jeffrey Epstein","author":"","date":"abril 29, 2026","format":false,"excerpt":"La exsecretaria de Justicia Pam Bondi tiene previsto testificar el pr\u00f3ximo mes en la investigaci\u00f3n de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes sobre Jeffrey Epstein.La comparecencia de Bondi \u2014ahora fijada para el 29 de mayo, seg\u00fan una portavoz de la comisi\u00f3n\u2014 se produce mientras el panel ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471885,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/04\/congreso-cita-pam-bondi-investigacion-epstein-trax\/","url_meta":{"origin":1472286,"position":2},"title":"El Congreso cita a la secretaria de Justicia Pam Bondi por la investigaci\u00f3n sobre Epstein","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes, liderada por los republicanos, vot\u00f3 para citar a la secretaria de Justicia de Estados Unidos, Pam Bondi, para que declare sobre su papel en la divulgaci\u00f3n de los archivos de Jeffrey Epstein como parte de la investigaci\u00f3n de la comisi\u00f3n sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468601,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/11\/22\/comision-supervision-camara-amplia-investigacion-jeffrey-epstein-trax\/","url_meta":{"origin":1472286,"position":3},"title":"Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes ampl\u00eda su investigaci\u00f3n sobre Jeffrey Epstein","author":"","date":"noviembre 22, 2025","format":false,"excerpt":"La Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes est\u00e1 ampliando su investigaci\u00f3n sobre el delincuente sexual infantil convicto Jeffrey Epstein y buscando nuevos objetivos.Las nuevas pesquisas har\u00edan pr\u00e1cticamente improbable que la controversia de Epstein se disipe incluso despu\u00e9s de que el Congreso obligara al Departamento de Justicia a divulgar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464796,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/07\/23\/camara-de-representantes-ghislaine-maxwell-declarar-trax\/","url_meta":{"origin":1472286,"position":4},"title":"La comisi\u00f3n de supervisi\u00f3n de la C\u00e1mara de Representantes cita a Ghislaine Maxwell a declarar","author":"","date":"julio 23, 2025","format":false,"excerpt":"El presidente de la comisi\u00f3n de supervisi\u00f3n de la C\u00e1mara de Representantes, James Comer, cit\u00f3 a la exsocia de Jeffrey Epstein, Ghislaine Maxwell, para una declaraci\u00f3n.La comisi\u00f3n dijo en un comunicado que la declaraci\u00f3n tendr\u00e1 lugar en la Instituci\u00f3n Correccional Federal en Tallahassee, Florida, el pr\u00f3ximo 11 de agosto.\u201cEl Departamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470398,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/22\/exclusivo-pelosi-democratas-desacato-clinton-epstein-trax\/","url_meta":{"origin":1472286,"position":5},"title":"Exclusivo: Pelosi critica a dem\u00f3cratas por votar para declarar en desacato a los Clinton en la investigaci\u00f3n sobre Epstein","author":"","date":"enero 22, 2026","format":false,"excerpt":"La expresidenta de la C\u00e1mara de Representantes, Nancy Pelosi, se mostr\u00f3 decepcionada despu\u00e9s de que casi la mitad de los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara votaran el mi\u00e9rcoles para declarar a Bill y Hillary Clinton en desacato al Congreso por no cumplir con las citaciones en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1472286"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472286\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1472286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1472286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1472286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}