{"id":1472295,"date":"2026-03-17T19:03:45","date_gmt":"2026-03-18T02:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/"},"modified":"2026-03-17T19:03:45","modified_gmt":"2026-03-18T02:03:45","slug":"dentro-de-isla-epstein-little-st-james-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/","title":{"rendered":"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas"},"content":{"rendered":"<p>Los banqueros adinerados, l\u00edderes pol\u00edticos y destacados acad\u00e9micos que visitaron la isla caribe\u00f1a de Jeffrey Epstein viajaban en jet privado y pasaban las tardes buceando o montando motos acu\u00e1ticas.<\/p>\n<p>Las ni\u00f1as y mujeres j\u00f3venes que Epstein trasladaba a la isla viv\u00edan una experiencia dr\u00e1sticamente distinta: les confiscaban los pasaportes, sufr\u00edan abusos sexuales sistem\u00e1ticos y enfrentaban condiciones tan desesperadas que al menos una dijo que intent\u00f3 escapar nadando.<\/p>\n<p>Durante casi dos d\u00e9cadas, Little St. James \u2014la isla de unas 70 acres (28,3 hect\u00e1reas) de Epstein\u2014 fue la herramienta perfecta para cultivar relaciones con personas poderosas y abusar de ni\u00f1as y mujeres j\u00f3venes. Le ofrec\u00eda un entorno glamoroso para atraer a figuras conocidas y, al mismo tiempo, el aislamiento que necesitaba para acechar a sus v\u00edctimas.<\/p>\n<p>Ahora, un conjunto de millones de p\u00e1ginas de documentos publicados por el Departamento de Justicia ofrece la imagen m\u00e1s clara hasta ahora de ese escenario en el Caribe, un lugar misterioso en el centro de un esc\u00e1ndalo de trata sexual que a\u00fan sacude la pol\u00edtica global.<\/p>\n<p>Una revisi\u00f3n de CNN de miles de correos electr\u00f3nicos, fotos, videos y documentos de esos archivos aporta nuevos detalles sobre c\u00f3mo Epstein transform\u00f3 la isla en su dominio personal y destaca se\u00f1ales de alerta del terrible abuso perpetrado all\u00ed que, seg\u00fan algunos empleados y v\u00edctimas, ocurr\u00eda a plena vista.<\/p>\n<p>El testimonio descrito en los documentos del Departamento de Justicia pone en duda las afirmaciones de algunos visitantes influyentes de la isla de Epstein, quienes han negado saber del tr\u00e1fico de personas con fines de explotaci\u00f3n sexual, y muestra a varios de esos invitados alardeando de supuestas haza\u00f1as sexuales o participando en conversaciones vulgares con el delincuente sexual condenado.<\/p>\n<p>\u201cLas actividades eran tan obvias y descaradas que cualquiera que pasara una cantidad significativa de tiempo en una de las residencias de Epstein habr\u00eda sido claramente consciente de lo que estaba ocurriendo\u201d, afirm\u00f3 una v\u00edctima en un documento judicial.<\/p>\n<p>Entre esas se\u00f1ales de alerta figuran fotograf\u00edas de ni\u00f1as j\u00f3venes desnudas en sus paredes, trabajadores del aeropuerto que reportaron que Epstein hab\u00eda viajado con ni\u00f1as que parec\u00edan menores de edad y un decorador de interiores que dijo que le pidieron dise\u00f1ar uno de los dormitorios de la isla con muebles rosados y literas.<\/p>\n<p>Algunos empleados y v\u00edctimas tambi\u00e9n se\u00f1alaron a invitados espec\u00edficos de Epstein, de acuerdo con los documentos, como el cofundador de Google Sergey Brin y la cofundadora de 23andMe Anne Wojcicki, quienes pasaron un d\u00eda en la isla en 2007, seg\u00fan la declaraci\u00f3n de una v\u00edctima. \u201cObservaron que no habl\u00e1bamos y que permanec\u00edamos mudas\u201d, escribi\u00f3 la v\u00edctima, cuyo nombre no figura en el documento p\u00fablico. \u201cPresenciaron el trauma en nuestros rostros y en nuestros ojos. Sergey y Anne presenciaron nuestras almas y cuerpos llenos de miedo. No dijeron nada. No hicieron nada\u201d.<\/p>\n<p>Brin y Wojcicki no respondieron a solicitudes de comentarios.<\/p>\n<p>Tras la <a href=\"https:\/\/cnnespanol.cnn.com\/2019\/08\/16\/jeffrey-epstein-se-suicido-por-ahorcamiento-dice-forense\">muerte de Epstein en una celda de una c\u00e1rcel federal en 2019,<\/a> su patrimonio vendi\u00f3 Little St. James y la isla vecina de Great St. James \u2014que Epstein tambi\u00e9n pose\u00eda\u2014 por unos US$ 60 millones, al menos una parte de los cuales se ha destinado a pagar acuerdos relacionados con sus abusos.<\/p>\n<p>Pero las preguntas sobre la isla y su lugar en el vasto imperio financiero de Epstein no han hecho m\u00e1s que crecer en los a\u00f1os transcurridos desde su muerte.<\/p>\n<p>Little St. James se convirti\u00f3 en \u201cel centro\u201d de la red de trata de Epstein porque era el lugar ideal para \u201caislar a sus v\u00edctimas\u201d, dijo Thomas Volscho, profesor de la Universidad de Nueva York que ha estudiado los cr\u00edmenes de Epstein.<\/p>\n<p>\u201cEst\u00e1s en el para\u00edso\u201d, dijo, \u201cpero est\u00e1s en el infierno al mismo tiempo\u201d.<\/p>\n<p>Cuando Epstein compr\u00f3 su isla por unos US$ 8 millones en 1998, era un financiero con un expediente penal impecable, una creciente red de amigos prominentes y una base en una de las mayores residencias privadas de Manhattan. En un anuncio inmobiliario del <a href=\"https:\/\/www.wsj.com\/articles\/SB861139935702093000\">Wall Street Journal <\/a>de la \u00e9poca, el anterior propietario de la isla, el capitalista de riesgo Arch Cummin, describi\u00f3 la vida en Little St. James: \u201cPuedes bajarte de un avi\u00f3n y no ver a nadie nunca m\u00e1s\u201d.<\/p>\n<p>La isla, azotada por el viento, est\u00e1 a m\u00e1s de 1,6 kil\u00f3metros de St. Thomas, en las Islas V\u00edrgenes de EE.UU., y solo es accesible en helic\u00f3ptero o en barco. A lo largo de 20 a\u00f1os, mapas y documentos ilustran c\u00f3mo Epstein transform\u00f3 la algo desolada Little St. James en lo que, en la superficie, parec\u00eda un lujoso destino vacacional, con teatro, biblioteca, gimnasio independiente, caba\u00f1a tiki y residencias para el personal.<\/p>\n<p>Im\u00e1genes satelitales de 2002 muestran apenas un pu\u00f1ado de edificios, con la casa principal y algunas caba\u00f1as y estructuras perif\u00e9ricas en la punta norte de la isla. A finales de la d\u00e9cada de 2000 y principios de la de 2010, Epstein ampli\u00f3 significativamente los espacios habitables, a\u00f1adiendo una piscina m\u00e1s grande, nuevas caba\u00f1as, un enorme reloj de sol y una extra\u00f1a estructura tipo templo con vista a la costa suroeste de la isla.<\/p>\n<p>Los archivos del Departamento de Justicia de Estados Unidos (DOJ, por sus siglas en ingl\u00e9s) describen c\u00f3mo Epstein volc\u00f3 su dinero en detalles que podr\u00edan impresionar a los visitantes. Gast\u00f3 casi US$ 300.000 en un escritorio \u201cde la casa principesca de Liechtenstein\u201d y casi US$ 100.000 en dos \u201cfiguras mitol\u00f3gicas de terracota\u201d que en su d\u00eda hab\u00edan adornado el edificio de la bolsa de Viena. En un intercambio de correos electr\u00f3nicos, un empleado de Epstein explor\u00f3 c\u00f3mo cumplir el deseo de su jefe de \u201ctener un rayo l\u00e1ser saliendo desde la proa a trav\u00e9s del cielo\u201d desde una escultura de un arquero en la propiedad.<\/p>\n<p>Para Epstein, que oficialmente registr\u00f3 Little St. James como su residencia principal, trasladar parte de sus negocios al territorio estadounidense significaba una rebaja fiscal. Sin embargo, ser due\u00f1o de su propia isla tambi\u00e9n representaba la entrada de Epstein a un nuevo nivel de riqueza de \u00e9lite: un poderoso s\u00edmbolo para el exprofesor que creci\u00f3 en una familia obrera de Brooklyn. A veces se refer\u00eda a la isla como \u201cLittle St. Jeff\u2019s\u201d y la describi\u00f3 en una declaraci\u00f3n como \u201cmi lugar favorito para estar\u201d.<\/p>\n<p>Mientras el personal de Epstein, los renovadores y los decoradores trabajaban las 24 horas para mantener y transformar Little St. James a su antojo, algunos notaron un comportamiento extra\u00f1o por parte de su jefe.<\/p>\n<p>Un exchef cont\u00f3 m\u00e1s tarde a investigadores federales que Epstein llevaba a una chica a su dormitorio principal cada hora y que, despu\u00e9s de su masaje, las mucamas iban a hacer la cama y limpiar. El dise\u00f1ador Robert Couturier dijo en una entrevista con el FBI en 2010 que Epstein le pidi\u00f3 que decorara un dormitorio en su isla con \u201cuna paleta muy colorida para sus chicas\u201d.<\/p>\n<p>Couturier asegur\u00f3 a CNN que, cuando visit\u00f3 la isla y vio literas, le pregunt\u00f3 a Epstein si ten\u00eda nietos. \u201cDijo: \u2018No, esto es para las chicas\u2019, y lo entend\u00ed de inmediato\u201d, record\u00f3 Couturier. Se retir\u00f3 del proyecto.<\/p>\n<p>Epstein \u201cno ocultaba nada\u201d, dijo Couturier, y a\u00f1adi\u00f3 que tambi\u00e9n vio fotos preocupantes de chicas dentro de la propiedad. \u201cCreo que algunas personas eligieron no verlo\u201d.<\/p>\n<p>Steve Scully, quien se encarg\u00f3 de la inform\u00e1tica de la isla a principios de la d\u00e9cada de 2000, dijo al FBI que Epstein ten\u00eda fotograf\u00edas de adolescentes en topless en su casa y record\u00f3 haber visto chicas menores de edad desnudas en la isla. Incluso trabajadores del aeropuerto local notaron a Epstein saliendo de su jet con chicas menores de edad y luego llev\u00e1ndolas en helic\u00f3ptero a su isla.<\/p>\n<p>Epstein hizo grandes esfuerzos para asegurar que Little St. James estuviera impecable. Un manual de la propiedad, incluido en los archivos del DOJ, describ\u00eda los horarios de limpieza y las normas para los empleados. Se instru\u00eda al personal a vestir atuendo formal mientras serv\u00eda a Epstein y a sus invitados y a dirigirse a ellos \u00fanicamente como \u201cse\u00f1or\u201d o \u201cse\u00f1ora\u201d. Cuando Epstein llegaba a la isla, deb\u00eda recibir una bebida de coco en el helipuerto reci\u00e9n aspirado, y deb\u00eda colocarse una cuatrimoto para su salida.<\/p>\n<p>La gu\u00eda tambi\u00e9n subrayaba la insistencia de Epstein en la privacidad: \u201cA menos que se le solicite, no desea tener personal en su presencia\u201d, se\u00f1alaba el manual. \u201cCuando el director entre en una habitaci\u00f3n en la que tambi\u00e9n haya personal, el personal debe permitirle su privacidad. Al atender al director, el personal debe estar callado, ser puntual, cort\u00e9s y salir lo antes posible\u201d.<\/p>\n<p>En 2016, Epstein busc\u00f3 expandir su imperio, comprando la isla vecina de Great St. James por m\u00e1s de US$ 20 millones, de acuerdo con registros judiciales, creando una especie de zona de amortiguamiento que garantizaba un c\u00edrculo a\u00fan m\u00e1s amplio de privacidad.<\/p>\n<p>Para 2018, Epstein se embarcaba en una nueva remodelaci\u00f3n de ambas islas, con planes que insinuaban uno de sus verdaderos prop\u00f3sitos para el terreno privado.<\/p>\n<p>Los planos y las representaciones incluidas en los documentos muestran una \u201cresidencia para mujeres\u201d y una \u201chabitaci\u00f3n privada para mujeres\u201d, con una piscina infinita, hamacas y amplias vistas al oc\u00e9ano.<\/p>\n<p>Epstein se centr\u00f3 en los detalles del dise\u00f1o: \u201cLa cocina de las mujeres debe ser m\u00e1s completa. La usar\u00e1n a menudo\u201d, escribi\u00f3 a su arquitecto en un correo electr\u00f3nico de abril de 2018 lleno de errores tipogr\u00e1ficos, criticando tambi\u00e9n la \u201cubicaci\u00f3n de las ni\u00f1as\u201d en los planos.<\/p>\n<p>Mientras Epstein constru\u00eda su refugio tropical, un flujo constante de mujeres j\u00f3venes y ni\u00f1as era llevado a la isla.<\/p>\n<p>Una mujer record\u00f3 que visit\u00f3 por primera vez Little St. James en 2006, en lo que pensaba que ser\u00eda un \u201cviaje de chicas\u201d, de acuerdo con un documento publicado en enero. Pero, cuando lleg\u00f3, le dijeron que no pod\u00eda irse y le quitaron el pasaporte, dijo.<\/p>\n<p>Seg\u00fan su testimonio, Epstein la viol\u00f3 repetidamente.<\/p>\n<p>Fue un patr\u00f3n que, de acuerdo con documentos y testimonios citados en una demanda, se repiti\u00f3 durante a\u00f1os en la isla, tanto antes como despu\u00e9s de que Epstein se declarara culpable en Florida en 2008 de reclutar a una menor para la prostituci\u00f3n, una condena que le supuso apenas 13 meses de c\u00e1rcel bajo un acuerdo indulgente.<\/p>\n<p>Una demanda presentada por abogados del Gobierno de las Islas V\u00edrgenes aleg\u00f3 que Epstein comenz\u00f3 a coaccionar a ni\u00f1as menores de edad y a mujeres j\u00f3venes para que realizaran actividad sexual en la isla ya en 2001 y continu\u00f3 hasta 2019, el a\u00f1o en que fue acusado de delitos federales de trata sexual y luego muri\u00f3 en la c\u00e1rcel. La demanda describi\u00f3 a v\u00edctimas de tan solo 12 a\u00f1os.<\/p>\n<p>La demanda \u2014que <a href=\"https:\/\/usvidoj.com\/u-s-virgin-islands-attorney-general-settles-sex-trafficking-case-against-estate-of-jeffrey-epstein-and-co-defendants-for-over-105-million\/\">se resolvi\u00f3 en 2022, <\/a>con el patrimonio de Epstein y otros demandados accediendo a pagar al Gobierno de las Islas V\u00edrgenes m\u00e1s de US$ 100 millones\u2014 afirmaba que una menor de 15 a\u00f1os que fue obligada a realizar actos sexuales con Epstein y otros intent\u00f3 escapar de la isla nadando.<\/p>\n<p>Una declaraci\u00f3n de una v\u00edctima contenida en archivos del DOJ describe un esfuerzo similar por escapar. \u201cUn d\u00eda me sent\u00eda muy angustiada y asustada\u201d, afirma el documento. \u201cIntent\u00e9 escapar de Epstein y de los otros tratando de nadar lejos de Little St. James. Epstein y Maxwell, despu\u00e9s de pasar el d\u00eda siendo violada, intimidada y menospreciada, me llevaron de vuelta como si no hubiera pasado nada\u201d. No est\u00e1 claro si esa declaraci\u00f3n corresponde al mismo incidente descrito en la demanda.<\/p>\n<p>Algunos de los socios de Epstein parec\u00edan bromear sobre la posibilidad de que sus v\u00edctimas escaparan nadando. En un correo electr\u00f3nico de 2013, alguien cuyo nombre fue editado por protecci\u00f3n en los documentos le sugiri\u00f3 a Epstein que una mujer o ni\u00f1a podr\u00eda \u201ccomenzar su \u2018entrenamiento\u2019\u201d en la isla. \u201cSer\u00eda mejor hablar con ella all\u00ed (porque no tendr\u00e1 opci\u00f3n, solo si se tira al agua y se va nadando, lol)\u201d, escribi\u00f3 el remitente, a\u00f1adiendo una carita sonriente al mensaje.<\/p>\n<p>V\u00edctimas entrevistadas por el FBI describieron c\u00f3mo <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/23\/eeuu\/ghislaine-maxwell-jeffrey-epstein-trump-trax\">Ghislaine Maxwell,<\/a> la exnovia de Epstein \u2014condenada por trata sexual de menores\u2014, instru\u00eda a las ni\u00f1as y a las mujeres j\u00f3venes sobre c\u00f3mo complacer a Epstein mientras estaban en la isla.<\/p>\n<p>\u201cMaxwell sab\u00eda que Epstein necesitaba mucho sexo. Maxwell lo presentaba como que \u2018es un ser sexual\u2019 y que \u2018si no te ocupas de sus necesidades mientras est\u00e1s en la isla, entonces no hay lugar para ti aqu\u00ed\u2019\u201d, dijo una v\u00edctima, de acuerdo con un registro de entrevistas del FBI.<\/p>\n<p>Otra v\u00edctima record\u00f3 que Maxwell les indic\u00f3 a ella y a otras tres chicas en la isla que \u201cse desnudaran y se envolvieran en film transparente\u201d como regalo de cumplea\u00f1os para Epstein.<\/p>\n<p>Una v\u00edctima le dijo al FBI que Epstein quer\u00eda construir un \u201char\u00e9n\u201d en la isla en el que pudiera alojar a varias ni\u00f1as. \u201cQuer\u00eda que fuera una estructura tipo castillo, parecida a la Alhambra en Espa\u00f1a\u201d, dice un informe del FBI.<\/p>\n<p>Las v\u00edctimas tambi\u00e9n alegaron que algunos empleados de Epstein hicieron la vista gorda ante sus cr\u00edmenes.<\/p>\n<p>\u201cSiempre entraban y sal\u00edan de los bungal\u00f3s, gui\u00e1ndonos y atendi\u00e9ndonos. Asegur\u00e1ndose de que todo funcionara sin problemas\u201d, escribi\u00f3 una v\u00edctima en su declaraci\u00f3n incluida en archivos del DOJ. \u201cSus sonrisas eran blancas y brillantes. Usaban las mismas sonrisas amistosas y c\u00e1lidas para consolarme despu\u00e9s de que Epstein me violara, y yo huyera, sangrando y llorando\u201d.<\/p>\n<p>Los documentos tambi\u00e9n ofrecen una ventana a c\u00f3mo Epstein atra\u00eda a sus v\u00edctimas a la isla. En un intercambio de 2017, Epstein le pidi\u00f3 a alguien cuyo nombre fue censurado que lo pusiera en contacto con una amiga que \u201cpodr\u00eda encontrar entretenida\u201d y que pudiera acompa\u00f1arlo en sus viajes. Continu\u00f3: \u201cDebes tener una amiga realmente muy guapa que ya no te guste mucho :)\u201d.<\/p>\n<p>Otra v\u00edctima, que conoci\u00f3 a Epstein cuando ten\u00eda 17 a\u00f1os, asegur\u00f3 al FBI que el vuelo a la isla fue su primera vez en un avi\u00f3n en m\u00e1s de una d\u00e9cada. Cuando Epstein la invit\u00f3, ella pens\u00f3 que el viaje \u201cser\u00eda solo unas vacaciones\u201d. Luego, una vez que estuvo all\u00ed, Epstein la llev\u00f3 a un dormitorio y, seg\u00fan su testimonio, la viol\u00f3. Despu\u00e9s de que regres\u00f3 a casa, le envi\u00f3 una caja de chocolates.<\/p>\n<p>Otros correos electr\u00f3nicos muestran c\u00f3mo Epstein interactuaba con mujeres despu\u00e9s de que se fueron de Little St. James. Cuando una persona, cuyo nombre est\u00e1 censurado, le escribi\u00f3 en 2013 para agradecerle un viaje a la isla, \u00e9l respondi\u00f3 con una orden tajante: \u201cEnv\u00edame una foto sexy tomada en el espejo\u201d.<\/p>\n<p>Durante a\u00f1os, Epstein enviaba con frecuencia mensajes a sus amigos bien conectados para pedirles que visitaran Little St. James. Las notas acogedoras \u2014y a veces incluso suplicantes\u2014 encajaban con su patr\u00f3n de construir meticulosamente una red de poder que lo ayud\u00f3 mientras enfrentaba el escrutinio por sus delitos.<\/p>\n<p>En correos electr\u00f3nicos enviados a\u00f1o tras a\u00f1o a figuras prominentes, Epstein invitaba a los destinatarios a \u201cvenir a visitarme a mi isla\u201d. Los registros muestran que organiz\u00f3 conferencias para acad\u00e9micos, ofreci\u00f3 vacaciones lujosas a funcionarios p\u00fablicos y trat\u00f3 de atraer a figuras influyentes para que pasaran por su propiedad caribe\u00f1a durante sus viajes.<\/p>\n<p>A menudo ofrec\u00eda ventajas. \u201cMe complace pagar el vuelo privado\u201d, escribi\u00f3 en 2014 a Joi Ito, entonces director del Media Lab del MIT, en una cadena de correos electr\u00f3nicos que inclu\u00eda a Reid Hoffman, cofundador de LinkedIn. \u201cPuedes usar mi isla conmigo o sin m\u00ed cuando quieras\u201d, escribi\u00f3 ese mismo a\u00f1o al reconocido f\u00edsico Lawrence Krauss.<\/p>\n<p>Los registros indican que los tres hombres aceptaron invitaciones de Epstein. Hoffman expres\u00f3 posteriormente arrepentimiento por haber interactuado con Epstein. Dijo en un podcast que su viaje a Little St. James fue \u201cla primera vez que he ido a una isla\u201d y a\u00f1adi\u00f3: \u201cNota mental: buscar en Google antes de ir\u201d. Ito <a href=\"https:\/\/joi.ito.com\/weblog\/2026\/03\/03\/statement-on-media-coverage.html\">dijo<\/a>: \u201cDe haber sabido lo que desde entonces ha salido a la luz, sin duda habr\u00eda cortado todo v\u00ednculo\u201d. Krauss ha dicho que sus interacciones con Epstein por lo general involucraban reuniones cient\u00edficas o tertulias con ponentes interesantes.<\/p>\n<p>Otros nombres de primera l\u00ednea tambi\u00e9n han revelado haber visitado la isla. Algunos lo hicieron antes de la primera condena de Epstein, en 2008, incluido Larry Summers, exsecretario del Tesoro y expresidente de Harvard, cuyo portavoz dijo que pas\u00f3 \u201cmenos de un d\u00eda\u201d en la isla durante su luna de miel, en 2005. Jes Staley, exdirector ejecutivo de Barclays, se qued\u00f3 en la isla en 2009 mientras el financiero cumpl\u00eda condena en prisi\u00f3n, seg\u00fan consta en los registros judiciales.<\/p>\n<p>Richard Branson, fundador de Virgin Group, recorri\u00f3 la isla durante 90 minutos en 2013 despu\u00e9s de que Epstein mencionara que quiz\u00e1 quisiera venderla, dijo su portavoz a CNN. Leon Black, un magnate de Wall Street, dijo en una carta revisada por CNN que la visit\u00f3 para un \u201calmuerzo de p\u00edcnic\u201d con su familia. Peter Mandelson, un legislador del Reino Unido que fue destituido el a\u00f1o pasado como embajador en Estados Unidos por sus v\u00ednculos con Epstein, dijo <a href=\"https:\/\/www.bbc.com\/news\/articles\/cd9el4dw0z3o\">a la BBC<\/a> que pas\u00f3 una o dos noches en la isla. Y un portavoz del ex primer ministro de Israel, Ehud Barak, dijo que visit\u00f3 la isla durante \u201cunas pocas horas durante el d\u00eda\u201d, acompa\u00f1ado por su esposa y su equipo de seguridad.<\/p>\n<p>Todos han negado cualquier irregularidad o haber visto algo impropio durante sus visitas, y muchos han expresado arrepentimiento por haberse asociado con Epstein.<\/p>\n<p>Algunos de los adinerados invitados de Epstein quedaron m\u00e1s impresionados por su isla que otros. Les Wexner, el multimillonario cuya fortuna Epstein administr\u00f3 anteriormente, dijo en una declaraci\u00f3n ante el Congreso el mes pasado que la hab\u00eda visitado una vez durante aproximadamente una hora con su esposa e hijos, y la describi\u00f3 como \u201cuna isla bastante mala\u201d.<\/p>\n<p>Muchos de quienes aceptaron las insinuaciones de Epstein para ir a su isla han insistido en que apenas lo conoc\u00edan.<\/p>\n<p>\u201cS\u00ed, almorc\u00e9 con \u00e9l, ya que estaba en un barco cruzando la isla de vacaciones con mi familia\u201d, dijo el secretario de Comercio, Howard Lutnick, sobre su visita a la isla en 2012 durante una audiencia en el Senado el mes pasado. \u201cNo ten\u00eda ninguna relaci\u00f3n con \u00e9l. Apenas tuve nada que ver con esa persona\u201d.<\/p>\n<p>Despu\u00e9s de su testimonio, surgi\u00f3 otra foto en los archivos del Departamento de Justicia que parece mostrar a Lutnick en la isla, y \u00e9l accedi\u00f3 a testificar ante la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara sobre Epstein.<\/p>\n<p>Una pregunta central y persistente en las investigaciones del caso Epstein en el Congreso es si, y en qu\u00e9 medida, se superpusieron durante su vida los dos mundos de Epstein: sus poderosos amigos y su red de ni\u00f1as y mujeres abusadas.<\/p>\n<p>Es una pregunta especialmente incisiva en Little St. James, donde sus invitados a veces estaban muy cerca de sus v\u00edctimas y, de acuerdo con testimonios citados en documentos, podr\u00edan haber pasado por alto se\u00f1ales de advertencia flagrantes.<\/p>\n<p>Varias v\u00edctimas relataron haber visto a personas prominentes durante viajes a la isla, incluida una que dijo en una declaraci\u00f3n que conoci\u00f3 a Brin y Wojcicki, y otra que, en una entrevista con el FBI, mencion\u00f3 haber visto a la supermodelo Naomi Campbell en la isla. Un abogado de Campbell dijo que ella se detuvo brevemente en la isla durante unas pocas horas, cuando viajaba con un grupo de personas rumbo a una carrera de la F\u00f3rmula 1, y que no vio a nadie participando en conducta inapropiada ni a nadie que ella creyera que hubiera sido victimizado por Epstein.<\/p>\n<p>Una v\u00edctima prominente de Epstein ha ido m\u00e1s lejos y ha alegado que fue abusada por un invitado poderoso en su isla.<\/p>\n<p>Virginia Giuffre<a href=\"https:\/\/www.theguardian.com\/us-news\/2025\/oct\/15\/prince-andrew-virginia-giuffre-abuse-epstein-maxwell\"> dijo <\/a>en una declaraci\u00f3n jurada y en su libro, publicado p\u00f3stumamente, que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/19\/mundo\/quien-es-exprincipe-andres-andrew-mountbatten-windsor-orix\">Andrew Mountbatten-Windsor, <\/a>el expr\u00edncipe del Reino Unido, y Epstein tuvieron una org\u00eda con ella y con \u201caproximadamente otras ocho chicas j\u00f3venes\u201d durante un viaje a la isla, cuando ella ten\u00eda \u201calrededor de 18\u201d a\u00f1os.<\/p>\n<p>Las otras ni\u00f1as \u201ctodas parec\u00edan ser menores de 18 y en realidad no hablaban ingl\u00e9s\u201d, escribi\u00f3. Esa fue una de tres ocasiones en las que fue abusada por Mountbatten-Windsor, y una de las muchas veces que Epstein abus\u00f3 de ella, dijo Giuffre, quien <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/04\/26\/mundo\/muere-virginia-giuffre-acusadora-principe-andres-trax\">muri\u00f3 por suicidio el a\u00f1o pasado.<\/a> Mountbatten-Windsor ha negado todas las acusaciones de Giuffre e insisti\u00f3 en que nunca presenci\u00f3 los abusos de Epstein. Las autoridades del Reino Unido <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/19\/mundo\/por-que-arresto-andres-mountbatten-windsor-trax\">arrestaron <\/a>a Mountbatten-Windsor el mes pasado, bajo sospecha de mala conducta en el ejercicio de un cargo p\u00fablico, y dijeron que estaban revisando afirmaciones de que comparti\u00f3 informaci\u00f3n sensible con Epstein.<\/p>\n<p>Una v\u00edctima de Epstein le dijo al FBI que Epstein la hab\u00eda llevado en avi\u00f3n a su isla y le indic\u00f3 que \u201centretuviera\u201d a uno de sus clientes, a quien describi\u00f3 como un acad\u00e9mico, \u201ccomo si ella fuera la novia del hombre\u201d. Inform\u00f3 que pas\u00f3 dos d\u00edas con el cliente no identificado, quien, seg\u00fan ella, \u201cquer\u00eda montar en motos acu\u00e1ticas y participar en otras actividades de la isla, adem\u00e1s de la actividad sexual que se esperaba\u201d. El nombre de la v\u00edctima est\u00e1 editado por protecci\u00f3n en el informe del FBI, pero los detalles biogr\u00e1ficos que describi\u00f3 en la entrevista coinciden con las afirmaciones p\u00fablicas de Giuffre.<\/p>\n<p>Otra v\u00edctima relat\u00f3 en su propia entrevista con el FBI que, durante un viaje a la isla de Epstein, Epstein la llev\u00f3 en avi\u00f3n a otra isla y la present\u00f3 a un multimillonario no identificado. \u201cAlmorzaron y nada parec\u00eda raro\u201d, relat\u00f3 la mujer.<\/p>\n<p>Algunos miembros del personal dicen que tambi\u00e9n vieron a los invitados de Epstein en situaciones preocupantes con mujeres y ni\u00f1as en la isla.<\/p>\n<p>Scully, el t\u00e9cnico que trabaj\u00f3 en la isla entre 1999 y mediados de la d\u00e9cada de 2000, asegur\u00f3 al FBI que observ\u00f3 a un hombre no identificado en la isla, acompa\u00f1ado por chicas que \u201cno parec\u00edan de 18 y estaban todas desnudas\u201d. Tambi\u00e9n les dijo a los investigadores que vio al entonces pr\u00edncipe Andr\u00e9s en la isla y que \u201crecord\u00f3 que se restregaba contra alguna chica joven en la piscina\u201d, de acuerdo con un informe del FBI.<\/p>\n<p>Otros correos electr\u00f3nicos incluidos en los documentos del DOJ muestran que algunas personas a las que Epstein invit\u00f3 a su isla intercambiaron correos electr\u00f3nicos lascivos y sugerentes con el delincuente sexual.<\/p>\n<p>Un sult\u00e1n de los Emiratos \u00c1rabes Unidos, Ahmed bin Sulayem, le escribi\u00f3 a Epstein en 2013 que iba a \u201cprobar una rusa fresca 100 % femenina en mi yate\u201d y le envi\u00f3 enlaces a sitios web pornogr\u00e1ficos en otro mensaje. Fotos incluidas en los documentos del DOJ muestran a Sulayem con Epstein en Little St. James.<\/p>\n<p>\u201cPor favor, env\u00edame algunas fotos de tu isla\u2026 Incluye tambi\u00e9n una foto o dos de chicas sexys (preferiblemente desnudas o semidesnudas)\u201d, le escribi\u00f3 a Epstein el empresario Boris Nikolic en 2013. En un mensaje de texto a CNN, Nikolic calific\u00f3 el intercambio como una \u201cbroma de mal gusto y fuera de contexto\u201d, y dijo que nunca presenci\u00f3 ning\u00fan comportamiento ilegal por parte de Epstein. \u201cLamento profundamente haberme asociado con \u00e9l\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Otros corresponsales de Epstein dicen que se sienten avergonzados por sus correos electr\u00f3nicos con \u00e9l. Olivier Colom, exasesor de un presidente de Francia que intercambi\u00f3 decenas de mensajes con Epstein a lo largo de los a\u00f1os, dijo a CNN que \u201clamento profunda y amargamente haber intercambiado alguna vez algo con este criminal\u201d, y a\u00f1adi\u00f3 que nunca visit\u00f3 la isla.<\/p>\n<p>En un mensaje de 2013, Colom le pregunt\u00f3 a Epstein d\u00f3nde estaba. \u201cEn mi isla en el Caribe, con un acuario lleno de chicas\u201d, escribi\u00f3 Epstein. \u201cClaro que disfrutar\u00eda la vista\u201d, le dijo Colom.<\/p>\n<p>Epstein respondi\u00f3 con un comentario que parec\u00eda resumir su trato hacia las chicas que hab\u00eda llevado a su porci\u00f3n de para\u00edso.<\/p>\n<p>\u201cAlgunas son como camarones\u201d, escribi\u00f3. \u201cTiras la cabeza y te quedas con el cuerpo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los banqueros adinerados, l\u00edderes pol\u00edticos y destacados acad\u00e9micos que visitaron la isla caribe\u00f1a de Jeffrey Epstein viajaban en jet privado y pasaban las tardes buceando o montando motos acu\u00e1ticas. Las ni\u00f1as y mujeres j\u00f3venes que Epstein trasladaba a la isla viv\u00edan una experiencia dr\u00e1sticamente distinta: les confiscaban los pasaportes, sufr\u00edan abusos sexuales sistem\u00e1ticos y enfrentaban [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472295","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los banqueros adinerados, l\u00edderes pol\u00edticos y destacados acad\u00e9micos que visitaron la isla caribe\u00f1a de Jeffrey Epstein viajaban en jet privado y pasaban las tardes buceando o montando motos acu\u00e1ticas. Las ni\u00f1as y mujeres j\u00f3venes que Epstein trasladaba a la isla viv\u00edan una experiencia dr\u00e1sticamente distinta: les confiscaban los pasaportes, sufr\u00edan abusos sexuales sistem\u00e1ticos y enfrentaban [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T02:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas\",\"datePublished\":\"2026-03-18T02:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/\"},\"wordCount\":4215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/\",\"name\":\"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-18T02:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas - Noticias","og_description":"Los banqueros adinerados, l\u00edderes pol\u00edticos y destacados acad\u00e9micos que visitaron la isla caribe\u00f1a de Jeffrey Epstein viajaban en jet privado y pasaban las tardes buceando o montando motos acu\u00e1ticas. Las ni\u00f1as y mujeres j\u00f3venes que Epstein trasladaba a la isla viv\u00edan una experiencia dr\u00e1sticamente distinta: les confiscaban los pasaportes, sufr\u00edan abusos sexuales sistem\u00e1ticos y enfrentaban [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-18T02:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"21 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/"},"author":{"name":"","@id":""},"headline":"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas","datePublished":"2026-03-18T02:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/"},"wordCount":4215,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/","name":"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-18T02:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La isla de Epstein: dentro del feudo caribe\u00f1o donde el financiero sedujo a los ricos y abus\u00f3 de chicas","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/dentro-de-isla-epstein-little-st-james-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-18T02:03:45Z","datePublished":"2026-03-18T02:03:45Z","dateModified":"2026-03-18T02:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La isla de Epstein: dentro del feudo caribe\\u00f1o donde el financiero sedujo a los ricos y abus\\u00f3 de chicas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/17\\\/dentro-de-isla-epstein-little-st-james-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/17\\\/dentro-de-isla-epstein-little-st-james-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-18T02:03:45Z\",\"datePublished\":\"2026-03-18T02:03:45Z\",\"dateModified\":\"2026-03-18T02:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470673,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/01\/30\/elon-musk-isla-epstein-correo-electronico-trax\/","url_meta":{"origin":1472295,"position":0},"title":"En un correo electr\u00f3nico de 2013, Elon Musk le pregunt\u00f3 a Epstein: &#171;\u00bfCu\u00e1ndo vamos a tu isla?&#187;","author":"","date":"enero 30, 2026","format":false,"excerpt":"Elon Musk le envi\u00f3 un correo electr\u00f3nico a Jeffrey Epstein a finales de 2013 para coordinar un viaje a la isla caribe\u00f1a del delincuente sexual convicto, seg\u00fan muestran documentos publicados por el Departamento de Justicia el viernes.Musk dijo anteriormente que hab\u00eda rechazado los intentos de Epstein de que visitara una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443507,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/01\/11\/que-revelaron-y-que-no-los-documentos-sobre-jeffrey-epstein\/","url_meta":{"origin":1472295,"position":1},"title":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?","author":"","date":"enero 11, 2024","format":false,"excerpt":"(CNN) -- Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes.El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447398,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/03\/26\/lo-que-aprendimos-y-lo-que-no-documentos-revelados-jeffrey-epstein-trax\/","url_meta":{"origin":1472295,"position":2},"title":"\u00bfQu\u00e9 revelaron (y qu\u00e9 no) los documentos sobre Jeffrey Epstein?","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Durante los \u00faltimos d\u00edas, cientos de documentos de una demanda relacionada con Jeffrey Epstein se hicieron p\u00fablicos por primera vez. El conjunto m\u00e1s reciente de esos documentos se revel\u00f3 este martes.El alcance total de la supuesta actividad criminal de Jeffrey Epstein sigue envuelto en un velo de misterio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447399,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2024\/03\/26\/12-mujeres-demandan-fbi-abusos-sexuales-jeffrey-epstein-trax\/","url_meta":{"origin":1472295,"position":3},"title":"Al menos 12 mujeres demandan al FBI por no protegerlas de los abusos sexuales de Jeffrey Epstein","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN) -- Los \"repetidos y continuos fallos, retrasos e inacci\u00f3n\" del FBI permitieron a Jeffrey Epstein mantener su operaci\u00f3n de tr\u00e1fico sexual durante m\u00e1s de 20 a\u00f1os, afirman 12 presuntas v\u00edctimas en una demanda presentada este mi\u00e9rcoles.La demanda, dirigida contra Estados Unidos en el Distrito Sur de Nueva York, afirma\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468933,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2025\/12\/03\/divulgan-fotos-isla-epstein-trax\/","url_meta":{"origin":1472295,"position":4},"title":"Dem\u00f3cratas de la C\u00e1mara de Representantes revelan fotos y videos de la isla privada de Epstein","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"Los dem\u00f3cratas de la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes divulgaron este mi\u00e9rcoles nuevas fotos y videos de una isla privada en el Caribe que perteneci\u00f3 a Jeffrey Epstein, arrojando nueva luz sobre lo que fue el epicentro de las d\u00e9cadas de abuso de ni\u00f1as y mujeres por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470836,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/02\/04\/analisis-archivos-epstein-trump-clinton-musk-trax\/","url_meta":{"origin":1472295,"position":5},"title":"Nuevos archivos profundizan un misterio cr\u00edtico sobre quienes se juntaron con Jeffrey Epstein","author":"","date":"febrero 4, 2026","format":false,"excerpt":"\u201cEl pueblo estadounidense debe comprender que no es un delito festejar con el se\u00f1or Epstein\u201d.Tal vez el vicesecretario de Justicia Todd Blanche tenga raz\u00f3n, dado el alto nivel de pruebas requerido para un procesamiento.Pero su comentario del lunes en Fox News ignor\u00f3 cruelmente a las v\u00edctimas de Jeffrey Epstein, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1472295"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472295\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1472295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1472295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1472295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}