{"id":1472322,"date":"2026-03-18T19:03:38","date_gmt":"2026-03-19T02:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/"},"modified":"2026-03-18T19:03:38","modified_gmt":"2026-03-19T02:03:38","slug":"mullin-bajo-escrutinio-senado-dhs-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/","title":{"rendered":"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos"},"content":{"rendered":"<p>Lo que suele ser un entorno amistoso para uno de los suyos se torn\u00f3 tenso este mi\u00e9rcoles en el Capitolio, donde senadores interrogaron a <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/17\/eeuu\/democratas-markwayne-mullin-departamento-seguridad-nacional-trax\">Markwayne Mullin<\/a> durante cerca de tres horas mientras busca convertirse en el pr\u00f3ximo secretario del Departamento de Seguridad Nacional del presidente Donald Trump.<\/p>\n<p>El presidente de la Comisi\u00f3n de Seguridad Nacional del Senado, el republicano Rand Paul, puso en duda si el legislador de Oklahoma tiene el temperamento necesario para dirigir un departamento con m\u00e1s de 260.000 empleados, reavivando una disputa de larga data en la que Mullin lo llam\u00f3 \u201cserpiente\u201d.<\/p>\n<p>El senador Gary Peters, principal dem\u00f3crata del panel, presion\u00f3 a Mullin sobre acusaciones de falsas afirmaciones sobre servicio militar y luego lo puso contra las cuerdas al exigirle una disculpa por un comentario anterior en el que dijo que Alex Pretti era un \u201cindividuo trastornado\u201d.<\/p>\n<p>Todo esto configur\u00f3 una audiencia de confirmaci\u00f3n particularmente intensa para Mullin en un momento cr\u00edtico para el Departamento de Seguridad Nacional, que permanece sin financiamiento mientras los legisladores retienen fondos para debatir reformas que podr\u00edan definir su futuro. El Gobierno y los legisladores esperan que el pr\u00f3ximo jefe del departamento, que supervisa agencias clave como el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s), la Administraci\u00f3n de Seguridad en el Transporte (TSA, por sus siglas en ingl\u00e9s) y la Guardia Costera, logre encauzar a una fuerza laboral bajo escrutinio p\u00fablico y en medio de turbulencia pol\u00edtica.<\/p>\n<p>Durante la audiencia, Mullin busc\u00f3 subrayar las diferencias entre su estilo de liderazgo y el de la secretaria saliente Kristi Noem, prometiendo reconocer sus errores y mantener un perfil m\u00e1s bajo. Sin embargo, queda por ver si logr\u00f3 convencer a los legisladores; se espera que la comisi\u00f3n vote el jueves sobre si avanza su designaci\u00f3n.<\/p>\n<p>En particular, Paul dijo a periodistas tras la audiencia que se opondr\u00e1 a Mullin.<\/p>\n<p>\u201cEl hecho de que no pueda decir que, en realidad, no deber\u00edamos resolver cuestiones pol\u00edticas con violencia, creo que ser\u00eda un ejemplo terrible para ICE y para nuestros agentes de la Patrulla Fronteriza\u201d, dijo Paul.<\/p>\n<p>\u201cEstamos en medio de una crisis en la que se necesita m\u00e1s direcci\u00f3n desde arriba, y alguien que se pelea, alguien que ni siquiera puede disculparse por desear violencia contra m\u00ed y pr\u00e1cticamente aplaudir el ataque que sufr\u00ed, \u00bfno puede decir eso? Desde mi punto de vista, no s\u00e9 c\u00f3mo podr\u00eda ser un l\u00edder de ICE o de la Patrulla Fronteriza\u201d.<\/p>\n<p>La oposici\u00f3n de Paul podr\u00eda poner en riesgo la confirmaci\u00f3n de Mullin, a menos que el senador dem\u00f3crata John Fetterman, quien ha dicho que votar\u00e1 a favor, se una a los republicanos para sacar adelante la designaci\u00f3n en la comisi\u00f3n.<\/p>\n<p>En el centro de las duras declaraciones iniciales de Paul est\u00e1n las frustraciones de Mullin por el hecho de que su colega suele ser un obst\u00e1culo para Trump y ha votado repetidamente en contra de las prioridades del Partido Republicano, lo que ha provocado retrasos y bloqueos en el pleno del Senado.<\/p>\n<p>Mullin dijo recientemente a un grupo de votantes en Oklahoma que \u201centend\u00eda\u201d por qu\u00e9 el vecino de Paul lo hab\u00eda atacado en 2017 y lo llam\u00f3 \u201cserpiente\u201d.<\/p>\n<p>Paul critic\u00f3 en\u00e9rgicamente este mi\u00e9rcoles los comentarios de Mullin, argumentando que su negativa a disculparse o a confrontarlo directamente pone en duda su car\u00e1cter y su capacidad para liderar el Departamento de Seguridad Nacional.<\/p>\n<p>\u201cMe sorprendi\u00f3 que justificara y celebrara este ataque violento que me caus\u00f3 tanto dolor a m\u00ed y a mi familia. Me pregunto si alguien que aplaude la violencia contra sus oponentes pol\u00edticos es la persona adecuada para dirigir una agencia que ha tenido dificultades para aceptar l\u00edmites en el uso adecuado de la fuerza\u201d, dijo Paul, de Kentucky, a Mullin.<\/p>\n<p>Mullin, dijo Paul, tendr\u00eda la oportunidad de \u201cmirarlo a los ojos\u201d y repetir esas palabras durante la audiencia. Luego, al acusar al senador de tener \u201cproblemas de ira\u201d, se\u00f1al\u00f3 un episodio durante una audiencia en 2023 en el que Mullin pareci\u00f3 dispuesto a enfrentarse f\u00edsicamente con un testigo.<\/p>\n<p>En repetidas ocasiones, Paul presion\u00f3 a Mullin para que se disculpara por sus comentarios, pero Mullin se neg\u00f3.<\/p>\n<p>En cambio, Mullin argument\u00f3 que ambos deber\u00edan \u201cdejarlo de lado\u201d y avanzar con la consideraci\u00f3n de su designaci\u00f3n. Reiter\u00f3 que se sent\u00eda honrado, siendo antes un joven de un peque\u00f1o pueblo con un impedimento del habla, de ser considerado para un cargo federal de tan alto nivel.<\/p>\n<p>\u201cTodos en esta sala saben que soy muy directo y voy al grano, y si tengo algo que decir, se lo dir\u00e9 directamente en la cara\u201d, dijo Mullin, al argumentar que Paul pasa m\u00e1s tiempo tratando de \u201cpelear con republicanos que trabajando con nosotros\u201d.<\/p>\n<p>\u201cPuedo dejarlo de lado, si usted est\u00e1 dispuesto a hacerlo. Perm\u00edtame ganarme su respeto. Perm\u00edtame ganarme el cargo. No le fallar\u00e9. No retroceder\u00e9 ante un desaf\u00edo\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Al decir \u201cpongan el video\u201d, Paul respondi\u00f3 mostrando un clip de la audiencia de 2023 junto con comentarios posteriores de Mullin en los que afirmaba no arrepentirse de su comportamiento.<\/p>\n<p>Mullin dijo a la comisi\u00f3n en respuesta que el testigo, el presidente de la Hermandad Internacional de Camioneros, Sean O\u2019Brien, se ha convertido en un \u201camigo cercano\u201d y que asist\u00eda a la audiencia como su invitado.<\/p>\n<p>Tras el intercambio, Fetterman inst\u00f3 a ambos a pasar p\u00e1gina y se\u00f1al\u00f3 a Mullin y a O\u2019Brien como ejemplo.<\/p>\n<p>\u201cS\u00e9 que hay muchos sentimientos personales dif\u00edciles aqu\u00ed y, absolutamente, yo\u2026 es terrible lo que ha pasado y la violencia pol\u00edtica, quiero decir, es algo que est\u00e1 muy extendido ahora. Pero tambi\u00e9n el presidente O\u2019Brien est\u00e1 aqu\u00ed, no para una segunda ronda. Est\u00e1 aqu\u00ed porque respalda plenamente su\u2026 as\u00ed que se trata de dejarlo ir y seguir adelante\u201d.<\/p>\n<p>Fetterman sostuvo que mantendr\u00e1 una \u201cmente abierta\u201d y elogi\u00f3 la \u201cconstante amabilidad y profesionalismo\u201d de Mullin.<\/p>\n<p>Mullin, que no tiene historial de servicio militar en EE.UU., tambi\u00e9n fue interrogado sobre acusaciones de que declaraciones previas y vagas que ha hecho sobre servir en el extranjero y \u201coler la guerra\u201d equival\u00edan a falsas afirmaciones sobre servicio militar.<\/p>\n<p>El senador republicano calific\u00f3 las acusaciones como un \u201cmalentendido\u201d y dijo que en 2016 se le pidi\u00f3 que se entrenara con un \u201cgrupo muy reducido y que se desplazara a una zona determinada\u201d. Como parte de ese viaje, dijo que particip\u00f3 en un entrenamiento de supervivencia, evasi\u00f3n, resistencia y escape, que describi\u00f3 a la vez como \u201calgo divertido\u201d y \u201cabsolutamente horrible\u201d.<\/p>\n<p>Algunos aspectos de ese entrenamiento y ese viaje eran clasificados, dijo.<\/p>\n<p>\u201cEntonces, \u00bfd\u00f3nde oli\u00f3 la guerra, se\u00f1or?\u201d, pregunt\u00f3 Peters, un dem\u00f3crata de Michigan.<\/p>\n<p>Mullin respondi\u00f3 que no pod\u00eda dar m\u00e1s detalles por tratarse de informaci\u00f3n clasificada.<\/p>\n<p>A lo largo de la comparecencia de Mullin se le plantearon varias preguntas al respecto, y Peters le dijo m\u00e1s tarde: \u201cNo ha sido sincero conmigo ni con esta comisi\u00f3n. Su versi\u00f3n de los hechos parece cambiar constantemente. Y, como sabe, la franqueza, la honestidad y la transparencia son absolutamente fundamentales, sobre todo en estos momentos, para intentar generar confianza como secretario de Seguridad Nacional\u201d.<\/p>\n<p>Despu\u00e9s de que Paul amenazara con suspender la votaci\u00f3n de la comisi\u00f3n prevista para este mi\u00e9rcoles a menos que Mullin les diera aclaraciones sobre el trabajo clasificado que afirmaba haber realizado, Mullin accedi\u00f3 a reunirse con los legisladores en un entorno seguro tras la audiencia.<\/p>\n<p>Varios legisladores salieron de esa sesi\u00f3n a puerta cerrada este mi\u00e9rcoles por la tarde sin saber muy bien qu\u00e9 pensar de los comentarios anteriores del senador.<\/p>\n<p>Pero Paul pareci\u00f3 dar a entender que la votaci\u00f3n en la comisi\u00f3n seguir\u00eda adelante. \u201cCreo que ya hemos terminado, m\u00e1s o menos. Todav\u00eda quedan algunas inc\u00f3gnitas sobre su servicio en la guerra, pero creo que, ya sabes, hemos llegado tan lejos como creo que \u00edbamos a llegar. La gente tiene que formarse una opini\u00f3n\u201d, declar\u00f3 a CNN.<\/p>\n<p>Durante la audiencia, Mullin hizo hincapi\u00e9 en las diferencias entre la forma en que \u00e9l planea dirigir el departamento y la forma en que Noem ha desempe\u00f1ado el cargo.<\/p>\n<p>Dijo a los senadores que no es \u201cperfecto\u201d y que asumir\u00e1 sus errores y aprender\u00e1 de ellos, en contraste con la reticencia de Noem a reconocer sus equivocaciones. \u201cMi objetivo en seis meses es que no seamos la noticia principal todos los d\u00edas\u201d, afirm\u00f3.<\/p>\n<p>Tambi\u00e9n dijo a la senadora dem\u00f3crata por Nueva Hampshire, Maggie Hassan: \u201cTodos tienen estilos de liderazgo diferentes. Mi estilo de gesti\u00f3n es empoderar a las personas\u201d, y prometi\u00f3 al senador por Nueva Jersey, Andy Kim, que ser\u00e1 receptivo con los miembros del Congreso, tras las frecuentes quejas de que, bajo Noem, el departamento no respond\u00eda a tiempo a las preguntas de los legisladores.<\/p>\n<p>\u201cCreo que todos los que hemos estado en la C\u00e1mara o en el Senado siempre nos quejamos del contacto con las agencias. Me comprometo a que eso ser\u00e1 lo mejor posible\u201d, dijo.<\/p>\n<p>\u201cVamos a trabajar con ustedes. Pero, lo m\u00e1s importante, creo que todos en este estrado tienen mi n\u00famero de tel\u00e9fono personal. Ese n\u00famero no va a cambiar. Y si me llaman, recibir\u00e1n una respuesta. Si me env\u00edan un mensaje, recibir\u00e1n una respuesta\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Los senadores dem\u00f3cratas cuestionaron a Mullin por sus comentarios previos sobre el encuentro mortal de Pretti con agentes federales de inmigraci\u00f3n en Minnesota a principios de este a\u00f1o, y el senador se disculp\u00f3 por haber llamado a Pretti \u201cun individuo trastornado\u201d inmediatamente despu\u00e9s del tiroteo.<\/p>\n<p>\u201cNo deb\u00ed haber dicho eso\u201d, reconoci\u00f3.<\/p>\n<p>\u201cLa investigaci\u00f3n est\u00e1 en curso y, como dije, a veces se cometen errores y yo los asumo\u201d, dijo en la audiencia. \u201cEn ese caso, habl\u00e9 demasiado r\u00e1pido. Respond\u00ed de inmediato sin tener los hechos. Es culpa m\u00eda\u201d.<\/p>\n<p>Tambi\u00e9n se\u00f1al\u00f3 que deber\u00eda haber cambios en la forma en que se despliega ICE en todo el pa\u00eds, y dijo a los senadores: \u201cMe gustar\u00eda ver que ICE tenga un rol m\u00e1s de transporte que de primera l\u00ednea\u201d, adem\u00e1s de comprometerse a exigir que los agentes de ICE obtengan \u00f3rdenes judiciales antes de ingresar a propiedades privadas, con excepciones limitadas.<\/p>\n<p>Los dem\u00f3cratas han exigido que el uso de \u00f3rdenes judiciales, en lugar de las \u00f3rdenes administrativas menos restrictivas que ha estado utilizando el ICE, se codifique en la legislaci\u00f3n en medio de las negociaciones sobre la financiaci\u00f3n del DHS.<\/p>\n<p>En general, sus comentarios sobre una mayor colaboraci\u00f3n de los agentes de inmigraci\u00f3n con las fuerzas del orden locales sugieren un retorno a las operaciones tradicionales llevadas a cabo por ICE, en lugar de las amplias redadas de inmigraci\u00f3n vistas bajo el mandato de Noem.<\/p>\n<p>Los colegas republicanos de Mullin le dieron oportunidades al senador para hablar sobre sus estrechas relaciones con exmiembros de la C\u00e1mara de Representantes, incluido el representante dem\u00f3crata Josh Gottheimer, quien se sent\u00f3 detr\u00e1s de Mullin durante la audiencia, as\u00ed como sobre su amistad con Trump.<\/p>\n<p>Al describir al presidente como un \u201camigo\u201d, Mullin dijo que habla con Trump \u201ca nivel personal, m\u00e1s que a nivel de pol\u00edtica p\u00fablica\u201d.<\/p>\n<p>Se mostr\u00f3 visiblemente emocionado al hablar de c\u00f3mo el presidente se mantuvo al tanto de la situaci\u00f3n de su hijo tras una lesi\u00f3n cerebral traum\u00e1tica en 2020, cuando el joven perdi\u00f3 gran parte de su memoria y control muscular.<\/p>\n<p>\u201cVoy a intentar decir esto sin llorar\u201d, dijo Mullin, al responder a una pregunta del senador republicano por Wisconsin, Ron Johnson, sobre el origen de su lealtad hacia Trump.<\/p>\n<p>\u201cCasi lo perdemos. Durante 26 horas tuvo un pulso extremadamente bajo; hubo un momento en que pensaron que lo perder\u00edan por completo\u201d, record\u00f3 Mullin.<\/p>\n<p>Trump, dijo, cambi\u00f3 el rumbo de la vida de su hijo al ofrecer enviar su \u201cavi\u00f3n personal\u201d para trasladarlo a un centro de neurorehabilitaci\u00f3n de primer nivel y al mantenerse en contacto frecuente con la familia. \u201cHemos sido amigos desde entonces\u201d, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo que suele ser un entorno amistoso para uno de los suyos se torn\u00f3 tenso este mi\u00e9rcoles en el Capitolio, donde senadores interrogaron a Markwayne Mullin durante cerca de tres horas mientras busca convertirse en el pr\u00f3ximo secretario del Departamento de Seguridad Nacional del presidente Donald Trump. El presidente de la Comisi\u00f3n de Seguridad Nacional [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472322","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Lo que suele ser un entorno amistoso para uno de los suyos se torn\u00f3 tenso este mi\u00e9rcoles en el Capitolio, donde senadores interrogaron a Markwayne Mullin durante cerca de tres horas mientras busca convertirse en el pr\u00f3ximo secretario del Departamento de Seguridad Nacional del presidente Donald Trump. El presidente de la Comisi\u00f3n de Seguridad Nacional [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T02:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos\",\"datePublished\":\"2026-03-19T02:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/\"},\"wordCount\":2104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/\",\"name\":\"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-19T02:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos - Noticias","og_description":"Lo que suele ser un entorno amistoso para uno de los suyos se torn\u00f3 tenso este mi\u00e9rcoles en el Capitolio, donde senadores interrogaron a Markwayne Mullin durante cerca de tres horas mientras busca convertirse en el pr\u00f3ximo secretario del Departamento de Seguridad Nacional del presidente Donald Trump. El presidente de la Comisi\u00f3n de Seguridad Nacional [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-19T02:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/"},"author":{"name":"","@id":""},"headline":"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos","datePublished":"2026-03-19T02:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/"},"wordCount":2104,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/","name":"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-19T02:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos","url":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/18\/mullin-bajo-escrutinio-senado-dhs-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-19T02:03:38Z","datePublished":"2026-03-19T02:03:38Z","dateModified":"2026-03-19T02:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mullin comparece ante el Senado, a la espera de ser confirmado como secretario de Seguridad, y enfrenta cuestionamientos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/18\\\/mullin-bajo-escrutinio-senado-dhs-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nueva-inglaterra\\\/2026\\\/03\\\/18\\\/mullin-bajo-escrutinio-senado-dhs-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-19T02:03:38Z\",\"datePublished\":\"2026-03-19T02:03:38Z\",\"dateModified\":\"2026-03-19T02:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472345,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/19\/mullin-dhs-apoyo-democrata-fetterman-trax\/","url_meta":{"origin":1472322,"position":0},"title":"La postulaci\u00f3n de Markwayne Mullin para dirigir el DHS avanza luego de que un senador dem\u00f3crata se uniera a los republicanos","author":"","date":"marzo 19, 2026","format":false,"excerpt":"La propuesta de Markwayne Mullin para ocupar el cargo de secretario del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) ser\u00e1 sometida a una votaci\u00f3n ante el pleno del Senado, despu\u00e9s de que el senador dem\u00f3crata John Fetterman se uniera a los republicanos en la Comisi\u00f3n de Seguridad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471929,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/05\/quien-es-markwayne-mullin-reemplazo-kristi-noem-dhs-trax\/","url_meta":{"origin":1472322,"position":1},"title":"\u00bfQui\u00e9n es Markwayne Mullin, nombrado por Trump para reemplazar a Kristi Noem como secretario de Seguridad Nacional?","author":"","date":"marzo 5, 2026","format":false,"excerpt":"El presidente Donald Trump anunci\u00f3 el jueves que destitu\u00eda a la secretaria del Departamento de Seguridad Nacional, Kristi Noem, y que el senador republicano Markwayne Mullin, de Oklahoma, la reemplazar\u00eda.Mullin, un senador de primer mandato que ha ocupado ese cargo desde 2023, es un exdeportista de arte marcial mixto y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472474,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/23\/confirman-markwayne-mullin-secretario-seguridad-nacional-trax\/","url_meta":{"origin":1472322,"position":2},"title":"Confirman a Markwayne Mullin como secretario de Seguridad Nacional en medio de la crisis de financiamiento","author":"","date":"marzo 23, 2026","format":false,"excerpt":"Markwayne Mullin se desempe\u00f1ar\u00e1 como el pr\u00f3ximo secretario del Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) de Donald Trump, elevando al senador estadounidense para encabezar la agencia en el centro del controvertido esfuerzo de aplicaci\u00f3n de las leyes migratorias del presidente y de un cierre en curso.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472269,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/17\/democratas-markwayne-mullin-departamento-seguridad-nacional-trax\/","url_meta":{"origin":1472322,"position":3},"title":"A los dem\u00f3cratas les gusta Markwayne Mullin. Eso no significa que voten por \u00e9l para el DHS de EE.UU.","author":"","date":"marzo 17, 2026","format":false,"excerpt":"En sus inicios en el Congreso, Markwayne Mullin intent\u00f3 combinar su chaqueta y corbata con unos vaqueros en la C\u00e1mara de Representantes. El entonces presidente de la C\u00e1mara, John Boehner, reprendi\u00f3 al joven republicano por infringir el c\u00f3digo de vestimenta.Puede que haya llegado a Washington con una apariencia poco convencional,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471998,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/03\/08\/senador-republicano-secretario-seguridad-nacional-independiente-stephen-miller-trax\/","url_meta":{"origin":1472322,"position":4},"title":"Legislador republicano dice que el pr\u00f3ximo secretario de Seguridad Nacional ser\u00e1 independiente de Stephen Miller","author":"","date":"marzo 8, 2026","format":false,"excerpt":"El senador republicano por Carolina del Norte Thom Tillis dijo que le alegraba que el presidente Donald Trump \u201cpasar\u00e1 la p\u00e1gina\u201d con la secretaria de Seguridad Nacional, Kristi Noem, a quien el presidente destituy\u00f3 la semana pasada, y a\u00f1adi\u00f3 que ella hab\u00eda estado influenciada por voces externas como el asesor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473405,"url":"https:\/\/noticiasya.com\/nueva-inglaterra\/2026\/04\/22\/senado-financiacion-dhs-trax\/","url_meta":{"origin":1472322,"position":5},"title":"El Senado da el primer paso para financiar ICE y CBP mientras Thune espera fondos para el DHS","author":"","date":"abril 22, 2026","format":false,"excerpt":"El l\u00edder de la mayor\u00eda en el Senado, John Thune, declar\u00f3 a CNN que espera que la C\u00e1mara de Representantes financie el resto del Departamento de Seguridad Nacional (DHS) una vez que el Senado d\u00e9 el primer paso para financiar al Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nueva-inglaterra\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/comments?post=1472322"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/posts\/1472322\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/media?parent=1472322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/categories?post=1472322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nueva-inglaterra\/wp-json\/wp\/v2\/tags?post=1472322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}