{"id":1448041,"date":"2024-04-12T17:03:44","date_gmt":"2024-04-13T00:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/"},"modified":"2024-04-12T17:03:44","modified_gmt":"2024-04-13T00:03:44","slug":"caso-ronald-ojeda-chile-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/","title":{"rendered":"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &#171;organiz\u00f3 y se solicit\u00f3&#187; desde Venezuela"},"content":{"rendered":"<p>(CNN) &#8212; H\u00e9ctor Barros, fiscal a cargo del caso que investiga el asesinato del exmilitar venezolano Ronald Ojeda en Chile, afirm\u00f3 en una entrevista a Chilevisi\u00f3n difundida este viernes que, de acuerdo con las indagaciones, el crimen \u201cse organiz\u00f3 y se solicit\u00f3 desde Venezuela\u201d.<\/p>\n<p>Consultado por la periodista de Chilevisi\u00f3n sobre la posibilidad de que el m\u00f3vil del crimen fuera pol\u00edtico, Barros dijo que no tiene \u201cantecedentes que nos indiquen hacia otro lado\u201d, y agreg\u00f3 que han \u201cdescartado todas las tesis que tengan que ver con alg\u00fan il\u00edcito\u201d.<\/p>\n<p>Qui\u00e9n era Ronald Ojeda, el exmilitar venezolano secuestrado y asesinado en Chile<\/p>\n<p>El fiscal a cargo del caso recalc\u00f3 que \u201chay un grado de organizaci\u00f3n, de ejecuci\u00f3n, que nosotros no hab\u00edamos visto\u201d.<\/p>\n<p>Barros agreg\u00f3 que ya elevaron \u201cun requerimiento de asistencia penal internacional a Venezuela, para que nos puedan ayudar con la detenci\u00f3n de dos ciudadanos venezolanos que est\u00e1n actualmente en Venezuela\u201d, por su posible vinculaci\u00f3n con el crimen.<\/p>\n<p>CNN intenta contactar a la Fiscal\u00eda chilena para conocer m\u00e1s detalles sobre el caso y con el Gobierno de Venezuela para conocer su postura ante las declaraciones.<\/p>\n<p>Fiscal\u00eda de Chile confirma que Ronald Ojeda muri\u00f3 por asfixia y revela el presunto v\u00ednculo del Tren de Aragua con su asesinato y secuestro<\/p>\n<p>El fiscal de Venezuela, Tarek William Saab, dijo este viernes en su cuenta de X, antes Twitter, que el jueves la instituci\u00f3n a su cargo recibi\u00f3 una solicitud de colaboraci\u00f3n por parte de la Fiscal\u00eda de Chile. Seg\u00fan Saab, la Fiscal\u00eda chilena pidi\u00f3 antecedentes penales de cinco personas presuntamente vinculadas con el asesinato de Ronald Ojeda y \u201cest\u00e1 procediendo a la ubicaci\u00f3n de los sujetos se\u00f1alados como presuntos involucrados en dicho crimen, para su inmediata detenci\u00f3n en el caso de que los mismos se encuentren en nuestro territorio\u201d.<\/p>\n<p>\u201cVenezuela y su Ministerio P\u00fablico tiene la m\u00e1s absoluta disposici\u00f3n de cooperar en la lucha contra el delito transnacional y ofrece a Chile toda su experiencia en el combate de estos grupos de delincuencia organizada\u201d, agreg\u00f3 Saab.<\/p>\n<p>Ronald Ojeda fue secuestrado en Santiago el pasado 21 de febrero por tres personas vestidas como agentes de la Polic\u00eda de Investigaciones de Chile (PDI). La Fiscal\u00eda chilena confirm\u00f3 el hallazgo de su cuerpo el 1 de marzo.<\/p>\n<p>Boric exige a Venezuela &#171;toda la colaboraci\u00f3n&#187; para capturar a sospechosos<\/p>\n<p>El presidente de Chile, Gabriel Boric, exigi\u00f3 este viernes a Venezuela su colaboraci\u00f3n para capturar a dos sospechosos del asesinato de Ojeda, quienes se encontrar\u00edan en ese pa\u00eds seg\u00fan la Fiscal\u00eda.<\/p>\n<p>\u201cEn esta nueva etapa de la investigaci\u00f3n, la colaboraci\u00f3n internacional es determinante. Por lo tanto, seguiremos apoyando a la Fiscal\u00eda en su solicitud de asistencia penal internacional\u201d, asegur\u00f3 Boric. \u201cSolicitamos y exigimos que pongan a disposici\u00f3n de la justicia a los sospechosos de haber perpetrado o colaborado en este vil asesinato\u201d, asegur\u00f3 el mandatario de prensa en la localidad de Los Andes.<\/p>\n<p>La m\u00e1xima autoridad chilena tambi\u00e9n critic\u00f3 los dichos del canciller venezolano Yvan Gil, quien asegur\u00f3 el pasado lunes que el Tren de Aragua es \u201cuna ficci\u00f3n por la medi\u00e1tica internacional\u201d.<\/p>\n<p>\u201cMe parece inaceptable que autoridades de otros pa\u00edses, pero en particular de Venezuela, realicen declaraciones que pongan en duda la existencia del Tren de Aragua, relativizando lo que habitantes de nuestro pa\u00eds han vivido respecto al actuar de esta banda del crimen organizado\u201d, afirm\u00f3 Boric.<\/p>\n<p>El mandatario chileno aclar\u00f3 que no ha tenido contacto directo con Nicol\u00e1s Maduro y que el nexo ha sido a trav\u00e9s de los cancilleres. Adem\u00e1s, Boric dijo que esta investigaci\u00f3n \u201ces parte de los motivos por los que hemos llamado a consulta a nuestro embajador en Venezuela, Jaime Gazmuri\u201d, con quien se reunir\u00e1 este s\u00e1bado.<\/p>\n<p>Por su parte, la ministra de Interior de Chile, Carolina Toh\u00e1, dijo este viernes que el asesinato del exmilitar venezolano \u201ces importante\u201d para la justicia chilena, y recalc\u00f3 que \u201clos ojos van a estar puestos\u201d en el comportamiento y la disposici\u00f3n de Caracas para colaborar con la investigaci\u00f3n.<\/p>\n<p>\u201cComo pa\u00eds hemos tenido experiencias complejas en casos similares, en que hemos buscado personas acusadas de delitos graves cometidos en Chile que se encuentran localizadas en Venezuela. En el \u00faltimo a\u00f1o hemos tenido cuatro casos y la experiencia no ha sido positiva. Creemos que el caso del exteniente Ojeda no puede correr la misma suerte. Esto que ha pasado en este crimen es importante para Chile. Le damos la mayor gravedad, pero tambi\u00e9n es importante para Venezuela. Los ojos van a estar puestos sobre su comportamiento y la disposici\u00f3n a colaborar en esta investigaci\u00f3n tiene que demostrarse en hechos\u201d, se\u00f1al\u00f3 Toh\u00e1.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; H\u00e9ctor Barros, fiscal a cargo del caso que investiga el asesinato del exmilitar venezolano Ronald Ojeda en Chile, afirm\u00f3 en una entrevista a Chilevisi\u00f3n difundida este viernes que, de acuerdo con las indagaciones, el crimen \u201cse organiz\u00f3 y se solicit\u00f3 desde Venezuela\u201d. Consultado por la periodista de Chilevisi\u00f3n sobre la posibilidad de que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448041","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &quot;organiz\u00f3 y se solicit\u00f3&quot; desde Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &quot;organiz\u00f3 y se solicit\u00f3&quot; desde Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; H\u00e9ctor Barros, fiscal a cargo del caso que investiga el asesinato del exmilitar venezolano Ronald Ojeda en Chile, afirm\u00f3 en una entrevista a Chilevisi\u00f3n difundida este viernes que, de acuerdo con las indagaciones, el crimen \u201cse organiz\u00f3 y se solicit\u00f3 desde Venezuela\u201d. Consultado por la periodista de Chilevisi\u00f3n sobre la posibilidad de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T00:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &#171;organiz\u00f3 y se solicit\u00f3&#187; desde Venezuela\",\"datePublished\":\"2024-04-13T00:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/\"},\"wordCount\":845,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/\",\"name\":\"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se \\\"organiz\u00f3 y se solicit\u00f3\\\" desde Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-13T00:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &#171;organiz\u00f3 y se solicit\u00f3&#187; desde Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se \"organiz\u00f3 y se solicit\u00f3\" desde Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se \"organiz\u00f3 y se solicit\u00f3\" desde Venezuela - Noticias","og_description":"(CNN) &#8212; H\u00e9ctor Barros, fiscal a cargo del caso que investiga el asesinato del exmilitar venezolano Ronald Ojeda en Chile, afirm\u00f3 en una entrevista a Chilevisi\u00f3n difundida este viernes que, de acuerdo con las indagaciones, el crimen \u201cse organiz\u00f3 y se solicit\u00f3 desde Venezuela\u201d. Consultado por la periodista de Chilevisi\u00f3n sobre la posibilidad de que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-13T00:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &#171;organiz\u00f3 y se solicit\u00f3&#187; desde Venezuela","datePublished":"2024-04-13T00:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/"},"wordCount":845,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/","name":"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se \"organiz\u00f3 y se solicit\u00f3\" desde Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-13T00:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &#171;organiz\u00f3 y se solicit\u00f3&#187; desde Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &#171;organiz\u00f3 y se solicit\u00f3&#187; desde Venezuela","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/12\/caso-ronald-ojeda-chile-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-13T00:03:44Z","datePublished":"2024-04-13T00:03:44Z","dateModified":"2024-04-13T00:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Caso Ronald Ojeda: fiscal de Chile dice que el crimen se &#171;organiz\\u00f3 y se solicit\\u00f3&#187; desde Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/12\\\/caso-ronald-ojeda-chile-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/12\\\/caso-ronald-ojeda-chile-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-13T00:03:44Z\",\"datePublished\":\"2024-04-13T00:03:44Z\",\"dateModified\":\"2024-04-13T00:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451081,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/07\/12\/arrestan-costa-rica-presunto-implicado-secuestro-homicidio-ronald-ojeda-orix\/","url_meta":{"origin":1448041,"position":0},"title":"Arrestan en Costa Rica a presunto implicado en secuestro y homicidio de exmilitar venezolano Ronald Ojeda en Chile","author":"","date":"julio 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Ministerio de Seguridad de Costa Rica confirm\u00f3 a CNN este viernes que las autoridades detuvieron a Maickel Villegas Rodr\u00edguez, que contaba con una notificaci\u00f3n internacional de b\u00fasqueda por su presunta participaci\u00f3n en el secuestro y homicidio del exmilitar venezolano Ronald Ojeda en Chile en febrero pasado.El se\u00f1alado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465518,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/arrestan-otro-presunto-responsable-homicidio-ronald-ojeda-orix\/","url_meta":{"origin":1448041,"position":1},"title":"Arrestan en Chile a otro presunto responsable del homicidio del exmilitar venezolano Ronald Ojeda. Suman 12 detenidos","author":"","date":"agosto 14, 2025","format":false,"excerpt":"Autoridades de Chile arrestaron la noche del mi\u00e9rcoles a otro presunto responsable del secuestro y homicidio del exmilitar venezolano Ronald Ojeda, con lo que suman 12 las personas detenidas por su presunta relaci\u00f3n con el caso, inform\u00f3 este jueves el fiscal que encabeza la investigaci\u00f3n, H\u00e9ctor Barros.Durante una rueda de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460567,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/28\/chile-corte-penal-internacional-caso-de-ronald-ojeda-orix\/","url_meta":{"origin":1448041,"position":2},"title":"Chile lleva a la Corte Penal Internacional el caso de Ronald Ojeda, el exmilitar venezolano asesinado en Santiago","author":"","date":"marzo 28, 2025","format":false,"excerpt":"La Fiscal\u00eda y la Canciller\u00eda de Chile llevaron este viernes ante la Corte Penal Internacional (CPI) el caso de Ronald Ojeda, el exmilitar venezolano asilado en Santiago y que fue secuestrado y asesinado el a\u00f1o pasado en la capital del pa\u00eds, seg\u00fan informaron ambas instituciones.El fiscal nacional de Chile, \u00c1ngel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459055,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/21\/ronald-ojeda-secuestro-asesinato-exmilitar-venezolano-chile-orix\/","url_meta":{"origin":1448041,"position":3},"title":"Un a\u00f1o del caso Ronald Ojeda: qu\u00e9 se sabe del secuestro y asesinato del exmilitar venezolano en Chile","author":"","date":"febrero 21, 2025","format":false,"excerpt":"El exmilitar venezolano Ronald Ojeda estaba en su vivienda de Santiago, Chile, el 21 de febrero de 2024 cuando fue secuestrado por personas vestidas como agentes de la Polic\u00eda de Investigaciones de Chile (PDI). Nueve d\u00edas despu\u00e9s, el 1 de marzo, las autoridades confirmaron el hallazgo de su cuerpo dentro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446511,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/03\/04\/ronald-ojeda-venezolano-quien-era-perfil-orix\/","url_meta":{"origin":1448041,"position":4},"title":"Qui\u00e9n era Ronald Ojeda, el exmilitar venezolano secuestrado y asesinado en Chile","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- El pasado 21 de febrero, al menos tres personas vestidas como la Polic\u00eda de Investigaciones de Chile (PDI) llegaron con un artefacto para forzar puertas hasta el departamento de Ronald Leandro Ojeda Moreno, un exmilitar venezolano de 32 a\u00f1os que viv\u00eda junto a su pareja, su hijo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446448,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/03\/04\/chile-confirma-hallazgo-cuerpo-roland-ojeda-venezolano-secuestrado-orix-2\/","url_meta":{"origin":1448041,"position":5},"title":"La Fiscal\u00eda de Chile confirma el hallazgo del cuerpo de Ronald Ojeda, el venezolano secuestrado en Santiago","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El cuerpo que las autoridades de Chile hallaron este viernes pertenece a Ronald Ojeda, el ciudadano venezolano que resid\u00eda en territorio chileno y que fue secuestrado en Santiago a finales del mes pasado, inform\u00f3 este viernes en una breve conferencia de prensa el fiscal regional metropolitano para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448041"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448041\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}