{"id":1448170,"date":"2024-04-16T17:03:45","date_gmt":"2024-04-17T00:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/"},"modified":"2024-04-16T17:03:45","modified_gmt":"2024-04-17T00:03:45","slug":"opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/","title":{"rendered":"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva"},"content":{"rendered":"<p>Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion.<\/p>\n<p>(CNN) &#8212;\u00a0Roberto Cavalli, el famoso y muy pionero dise\u00f1ador italiano, ha muerto a los 83 a\u00f1os. Y sus muchos seguidores lo recordar\u00e1n siempre por su seductor uso (\u00a1con verdadero fervor!) de los animal prints -o estampados de animales, especialmente de cebras-, su amor al color\u2026 \u00a1y a las mujeres!<\/p>\n<p>El d\u00eda que lo conoc\u00ed -y lo entrevist\u00e9 en Nueva York- hace unos a\u00f1os, tengo que confesar que hasta me asust\u00f3 su intensidad y el desbordante \u201citalianismo\u201d de su personalidad.<\/p>\n<p>Muere el dise\u00f1ador italiano Roberto Cavalli, famoso por sus arriesgados estampados, a los 83 a\u00f1os<\/p>\n<p>Era sin duda un hombre larger than life, que daba igual qu\u00e9 edad tuviera, porque estaba lleno de vida y de pasi\u00f3n por la vida. \u00a1Y lo mostraba con fuerza!<\/p>\n<p>Abriendo boutiques en lugares de moda, como St. Tropez y St. Barts, Cavalli tambi\u00e9n fue un genio del marketing y de la publicidad y as\u00ed logr\u00f3 que su nombre se conociera, y sus creaciones estuvieran en todas partes. \u00bfCelebridades que han usado sus dise\u00f1os? Jennifer L\u00f3pez, Beyonc\u00e9, Rihanna, Madonna, Cher, Cindy Crawford, Demi Moore, Catherine Zeta-Jones, Gwyneth Paltrow, Charlize Theron, Victoria Beckham, Kate Hudson y muchas m\u00e1s.<\/p>\n<p>El d\u00eda que nos conocimos, su entusiasmo por la ropa que me mostraba llenaba aquel gran espacio en la calle 56 de Nueva York. En realidad me dej\u00f3 sin habla. Acariciaba sus telas con sensualidad y era algo muy interesante de observar. Creo que solo le hice dos o tres preguntas. Sus respuestas y explicaciones eran tan barrocas como sus dise\u00f1os. Y estos siempre fueron extravagantes, sexys, muy showbiz, impactantes, \u00a1y con tendencias que otros dise\u00f1adores, algunos incluso muy famosos, imitaron 15 y 20 a\u00f1os m\u00e1s tarde!<\/p>\n<p>Aparte de su amor por los estampados de animales, Cavalli fue un creador muy adelantado a su tiempo, lanzando atrevidas transparencias, adornos de plumas, cuero impreso con estampados, telas que parecen piel de serpientes, jeans bordados con brillantes, combinaciones inesperadas de colores y texturas y la sensualidad m\u00e1s flagrante. Cavalli nombr\u00f3 a Fausto Puglisi como director creativo de su marca en octubre de 2020, aunque segu\u00eda manteniendo el control de su inmenso y muy productivo negocio.<\/p>\n<p>Y debido a su presencia tan potente en la moda, me dio pena cuando hace una semana lleg\u00f3 la noticia de que Cavalli hab\u00eda muerto en su nativa Florencia, la capital de la regi\u00f3n donde su padre fue fusilado por las tropas alemanas durante la Segunda Guerra Mundial en la masacre de Cavriglia y muy cerca de su \u00faltimo gran amor desde 2014, la jovenc\u00edsima sueca Sandra Nillsson, 45 a\u00f1os menor que \u00e9l y madre de su hijo peque\u00f1o Giorgio, de solo 1 a\u00f1o, que naci\u00f3 cuando Cavalli ten\u00eda 82 a\u00f1os. Y una mujer que lo hizo tan feliz \u00a1que el dise\u00f1ador le compro una isla en Suecia! \u00a1Todo muy Cavalli!<\/p>\n<p>\u00a1Qu\u00e9 pena que se ha ido!<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion. (CNN) &#8212;\u00a0Roberto Cavalli, el famoso y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448170","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion. (CNN) &#8212;\u00a0Roberto Cavalli, el famoso y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T00:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva\",\"datePublished\":\"2024-04-17T00:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/\"},\"wordCount\":577,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/\",\"name\":\"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-17T00:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/","og_locale":"es_ES","og_type":"article","og_title":"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva - Noticias","og_description":"Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion. (CNN) &#8212;\u00a0Roberto Cavalli, el famoso y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-17T00:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/"},"author":{"name":"","@id":""},"headline":"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva","datePublished":"2024-04-17T00:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/"},"wordCount":577,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/","name":"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-17T00:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"OPINI\u00d3N | Roberto Cavalli: adi\u00f3s al rey de la selva","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/16\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-17T00:03:45Z","datePublished":"2024-04-17T00:03:45Z","dateModified":"2024-04-17T00:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"OPINI\\u00d3N | Roberto Cavalli: adi\\u00f3s al rey de la selva\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/16\\\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/16\\\/opinion-roberto-cavalli-adios-al-rey-de-la-selva-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-17T00:03:45Z\",\"datePublished\":\"2024-04-17T00:03:45Z\",\"dateModified\":\"2024-04-17T00:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448032,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/12\/roberto-cavalli-muerte-trax\/","url_meta":{"origin":1448170,"position":0},"title":"Muere el dise\u00f1ador italiano Roberto Cavalli, famoso por sus arriesgados estampados, a los 83 a\u00f1os","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Roberto Cavalli, el dise\u00f1ador de modas italiano que dej\u00f3 huella con sus distintivos y glamorosos estampados animal print, muri\u00f3 a los 83 a\u00f1os. Su marca, que lleva su mismo nombre, confirm\u00f3 la noticia en un comunicado compartido en redes sociales este viernes, destacando la vida que Cavalli \"vivi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452029,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/08\/21\/imagenes-los-mejores-outfits-del-eras-tour-de-taylor-swift-momento-trax\/","url_meta":{"origin":1448170,"position":1},"title":"En im\u00e1genes: Los mejores outfits del Eras Tour de Taylor Swift hasta el momento","author":"","date":"agosto 21, 2024","format":false,"excerpt":"(CNN) -- Millones de fans, un artista que rompe r\u00e9cords, casi 150 shows con entradas agotadas y un vestuario rotativo de 11 dise\u00f1adores: estos han sido los ingredientes ganadores de la famosa gira mundial de Taylor Swift.M\u00e1s de la mitad de su recorrido, el Eras Tour es ahora oficialmente la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448439,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/estamos-obsesionados-comida-ichaso-orix\/","url_meta":{"origin":1448170,"position":2},"title":"OPINI\u00d3N | \u00bfTe has dado cuenta de que estamos obsesionados con la comida?","author":"","date":"abril 23, 2024","format":false,"excerpt":"Nota del editor: Mari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449833,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/29\/opinion-fenomeno-musical-hamilton-hispano-orix\/","url_meta":{"origin":1448170,"position":3},"title":"OPINI\u00d3N | Una nueva forma de contar la historia: el fen\u00f3meno musical &#171;Hamilton&#187; lo cre\u00f3 un hispano","author":"","date":"mayo 29, 2024","format":false,"excerpt":"Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion(CNN Espa\u00f1ol)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453228,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/09\/30\/opinion-eduardo-suarez-de-la-habana-a-times-square-orix\/","url_meta":{"origin":1448170,"position":4},"title":"OPINION | Eduardo Su\u00e1rez, de La Habana a Times Square","author":"","date":"septiembre 30, 2024","format":false,"excerpt":"Jorge D\u00e1vila Miguel es licenciado en Periodismo desde 1973 y ha mantenido una carrera continuada en su profesi\u00f3n hasta la fecha. Ostenta posgrados en Ciencias de la Informaci\u00f3n Social y Medios de Comunicaci\u00f3n Sociales, as\u00ed como estudios superiores posuniversitarios en Relaciones Internacionales, Econom\u00eda Pol\u00edtica e Historia Latinoamericana. Es de nacionalidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450185,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/06\/10\/futuro-princesa-kate-trax\/","url_meta":{"origin":1448170,"position":5},"title":"OPINI\u00d3N | El futuro de la princesa Kate","author":"","date":"junio 10, 2024","format":false,"excerpt":"Nota del editor:\u202fMari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u202fcnne.com\/opinion(CNN) --El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448170"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448170\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}