{"id":1448179,"date":"2024-04-17T01:03:43","date_gmt":"2024-04-17T08:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/"},"modified":"2024-04-17T01:03:43","modified_gmt":"2024-04-17T08:03:43","slug":"astronomos-agujero-negro-gigante-dormido-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","title":{"rendered":"Los astr\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\u00f1os luz de la Tierra"},"content":{"rendered":"<p>(CNN) &#8212; Los astr\u00f3nomos descubrieron el agujero negro estelar m\u00e1s masivo conocido en la V\u00eda L\u00e1ctea despu\u00e9s de detectar una oscilaci\u00f3n inusual en el espacio.<\/p>\n<p>El llamado \u201cgigante durmiente\u201d, denominado Gaia BH3, tiene una masa casi 33 veces mayor que la de nuestro Sol y est\u00e1 ubicado a 1.926 a\u00f1os luz en la constelaci\u00f3n de Aquila, lo que lo convierte en el segundo agujero negro m\u00e1s cercano conocido a la Tierra. El agujero negro m\u00e1s cercano es Gaia BH1, que se encuentra a unos 1.500 a\u00f1os luz de distancia y tiene una masa casi 10 veces mayor que la de nuestro Sol.<\/p>\n<p>Los astr\u00f3nomos descubrieron el agujero negro mientras revisaban las observaciones tomadas por el telescopio espacial Gaia de la Agencia Espacial Europea para una pr\u00f3xima publicaci\u00f3n de datos a la comunidad cient\u00edfica. Los investigadores no esperaban encontrar nada, pero un movimiento peculiar, causado por la influencia gravitacional de Gaia BH3 sobre un compa\u00f1ero cercano, llam\u00f3 su atenci\u00f3n.<\/p>\n<p>La NASA lanzar\u00e1 un nuevo telescopio de rayos X dise\u00f1ado para resolver los misterios de los agujeros negros<\/p>\n<p>Muchos agujeros negros \u201cinactivos\u201d no tienen un compa\u00f1ero lo suficientemente cerca como para masticarlos, por lo que son mucho m\u00e1s dif\u00edciles de detectar y no generan luz. Pero otros agujeros negros estelares extraen material de estrellas compa\u00f1eras, y este intercambio de materia libera rayos X brillantes que pueden detectarse a trav\u00e9s de telescopios.<\/p>\n<p>El movimiento oscilante de una vieja estrella gigante en la constelaci\u00f3n de Aquila revel\u00f3 que estaba en una danza orbital con un agujero negro inactivo, y es el tercer agujero negro inactivo detectado por Gaia.<\/p>\n<p>Los investigadores utilizaron el Very Large Telescope del Observatorio Europeo Austral en el desierto de Atacama de Chile y otros observatorios terrestres para confirmar la masa de Gaia BH3, y su estudio tambi\u00e9n ha ofrecido nuevas pistas sobre c\u00f3mo surgieron estos enormes agujeros negros. Los hallazgos aparecieron este martes en la revista Astronomy &#038; Astrophysics.<\/p>\n<p>&#171;Nadie esperaba encontrar un agujero negro de gran masa acechando cerca, sin haber sido detectado hasta ahora&#187;, dijo el autor principal del estudio, Pasquale Panuzzo, astr\u00f3nomo del Observatorio de Par\u00eds, parte del Centro Nacional de Investigaci\u00f3n Cient\u00edfica de Francia, y miembro de la colaboraci\u00f3n de Gaia en un comunicado. &#171;\u00c9ste es el tipo de descubrimiento que se hace una vez en la vida&#187;.<\/p>\n<p>Los secretos de las estrellas antiguas<\/p>\n<p>El t\u00edtulo del agujero negro m\u00e1s masivo de nuestra galaxia siempre pertenecer\u00e1 a Sagitario A*, el agujero negro supermasivo situado en el centro de la V\u00eda L\u00e1ctea, que tiene unas 4 millones de veces la masa del Sol, pero eso se debe a que es un agujero negro supermasivo, en lugar de un agujero negro estelar.<\/p>\n<p>El proceso por el cual se forman los agujeros negros supermasivos no se comprende bien, pero una teor\u00eda sugiere que ocurre cuando colapsan nubes c\u00f3smicas masivas. Los agujeros negros estelares se forman cuando mueren estrellas masivas. Entonces Gaia BH3 es el agujero negro m\u00e1s masivo de nuestra galaxia que se form\u00f3 a partir de la muerte de una estrella masiva.<\/p>\n<p>Los agujeros negros estelares observados en la V\u00eda L\u00e1ctea tienen en promedio unas 10 veces la masa del Sol. Hasta el descubrimiento de Gaia BH3, el agujero negro estelar m\u00e1s grande conocido en nuestra galaxia era Cygnus X-1, que tiene 21 veces la masa del Sol. Si bien Gaia BH3 es un hallazgo excepcional dentro de nuestra galaxia seg\u00fan los est\u00e1ndares de los astr\u00f3nomos, es similar en masa a objetos encontrados en galaxias muy distantes.<\/p>\n<p>Tres agujeros negros estelares encontrados en nuestra galaxia, Gaia BH1, Cygnus X-1 y Gaia BH3, tienen masas 10, 21 y 33 veces la del Sol, respectivamente. (Cr\u00e9dito: M. Feria del Cereal\/ESO)<\/p>\n<p>Los cient\u00edficos creen que los agujeros negros estelares con masas como la de Gaia BH3 se formaron cuando colapsaron estrellas pobres en metales. Se cree que estas estrellas, que incluyen hidr\u00f3geno y helio como sus elementos m\u00e1s pesados, pierden menos masa a lo largo de su vida, por lo que al final tienen m\u00e1s material que puede resultar en un agujero negro de gran masa.<\/p>\n<p>Pero los astr\u00f3nomos no hab\u00edan podido encontrar evidencia que vinculara directamente los agujeros negros de gran masa y las estrellas pobres en metales hasta que encontraron Gaia BH3.<\/p>\n<p>Los autores del estudio dijeron que las estrellas emparejadas tienden a tener una composici\u00f3n similar. Fieles a las expectativas, los investigadores descubrieron que la estrella que orbitaba alrededor de Gaia BH3 era pobre en metales, lo que significa que la estrella que form\u00f3 Gaia BH3 probablemente era la misma.<\/p>\n<p>Los agujeros negros supermasivos pueden generar &#171;tsunamis&#187; durante escape de gas<\/p>\n<p>&#171;Lo que me sorprende es que la composici\u00f3n qu\u00edmica de la compa\u00f1era es similar a la que encontramos en las estrellas antiguas pobres en metales de la galaxia&#187;, dijo en un comunicado la coautora del estudio Elisabetta Caffau, miembro de la colaboraci\u00f3n Gaia en el Observatorio de Par\u00eds.<\/p>\n<p>La estrella que orbita Gaia BH3 probablemente se form\u00f3 en los primeros 2.000 millones de a\u00f1os despu\u00e9s de que el Big Bang creara el universo hace 13.800 millones de a\u00f1os. La trayectoria de la estrella, que se mueve en direcci\u00f3n opuesta a la de muchas estrellas del disco gal\u00e1ctico de la V\u00eda L\u00e1ctea, sugiere que era parte de una peque\u00f1a galaxia que se fusion\u00f3 con la V\u00eda L\u00e1ctea hace m\u00e1s de 8.000 millones de a\u00f1os.<\/p>\n<p>Ahora, el equipo espera que la investigaci\u00f3n pueda permitir a otros astr\u00f3nomos estudiar el colosal agujero negro y descubrir m\u00e1s secretos sin tener que esperar a que se publique el resto de los datos de Gaia, previstos para finales de 2025.<\/p>\n<p>&#171;Es impresionante ver el impacto transformador que Gaia est\u00e1 teniendo en la astronom\u00eda y la astrof\u00edsica&#187;, dijo Carole Mundell, directora de ciencia de la Agencia Espacial Europea, en un comunicado. &#171;Sus descubrimientos van mucho m\u00e1s all\u00e1 del prop\u00f3sito original de la misi\u00f3n, que es crear un mapa multidimensional extraordinariamente preciso de m\u00e1s de 1.000 millones de estrellas en toda nuestra V\u00eda L\u00e1ctea&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los astr\u00f3nomos descubrieron el agujero negro estelar m\u00e1s masivo conocido en la V\u00eda L\u00e1ctea despu\u00e9s de detectar una oscilaci\u00f3n inusual en el espacio. El llamado \u201cgigante durmiente\u201d, denominado Gaia BH3, tiene una masa casi 33 veces mayor que la de nuestro Sol y est\u00e1 ubicado a 1.926 a\u00f1os luz en la constelaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448179","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los astr\u00f3nomos detectan un enorme agujero negro &#039;gigante dormido&#039; a menos de 2.000 a\u00f1os luz de la Tierra - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los astr\u00f3nomos detectan un enorme agujero negro &#039;gigante dormido&#039; a menos de 2.000 a\u00f1os luz de la Tierra - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los astr\u00f3nomos descubrieron el agujero negro estelar m\u00e1s masivo conocido en la V\u00eda L\u00e1ctea despu\u00e9s de detectar una oscilaci\u00f3n inusual en el espacio. El llamado \u201cgigante durmiente\u201d, denominado Gaia BH3, tiene una masa casi 33 veces mayor que la de nuestro Sol y est\u00e1 ubicado a 1.926 a\u00f1os luz en la constelaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T08:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los astr\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\u00f1os luz de la Tierra\",\"datePublished\":\"2024-04-17T08:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/\"},\"wordCount\":1089,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/\",\"name\":\"Los astr\u00f3nomos detectan un enorme agujero negro 'gigante dormido' a menos de 2.000 a\u00f1os luz de la Tierra - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-17T08:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los astr\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\u00f1os luz de la Tierra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los astr\u00f3nomos detectan un enorme agujero negro 'gigante dormido' a menos de 2.000 a\u00f1os luz de la Tierra - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los astr\u00f3nomos detectan un enorme agujero negro 'gigante dormido' a menos de 2.000 a\u00f1os luz de la Tierra - Noticias","og_description":"(CNN) &#8212; Los astr\u00f3nomos descubrieron el agujero negro estelar m\u00e1s masivo conocido en la V\u00eda L\u00e1ctea despu\u00e9s de detectar una oscilaci\u00f3n inusual en el espacio. El llamado \u201cgigante durmiente\u201d, denominado Gaia BH3, tiene una masa casi 33 veces mayor que la de nuestro Sol y est\u00e1 ubicado a 1.926 a\u00f1os luz en la constelaci\u00f3n de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-17T08:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/"},"author":{"name":"","@id":""},"headline":"Los astr\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\u00f1os luz de la Tierra","datePublished":"2024-04-17T08:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/"},"wordCount":1089,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","name":"Los astr\u00f3nomos detectan un enorme agujero negro 'gigante dormido' a menos de 2.000 a\u00f1os luz de la Tierra - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-17T08:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los astr\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\u00f1os luz de la Tierra"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los astr\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\u00f1os luz de la Tierra","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/17\/astronomos-agujero-negro-gigante-dormido-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-17T08:03:43Z","datePublished":"2024-04-17T08:03:43Z","dateModified":"2024-04-17T08:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los astr\\u00f3nomos detectan un enorme agujero negro &#8216;gigante dormido&#8217; a menos de 2.000 a\\u00f1os luz de la Tierra\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/17\\\/astronomos-agujero-negro-gigante-dormido-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/17\\\/astronomos-agujero-negro-gigante-dormido-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-17T08:03:43Z\",\"datePublished\":\"2024-04-17T08:03:43Z\",\"dateModified\":\"2024-04-17T08:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449567,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/17\/estudio-agujeros-negros-region-de-caida-albert-einstein-trax\/","url_meta":{"origin":1448179,"position":0},"title":"Un estudio demuestra que los agujeros negros tienen una &#171;regi\u00f3n de ca\u00edda&#187;, tal como predijo Einstein","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN) -- Albert Einstein ten\u00eda raz\u00f3n: hay un \u00e1rea en el borde de los agujeros negros donde la materia ya no puede permanecer en \u00f3rbita y cae, como predijo su teor\u00eda de la gravedad.Utilizando telescopios capaces de detectar rayos X, un equipo de astr\u00f3nomos ha observado por primera vez esta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458944,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/19\/telescopio-webb-agujero-negro-via-lactea-trax\/","url_meta":{"origin":1448179,"position":1},"title":"El telescopio Webb observa el destello constante del agujero negro en la V\u00eda L\u00e1ctea","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Los astr\u00f3nomos que utilizan el telescopio espacial James Webb detectaron llamaradas din\u00e1micas de luz cerca del agujero negro supermasivo situado en el centro de la V\u00eda L\u00e1ctea. El despliegue constante y r\u00e1pido incluye destellos cortos de segundos de duraci\u00f3n y llamaradas de luz m\u00e1s largas y cegadoramente brillantes a diario.Las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472283,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/17\/fotos-telescopio-webb-puntos-rojos-trax\/","url_meta":{"origin":1448179,"position":2},"title":"Las fotos del telescopio Webb muestran misteriosos peque\u00f1os puntos rojos; los astr\u00f3nomos no saben qu\u00e9 son","author":"","date":"marzo 17, 2026","format":false,"excerpt":"Como diminutos intrusos en las fotos, anomal\u00edas c\u00f3smicas que se parecen a peque\u00f1os puntos rojos brillantes aparecen en casi cada instant\u00e1nea tomada por el telescopio espacial m\u00e1s potente jam\u00e1s construido. Los astr\u00f3nomos ahora los llaman peque\u00f1os puntos rojos, o LRD (little red dots, en ingl\u00e9s), pero todav\u00eda no hay consenso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453047,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/09\/25\/chorros-enormes-agujeros-negros-universo-lofar-porfirion-trax\/","url_meta":{"origin":1448179,"position":3},"title":"Descubren chorros enormes que salen de un agujero que equivalen a 140 galaxias como la V\u00eda L\u00e1ctea, seg\u00fan los cient\u00edficos","author":"","date":"septiembre 25, 2024","format":false,"excerpt":"(CNN) -- Los astr\u00f3nomos han observado un par de chorros enormes que salen de un agujero negro supermasivo a 7.500 millones de a\u00f1os luz de la Tierra. La megaestructura se extiende por 23 millones de a\u00f1os luz de longitud, lo que convierte a estos chorros de agujero negro en los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463119,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/06\/02\/colision-galaxias-via-lactea-andromeda-trax\/","url_meta":{"origin":1448179,"position":4},"title":"Una teor\u00eda popular sobre el destino de nuestra galaxia podr\u00eda ser err\u00f3nea, afirman  astr\u00f3nomos","author":"","date":"junio 2, 2025","format":false,"excerpt":"Desde 1912, los astr\u00f3nomos han anticipado una colisi\u00f3n entre nuestra galaxia, la V\u00eda L\u00e1ctea, y su vecina m\u00e1s grande, la galaxia de Andr\u00f3meda, prevista para dentro de unos 4.500 millones de a\u00f1os. Sin embargo, nuevas investigaciones sugieren que la probabilidad de este choque gal\u00e1ctico, conocido en ingl\u00e9s como \u201cMilkomeda\u201d, es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466369,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/11\/colision-agujeros-negros-predicciones-einstein-hawking-ligo-trax\/","url_meta":{"origin":1448179,"position":5},"title":"Colisi\u00f3n de agujeros negros confirma predicciones de Einstein y Hawking de hace d\u00e9cadas","author":"","date":"septiembre 11, 2025","format":false,"excerpt":"Astr\u00f3nomos han detectado una colisi\u00f3n entre dos agujeros negros con un detalle sin precedentes, ofreciendo la visi\u00f3n m\u00e1s clara hasta ahora sobre la naturaleza de estas rarezas c\u00f3smicas y confirmando predicciones de larga data hechas por los legendarios f\u00edsicos Albert Einstein y Stephen Hawking.El evento, denominado GW250114, se dio a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448179"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448179\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}