{"id":1448267,"date":"2024-04-19T07:03:41","date_gmt":"2024-04-19T14:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/"},"modified":"2024-04-19T07:03:41","modified_gmt":"2024-04-19T14:03:41","slug":"trader-joes-retira-albahaca-organica-salmonella-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/","title":{"rendered":"Trader Joe&#8217;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0 Trader Joe&#8217;s retir\u00f3 del mercado su albahaca org\u00e1nica Infinite Herbs el mi\u00e9rcoles, despu\u00e9s de que el producto fuera relacionado con una docena de infecciones por Salmonella en siete estados.<\/p>\n<p>El producto se vendi\u00f3 en paquetes de 70 gramos entre el 1 de febrero y el 6 de abril en 29 estados y en la ciudad de Washington, dijo la compa\u00f1\u00eda.<\/p>\n<p>Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC) emitieron una alerta advirtiendo a los consumidores que desechen cualquier albahaca org\u00e1nica de Infinite Herbs comprada en Trader Joe&#8217;s y que limpien las superficies y art\u00edculos que pudieran haber estado en contacto con la albahaca contaminada.<\/p>\n<p>\u00bfQu\u00e9 es la salmonela y c\u00f3mo prevenirla?<\/p>\n<p>Los CDC dijeron que recibieron 12 informes de infecciones por Salmonella en siete estados relacionados con el producto: una persona fue hospitalizada pero no se reportaron muertes. Los investigadores todav\u00eda est\u00e1n trabajando para identificar otros productos potencialmente contaminados. La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA), los CDC y las autoridades sanitarias locales y estatales est\u00e1n investigando el brote.<\/p>\n<p>La infecci\u00f3n por Salmonella se caracteriza por s\u00edntomas de diarrea, fiebre y calambres estomacales, seg\u00fan los CDC. Los s\u00edntomas se desarrollan de seis horas a seis d\u00edas despu\u00e9s de la ingesti\u00f3n de la bacteria y la mayor\u00eda de las personas se recuperan sin tratamiento entre los d\u00edas 4 a 7. Las personas con sistemas inmunol\u00f3gicos debilitados, los ni\u00f1os y los ancianos pueden experimentar enfermedades m\u00e1s graves que requieran tratamiento u hospitalizaci\u00f3n, dijeron los CDC.<\/p>\n<p>Los CDC recomiendan que las personas llamen a sus proveedores de atenci\u00f3n m\u00e9dica si tienen s\u00edntomas graves de Salmonella, como diarrea con sangre, diarrea que no mejora durante m\u00e1s de tres d\u00edas y signos de deshidrataci\u00f3n.<\/p>\n<p>Los consumidores pueden comunicarse directamente con Relaciones con el Cliente de Trader Joe al (626) 599-3817 e informar eventos adversos relacionados con el producto en el sitio MedWatch de la FDA.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0 Trader Joe&#8217;s retir\u00f3 del mercado su albahaca org\u00e1nica Infinite Herbs el mi\u00e9rcoles, despu\u00e9s de que el producto fuera relacionado con una docena de infecciones por Salmonella en siete estados. El producto se vendi\u00f3 en paquetes de 70 gramos entre el 1 de febrero y el 6 de abril en 29 estados y en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448267","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trader Joe&#039;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trader Joe&#039;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0 Trader Joe&#8217;s retir\u00f3 del mercado su albahaca org\u00e1nica Infinite Herbs el mi\u00e9rcoles, despu\u00e9s de que el producto fuera relacionado con una docena de infecciones por Salmonella en siete estados. El producto se vendi\u00f3 en paquetes de 70 gramos entre el 1 de febrero y el 6 de abril en 29 estados y en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-19T14:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trader Joe&#8217;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella\",\"datePublished\":\"2024-04-19T14:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/\",\"name\":\"Trader Joe's retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-19T14:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trader Joe&#8217;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trader Joe's retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trader Joe's retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella - Noticias","og_description":"(CNN) &#8212;\u00a0 Trader Joe&#8217;s retir\u00f3 del mercado su albahaca org\u00e1nica Infinite Herbs el mi\u00e9rcoles, despu\u00e9s de que el producto fuera relacionado con una docena de infecciones por Salmonella en siete estados. El producto se vendi\u00f3 en paquetes de 70 gramos entre el 1 de febrero y el 6 de abril en 29 estados y en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-19T14:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/"},"author":{"name":"","@id":""},"headline":"Trader Joe&#8217;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella","datePublished":"2024-04-19T14:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/","name":"Trader Joe's retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-19T14:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trader Joe&#8217;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trader Joe&#8217;s retira del mercado una albahaca org\u00e1nica vinculada a varias infecciones por Salmonella","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/19\/trader-joes-retira-albahaca-organica-salmonella-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-19T14:03:41Z","datePublished":"2024-04-19T14:03:41Z","dateModified":"2024-04-19T14:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trader Joe&#8217;s retira del mercado una albahaca org\\u00e1nica vinculada a varias infecciones por Salmonella\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/19\\\/trader-joes-retira-albahaca-organica-salmonella-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/19\\\/trader-joes-retira-albahaca-organica-salmonella-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-19T14:03:41Z\",\"datePublished\":\"2024-04-19T14:03:41Z\",\"dateModified\":\"2024-04-19T14:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1445345,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/02\/13\/retiran-del-mercado-quesos-yogures-y-productos-lacteos-esta-es-la-lista-completa-de-los-productos-relacionados-con-el-brote-de-listeria-en-ee-uu\/","url_meta":{"origin":1448267,"position":0},"title":"Retiran del mercado quesos, yogures y productos l\u00e1cteos: esta es la lista completa de los productos relacionados con el brote de listeria en EE.UU.","author":"","date":"febrero 13, 2024","format":false,"excerpt":"(CNN) -- Varios grandes minoristas, entre ellos Costco y Trader Joe's, retiraron productos l\u00e1cteos de Rizo-L\u00f3pez Foods Inc. debido a una posible contaminaci\u00f3n por listeria.Rizo-L\u00f3pez Foods Inc. retir\u00f3 inicialmente docenas de productos l\u00e1cteos la semana pasada despu\u00e9s de que una investigaci\u00f3n los identificara como la fuente de un brote de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458572,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/11\/costco-trader-joes-huevos-limite-compra-ee-uu-trax\/","url_meta":{"origin":1448267,"position":1},"title":"Costco y Trader Joe&#8217;s est\u00e1n limitando la cantidad de huevos que las personas pueden comprar en EE.UU.","author":"","date":"febrero 11, 2025","format":false,"excerpt":"Costco y Trader Joe\u2019s est\u00e1n limitando la cantidad de huevos que los clientes pueden comprar debido a la escasez causada por la gripe aviar.\u201cDebido a problemas actuales con el suministro de huevos, actualmente estamos limitando las compras de huevos a una docena por cliente, por d\u00eda, en todas las tiendas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458609,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/11\/retiran-mercado-atun-enlatado-trader-joes-costco-walmart-botulismo-trax\/","url_meta":{"origin":1448267,"position":2},"title":"Retiran del mercado at\u00fan enlatado que se vend\u00eda en Trader Joe\u2019s, Costco y Walmart debido a riesgo de botulismo","author":"","date":"febrero 11, 2025","format":false,"excerpt":"Tri-Union Seafoods retir\u00f3 del mercado ciertos productos de at\u00fan enlatado que se vend\u00edan en Costco, H-E-B, Kroger, Trader Joe\u2019s, Walmart y otras tiendas.Hubo un defecto en la fabricaci\u00f3n de la leng\u00fceta de apertura f\u00e1cil en las tapas del at\u00fan, comercializado como Genova, Van Camp\u2019s o varias marcas de tiendas. Sin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468280,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/11\/12\/brote-listeria-enfermos-muertos-eeuu-trax\/","url_meta":{"origin":1448267,"position":3},"title":"Qu\u00e9 se sabe del brote de listeria que ha dejado al menos 27 personas enfermas y 6 muertas en EE.UU.","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"Al menos seis personas han muerto debido a un brote multiestatal de listeria vinculado a comidas preparadas de pasta que ya fueron retiradas del mercado y se vend\u00edan en grandes cadenas de supermercados, incluyendo Albertsons, Kroger, Sprouts Farmers Market y Trader Joe\u2019s.La advertencia de los funcionarios federales de salud se\u00f1al\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452922,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/09\/21\/por-que-ahora-todo-es-mini-trax\/","url_meta":{"origin":1448267,"position":4},"title":"\u00bfPor qu\u00e9 ahora todo es &#171;mini&#187;?","author":"","date":"septiembre 21, 2024","format":false,"excerpt":"(CNN) -- No eres solo t\u00fa. Todo se est\u00e1 encogiendo.Esta semana, la cadena Trader Joe\u2019s reabasteci\u00f3 las bolsas de mano mini de US$ 2.99 que se revendieron por hasta US$ 500 en eBay a principios de este a\u00f1o. Las tiendas exhiben prominentemente productos de cuidado del cabello, de la piel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455889,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/11\/17\/brote-e-coli-zanahorias-organicas-1-muerto-decenas-enfermos-ee-uu-trax\/","url_meta":{"origin":1448267,"position":5},"title":"Brote de E. coli vinculado a zanahorias org\u00e1nicas deja 1 muerto y decenas de enfermos en EE.UU.","author":"","date":"noviembre 17, 2024","format":false,"excerpt":"(CNN) \u2014 Los Centros para el Control y la Prevenci\u00f3n de Enfermedades (CDC, por sus siglas en ingl\u00e9s) de Estados Unidos investigan un brote de E. coli en al menos 18 estados vinculado a algunas zanahorias org\u00e1nicas, lo que ha causado al menos una muerte.Al menos 39 casos de E.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448267"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448267\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}