{"id":1448328,"date":"2024-04-21T05:03:48","date_gmt":"2024-04-21T12:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/"},"modified":"2024-04-21T05:03:48","modified_gmt":"2024-04-21T12:03:48","slug":"campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/","title":{"rendered":"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n"},"content":{"rendered":"<p>(CNN) &#8212; El campe\u00f3n nigeriano de ajedrez y defensor de la educaci\u00f3n infantil Tunde Onakoya ha batido el r\u00e9cord del marat\u00f3n de ajedrez m\u00e1s largo despu\u00e9s de jugar durante extraordinarias 60 horas sin parar bajo las brillantes luces de Times Square en la ciudad de Nueva York.<\/p>\n<p>La organizaci\u00f3n Guinness World Record a\u00fan no ha confirmado el intento de Onakoya, que a veces puede tardar semanas, pero para muchos nigerianos, el joven de 29 a\u00f1os ya es considerado una especie de h\u00e9roe nacional.<\/p>\n<p>Onakoya est\u00e1 intentando recaudar 1 mill\u00f3n de d\u00f3lares para una organizaci\u00f3n ben\u00e9fica que apoya la educaci\u00f3n de los ni\u00f1os en toda \u00c1frica.<\/p>\n<p>Su objetivo era jugar durante 58 horas, pero continu\u00f3 hasta alcanzar la marca de 60 horas en las primeras horas de la ma\u00f1ana de este s\u00e1bado, superando el r\u00e9cord anterior de 56 horas, 9 minutos y 37 segundos establecido en 2018 por Hallvard Haug Flateb\u00f8 y Sjur Ferkingstad de Noruega. .<\/p>\n<p>Onakoya recurri\u00f3 a X , anteriormente conocido como Twitter, para anunciar su intenci\u00f3n de jugar por m\u00e1s tiempo y dijo: \u201cEstamos avanzando a 60 horas, muchachos. No paramos todav\u00eda. Avancemos. Tenemos un objetivo de recaudaci\u00f3n de fondos para la educaci\u00f3n de los ni\u00f1os africanos en todo el mundo. Este es nuestro por qu\u00e9: la raz\u00f3n por la que hacemos esto\u201d.<\/p>\n<p>Chess in Slums Africa, la organizaci\u00f3n ben\u00e9fica que Onakoya fund\u00f3 en 2018, tiene como objetivo ayudar a educar a 1 mill\u00f3n de ni\u00f1os en comunidades de barrios marginales en todo el continente.<\/p>\n<p>Onakoya jug\u00f3 contra Shawn Mart\u00ednez, un campe\u00f3n de ajedrez de Estados Unidos, de acuerdo con las pautas del R\u00e9cord Mundial Guinness de que cualquier intento de romper el r\u00e9cord debe ser realizado por dos jugadores que jueguen continuamente durante todo el tiempo.<\/p>\n<p>Impulsado por el arroz jollof nigeriano, la m\u00fasica afrobeats y los mensajes de apoyo de todo el mundo, Onakoya gan\u00f3 todos los partidos contra Mart\u00ednez. Entre los que salieron a animarlo en Manhattan se encontraban la superestrella nigeriana del afrobeat Davido y el cantante Adekunle Gold.<\/p>\n<p>El presidente de Nigeria, Bola Tinubu, estuvo entre los que felicitaron a Onakoya en l\u00ednea, elogi\u00e1ndolo por &#171;establecer un nuevo r\u00e9cord mundial de ajedrez y hacer sonar el gong de la resiliencia, la confianza en s\u00ed mismo y el ingenio de Nigeria en la plaza de la aclamaci\u00f3n mundial&#187;, en una declaraci\u00f3n compartida por su asistente Ajuri Ngelale.<\/p>\n<p>\u201cCelebro a este campe\u00f3n nigeriano de ajedrez y fundador de Chess in Slums Africa por su rara haza\u00f1a, pero especialmente por la raz\u00f3n que impulsa esta convincente demostraci\u00f3n de car\u00e1cter, que es recaudar fondos para que los ni\u00f1os africanos aprendan y encuentren oportunidades a trav\u00e9s del ajedrez\u201d, a\u00f1adi\u00f3 Tinubu.<\/p>\n<p>El partido atrajo mucha atenci\u00f3n en Nigeria y se transmiti\u00f3 en m\u00faltiples ubicaciones en Lagos, la ciudad m\u00e1s grande del pa\u00eds, con fiestas para verlos y vallas publicitarias digitales.<\/p>\n<p>Onakoya fund\u00f3 Chess in Slums Africa, que busca empoderar a los ni\u00f1os de comunidades desfavorecidas mediante el uso del ajedrez para mejorar el pensamiento cr\u00edtico y las habilidades de resoluci\u00f3n de problemas, en Lagos.<\/p>\n<p>La gente celebra cuando Tunde Onakoya cumple 46 horas consecutivas jugando una partida de ajedrez en Times Square, el viernes 19 de abril de 2024, en Nueva York. Yuki Iwamura\/AP<\/p>\n<p>En febrero de este a\u00f1o, el maestro de ajedrez cautiv\u00f3 a la comunidad mundial de ajedrez con su actuaci\u00f3n viral en la conferencia Digital\u2013Life \u2013 Design en Berl\u00edn. Despu\u00e9s de superar los desaf\u00edos de la visa, demostr\u00f3 sus habilidades jugando (y ganando) partidos simult\u00e1neos contra 10 jugadores, incluido el distinguido cient\u00edfico y pol\u00edtico b\u00falgaro Solomon Passy.<\/p>\n<p>Onakoya tambi\u00e9n forma parte del tablero de The Gift of Chess, fundado por el entrenador de ajedrez estadounidense Russell Makofsky, que espera distribuir un mill\u00f3n de juegos de ajedrez a comunidades de todo el mundo para 2030.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El campe\u00f3n nigeriano de ajedrez y defensor de la educaci\u00f3n infantil Tunde Onakoya ha batido el r\u00e9cord del marat\u00f3n de ajedrez m\u00e1s largo despu\u00e9s de jugar durante extraordinarias 60 horas sin parar bajo las brillantes luces de Times Square en la ciudad de Nueva York. La organizaci\u00f3n Guinness World Record a\u00fan no ha [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448328","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El campe\u00f3n nigeriano de ajedrez y defensor de la educaci\u00f3n infantil Tunde Onakoya ha batido el r\u00e9cord del marat\u00f3n de ajedrez m\u00e1s largo despu\u00e9s de jugar durante extraordinarias 60 horas sin parar bajo las brillantes luces de Times Square en la ciudad de Nueva York. La organizaci\u00f3n Guinness World Record a\u00fan no ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-21T12:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n\",\"datePublished\":\"2024-04-21T12:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/\"},\"wordCount\":716,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/\",\"name\":\"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-21T12:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n - Noticias","og_description":"(CNN) &#8212; El campe\u00f3n nigeriano de ajedrez y defensor de la educaci\u00f3n infantil Tunde Onakoya ha batido el r\u00e9cord del marat\u00f3n de ajedrez m\u00e1s largo despu\u00e9s de jugar durante extraordinarias 60 horas sin parar bajo las brillantes luces de Times Square en la ciudad de Nueva York. La organizaci\u00f3n Guinness World Record a\u00fan no ha [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-21T12:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/"},"author":{"name":"","@id":""},"headline":"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n","datePublished":"2024-04-21T12:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/"},"wordCount":716,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/","name":"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-21T12:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El campe\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\u00e9cord de marat\u00f3n","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/21\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-21T12:03:48Z","datePublished":"2024-04-21T12:03:48Z","dateModified":"2024-04-21T12:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El campe\\u00f3n nigeriano de ajedrez Tunde Onakoya juega durante 60 horas en Times Square y bate el r\\u00e9cord de marat\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/21\\\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/21\\\/campeon-nigeriano-de-ajedrez-tunde-onakoya-juega-durante-60-horas-en-times-square-y-bate-el-record-de-maraton-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-21T12:03:48Z\",\"datePublished\":\"2024-04-21T12:03:48Z\",\"dateModified\":\"2024-04-21T12:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455158,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/10\/16\/ajedrez-expulsan-competicion-maestro-kirill-shevchenko-presunto-uso-celular-trax\/","url_meta":{"origin":1448328,"position":0},"title":"Expulsan de una competici\u00f3n al gran maestro de ajedrez Kirill Shevchenko por presunto uso de un tel\u00e9fono m\u00f3vil durante las partidas","author":"","date":"octubre 16, 2024","format":false,"excerpt":"(CNN) \u2014 Un gran maestro de ajedrez rumano fue expulsado de una competici\u00f3n nacional tras ser acusado de utilizar un tel\u00e9fono m\u00f3vil durante las partidas, anunciaron el lunes los organizadores.Kirill Shevchenko, actualmente en el puesto 69 de la clasificaci\u00f3n mundial de ajedrez, compet\u00eda en el Campeonato de Espa\u00f1a por Equipos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465542,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/15\/ninia-10-anios-prodigio-ajedrez-vence-gran-maestro-trax\/","url_meta":{"origin":1448328,"position":1},"title":"Una prodigio del ajedrez de 10 a\u00f1os se convierte en la jugadora m\u00e1s joven en vencer a un gran maestro","author":"","date":"agosto 15, 2025","format":false,"excerpt":"Una ni\u00f1a brit\u00e1nica de 10 a\u00f1os ha hecho historia en el ajedrez al convertirse en la jugadora m\u00e1s joven en vencer a un gran maestro.Bodhana Sivanandan, del noroeste de Londres, derrot\u00f3 al gran maestro Pete Wells, de 60 a\u00f1os, en la ronda final del Campeonato Brit\u00e1nico de Ajedrez 2025 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456532,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/12\/gukesh-dommaraju-campeon-mundial-ajedrez-trax\/","url_meta":{"origin":1448328,"position":2},"title":"El indio Gukesh Dommaraju, de 18 a\u00f1os, se convierte en el campe\u00f3n mundial de ajedrez m\u00e1s joven de la historia","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"El adolescente Gukesh Dommaraju se convirti\u00f3 en el campe\u00f3n mundial m\u00e1s joven de ajedrez cl\u00e1sico de la historia tras vencer a Ding Liren por 7,5-6,5 en la final al mejor de 14 en Singapur este jueves.Gukesh, de 18 a\u00f1os y el campe\u00f3n defensor Ding llegaron al \u00faltimo juego empatados y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473521,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/26\/sebastian-sawa-record-maraton-londres-trax\/","url_meta":{"origin":1448328,"position":3},"title":"Sebastian Sawa, de Kenia, es el primer atleta en correr un marat\u00f3n en menos de dos horas","author":"","date":"abril 26, 2026","format":false,"excerpt":"El corredor keniano Sabastian Sawe hizo historia al convertirse en el primer atleta en correr un marat\u00f3n en menos de dos horas en una carrera competitiva para ganar el Marat\u00f3n de Londres.Sawe rompi\u00f3 el r\u00e9cord mundial al completar el Marat\u00f3n de Londres en 1:59:30.Su tiempo pulveriza el r\u00e9cord mundial anterior,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445315,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/02\/12\/kelvin-kiptum-plusmarquista-mundial-de-maraton-y-su-entrenador-mueren-en-un-accidente\/","url_meta":{"origin":1448328,"position":4},"title":"Kelvin Kiptum, plusmarquista mundial de marat\u00f3n, y su entrenador mueren en un accidente","author":"","date":"febrero 12, 2024","format":false,"excerpt":"(CNN) -- El actual plusmarquista mundial de marat\u00f3n, Kelvin Kiptum, y su entrenador, Gervais Hakizimana, murieron el domingo por la noche en un accidente de tr\u00e1fico a las afueras de la ciudad de Eldoret, en el valle del Rift, seg\u00fan confirm\u00f3 la polic\u00eda keniana.El atleta keniano de 24 a\u00f1os, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445328,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/02\/12\/kelvin-kiptum-plusmarquista-mundial-de-maraton-y-su-entrenador-mueren-en-un-accidente-2\/","url_meta":{"origin":1448328,"position":5},"title":"Kelvin Kiptum, plusmarquista mundial de marat\u00f3n, y su entrenador mueren en un accidente","author":"","date":"febrero 12, 2024","format":false,"excerpt":"(CNN) -- El actual plusmarquista mundial de marat\u00f3n, Kelvin Kiptum, y su entrenador, Gervais Hakizimana, murieron el domingo por la noche en un accidente de tr\u00e1fico a las afueras de la ciudad de Eldoret, en el valle del Rift, seg\u00fan confirm\u00f3 la polic\u00eda keniana.El atleta keniano de 24 a\u00f1os, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448328"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448328\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}