{"id":1448376,"date":"2024-04-22T14:03:46","date_gmt":"2024-04-22T21:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/"},"modified":"2024-04-22T14:03:46","modified_gmt":"2024-04-22T21:03:46","slug":"fosa-comun-hospital-nasser-khan-younis-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/","title":{"rendered":"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza"},"content":{"rendered":"<p>(CNN) &#8212; Una fosa com\u00fan con casi 300 cad\u00e1veres fue descubierta en un hospital de la ciudad de Khan Younis, en el sur de Gaza, dijeron el lunes trabajadores de la Defensa Civil de Gaza, tras la salida de las fuerzas israel\u00edes de la zona a principios de este mes.<\/p>\n<p>Yamen Abu Suleiman, director de Defensa Civil en Khan Younis, dijo a CNN el lunes que \u201choy se recuperaron 73 cad\u00e1veres\u201d en el patio del Complejo M\u00e9dico Nasser, lo que elev\u00f3 el \u201cn\u00famero total a 283\u201d.<\/p>\n<p>Suleiman indic\u00f3 que algunos de los cad\u00e1veres hab\u00edan sido encontrados con las manos y los pies atados, \u201cy hab\u00eda se\u00f1ales de ejecuciones en el campo. No sabemos si fueron enterrados vivos o si fueron ejecutados. La mayor\u00eda de los cuerpos est\u00e1n en descomposici\u00f3n\u201d.<\/p>\n<p>\u00daltima hora de Ir\u00e1n, la guerra de Israel con Hamas y la situaci\u00f3n en Gaza, en vivo: noticias, reacciones y m\u00e1s<\/p>\n<p>CNN no puede verificar las afirmaciones de Suleiman y no puede confirmar las causas de muerte entre los cuerpos hallados.<\/p>\n<p>CNN se comunic\u00f3 con las Fuerzas de Defensa de Israel (FDI) para solicitar comentarios luego del descubrimiento de la fosa com\u00fan, espec\u00edficamente sobre si los cuerpos encontrados en el hospital hab\u00edan sido desenterrados para pruebas de ADN y si hab\u00edan sido enterrados nuevamente. CNN envi\u00f3 varias preguntas a las FDI el domingo y lunes.<\/p>\n<p>Trabajadores de salud palestinos recuperan cuerpos enterrados en una fosa com\u00fan en el complejo del Hospital M\u00e9dico Nasser en Khan Younis, Gaza, el 21 de abril. Cr\u00e9dito: Ahmad Salem\/Bloomberg\/Getty Images<\/p>\n<p>Anteriormente, un portavoz de la Defensa Civil de Khan Younis y jefe de la misi\u00f3n de b\u00fasqueda, Raed Saqr, dijo a CNN que buscan los cuerpos de otras 400 personas desaparecidas despu\u00e9s de que el ej\u00e9rcito israel\u00ed se marchara de la zona el 7 de abril.<\/p>\n<p>Un corresponsal de CNN que visit\u00f3 el lugar el domingo dijo que la gente enterr\u00f3 los cuerpos de familiares que murieron en los terrenos del hospital en enero como medida temporal. Cuando regresaron despu\u00e9s de la retirada israel\u00ed, descubrieron que los cuerpos hab\u00edan sido exhumados, aparentemente porque las FDI utilizaban pruebas de ADN para determinar si alguno de los rehenes retenidos en Gaza se encontraba entre los muertos.<\/p>\n<p>Luego los cuerpos fueron colocados en al menos una fosa colectiva, dijo el periodista.<\/p>\n<p>Un hombre en el lugar le dijo a CNN que a\u00fan no hab\u00eda encontrado el cuerpo de su hijo de 21 a\u00f1os, que muri\u00f3 en enero.<\/p>\n<p>\u201cNo lo he encontrado todav\u00eda. Lo hab\u00edamos enterrado all\u00ed. Pero no podemos encontrarlo. Y queremos hacerle una tumba digna\u201d.<\/p>\n<p>Otro hombre, que dijo que su hermano Alaa tambi\u00e9n muri\u00f3 en enero, dijo: \u201cEstoy aqu\u00ed busc\u00e1ndolo. He venido al hospital durante las \u00faltimas dos semanas tratando de encontrarlo. Con suerte, podr\u00e9 encontrarlo\u201d.<\/p>\n<p>Se\u00f1alando una palmera ca\u00edda, el hombre dijo que su hermano fue enterrado temporalmente en ese lugar.<\/p>\n<p>\u201cLo hab\u00eda enterrado all\u00ed a un lado, pero no puedo encontrarlo. Los israel\u00edes desenterraron los cad\u00e1veres y los cambiaron. Hicieron pruebas de ADN y extraviaron todos los cad\u00e1veres\u201d.<\/p>\n<p>La madre del hombre dijo que han buscado durante dos semanas y no hab\u00edan podido encontrar su cuerpo.<\/p>\n<p>Otra mujer le dijo a CNN que pas\u00f3 10 d\u00edas buscando el cuerpo de su hija, que fue enterrada en los terrenos del hospital a fines de enero despu\u00e9s de que un edificio residencial cercano fuera atacado.<\/p>\n<p>Dijo que los israel\u00edes \u201cexcavaron los cad\u00e1veres y los cambiaron. Ella y la esposa de su t\u00edo fueron enterradas a la misma hora\u201d.<\/p>\n<p>\u201cHemos encontrado el cuerpo de la esposa de su t\u00edo. Pero el resto no podemos encontrarlos\u201d, agreg\u00f3 la madre.<\/p>\n<p>Saqr dijo a CNN el domingo que el personal de Defensa Civil ha buscado cad\u00e1veres en el complejo m\u00e9dico durante tres d\u00edas hasta el momento y que la operaci\u00f3n sigue en curso.<\/p>\n<p>&#171;Tenemos informaci\u00f3n de que hay 400 personas desaparecidas y seguimos buscando el resto de los cuerpos&#187;.<\/p>\n<p>Las FDI han dicho que sacaron docenas de cuerpos de Gaza para realizar pruebas de ADN en Israel, antes de devolver los restos en contenedores.<\/p>\n<p>La zona alrededor del Complejo M\u00e9dico Nasser fue testigo de intensos bombardeos y combates en enero y febrero. En ese momento, CNN inform\u00f3 sobre el entierro de cad\u00e1veres en los terrenos del hospital debido a la falta de acceso seguro a los cementerios.<\/p>\n<p>El periodista Tareq Al Hilou contribuy\u00f3 con este reportaje desde Gaza.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Una fosa com\u00fan con casi 300 cad\u00e1veres fue descubierta en un hospital de la ciudad de Khan Younis, en el sur de Gaza, dijeron el lunes trabajadores de la Defensa Civil de Gaza, tras la salida de las fuerzas israel\u00edes de la zona a principios de este mes. Yamen Abu Suleiman, director de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448376","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Una fosa com\u00fan con casi 300 cad\u00e1veres fue descubierta en un hospital de la ciudad de Khan Younis, en el sur de Gaza, dijeron el lunes trabajadores de la Defensa Civil de Gaza, tras la salida de las fuerzas israel\u00edes de la zona a principios de este mes. Yamen Abu Suleiman, director de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T21:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza\",\"datePublished\":\"2024-04-22T21:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/\"},\"wordCount\":813,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/\",\"name\":\"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-22T21:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza - Noticias","og_description":"(CNN) &#8212; Una fosa com\u00fan con casi 300 cad\u00e1veres fue descubierta en un hospital de la ciudad de Khan Younis, en el sur de Gaza, dijeron el lunes trabajadores de la Defensa Civil de Gaza, tras la salida de las fuerzas israel\u00edes de la zona a principios de este mes. Yamen Abu Suleiman, director de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-22T21:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza","datePublished":"2024-04-22T21:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/"},"wordCount":813,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/","name":"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-22T21:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Encuentran casi 300 cad\u00e1veres en una fosa com\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/22\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-22T21:03:46Z","datePublished":"2024-04-22T21:03:46Z","dateModified":"2024-04-22T21:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Encuentran casi 300 cad\\u00e1veres en una fosa com\\u00fan en un hospital de Khan Younis, dice la Defensa Civil de Gaza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/22\\\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/22\\\/fosa-comun-hospital-nasser-khan-younis-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-22T21:03:46Z\",\"datePublished\":\"2024-04-22T21:03:46Z\",\"dateModified\":\"2024-04-22T21:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448525,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/25\/casi-400-cadaveres-fosas-hospital-nasser-gaza-khan-younis-trax\/","url_meta":{"origin":1448376,"position":0},"title":"Casi 400 cad\u00e1veres fueron encontrados en la fosa com\u00fan de un hospital de Gaza, dice la Defensa Civil Palestina","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Las autoridades de Gaza concluyeron su b\u00fasqueda de fosas comunes en un hospital en el sur de Gaza y dijeron que descubrieron un total de 392 cad\u00e1veres, incluidos algunos que todav\u00eda llevaban batas quir\u00fargicas.En una conferencia de prensa el jueves, un funcionario de la Defensa Civil Palestina en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451499,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/07\/30\/destruccion-masiva-residentes-khan-younis-trax\/","url_meta":{"origin":1448376,"position":1},"title":"&#171;La destrucci\u00f3n es masiva&#187;: Los residentes de Khan Younis regresan a una zona en ruinas tras la retirada del ej\u00e9rcito israel\u00ed","author":"","date":"julio 30, 2024","format":false,"excerpt":"Khan Younis, Gaza (CNN) --\u00a0Los palestinos que huyeron de la ciudad de Khan Younis, en el sur de Gaza, hace poco m\u00e1s de una semana, comenzaron a regresar a sus hogares el martes para encontrar una gran destrucci\u00f3n, con muchas casas y edificios de varios pisos reducidos a ruinas, despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457085,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/30\/fosa-comun-cientos-cadaveres-aleppo-siria-trax\/","url_meta":{"origin":1448376,"position":2},"title":"Encuentran fosa com\u00fan con cientos de cad\u00e1veres en Aleppo, seg\u00fan autoridades","author":"","date":"diciembre 30, 2024","format":false,"excerpt":"Las autoridades de Siria descubrieron este lunes una supuesta fosa com\u00fan con cientos de cad\u00e1veres en Aleppo, seg\u00fan inform\u00f3 la agencia estatal de noticias siria SANA.\u201cUn residente de Aleppo inform\u00f3 al mando policial de la presencia de una fosa com\u00fan con cientos de cad\u00e1veres\u201d, dijo el Ministerio del Interior de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464313,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/08\/israel-gaza-muertos-evacuacion-khan-younis-trax\/","url_meta":{"origin":1448376,"position":3},"title":"Israel bombardea objetivos en Gaza: reportan m\u00e1s de 60 muertos y ordenan evacuaci\u00f3n de una amplia zona","author":"","date":"julio 8, 2025","format":false,"excerpt":"Israel atac\u00f3 este martes varias zonas de Gaza, y los servicios de emergencia y hospitales reportaron m\u00e1s de 60 muertos.Aproximadamente la mitad de los fallecidos viv\u00edan en tiendas de campa\u00f1a en el sur de Gaza, seg\u00fan el Complejo M\u00e9dico Nasser en Khan Younis, que inform\u00f3 haber recibido 45 cad\u00e1veres este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448399,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/5-cosas-23-abril-referendo-ecuador-orix\/","url_meta":{"origin":1448376,"position":4},"title":"Las 5 cosas que debes saber este 23 de abril: \u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo?","author":"","date":"abril 23, 2024","format":false,"excerpt":"Encuentran fosa com\u00fan en un hospital de Gaza. TikTok promete desafiar legalmente su posible prohibici\u00f3n en EE.UU. Momento \"m\u00e1gico\": surfista comparte ola con una manada de delfines. Esto es lo que debes saber para comenzar el d\u00eda.\u00a0Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo1. \u00bfQu\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448681,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/29\/ataque-aereo-israeli-rafah-22-muertos-hospital-trax\/","url_meta":{"origin":1448376,"position":5},"title":"&#171;Toda mi familia muri\u00f3&#187;: ataque a\u00e9reo israel\u00ed en Rafah mat\u00f3 a 22 personas, seg\u00fan el personal de un hospital","author":"","date":"abril 29, 2024","format":false,"excerpt":"Nota del editor: Advertencia: Esta historia tiene contenido expl\u00edcito.(CNN) -- Al menos 22 personas, entre ellas al menos un beb\u00e9 y un ni\u00f1o, murieron en un ataque a\u00e9reo israel\u00ed sobre Rafah, Gaza, durante la madrugada de este lunes, seg\u00fan fuentes de un hospital.Tras el ataque, los fallecidos fueron trasladados al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448376"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448376\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}