{"id":1448391,"date":"2024-04-23T00:03:59","date_gmt":"2024-04-23T07:03:59","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/"},"modified":"2024-04-23T00:03:59","modified_gmt":"2024-04-23T07:03:59","slug":"columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","title":{"rendered":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad"},"content":{"rendered":"<p>(CNN) &#8212; La Universidad de Columbia enfrenta un s\u00e9ptimo d\u00eda de tensas manifestaciones pro palestinas mientras las protestas de solidaridad se han extendido a otras universidades y han provocado arrestos en la Universidad de Nueva York y Yale. Cuando la semana de la Pascua comenz\u00f3 este lunes, las crecientes tensiones en el campus y las crecientes preocupaciones por la seguridad entre los estudiantes jud\u00edos han provocado la condena de donantes, l\u00edderes y legisladores, aumentando la presi\u00f3n sobre el presidente de la escuela para que disuelva las manifestaciones. Aqu\u00ed est\u00e1 lo \u00faltimo.<\/p>\n<p>\u2022 Columbia pasa a clases h\u00edbridas en medio de la agitaci\u00f3n: Como algunos estudiantes expresaron preocupaciones por la seguridad, Columbia dijo que casi todas las clases en su campus principal ser\u00e1n h\u00edbridas (si la tecnolog\u00eda lo permite) hasta el final del semestre. &#171;La seguridad es nuestra m\u00e1xima prioridad mientras nos esforzamos por apoyar el aprendizaje de nuestros estudiantes y todas las operaciones acad\u00e9micas requeridas&#187;, dijo la universidad en un anuncio el lunes por la noche.<\/p>\n<p>\u2022 Estudiantes y profesores de la Universidad de Nueva York arrestados mientras proliferan las protestas: estudiantes y profesores de la Universidad de Nueva York fueron arrestados durante protestas en el campus de la escuela este lunes por la noche, dijo la polic\u00eda. La protesta fue una de varias manifestaciones pro-palestinas que han surgido en los principales colegios y universidades estadounidenses en solidaridad con las protestas de Columbia, incluidas Yale, MIT, Harvard y la Universidad de Boston.<\/p>\n<p>\u2022 Estudiantes jud\u00edos en alerta m\u00e1xima: cuando la importante festividad jud\u00eda de Pesaj comenz\u00f3 el lunes, las organizaciones de estudiantes jud\u00edos de Columbia dijeron que han aumentado la seguridad alrededor de sus reuniones debido a preocupaciones de seguridad, incluida la presencia de una polic\u00eda en el centro cultural jud\u00edo del campus. Antes de que comenzara Pesaj, un rabino vinculado a la universidad inst\u00f3 a los estudiantes a regresar a sus hogares porque cree que las autoridades \u201cno pueden garantizar la seguridad de los estudiantes jud\u00edos\u201d.<\/p>\n<p>\u2022 El rector de la universidad acorralado por bandos enfrentados: el rector de la universidad, Minouche Shafik, enfrenta una inmensa presi\u00f3n por parte de exalumnos y legisladores para frenar las protestas, mientras que otros dicen que tal acci\u00f3n equivaldr\u00eda a sofocar la libertad de expresi\u00f3n. El Comit\u00e9 de Educaci\u00f3n de la C\u00e1mara de Representantes, liderado por los republicanos, pidi\u00f3 a Shafik este lunes que pidiera a la polic\u00eda que despejara el campamento y expulsara o despidiera a cualquier estudiante o profesorado que estuviera involucrado. Pero la presidenta ya enfrenta cr\u00edticas de algunos profesores por su decisi\u00f3n de llamar a la polic\u00eda de Nueva York para dispersar una protesta pro palestina la semana pasada.<\/p>\n<p>\u2022 La universidad puede estar violando la ley, dicen los legisladores: Varios legisladores, incluido un contingente de representantes jud\u00edos que visitaron el campus el lunes, argumentan que la falta de acci\u00f3n de la universidad contra los manifestantes puede estar violando el T\u00edtulo IX, una ley que protege a los estudiantes de la discriminaci\u00f3n y el acoso. en funci\u00f3n de su raza o nacionalidad. La representante republicana Virginia Foxx advirti\u00f3 a los l\u00edderes universitarios sobre las consecuencias si no controlan las protestas.<\/p>\n<p>Estudiantes arrestados en protestas en Yale y NYU<\/p>\n<p>A medida que las manifestaciones en Columbia se fueron extendiendo, surgieron protestas m\u00e1s peque\u00f1as \u2013algunas con sus propios campamentos\u2013 en varios colegios y universidades importantes, incluidas Yale y NYU, donde se realizaron arrestos este lunes.<\/p>\n<p>En el campus de Yale este lunes por la ma\u00f1ana, al menos 45 personas fueron arrestadas y acusadas de allanamiento de morada despu\u00e9s de negarse a abandonar una protesta en el campus, dijo la polic\u00eda de New Haven.<\/p>\n<p>Los manifestantes \u201cabogaban por la desinversi\u00f3n de Yale en los fabricantes de armas militares\u201d, dijo un portavoz de la universidad.<\/p>\n<p>&#171;Los estudiantes que fueron arrestados tambi\u00e9n ser\u00e1n remitidos a medidas disciplinarias de Yale, que incluyen una variedad de sanciones, como amonestaci\u00f3n, libertad condicional o suspensi\u00f3n&#187;, dijo la universidad.<\/p>\n<p>Este lunes por la noche, estudiantes y profesores de la Universidad de Nueva York fueron arrestados durante una manifestaci\u00f3n frente a su escuela de negocios cerca de Washington Square Park despu\u00e9s de que se \u201cinformaran c\u00e1nticos intimidantes y varios incidentes antisemitas\u201d, dijo un portavoz de la universidad.<\/p>\n<p>Una protesta inicial de unas 50 personas comenz\u00f3 frente al edificio este lunes por la ma\u00f1ana, dijo el portavoz de la Universidad de Nueva York, John Beckman, en un comunicado.<\/p>\n<p>\u201cLa Universidad cerr\u00f3 el acceso a la plaza, coloc\u00f3 barreras y dej\u00f3 en claro que no permitir\u00edamos que se unieran m\u00e1s manifestantes porque las protestas ya perturbaban considerablemente las clases y otras operaciones en las escuelas alrededor de la plaza\u201d.<\/p>\n<p>Otros manifestantes (muchos de los cuales la universidad cree que no estaban afiliados a la Universidad de Nueva York) atravesaron barreras y se unieron a la manifestaci\u00f3n el lunes por la tarde y la escuela fue testigo de \u201ccomportamiento desordenado, perturbador y antag\u00f3nico\u201d, dijo la escuela.<\/p>\n<p>En una carta a la Polic\u00eda de Nueva York, la Universidad de Nueva York dijo que los manifestantes rechazaron repetidas solicitudes para irse y la escuela solicit\u00f3 que la polic\u00eda desalojara a los manifestantes, a quienes la escuela consideraba intrusos, seg\u00fan una copia de la carta compartida por el subcomisionado de operaciones de la polic\u00eda, Kaz Daughtry.<\/p>\n<p>Un portavoz de la Polic\u00eda de Nueva York no confirm\u00f3 cu\u00e1ntas personas han sido arrestadas.<\/p>\n<p>Chris Boyette, Holly Yan, Caroll Alvarado,\u00a0Ramishah Maruf,\u00a0Chandelis Duster, Nic F. Anderson, Shimon Prokupecz, Matt Egan, Cindy Von Quednow y Robert Ilich de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La Universidad de Columbia enfrenta un s\u00e9ptimo d\u00eda de tensas manifestaciones pro palestinas mientras las protestas de solidaridad se han extendido a otras universidades y han provocado arrestos en la Universidad de Nueva York y Yale. Cuando la semana de la Pascua comenz\u00f3 este lunes, las crecientes tensiones en el campus y las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448391","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La Universidad de Columbia enfrenta un s\u00e9ptimo d\u00eda de tensas manifestaciones pro palestinas mientras las protestas de solidaridad se han extendido a otras universidades y han provocado arrestos en la Universidad de Nueva York y Yale. Cuando la semana de la Pascua comenz\u00f3 este lunes, las crecientes tensiones en el campus y las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T07:03:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad\",\"datePublished\":\"2024-04-23T07:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/\"},\"wordCount\":1005,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/\",\"name\":\"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-23T07:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad - Noticias","og_description":"(CNN) &#8212; La Universidad de Columbia enfrenta un s\u00e9ptimo d\u00eda de tensas manifestaciones pro palestinas mientras las protestas de solidaridad se han extendido a otras universidades y han provocado arrestos en la Universidad de Nueva York y Yale. Cuando la semana de la Pascua comenz\u00f3 este lunes, las crecientes tensiones en el campus y las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-23T07:03:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/"},"author":{"name":"","@id":""},"headline":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad","datePublished":"2024-04-23T07:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/"},"wordCount":1005,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","name":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-23T07:03:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-23T07:03:59Z","datePublished":"2024-04-23T07:03:59Z","dateModified":"2024-04-23T07:03:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Universidad de Columbia extiende las clases h\\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/23\\\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/23\\\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-23T07:03:59Z\",\"datePublished\":\"2024-04-23T07:03:59Z\",\"dateModified\":\"2024-04-23T07:03:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448457,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/24\/manifestantes-universidad-columbia-fecha-limite-desmantelar-campamento-trax\/","url_meta":{"origin":1448391,"position":0},"title":"Universidad de Columbia extiende negociaciones con estudiantes que protestan por el campamento despu\u00e9s del &#171;di\u00e1logo constructivo&#187; durante la noche","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN) --La Universidad de Columbia y los estudiantes que protestan continuar\u00e1n las negociaciones sobre el desmantelamiento del campamento propalestino durante las pr\u00f3ximas 48 horas, seg\u00fan un portavoz de la universidad.\"Estamos logrando avances importantes con los representantes del campamento de estudiantes en el c\u00e9sped oeste\", afirm\u00f3 un portavoz de la universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448388,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/22\/tensiones-protestas-propalestina-campus-universidades-columbia-nyu-trax\/","url_meta":{"origin":1448391,"position":1},"title":"Clases del campus principal de la Universidad de Columbia ser\u00e1n h\u00edbridas hasta fin de semestre; estudiantes y profesores de NYU fueron detenidos durante protestas","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia, epicentro de las protestas propalestinas en los campus universitarios estadounidenses en los \u00faltimos d\u00edas, inform\u00f3 que todas las clases en su campus principal ser\u00e1n h\u00edbridas \u2014si la tecnolog\u00eda lo permite\u2014 hasta que finalice el semestre de primavera.\"La seguridad es nuestra m\u00e1xima prioridad mientras nos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448359,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/21\/rabino-recomienda-judios-volver-casa-protestas-universidad-columbia-trax\/","url_meta":{"origin":1448391,"position":2},"title":"La Universidad de Columbia enfrenta una grave crisis mientras un rabino pide a los estudiantes jud\u00edos que \u201cregresen a casa\u201d","author":"","date":"abril 21, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia se enfrenta a una crisis en toda regla de cara a la Pascua, cuando un rabino vinculado a la escuela de la Ivy League inst\u00f3 a los estudiantes jud\u00edos a quedarse en casa y los tensos enfrentamientos en el campus generaron la condena de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448441,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/google-despidio-50-empleados-protestas-israel-trax\/","url_meta":{"origin":1448391,"position":3},"title":"Google despidi\u00f3 a 50 empleados tras las protestas por un acuerdo de servicios en la nube con Israel, seg\u00fan activistas","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN) -- Google despidi\u00f3 a otros 20 trabajadores que, seg\u00fan afirma, participaron en las protestas de la semana pasada por el contrato de servicios de computaci\u00f3n en nube de la empresa con el Gobierno de Israel, con lo que el n\u00famero total de trabajadores despedidos asciende a 50, seg\u00fan el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462697,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/22\/universidad-columbia-violacion-derechos-civiles-trax\/","url_meta":{"origin":1448391,"position":4},"title":"Gobierno de Trump denuncia a la Universidad de Columbia por no proteger a estudiantes jud\u00edos y violar derechos civiles","author":"","date":"mayo 22, 2025","format":false,"excerpt":"La administraci\u00f3n Trump aleg\u00f3 este jueves que la Universidad de Columbia viol\u00f3 la ley federal de derechos civiles al actuar con \u201cindiferencia deliberada\u201d ante el acoso a estudiantes jud\u00edos en el campus desde octubre de 2023.La Oficina de Derechos Civiles del Departamento de Salud y Servicios Humanos de EE.UU. acus\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448839,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","url_meta":{"origin":1448391,"position":5},"title":"Se realizan protestas universitarias propalestinas alrededor del mundo","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN) -- Las manifestaciones en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza se han extendido por los campus universitarios de Estados Unidos y alrededor del mundo en las \u00faltimas semanas.M\u00e1s de 2.000 personas han sido detenidas en campus estadounidenses desde el 18 de abril, en medio de polarizados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448391"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448391\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}