{"id":1448432,"date":"2024-04-23T13:03:41","date_gmt":"2024-04-23T20:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/"},"modified":"2024-04-23T13:03:41","modified_gmt":"2024-04-23T20:03:41","slug":"empresa-mineria-asteroides-minerales-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/","title":{"rendered":"Esta empresa quiere hacer realidad la miner\u00eda de asteroides"},"content":{"rendered":"<p>(CNN) &#8212; Cuando la empresa de scooters el\u00e9ctricos para la que trabajaba Matt Gialich tuvo que interrumpir la producci\u00f3n por escasez de platino, un componente clave del microprocesador que traduce las \u00f3rdenes de los mandos al motor, se lanz\u00f3 a la b\u00fasqueda de metales.<\/p>\n<p>Gialich, cuyo amor por el espacio le llev\u00f3 de ni\u00f1o a la ingenier\u00eda y a trabajar en la empresa de lanzamiento de sat\u00e9lites Virgin Orbit antes de su quiebra, empez\u00f3 a preguntarse c\u00f3mo extraer el metal de los asteroides. Los cient\u00edficos creen que estos trozos de desechos celestes, que son subproductos del nacimiento del sistema solar hace 4.500 millones de a\u00f1os, son ricos en metales que escasean en la Tierra.<\/p>\n<p>En 2022, Gialich y Jos\u00e9 Acain, que cuenta con casi una d\u00e9cada de experiencia en SpaceX y la NASA, fundaron AstroForge. Ahora, la startup con sede en California intenta hacer realidad la miner\u00eda de asteroides.<\/p>\n<p>La empresa no est\u00e1 sola. Se espera que la transici\u00f3n hacia una energ\u00eda limpia dispare la demanda de recursos minerales, y el inter\u00e9s por extraerlos de fuentes hasta ahora inexplotadas, como el fondo oce\u00e1nico y el espacio, es cada vez mayor. Empresas de todo el mundo han recaudado decenas de millones de d\u00f3lares para probar tecnolog\u00edas de extracci\u00f3n de asteroides.<\/p>\n<p>Algunos dicen que la idea es una fantas\u00eda descabellada y prohibitivamente cara. Pero Gialich, de 38 a\u00f1os, cree que pronto podr\u00eda ponerse en pr\u00e1ctica. &#171;Salir a buscar recursos al espacio es el Santo Grial&#187;, afirma. &#171;Creo que por fin estamos en este punto de inflexi\u00f3n en el que podemos asumirlo&#187;.<\/p>\n<p>\u00bfProyecto inalcanzable?<\/p>\n<p>Gialich no tiene problemas en admitir que los planes de su empresa son ambiciosos. &#171;Vamos a tener muchos fracasos&#187;, dice.<\/p>\n<p>En resumen, AstroForge pretende enviar al espacio una peque\u00f1a refiner\u00eda capaz de extraer minerales de un asteroide y traer a la Tierra los metales valiosos, dejando el resto. La empresa busca metales del grupo del platino (MGP) en asteroides de tipo M o met\u00e1licos, que se utilizan en todo tipo de productos, desde joyas hasta catalizadores que filtran los gases de escape de los autom\u00f3viles o f\u00e1rmacos contra el c\u00e1ncer.<\/p>\n<p>Los MGP, como el platino y el iridio, tambi\u00e9n son materias primas fundamentales para las tecnolog\u00edas emergentes de energ\u00edas limpias. Por ejemplo, se espera que la producci\u00f3n de hidr\u00f3geno verde impulse un importante crecimiento de la demanda de estos minerales. Pero las reservas terrestres son limitadas y est\u00e1n concentradas geogr\u00e1ficamente.<\/p>\n<p>Los cofundadores de AstroForge Jose Acain (izquierda) y Matt Gialich (derecha). Cr\u00e9dito: Eduardo Carre\u00f3n<\/p>\n<p>Aunque parece una trama sacada directamente de la \u00faltima temporada de la serie de Apple TV+ &#171;For All Mankind&#187;, que implicaba un elaborado plan para aprovechar un asteroide y traerlo a la \u00f3rbita de la Tierra para su explotaci\u00f3n minera, Gialich dice que &#171;eso no es lo que estamos haciendo en absoluto&#187;.<\/p>\n<p>El pasado mes de abril, AstroForge lanz\u00f3 su misi\u00f3n inaugural, denominada Brokkr-1, enviando al espacio un sat\u00e9lite en miniatura equipado con un sistema de refiner\u00eda del tama\u00f1o de dos barras de pan. La nave llevaba material precargado similar a un asteroide que planeaba vaporizar y separar en componentes elementales mientras estuviera en \u00f3rbita.<\/p>\n<p>No todo sali\u00f3 seg\u00fan lo previsto, y la demostraci\u00f3n de la refiner\u00eda a\u00fan no ha ocurrido. Pero Gialich afirma que la empresa ha aprendido muchas cosas, por ejemplo, c\u00f3mo funcionar\u00eda el equipo suministrado por los proveedores y si la m\u00e1quina podr\u00eda sobrevivir al despegue y enviar se\u00f1ales desde el espacio.<\/p>\n<p>La refiner\u00eda, patentada por AstroForge, ya se ha probado en condiciones similares a las del espacio. Esto convierte a AstroForge en la \u00fanica empresa con una refiner\u00eda capaz de convertir asteroides de tipo M en MGP en el espacio, a\u00f1ade.<\/p>\n<p>Este a\u00f1o, una nave espacial de AstroForge viajar\u00e1 a la Luna en una misi\u00f3n de la empresa estadounidense de exploraci\u00f3n espacial Intuitive Machines. Pero ya all\u00ed, AstroForge utilizar\u00e1 su propio sistema de propulsi\u00f3n para volar junto a un asteroide que considere met\u00e1lico, comprobar\u00e1 su composici\u00f3n y tomar\u00e1 fotograf\u00edas. (Gialich declin\u00f3 especificar a cu\u00e1l asteroide apunta). Si esta misi\u00f3n tiene \u00e9xito, AstroForge se convertir\u00e1 en la primera empresa comercial en aventurarse en el espacio profundo. Tambi\u00e9n podr\u00eda proporcionar las primeras im\u00e1genes de alta resoluci\u00f3n de un asteroide met\u00e1lico.<\/p>\n<p>Alto riesgo, alta recompensa<\/p>\n<p>El inter\u00e9s por los asteroides, tanto para comprender mejor los or\u00edgenes de la Tierra como su composici\u00f3n, que podr\u00eda sentar las bases para su explotaci\u00f3n minera, se est\u00e1 disparando, y los expertos afirman que la explotaci\u00f3n minera de asteroides puede ser solo cuesti\u00f3n de tiempo.<\/p>\n<p>Dan Britt, director del Centro de Ciencias de la Superficie Lunar y de Asteroides de la Universidad de Florida Central, que no participa directamente en AstroForge, reflexiona: &#171;Supongo que cabe preguntarse si [los humanos] est\u00e1n totalmente locos por hacer esto. La respuesta es que quiz\u00e1 sea un poco pronto, pero no estamos totalmente locos&#187;.<\/p>\n<p>La agencia espacial japonesa JAXA y la NASA ya han tra\u00eddo a la Tierra muestras de asteroides, lo que demuestra, al menos hasta cierto punto, que es posible.<\/p>\n<p>China tiene previsto lanzar una misi\u00f3n en 2025 para recoger muestras de un asteroide cercano a la Tierra, mientras que la Agencia Espacial de Emiratos \u00c1rabes Unidos planea explorar el cintur\u00f3n de asteroides con una misi\u00f3n cuyo lanzamiento est\u00e1 previsto para 2028.<\/p>\n<p>Los Emiratos \u00c1rabes Unidos planean una misi\u00f3n para explorar el cintur\u00f3n de asteroides. Esta infograf\u00eda facilitada por la Agencia Espacial de los EAU muestra el Explorador MBR, cuyo lanzamiento est\u00e1 previsto para 2028 con el fin de estudiar varios asteroides.\u00a0 Cr\u00e9dito: Agencia Espacial de los EAU\/AP<\/p>\n<p>La NASA tiene una nave espacial en ruta hacia el asteroide Psyche, que orbita alrededor del Sol entre Marte y J\u00fapiter, pero no llegar\u00e1 hasta 2029. Seg\u00fan algunas estimaciones, el hierro del asteroide de 225 kil\u00f3metros de ancho, rico en metales, tiene un valor de US$ 10.000 trillones, m\u00e1s que el valor de toda la econom\u00eda mundial. (Gialich afirma que los cient\u00edficos de la NASA han sido excelentes aliados, aportando una experiencia inestimable a AstroForge).<\/p>\n<p>La NASA enviar\u00e1 una misi\u00f3n al asteroide Psyche, un mundo de metal. \u00bfCu\u00e1les son las razones?<\/p>\n<p>Algunos miembros de la comunidad cient\u00edfica se muestran esc\u00e9pticos ante la posibilidad de que el sector privado pueda permitirse la extracci\u00f3n de asteroides. La misi\u00f3n Osiris-Rex de la NASA, la primera misi\u00f3n estadounidense que recogi\u00f3 una muestra de asteroide y la trajo de vuelta a la Tierra, cost\u00f3 cientos de millones de d\u00f3lares, sin contar el costo de lanzamiento. Su devoluci\u00f3n, de tan solo 122 gramos, que aterriz\u00f3 en un desierto de Utah el a\u00f1o pasado, es la mayor muestra de asteroide jam\u00e1s recogida.<\/p>\n<p>&#171;En realidad, no se trata de si se puede hacer desde el punto de vista de la f\u00edsica&#187;, dice Gialich. &#171;Es una cuesti\u00f3n de si se puede hacer para que tenga alg\u00fan sentido monetario&#187;.<\/p>\n<p>Otros lo han intentado y han fracasado. Planetary Resources, por ejemplo, se lanz\u00f3 en 2012 con el respaldo de inversores de alto perfil, entre ellos el director de &#171;Titanic&#187; James Cameron y el cofundador de Google Larry Page. En 2020, organiz\u00f3 una subasta en l\u00ednea despu\u00e9s de enfrentarse a dificultades de financiaci\u00f3n y ser adquirida por una empresa de blockchain. (Los compradores en la subasta de Internet se anotaron art\u00edculos como una ba\u00f1era de pl\u00e1stico llena de cables el\u00e9ctricos variados y enredados por US$ 10 y un par de guantes aislantes bien usados por US$ 20).<\/p>\n<p>La NASA renombra la misi\u00f3n Osiris-Rex y la env\u00eda a estudiar un nuevo asteroide<\/p>\n<p>Tambi\u00e9n han cambiado muchas cosas. Empresas privadas como SpaceX han reducido dr\u00e1sticamente el costo de los viajes espaciales. Gialich dice que hoy se sabe m\u00e1s sobre los 1,3 millones de asteroides del sistema solar, por lo que empresas como la suya no tienen que malgastar recursos busc\u00e1ndolos, y que AstroForge ha invertido en desarrollar algoritmos que le permitan compartir viajes y llegar a donde quiere.<\/p>\n<p>&#171;El abaratamiento de los costos de transporte es clave para desarrollar una econom\u00eda extraterrestre&#187;, afirma Britt, que ha contribuido a cuatro misiones de la NASA, entre ellas un sobrevuelo de un asteroide del Cintur\u00f3n de Kuiper, un anillo de escombros con forma de dona situado en los confines del sistema solar, y una serie de viajes a asteroides cercanos a J\u00fapiter, y tiene un asteroide que lleva su nombre por sus contribuciones a la investigaci\u00f3n de asteroides.<\/p>\n<p>Los cambios han suscitado una oleada de nuevo inter\u00e9s. Otras empresas, como TransAstra, con sede en Los \u00c1ngeles, y Origin Space, con sede en China, trabajan en tecnolog\u00edas capaces de extraer recursos del espacio.<\/p>\n<p>La refiner\u00eda de AstroForge funcionando en un vac\u00edo espacial simulado. Cr\u00e9dito: Eduardo Carre\u00f3n<\/p>\n<p>Hasta ahora, AstroForge ha recaudado US$ 13 millones en financiaci\u00f3n inicial. Dice que su segunda misi\u00f3n costar\u00e1 menos de US$ 10 millones, lo que significa que la empresa pondr\u00e1 la mayor parte de sus huevos en la misma cesta. &#171;Se trata de empresas de alto riesgo y grandes recompensas&#187;, afirma Gialich.<\/p>\n<p>A\u00fan no tiene un plan B si las misiones previstas no tienen \u00e9xito. &#171;\u00bfA qui\u00e9n le importa? Sales e intentas estas grandes misiones, estas grandes apuestas, y si no funciona, no s\u00e9. Supongo que me buscar\u00e9 un trabajo en alg\u00fan sitio&#187;, dice. &#171;Solo estoy centrado en el plan A y en intentar que funcione&#187;.<\/p>\n<p>Suministros desde el cielo<\/p>\n<p>Si todo va bien, el objetivo final de la empresa es traer de vuelta unos 1.000 kilogramos de MGP por misi\u00f3n, una carga \u00fatil que podr\u00eda valer unos US$ 70 millones, dependiendo de los metales y de su precio en ese momento.<\/p>\n<p>&#171;Incluso con m\u00faltiples contratiempos en nuestro calendario, estamos intentando extraer un asteroide y lo habremos tra\u00eddo de vuelta antes del final de esta d\u00e9cada&#187;, afirma Gialich.<\/p>\n<p>Dado que la empresa se centra en asteroides relativamente peque\u00f1os, afirma que habr\u00e1 menos gravedad que superar y, por tanto, menos combustible que quemar.<\/p>\n<p>Su planteamiento de &#171;todo o nada&#187; y menor costo puede ayudar a acercar la miner\u00eda de asteroides a la realidad.<\/p>\n<p>Un cohete de SpaceX lanz\u00f3 la nave espacial Pysche desde el Centro Espacial Kennedy de la NASA en Florida el 13 de octubre de 2023. Se espera que la nave llegue al asteroide en 2029. Cr\u00e9dito: Aubrey Gemignani\/NASA\/Getty Images<\/p>\n<p>&#171;Aunque no tengamos \u00e9xito y fracasemos como empresa, espero que impulsemos esto un poco&#187;, dice, y demostremos que &#171;se puede hacer mucha m\u00e1s ciencia con mucho menos capital&#187;.<\/p>\n<p>Britt afirma que es probable que la miner\u00eda de asteroides &#171;acabe ocurriendo&#187; y que la tecnolog\u00eda en el mercado ya es mucho m\u00e1s avanzada que &#171;una servilleta de bar repleta de un mont\u00f3n de ecuaciones y diagramas&#187;.<\/p>\n<p>Pero espera que las tecnolog\u00edas tengan que avanzar a\u00fan m\u00e1s antes de que los inversores est\u00e9n dispuestos a invertir grandes cantidades de capital en ellas.<\/p>\n<p>&#171;Esa es una de las cosas que est\u00e1n haciendo las empresas emergentes como AstroForge: crear esa nueva tecnolog\u00eda e ingenier\u00eda&#187;, afirma Britt.<\/p>\n<p>Es posible que pasen a\u00f1os antes de que sepamos si los intentos de AstroForge tendr\u00e1n un impacto duradero en el impulso general para extraer minerales del espacio. Pero es probable que se recuerde su enfoque &#171;todo o nada&#187;.<\/p>\n<p>&#171;Espero que, aunque solo sea eso&#187;, dice Gialich, &#171;se nos conozca como una empresa espacial que fue a por todas&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Cuando la empresa de scooters el\u00e9ctricos para la que trabajaba Matt Gialich tuvo que interrumpir la producci\u00f3n por escasez de platino, un componente clave del microprocesador que traduce las \u00f3rdenes de los mandos al motor, se lanz\u00f3 a la b\u00fasqueda de metales. Gialich, cuyo amor por el espacio le llev\u00f3 de ni\u00f1o a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448432","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esta empresa quiere hacer realidad la miner\u00eda de asteroides - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta empresa quiere hacer realidad la miner\u00eda de asteroides - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Cuando la empresa de scooters el\u00e9ctricos para la que trabajaba Matt Gialich tuvo que interrumpir la producci\u00f3n por escasez de platino, un componente clave del microprocesador que traduce las \u00f3rdenes de los mandos al motor, se lanz\u00f3 a la b\u00fasqueda de metales. Gialich, cuyo amor por el espacio le llev\u00f3 de ni\u00f1o a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T20:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esta empresa quiere hacer realidad la miner\u00eda de asteroides\",\"datePublished\":\"2024-04-23T20:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/\"},\"wordCount\":2016,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/\",\"name\":\"Esta empresa quiere hacer realidad la miner\u00eda de asteroides - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-23T20:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta empresa quiere hacer realidad la miner\u00eda de asteroides\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta empresa quiere hacer realidad la miner\u00eda de asteroides - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Esta empresa quiere hacer realidad la miner\u00eda de asteroides - Noticias","og_description":"(CNN) &#8212; Cuando la empresa de scooters el\u00e9ctricos para la que trabajaba Matt Gialich tuvo que interrumpir la producci\u00f3n por escasez de platino, un componente clave del microprocesador que traduce las \u00f3rdenes de los mandos al motor, se lanz\u00f3 a la b\u00fasqueda de metales. Gialich, cuyo amor por el espacio le llev\u00f3 de ni\u00f1o a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-23T20:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/"},"author":{"name":"","@id":""},"headline":"Esta empresa quiere hacer realidad la miner\u00eda de asteroides","datePublished":"2024-04-23T20:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/"},"wordCount":2016,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/","name":"Esta empresa quiere hacer realidad la miner\u00eda de asteroides - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-23T20:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esta empresa quiere hacer realidad la miner\u00eda de asteroides"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esta empresa quiere hacer realidad la miner\u00eda de asteroides","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/empresa-mineria-asteroides-minerales-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-23T20:03:41Z","datePublished":"2024-04-23T20:03:41Z","dateModified":"2024-04-23T20:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esta empresa quiere hacer realidad la miner\\u00eda de asteroides\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/23\\\/empresa-mineria-asteroides-minerales-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/23\\\/empresa-mineria-asteroides-minerales-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-23T20:03:41Z\",\"datePublished\":\"2024-04-23T20:03:41Z\",\"dateModified\":\"2024-04-23T20:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459198,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/25\/astroforge-primera-mision-espacio-profundo-trax\/","url_meta":{"origin":1448432,"position":0},"title":"Esta empresa podr\u00eda hacer historia con su primera misi\u00f3n al espacio profundo. El CEO est\u00e1 &#171;aterrorizado&#187;","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Su empresa puede parecer arriesgada, pero el CEO de Astroforge, Matt Gialich, no se hace ilusiones. Este ingeniero cofund\u00f3 la audaz empresa californiana AstroForge en 2022 con el objetivo de buscar metales preciosos en el espacio, y es muy consciente de que el \u00e9xito no est\u00e1 garantizado.Y, francamente, tiene miedo.\u201cEstoy\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458432,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/07\/astronomos-coche-musk-asteroide-trax\/","url_meta":{"origin":1448432,"position":1},"title":"Los astr\u00f3nomos llegaron a pensar que el auto de Musk era un asteroide. Esto podr\u00eda ser un problema m\u00e1s amplio","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Siete a\u00f1os despu\u00e9s de que SpaceX puso en \u00f3rbita alrededor del Sol al deportivo rojo cereza de Elon Musk, los astr\u00f3nomos, sin saberlo, volvieron a prestar atenci\u00f3n a sus movimientos.Los investigadores vieron e identificaron correctamente el veh\u00edculo cuando inici\u00f3 su excursi\u00f3n extraterrestre en febrero de 2018, despu\u00e9s de haber despegado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450419,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/06\/16\/telescopio-webb-colision-asteroides-gigantes-trax\/","url_meta":{"origin":1448432,"position":2},"title":"Observaciones del telescopio Webb insin\u00faan una colisi\u00f3n de asteroides gigantes en un sistema planetario cercano","author":"","date":"junio 16, 2024","format":false,"excerpt":"(CNN) -- Es probable que en los \u00faltimos a\u00f1os se haya producido una colisi\u00f3n entre asteroides gigantes en un sistema estelar vecino llamado Beta Pictoris. Dos observatorios espaciales diferentes ayudan a contar la historia.El sistema Beta Pictoris, ubicado a 63 a\u00f1os luz de la Tierra, intrig\u00f3 durante mucho tiempo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458781,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/15\/asteroide-impactar-tierra-2032-rastreando-trax\/","url_meta":{"origin":1448432,"position":3},"title":"Un asteroide tiene un 2% de probabilidad de impactar la Tierra en 2032. As\u00ed es como los astr\u00f3nomos lo est\u00e1n rastreando","author":"","date":"febrero 15, 2025","format":false,"excerpt":"Un asteroide descubierto recientemente, llamado 2024 YR4, tiene en promedio un 2% de probabilidad de impactar la Tierra en 2032. Aunque esas probabilidades de un impacto son bajas, los astr\u00f3nomos est\u00e1n siguiendo de cerca la roca espacial para descubrir m\u00e1s detalles, un proceso que pronto podr\u00eda involucrar el observatorio m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464868,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/26\/asteroide-2024-yr4-luna-posible-impacto-trax\/","url_meta":{"origin":1448432,"position":4},"title":"El asteroide que iba a impactar en la Tierra podr\u00eda ahora caer en la Luna. \u00bfQu\u00e9 pasar\u00e1 si eso sucede?","author":"","date":"julio 26, 2025","format":false,"excerpt":"Desde la Tierra ya no se puede ver el asteroide conocido como 2024 YR4, pero todav\u00eda est\u00e1 muy presente en la mente de los cient\u00edficos.El objeto del tama\u00f1o de un edificio, que inicialmente parec\u00eda estar en un curso de una posible colisi\u00f3n con la Tierra, actualmente se est\u00e1 acercando, m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472031,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/09\/nasa-impacto-nave-espacial-desvio-asteroides-orbita-trax\/","url_meta":{"origin":1448432,"position":5},"title":"Nuevas im\u00e1genes muestran las secuelas del choque de una nave de la NASA contra un asteroide","author":"","date":"marzo 9, 2026","format":false,"excerpt":"En 2022, una nave espacial de la NASA se estrell\u00f3 intencionalmente contra el peque\u00f1o asteroide Dimorphos durante una prueba de defensa planetaria. El objetivo era evaluar si la humanidad pod\u00eda proteger a la Tierra de amenazas c\u00f3smicas, como las rocas espaciales. Nuevas observaciones ahora revelan que la prueba de defensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448432"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448432\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}