{"id":1448538,"date":"2024-04-26T03:03:51","date_gmt":"2024-04-26T10:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/"},"modified":"2024-04-26T03:03:51","modified_gmt":"2024-04-26T10:03:51","slug":"boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/","title":{"rendered":"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial"},"content":{"rendered":"<p>(CNN) &#8212; Tras a\u00f1os de retrasos y una vertiginosa serie de contratiempos durante los vuelos de prueba, la nave espacial Starliner de Boeing est\u00e1 finalmente lista para realizar su lanzamiento inaugural con tripulaci\u00f3n.<\/p>\n<p>La misi\u00f3n est\u00e1 en camino de despegar de Florida tan pronto como el 6 de mayo, llevando a los astronautas de la NASA Suni Williams y Butch Wilmore a la Estaci\u00f3n Espacial Internacional, marcando lo que podr\u00eda ser una victoria hist\u00f3rica y largamente esperada para el asediado programa Starliner.<\/p>\n<p>&#171;El dise\u00f1o y el desarrollo son dif\u00edciles, sobre todo cuando se trata de un veh\u00edculo espacial humano&#187;, dijo este jueves Mark Nappi, vicepresidente y director del programa Starliner de Boeing. &#171;Hay una serie de cosas que fueron sorpresas en el camino que tuvimos que superar. &#8230; El equipo se ha hecho muy, muy fuerte. Estoy muy orgulloso de c\u00f3mo han superado cada uno de los problemas que hemos encontrado y nos han llevado hasta este punto&#187;.<\/p>\n<p>Los responsables de Boeing y de la NASA tomaron este jueves la decisi\u00f3n de seguir adelante con el intento de lanzamiento en menos de dos semanas. Sin embargo, Ken Bowersox, administrador asociado de la Direcci\u00f3n de Misiones de Operaciones Espaciales de la NASA, se\u00f1al\u00f3 que el 6 de mayo &#171;no es una fecha m\u00e1gica&#187;.<\/p>\n<p>&#171;Lanzaremos cuando estemos preparados&#187;, dijo.<\/p>\n<p>NASA y SpaceX lanzan la misi\u00f3n Crew-8 la Estaci\u00f3n Espacial Internacional<\/p>\n<p>Boeing desarroll\u00f3 la c\u00e1psula Starliner como parte del Programa de Tripulaci\u00f3n Comercial de la NASA. Esta imagen muestra la nave tal y como se ver\u00eda en \u00f3rbita. (Cr\u00e9dito: Boeing)<\/p>\n<p>Si tiene \u00e9xito, el Starliner se unir\u00e1 a la nave espacial Crew Dragon de SpaceX para hacer viajes de rutina a la estaci\u00f3n espacial, manteniendo el puesto de avanzada en \u00f3rbita con todo el personal de astronautas de la NASA y sus agencias espaciales asociadas.<\/p>\n<p>La agencia espacial estadounidense llevaba mucho tiempo esperando un escenario as\u00ed, con Crew Dragon y Starliner volando con regularidad.<\/p>\n<p>&#171;Estamos haciendo historia&#187;, dijo el administrador de la NASA Bill Nelson sobre la pr\u00f3xima misi\u00f3n Starliner durante una conferencia de prensa el 22 de marzo. &#171;Ahora estamos en la era dorada de la exploraci\u00f3n espacial&#187;.<\/p>\n<p>Cinco formas en que el desastre del transbordador espacial Columbia cambi\u00f3 los vuelos espaciales para siempre<\/p>\n<p>SpaceX y Boeing desarrollaron sus respectivos veh\u00edculos en el marco del Programa de Tripulaci\u00f3n Comercial de la NASA, una asociaci\u00f3n con contratistas de la industria privada. Desde el principio, la agencia espacial se propuso que ambas empresas operaran a la vez. Las naves espaciales Crew Dragon y Starliner servir\u00edan cada una como reserva de la otra, dando a los astronautas la opci\u00f3n de seguir volando, incluso si problemas t\u00e9cnicos u otros contratiempos dejaban en tierra una de las naves.<\/p>\n<p>Sin embargo, la NASA no previ\u00f3 inicialmente que la nave Crew Dragon de SpaceX funcionar\u00eda por s\u00ed sola durante casi cuatro a\u00f1os antes de que la Starliner de Boeing realizara su primer vuelo de prueba tripulado.<\/p>\n<p>En los primeros d\u00edas del programa, que adjudic\u00f3 contratos a SpaceX y Boeing en 2014, la NASA hab\u00eda favorecido a Boeing \u2014un socio cercano que se remonta a mediados del siglo XX\u2014 frente a SpaceX, que la agencia federal ve\u00eda como un advenedizo relativamente joven y caprichoso.<\/p>\n<p>Boeing, SpaceX y la visi\u00f3n de la NASA<\/p>\n<p>Todav\u00eda en 2016, la NASA planificaba su calendario con la idea de que el Starliner llegar\u00eda antes que el Crew Dragon a la plataforma de lanzamiento.<\/p>\n<p>Pero la carrera entre Boeing y SpaceX dio un claro giro en 2020. El a\u00f1o anterior, un vuelo de prueba del Starliner estuvo plagado de errores, lo que hizo que los responsables de la NASA y Boeing se esforzaran por averiguar qu\u00e9 hab\u00eda fallado. El Starliner no se acopl\u00f3 a la estaci\u00f3n espacial en esa misi\u00f3n debido a problemas de software, incluido un problema con el reloj interno de la nave espacial, que se retras\u00f3 11 horas.<\/p>\n<p>Mientras tanto, SpaceX hizo historia en mayo de 2020 con el lanzamiento de su vuelo de prueba Demo-2, que transport\u00f3 a los astronautas Bob Behnken y Doug Hurley en una misi\u00f3n de dos meses a la Estaci\u00f3n Espacial Internacional.<\/p>\n<p>Crew Dragon de SpaceX ha estado volando viajes de rutina desde entonces, llevando astronautas de la NASA e incluso clientes de pago y turistas. La nave ya ha realizado 13 misiones tripuladas en \u00f3rbita.<\/p>\n<p>Turismo espacial: las diferencias entre las misiones de SpaceX, Virgin Galactic y Blue Origin (2021)<\/p>\n<p>Boeing, sin embargo, se ha pasado varios a\u00f1os enfrent\u00e1ndose a una serie de retos, incluida una lista de problemas que se descubrieron en 2022 durante el segundo vuelo de prueba sin tripulaci\u00f3n de la nave espacial. La divisi\u00f3n de aviones comerciales de Boeing tambi\u00e9n se ha enfrentado a una serie de esc\u00e1ndalos \u2014incluida la crisis del 737 Max y los recientes problemas de control de calidad puestos de manifiesto despu\u00e9s de que el tap\u00f3n de una puerta saltara durante un vuelo de Alaska Airlines en enero\u2014 que han da\u00f1ado la marca de la empresa.<\/p>\n<p>Funcionarios de la NASA en un momento en 2020 incluso admitieron que hab\u00edan dirigido m\u00e1s escrutinio hacia SpaceX y sus formas poco ortodoxas, mientras que los problemas con el Starliner de Boeing se deslizaron a trav\u00e9s de las grietas.<\/p>\n<p>&#171;Tal vez no ten\u00edamos tantas personas integradas en ese proceso como deber\u00edamos&#187;, dijo Steve Stich, gerente del Programa de Tripulaci\u00f3n Comercial de la NASA, en una conferencia de prensa en julio de 2020.<\/p>\n<p>&#171;Cuando un proveedor (SpaceX) tiene un enfoque m\u00e1s nuevo que otro, a menudo es natural que un ser humano dedique m\u00e1s tiempo a ese enfoque m\u00e1s nuevo, y tal vez no nos tomamos todo el tiempo que necesit\u00e1bamos con el enfoque m\u00e1s tradicional (de Boeing)&#187;.<\/p>\n<p>Internet en la Luna: Nokia y la NASA llevan el 4G al espacio<\/p>\n<p>Los contratiempos del Starliner<\/p>\n<p>La divisi\u00f3n espacial de Boeing opera por separado de su equipo de aerol\u00edneas comerciales, y los responsables de la NASA y del gigante aeroespacial estadounidense han tratado habitualmente de hacer esa distinci\u00f3n.<\/p>\n<p>Los funcionarios de la NASA tambi\u00e9n han dejado claro que est\u00e1n trabajando m\u00e1s estrechamente que nunca con Boeing, con personal sobre el terreno en las instalaciones de Boeing supervisando algunas de las correcciones que la compa\u00f1\u00eda ha puesto en marcha antes del pr\u00f3ximo vuelo del Starliner.<\/p>\n<p>&#171;Se trata de una capacidad importante para la NASA. Nos apuntamos para hacerlo, y vamos a hacerlo con \u00e9xito&#187;, dijo Nappi este jueves. &#171;No pienso en ello en t\u00e9rminos de lo que es importante para Boeing tanto como lo pienso en t\u00e9rminos de lo que es importante para este programa&#187;.<\/p>\n<p>Aun as\u00ed, Boeing y la NASA han tenido una larga lista de problemas que resolver.<\/p>\n<p>AN\u00c1LISIS | C\u00f3mo Boeing se meti\u00f3 en un problema a\u00fan mayor<\/p>\n<p>Durante la \u00faltima prueba de vuelo en 2022, por ejemplo, los ingenieros descubrieron que las l\u00edneas de suspensi\u00f3n del paraca\u00eddas del Starliner ten\u00edan un umbral de fallo m\u00e1s bajo de lo esperado inicialmente.<\/p>\n<p>Los ingenieros de la NASA y Boeing probaron una soluci\u00f3n para ese problema a principios de este a\u00f1o, pero los paraca\u00eddas seguir\u00e1n siendo prioritarios mientras se realizan algunas comprobaciones de \u00faltima hora antes del despegue, dijo Stich este jueves.<\/p>\n<p>Seg\u00fan Nappi, se descubri\u00f3 que parte de la cinta adhesiva utilizada para proteger los mazos de cables era inflamable, por lo que Boeing tuvo que retirar y sustituir el equivalente a 1,5 km de este material.<\/p>\n<p>Boeing podr\u00eda incluso tener que redise\u00f1ar algunas de las v\u00e1lvulas de la nave debido a problemas de corrosi\u00f3n. Sin embargo, no se espera que esta actualizaci\u00f3n est\u00e9 lista hasta el segundo vuelo tripulado, previsto para 2025, como muy pronto.<\/p>\n<p>En el vuelo tripulado inaugural de mayo, Boeing utilizar\u00e1 en su lugar una &#171;mitigaci\u00f3n perfectamente aceptable&#187; que deber\u00eda evitar que las v\u00e1lvulas se atasquen, dijo Nappi en marzo.<\/p>\n<p>\u00bfQu\u00e9 factores condicionan los viajes tripulados a Marte? 1:42<\/p>\n<p>Starliner y la seguridad<\/p>\n<p>A pesar del largo camino hasta la plataforma de lanzamiento, las dos personas que protagonizar\u00e1n la primera misi\u00f3n tripulada del Starliner \u2014Williams y Wilmore, dos astronautas de la NASA con muchos a\u00f1os de experiencia\u2014 dijeron a su llegada al lugar de lanzamiento que est\u00e1n m\u00e1s seguros que nunca.<\/p>\n<p>&#171;Queremos que el p\u00fablico en general piense que es f\u00e1cil, pero no lo es: es muy duro&#187;, dijo Wilmore tras llegar al lugar de lanzamiento del Starliner en Florida este jueves. &#171;No estar\u00edamos aqu\u00ed si no estuvi\u00e9ramos preparados. Estamos preparados. La nave espacial est\u00e1 lista y los equipos est\u00e1n listos&#187;.<\/p>\n<p>Wilmore mencion\u00f3 en una conferencia de prensa en marzo que no espera que la nave espacial Starliner entre en ning\u00fan &#171;modo de fallo&#187;.<\/p>\n<p>Boeing logra despegue de Starliner, su cohete para llevar astronautas a la Estaci\u00f3n Espacial Internacional<\/p>\n<p>&#171;Pero si algo ocurriera \u2014porque todos somos humanos, no podemos construir las cosas perfectamente\u2014 si algo ocurriera, tenemos varios modos de descenso&#187;, dijo durante la conferencia de prensa, refiri\u00e9ndose a los modos que dan a los astronautas la capacidad de tomar m\u00e1s control manual sobre la nave espacial si algo no sale seg\u00fan lo planeado.<\/p>\n<p>Williams dijo durante un acto informativo en marzo: &#171;No estar\u00edamos sentados aqu\u00ed si no nos sinti\u00e9ramos \u2014y dij\u00e9ramos a nuestras familias que nos sentimos\u2014 seguros de esta nave espacial y de nuestras capacidades para controlarla&#187;.<\/p>\n<p>A\u00f1adi\u00f3 durante la rueda de prensa del jueves en Florida: &#171;Tengo toda la confianza no s\u00f3lo en nuestras capacidades y en las de la nave espacial, sino tambi\u00e9n en nuestro equipo de control de la misi\u00f3n, que est\u00e1 preparado para el desaf\u00edo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Tras a\u00f1os de retrasos y una vertiginosa serie de contratiempos durante los vuelos de prueba, la nave espacial Starliner de Boeing est\u00e1 finalmente lista para realizar su lanzamiento inaugural con tripulaci\u00f3n. La misi\u00f3n est\u00e1 en camino de despegar de Florida tan pronto como el 6 de mayo, llevando a los astronautas de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448538","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Tras a\u00f1os de retrasos y una vertiginosa serie de contratiempos durante los vuelos de prueba, la nave espacial Starliner de Boeing est\u00e1 finalmente lista para realizar su lanzamiento inaugural con tripulaci\u00f3n. La misi\u00f3n est\u00e1 en camino de despegar de Florida tan pronto como el 6 de mayo, llevando a los astronautas de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T10:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial\",\"datePublished\":\"2024-04-26T10:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/\"},\"wordCount\":1703,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/\",\"name\":\"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-26T10:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial - Noticias","og_description":"(CNN) &#8212; Tras a\u00f1os de retrasos y una vertiginosa serie de contratiempos durante los vuelos de prueba, la nave espacial Starliner de Boeing est\u00e1 finalmente lista para realizar su lanzamiento inaugural con tripulaci\u00f3n. La misi\u00f3n est\u00e1 en camino de despegar de Florida tan pronto como el 6 de mayo, llevando a los astronautas de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-26T10:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/"},"author":{"name":"","@id":""},"headline":"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial","datePublished":"2024-04-26T10:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/"},"wordCount":1703,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/","name":"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-26T10:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Boeing y la NASA deciden seguir adelante con el hist\u00f3rico lanzamiento tripulado de una nueva nave espacial","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-26T10:03:51Z","datePublished":"2024-04-26T10:03:51Z","dateModified":"2024-04-26T10:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Boeing y la NASA deciden seguir adelante con el hist\\u00f3rico lanzamiento tripulado de una nueva nave espacial\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/26\\\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/26\\\/boeing-nasa-historico-lanzamiento-tripulado-nueva-nave-espacial-spacex-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-26T10:03:51Z\",\"datePublished\":\"2024-04-26T10:03:51Z\",\"dateModified\":\"2024-04-26T10:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448909,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/05\/vuelo-tripulado-nave-espacial-starliner-boeing-trax\/","url_meta":{"origin":1448538,"position":0},"title":"C\u00f3mo ver el primer vuelo tripulado de la tan esperada nave espacial Starliner de Boeing","author":"","date":"mayo 5, 2024","format":false,"excerpt":"(CNN) -- El programa de vuelos espaciales de Boeing puede alcanzar un hito importante este lunes por la noche con el lanzamiento de su nave espacial Starliner, que llevar\u00e1 a dos astronautas de la NASA a la \u00f3rbita.La misi\u00f3n, denominada Prueba de Vuelo de Tripulaci\u00f3n, est\u00e1 programada para despegar este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449677,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/22\/lanzamiento-tripulado-boeing-starliner-retrasarse-trax\/","url_meta":{"origin":1448538,"position":1},"title":"El hist\u00f3rico lanzamiento tripulado del Boeing Starliner vuelve a retrasarse indefinidamente","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN) -- Aunque estaba previsto que este s\u00e1bado se lanzara el tan esperado viaje inaugural tripulado del Starliner de Boeing, esa fecha ya no est\u00e1 sobre la mesa, y la NASA no ha nombrado de inmediato una nueva.\"El equipo ha estado en reuniones durante dos d\u00edas consecutivos, evaluando la justificaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449002,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/07\/funcionarios-rumor-cancelacion-lanzamiento-tripulado-boeing-starliner-trax\/","url_meta":{"origin":1448538,"position":2},"title":"Los funcionarios describen el &#8216;rumor&#8217; que llev\u00f3 a la cancelaci\u00f3n de \u00faltimo minuto del lanzamiento tripulado del Boeing Starliner","author":"","date":"mayo 7, 2024","format":false,"excerpt":"(CNN) -- Los astronautas de la NASA hab\u00edan llegado a las \u00faltimas horas antes de un esperado intento de lanzamiento a bordo de la c\u00e1psula Starliner de Boeing, la primera misi\u00f3n tripulada de la nueva nave espacial.Pero la misi\u00f3n fue cancelada unas dos horas antes de que el reloj de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448985,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/06\/retrasan-lanzamiento-nave-espacial-starliner-boeing-problema-tecnico-trax\/","url_meta":{"origin":1448538,"position":3},"title":"Posponen lanzamiento de la nave espacial Starliner de Boeing por problema t\u00e9cnico","author":"","date":"mayo 6, 2024","format":false,"excerpt":"(CNN) -- La nave espacial Starliner de Boeing y los dos astronautas que deb\u00edan pilotar el veh\u00edculo en su primer lanzamiento tripulado permanecer\u00e1n en tierra al menos un d\u00eda m\u00e1s.Dos astronautas de la NASA llegaron horas antes de un esperado intento de lanzamiento a bordo de la c\u00e1psula Starliner de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450106,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/06\/06\/boeing-starliner-estacion-espacial-internacional-trax\/","url_meta":{"origin":1448538,"position":4},"title":"\u200b\u200bLa misi\u00f3n Starliner de Boeing se acopl\u00f3 con la Estaci\u00f3n Espacial Internacional, despu\u00e9s de haber tenido problemas en el camino","author":"","date":"junio 6, 2024","format":false,"excerpt":"(CNN) -- La misi\u00f3n Starliner de Boeing se acopl\u00f3 de forma segura a la Estaci\u00f3n Espacial Internacional (ISS, por sus siglas en ingl\u00e9s) y la tripulaci\u00f3n de la nave espacial, los astronautas de la NASA Butch Wilmore y Suni Williams, lleg\u00f3 a bordo de la estaci\u00f3n despu\u00e9s de sortear nuevos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449920,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/06\/01\/mision-starliner-boeing-intenta-historico-primer-lanzamiento-tripulado-trax\/","url_meta":{"origin":1448538,"position":5},"title":"Cancelan el lanzamiento de la misi\u00f3n Starliner de Boeing por problemas t\u00e9cnicos","author":"","date":"junio 1, 2024","format":false,"excerpt":"(CNN) --\u00a0La nave espacial Starliner de Boeing y dos astronautas preparados para volar el veh\u00edculo durante su primer lanzamiento tripulado permanecer\u00e1n en tierra al menos un d\u00eda m\u00e1s despu\u00e9s de que se anunciara su cancelaci\u00f3n.Los dos astronautas estaban a menos de cuatro minutos del lanzamiento cuando un sistema autom\u00e1tico provoc\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448538"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448538\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}