{"id":1448542,"date":"2024-04-26T06:03:39","date_gmt":"2024-04-26T13:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/"},"modified":"2024-04-26T06:03:39","modified_gmt":"2024-04-26T13:03:39","slug":"manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","title":{"rendered":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU."},"content":{"rendered":"<p>(CNN) &#8212; Los campus universitarios de todo Estados Unidos se han visto sacudidos por disturbios que han resultado en enfrentamientos con la polic\u00eda, el cierre de algunas aulas y que han captado la atenci\u00f3n de la naci\u00f3n.<\/p>\n<p>Aunque gran parte de la atenci\u00f3n inicial se ha centrado en los incidentes antisemitas y en c\u00f3mo los funcionarios universitarios y la polic\u00eda est\u00e1n respondiendo a las manifestaciones, todo esto plantea una pregunta fundamental: \u00bfqu\u00e9 quieren realmente los manifestantes propalestinos?<\/p>\n<p>\u00bfPor qu\u00e9 hay protestas estudiantiles en universidades de Estados Unidos?<\/p>\n<p>Las demandas espec\u00edficas de los manifestantes var\u00edan un poco de una escuela a otra, pero la demanda central es que las universidades se deshagan de empresas vinculadas a Israel o de negocios que se est\u00e1n beneficiando de su guerra con Hamas. Las universidades se han negado en gran medida a ceder ante esta demanda, y los expertos dicen que la desinversi\u00f3n puede no tener un impacto significativo en las propias empresas.<\/p>\n<p>Otros hilos comunes incluyen exigir a las universidades que revelen sus inversiones, cortar los v\u00ednculos acad\u00e9micos con las universidades israel\u00edes y apoyar un alto el fuego en Gaza.<\/p>\n<p>&#171;No iremos a ninguna parte hasta que se cumplan nuestras demandas&#187;, dijo Khymani James, estudiante de la Universidad de Columbia, durante una conferencia de prensa el mi\u00e9rcoles.<\/p>\n<p>Manifestantes estudiantiles ocupan el &#171;Campamento de Solidaridad con Gaza&#187; propalestino en el jard\u00edn oeste de la Universidad de Columbia el 24 de abril de 2024 en la ciudad de Nueva York. Michael M. Santiago\/Getty Images<\/p>\n<p>Los movimientos de protesta en algunas universidades tambi\u00e9n exigen a los funcionarios escolares que protejan la libertad de expresi\u00f3n y eviten que los estudiantes sean castigados por participar en las protestas.<\/p>\n<p>En la Universidad del Sur de California, donde decenas de personas fueron arrestadas el mi\u00e9rcoles, los manifestantes exigen una \u201camnist\u00eda total\u201d para los detenidos y que \u201cno haya vigilancia policial en el campus\u201d.<\/p>\n<p>En la Universidad de Princeton, los manifestantes exigen, entre otras cosas, que la escuela perteneciente a la Ivy League ponga fin a la investigaci\u00f3n sobre armas de guerra \u201cutilizadas para permitir el genocidio\u201d, seg\u00fan un volante en una manifestaci\u00f3n en el campus el jueves.<\/p>\n<p>Algunas demandas tienen que ver con asuntos locales.<\/p>\n<p>En la Universidad de Columbia, donde comenz\u00f3 el movimiento de protesta propalestino la semana pasada,\u00a0los manifestantes exigen apoyo para los residentes de bajos ingresos de Harlem, incluidas viviendas y reparaciones, seg\u00fan Apartheid Divest de la Universidad de Columbia, el grupo estudiantil responsable de organizar el campamento.<\/p>\n<p>Los manifestantes de Columbia tambi\u00e9n exigen que la universidad \u201crevele y rompa todos los v\u00ednculos\u201d con el Departamento de Polic\u00eda de Nueva York.<\/p>\n<p>Los estudiantes tambi\u00e9n est\u00e1n pidiendo un boicot acad\u00e9mico a las universidades israel\u00edes. Por ejemplo, los manifestantes de Columbia quieren que la universidad rompa los v\u00ednculos con el centro de la escuela en Tel Aviv y un programa de doble titulaci\u00f3n con la Universidad de Tel Aviv. Los manifestantes de la Universidad de Nueva York tambi\u00e9n utilizan el centro sobre Tel Aviv de la escuela como grito de guerra.<\/p>\n<p>Manifestantes estudiantiles ocupan el &#171;Campamento de Solidaridad con Gaza&#187; propalestino en el jard\u00edn oeste de la Universidad de Columbia el 24 de abril de 2024 en la ciudad de Nueva York. (Michael M. Santiago\/Getty Images)<\/p>\n<p>\u00bfEs posible desinvertir?<\/p>\n<p>A\u00fan as\u00ed, la desinversi\u00f3n encabeza la lista de demandas de los manifestantes y la que mencionan con m\u00e1s frecuencia.<\/p>\n<p>Mientras el presidente \u2014republicano\u2014 de la C\u00e1mara de Representantes, Mike Johnson, se dirig\u00eda a los estudiantes de Columbia el mi\u00e9rcoles, los estudiantes coreaban: \u201cRevelar, desinvertir, no pararemos, no descansaremos\u201d.<\/p>\n<p>Como muchas universidades importantes, Columbia tiene una dotaci\u00f3n (inversi\u00f3n en empresas) enorme. Esas inversiones estaban valoradas en US$ 13.600 millones a mediados de 2023.<\/p>\n<p>Y hay una historia de activistas estudiantiles que atacan las donaciones durante las manifestaciones. En la d\u00e9cada de 1980, los estudiantes lograron persuadir a Columbia para que se deshiciera del apartheid en Sud\u00e1frica.<\/p>\n<p>M\u00e1s recientemente, Columbia y otras universidades\u00a0 han desinvertido en combustibles f\u00f3siles y prisiones privadas.<\/p>\n<p>Charlie Eaton, profesor asistente de Sociolog\u00eda en la Universidad de California en Merced y autor de \u201cBankers in the Ivory Tower\u201d, dijo que Columbia \u201cabsolutamente\u201d puede tomar la decisi\u00f3n de desinvertir en inversiones vinculadas a Israel.<\/p>\n<p>\u201cNo es una pr\u00e1ctica descabellada que las escuelas tomen decisiones sobre c\u00f3mo invertir bas\u00e1ndose no s\u00f3lo en maximizar los retornos de la inversi\u00f3n, sino tambi\u00e9n en torno a principios de equidad y justicia en lo que invierten\u201d, dijo.<\/p>\n<p>Pero Mark Yudof, presidente de la Red de Participaci\u00f3n Acad\u00e9mica, que se opone al antisemitismo en los campus, dijo que no es una soluci\u00f3n sencilla de implementar.<\/p>\n<p>&#171;La verdad es que a veces resulta confuso determinar qui\u00e9n hace negocios en Israel y cu\u00e1l es la relaci\u00f3n con la guerra&#187;, dijo Yudof.<\/p>\n<p>Yudof, expresidente de la Universidad de California, dijo que no tiene conocimiento de una sola universidad que haya desinvertido en Israel a pesar de a\u00f1os de presi\u00f3n para que lo hiciera.<\/p>\n<p>&#171;No creo que eso suceda&#187;, dijo.<\/p>\n<p>&#171;Hostil y amenazante&#187;<\/p>\n<p>Sin embargo, ninguna de las universidades ha anunciado planes de desinvertir en inversiones vinculadas a Israel y algunos expertos dicen que ser\u00e1n muy reacios a aceptar esta demanda.<\/p>\n<p>\u201cUn obst\u00e1culo importante para la desinversi\u00f3n es que cualquier universidad que apoye la desinversi\u00f3n estar\u00eda enviando una se\u00f1al clara de que: (a) acepta; o (b) apoyar la destrucci\u00f3n del Estado de Israel y sus ciudadanos\u201d, dijo Jonathan Macey, profesor de la Facultad de Derecho de Yale.<\/p>\n<p>Macey dijo que, si bien los manifestantes podr\u00edan apoyar una medida de este tipo, muchos estudiantes, profesores y personal la considerar\u00edan \u201chostil y amenazadora\u201d.<\/p>\n<p>Lauren Post, analista de la Liga Antidifamaci\u00f3n (ADL por sus siglas en ingl\u00e9s), dijo que el impulso a la desinversi\u00f3n est\u00e1 relacionado con el movimiento Boicot, Desinversi\u00f3n y Sanciones (BDS).<\/p>\n<p>Aunque Post reconoci\u00f3 que algunas personas pueden estar presionando por la desinversi\u00f3n como una forma de responsabilizar a Israel, dijo que la ADL considera los objetivos del BDS como antisemitas.<\/p>\n<p>\u201cEl objetivo, desmantelar en \u00faltima instancia el Estado de Israel, es antisemita\u201d, dijo Post.<\/p>\n<p>Yudof, expresidente de la Universidad de California, dijo que tambi\u00e9n considera que es antisemita.<\/p>\n<p>\u201cHuele a doble rasero. \u00bfPor qu\u00e9 es s\u00f3lo Israel?\u201d.Yudof critic\u00f3 a los estudiantes universitarios que protestaban por centrarse en Israel en lugar de en los reg\u00edmenes antidemocr\u00e1ticos de todo el mundo, incluidos Ir\u00e1n y Rusia.<\/p>\n<p>Vale la pena se\u00f1alar, sin embargo, que las protestas estudiantiles no dicen directamente que est\u00e9n afiliadas al BDS.<\/p>\n<p>Las universidades no poseen tantas acciones<\/p>\n<p>Tambi\u00e9n existe un debate sobre cu\u00e1n efectivas son las campa\u00f1as de desinversi\u00f3n.<\/p>\n<p>Un problema es que vender acciones de una empresa significa que la universidad renunciar\u00eda a su influencia sobre la empresa.<\/p>\n<p>\u201cTen cuidado con lo que pides. Si vende sus acciones, alguien m\u00e1s las comprar\u00e1 y es posible que se preocupe menos por el tema que le preocupa a usted\u201d, dijo Cary Krosinsky, profesor de Yale que ha asesorado sobre donaciones universitarias.<\/p>\n<p>Otro problema es que, si bien las dotaciones universitarias a empresas son cuantiosas, las empresas p\u00fablicas son mucho mayores. Si una universidad desinvierte, muchas empresas ni siquiera se dar\u00edan cuenta.<\/p>\n<p>Las dotaciones universitarias poseen aproximadamente el 0,1% de las empresas p\u00fablicas, seg\u00fan una investigaci\u00f3n de Kroskinsky.<\/p>\n<p>\u201cEl 0,1% no va a mover mucho la aguja. Alguien m\u00e1s comprar\u00e1 las acciones y la vida seguir\u00e1\u201d, dijo.<\/p>\n<p>La mayor\u00eda de los fondos universitarios se invierten en fondos de capital privado y fondos de cobertura, en lugar de fondos mutuos o indexados de amplio alcance.<\/p>\n<p>Por supuesto, el impulso de desinversi\u00f3n va m\u00e1s all\u00e1 de castigar directamente a las empresas. Se trata del deseo de enviar un mensaje y crear conciencia.<\/p>\n<p>M\u00e1s que querer acabar con contratistas de defensa como Lockheed Martin y Raytheon, los manifestantes ver\u00edan la desinversi\u00f3n como una victoria simb\u00f3lica para la justicia y la igualdad.<\/p>\n<p>Los estudiantes son \u201cc\u00f3mplices de lo que hace esta instituci\u00f3n\u201d, dijo el mi\u00e9rcoles a CNN la estudiante graduada Basil Rodr\u00edguez, se\u00f1alando que los estudiantes pagan matr\u00edcula.<\/p>\n<p>Rodr\u00edguez es palestina y dijo que sus familiares han sido \u201casesinados y ejecutados\u201d y desplazados.<\/p>\n<p>Los estudiantes que protestan dicen que las demandas de divulgaci\u00f3n y desinversi\u00f3n est\u00e1n interconectadas.<\/p>\n<p>Los manifestantes argumentan que muchos de los intereses financieros de las universidades son opacos y que los v\u00ednculos con Israel pueden ser incluso mayores de lo que creen los funcionarios.<\/p>\n<p>&#171;Al mismo tiempo, esto es solo la punta del iceberg&#187;, dijo Rodr\u00edguez. &#171;Exigimos total transparencia financiera&#187;.<\/p>\n<p>Con informaci\u00f3n de John Towfighi de CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Los campus universitarios de todo Estados Unidos se han visto sacudidos por disturbios que han resultado en enfrentamientos con la polic\u00eda, el cierre de algunas aulas y que han captado la atenci\u00f3n de la naci\u00f3n. Aunque gran parte de la atenci\u00f3n inicial se ha centrado en los incidentes antisemitas y en c\u00f3mo los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448542","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Los campus universitarios de todo Estados Unidos se han visto sacudidos por disturbios que han resultado en enfrentamientos con la polic\u00eda, el cierre de algunas aulas y que han captado la atenci\u00f3n de la naci\u00f3n. Aunque gran parte de la atenci\u00f3n inicial se ha centrado en los incidentes antisemitas y en c\u00f3mo los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T13:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU.\",\"datePublished\":\"2024-04-26T13:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/\"},\"wordCount\":1536,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/\",\"name\":\"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-26T13:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU. - Noticias","og_description":"(CNN) &#8212; Los campus universitarios de todo Estados Unidos se han visto sacudidos por disturbios que han resultado en enfrentamientos con la polic\u00eda, el cierre de algunas aulas y que han captado la atenci\u00f3n de la naci\u00f3n. Aunque gran parte de la atenci\u00f3n inicial se ha centrado en los incidentes antisemitas y en c\u00f3mo los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-26T13:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/"},"author":{"name":"","@id":""},"headline":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU.","datePublished":"2024-04-26T13:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/"},"wordCount":1536,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","name":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-26T13:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU.","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-26T13:03:39Z","datePublished":"2024-04-26T13:03:39Z","dateModified":"2024-04-26T13:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/26\\\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/26\\\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-26T13:03:39Z\",\"datePublished\":\"2024-04-26T13:03:39Z\",\"dateModified\":\"2024-04-26T13:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448839,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","url_meta":{"origin":1448542,"position":0},"title":"Se realizan protestas universitarias propalestinas alrededor del mundo","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN) -- Las manifestaciones en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza se han extendido por los campus universitarios de Estados Unidos y alrededor del mundo en las \u00faltimas semanas.M\u00e1s de 2.000 personas han sido detenidas en campus estadounidenses desde el 18 de abril, en medio de polarizados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448760,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/01\/desinversion-israel-protestas-propalestina-universidades-estados-unidos-trax\/","url_meta":{"origin":1448542,"position":1},"title":"Las protestantes propalestinos en las universidades de EE.UU. llaman a la desinversi\u00f3n. Esto es lo que eso significa","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN) -- Este mes, se han llevado a cabo protestas propalestina en campus universitarios de todo Estados Unidos.Si bien las demandas de los manifestantes var\u00edan en cada universidad, casi todas las protestas piden a las universidades que \"desinviertan\" en Israel de alguna forma.Pero desinvertir puede no ser tan sencillo para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448388,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/22\/tensiones-protestas-propalestina-campus-universidades-columbia-nyu-trax\/","url_meta":{"origin":1448542,"position":2},"title":"Clases del campus principal de la Universidad de Columbia ser\u00e1n h\u00edbridas hasta fin de semestre; estudiantes y profesores de NYU fueron detenidos durante protestas","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia, epicentro de las protestas propalestinas en los campus universitarios estadounidenses en los \u00faltimos d\u00edas, inform\u00f3 que todas las clases en su campus principal ser\u00e1n h\u00edbridas \u2014si la tecnolog\u00eda lo permite\u2014 hasta que finalice el semestre de primavera.\"La seguridad es nuestra m\u00e1xima prioridad mientras nos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448731,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/01\/analisis-disturbios-estudiantiles-agravan-ano-electoral-tenso-trax\/","url_meta":{"origin":1448542,"position":3},"title":"AN\u00c1LISIS | Los disturbios estudiantiles agravan un a\u00f1o electoral ya de por s\u00ed tenso","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN) -- Las dram\u00e1ticas protestas en los campus universitarios est\u00e1n inyectando un nuevo elemento incendiario en un a\u00f1o electoral que ya amenaza con llevar la unidad nacional a un punto de ruptura.Las tensiones se dispararon a \u00faltima hora de este martes tras una operaci\u00f3n de los equipos de refuerzo del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448457,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/24\/manifestantes-universidad-columbia-fecha-limite-desmantelar-campamento-trax\/","url_meta":{"origin":1448542,"position":4},"title":"Universidad de Columbia extiende negociaciones con estudiantes que protestan por el campamento despu\u00e9s del &#171;di\u00e1logo constructivo&#187; durante la noche","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN) --La Universidad de Columbia y los estudiantes que protestan continuar\u00e1n las negociaciones sobre el desmantelamiento del campamento propalestino durante las pr\u00f3ximas 48 horas, seg\u00fan un portavoz de la universidad.\"Estamos logrando avances importantes con los representantes del campamento de estudiantes en el c\u00e9sped oeste\", afirm\u00f3 un portavoz de la universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451840,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/08\/14\/juez-ucla-no-puede-permitir-manifestantes-impidan-ingreso-estudiantes-judios-campus-ap\/","url_meta":{"origin":1448542,"position":5},"title":"Juez dictamina que UCLA no puede permitir que manifestantes impidan el ingreso de estudiantes jud\u00edos al campus","author":"","date":"agosto 14, 2024","format":false,"excerpt":"(CNN) -- Un juez federal dictamin\u00f3 este martes que la Universidad de California en Los \u00c1ngeles no puede permitir que manifestantes propalestinos impidan a los estudiantes jud\u00edos acceder a clases y otras partes del campus.Esta medida cautelar marca la primera vez que un juez estadounidense falla en contra de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448542"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448542\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}