{"id":1448641,"date":"2024-04-28T15:03:44","date_gmt":"2024-04-28T22:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/"},"modified":"2024-04-28T15:03:44","modified_gmt":"2024-04-28T22:03:44","slug":"4-muertos-ola-tornado-oklahoma-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","title":{"rendered":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas"},"content":{"rendered":"<p>(CNN) &#8212; Al menos cuatro personas murieron, entre ellas un beb\u00e9, despu\u00e9s de un tornado que azot\u00f3 Oklahoma durante la noche, mientras fuertes tormentas amenazan con m\u00e1s tornados, fuertes lluvias y granizo desde Missouri hasta Texas este domingo.<\/p>\n<p>Seg\u00fan el Servicio Meteorol\u00f3gico Nacional de EE.UU., se reportaron simult\u00e1neamente m\u00faltiples tornados grandes y muy peligrosos en tierra durante la noche en partes de Oklahoma.<\/p>\n<p>Dos muertes ocurrieron en Holdenville y una tercera cerca de Marietta en la I-35, seg\u00fan Keli Cain, directora de asuntos p\u00fablicos del Departamento de Manejo de Emergencias y Seguridad Nacional de Oklahoma.<\/p>\n<p>La cuarta muerte ocurri\u00f3 en la ciudad m\u00e1s afectada de Sulphur en el condado de Murray, Oklahoma, dijo el gobernador Kevin Stitt en una conferencia de prensa este domingo.<\/p>\n<p>Por brote de tornados en Oklahoma llaman a resguardarse mientras la amenaza de fuertes tormentas contin\u00faa desde Missouri hasta Texas<\/p>\n<p>\u201cParece que todos los negocios del centro fueron destruidos aqu\u00ed en Sulphur\u201d, dijo Stitt. \u201cDefinitivamente es el mayor da\u00f1o que he visto desde que soy gobernador\u201d.<\/p>\n<p>Stitt a\u00f1adi\u00f3 que unas 30 personas resultaron heridas en Sulphur y se desconoce su estado.<\/p>\n<p>El gobernador emiti\u00f3 una declaraci\u00f3n de desastre de emergencia y recorrer\u00e1 los da\u00f1os de la tormenta en Sulphur y Holdenville, seg\u00fan comparti\u00f3 en un mensaje de video.<\/p>\n<p>Da\u00f1os en la localidad de Sulphur, Oklahoma, el 28 de abril, tras un tornado. Cr\u00e9dito: KOCO.<\/p>\n<p>Se reportaron heridos, da\u00f1os a la propiedad, inundaciones y l\u00edneas el\u00e9ctricas y \u00e1rboles ca\u00eddos en varios condados este s\u00e1bado por la noche, dijo el Departamento de Manejo de Emergencias de Oklahoma. La magnitud de los da\u00f1os no estaba clara este domingo por la ma\u00f1ana.<\/p>\n<p>Sulphur, a unos 130 kil\u00f3metros al sur de la ciudad de Oklahoma, sufri\u00f3 lesiones e impactos de lo que parecen ser al menos dos grandes tornados durante la noche cuando se emiti\u00f3 una advertencia de inundaci\u00f3n para la ciudad, seg\u00fan el servicio meteorol\u00f3gico.<\/p>\n<p>\u201cUn tornado grande y extremadamente peligroso se identific\u00f3 al sur de Sulphur y se mov\u00eda hacia el norte a 35 mph. \u00a1\u00a1\u00a1Los socorristas deben prepararse inmediatamente para impactos adicionales de tornados!!!\u201d advirti\u00f3 el servicio meteorol\u00f3gico de Norman.<\/p>\n<p>Los servicios de emergencia trabajan en Sulphur, Oklahoma, el 28 de abril, luego de un tornado. Cr\u00e9dito: KOCO.<\/p>\n<p>Casi 47 millones de personas corren riesgo de sufrir condiciones clim\u00e1ticas severas este domingo desde el este de Texas hacia el norte hasta la parte superior del valle del r\u00edo Mississippi, mientras las comunidades de Nebraska e Iowa examinan la destrucci\u00f3n que las tormentas dejaron.<\/p>\n<p>Ciudades como Dallas y Austin en Texas, Oklahoma City y Tulsa en Oklahoma, Wichita y Topeka en Kansas y el \u00e1rea metropolitana de Kansas City podr\u00edan sufrir fuertes tornados a medida que las tormentas avancen hacia el este a trav\u00e9s de las llanuras del sur.<\/p>\n<p>M\u00e1s de 7 millones de personas est\u00e1n bajo alerta de tornado la madrugada de este domingo, que se extiende m\u00e1s de 1.287 kil\u00f3metros desde Texas hasta el sur de Wisconsin. Las alertas expirar\u00e1n entre las 4 a.m. y las 8 a.m. ET.<\/p>\n<p>Mientras tanto, el Centro de Predicci\u00f3n de Tormentas emiti\u00f3 una alerta de tornado para partes del este de Texas que afecta a m\u00e1s de 2 millones de personas hasta las 10 p.m. ET de este domingo, incluidas \u00e1reas alrededor de San Antonio, Austin y Houston. Ninguno de los centros de las ciudades estaba incluido en la alerta hasta este domingo por la tarde.<\/p>\n<p>Las principales amenazas asociadas con la alerta son tornados, granizo grande de hasta 5 cent\u00edmetros de di\u00e1metro y r\u00e1fagas de viento da\u00f1inas de hasta 112 km\/h, seg\u00fan el Centro de Predicci\u00f3n de Tormentas.<\/p>\n<p>El servicio meteorol\u00f3gico inform\u00f3 de dos tornados que cruzaban la autopista 9 de Oklahoma entre Goldsby y Blanchard al mismo tiempo este s\u00e1bado por la noche, as\u00ed como un avistamiento justo al este de la Base de la Fuerza A\u00e9rea Tinker. Y mientras un tornado se dirig\u00eda hacia Norman, la Universidad de Oklahoma advirti\u00f3 a los estudiantes y al personal que &#171;busquen refugio AHORA dentro del edificio en el que se encuentran. Vayan al piso m\u00e1s bajo o a la sala interior&#187;.<\/p>\n<p>El centro de operaciones de emergencia de Oklahoma fue activado este s\u00e1bado, seg\u00fan una publicaci\u00f3n en Facebook del gobernador Kevin Stitt. &#171;Est\u00e9 atento al tiempo y sepa d\u00f3nde refugiarte si una tormenta severa amenaza tu \u00e1rea&#187;, dijo a los residentes.<\/p>\n<p>Adem\u00e1s de los tornados, las tormentas tambi\u00e9n traen fuertes precipitaciones.<\/p>\n<p>Im\u00e1genes de dron muestran el devastador paso de tornados en EE. UU.<\/p>\n<p>Seg\u00fan el servicio meteorol\u00f3gico, las advertencias de inundaciones repentinas estuvieron vigentes en Texas, incluidos los condados de Dallas, Johnson, Parker y Tarrant, hasta este domingo por la ma\u00f1ana.<\/p>\n<p>El Centro de Predicci\u00f3n de Tormentas aument\u00f3 la amenaza de tormenta severa para este domingo a un nivel 3 de 5 desde el este de Texas hasta el sur de Missouri, incluyendo Shreveport, Little Rock y Springfield. Las comunidades desde el sureste de Texas hasta el sur de Iowa est\u00e1n bajo una amenaza de tormenta severa de nivel 2 de 5.<\/p>\n<p>Se espera que el tiempo inestable contin\u00fae en la parte central del pa\u00eds hasta este lunes.<\/p>\n<p>\u201cAdem\u00e1s del clima severo, se espera que en ocasiones las precipitaciones intensas acompa\u00f1en a estas tormentas, lo que eleva el riesgo de inundaciones repentinas de moderado a alto\u201d, dijo el Servicio Meteorol\u00f3gico Nacional.<\/p>\n<p>Las tormentas alimentaron decenas de reportes de tornados en al menos seis estados este viernes y s\u00e1bado, con im\u00e1genes de casas arrasadas y escombros que cubr\u00edan comunidades de Nebraska e Iowa.<\/p>\n<p>Tornados causan estragos en Nebraska y Iowa<\/p>\n<p>Una persona muri\u00f3 despu\u00e9s de que un tornado azotara Minden, Iowa, durante el severo brote de clima de este viernes, seg\u00fan el Manejo de Emergencias del Condado de Pottawattamie.<\/p>\n<p>De las cuatro personas heridas por con la tormenta, tres fueron tratadas y dadas de alta este viernes, mientras que la cuarta, que inicialmente se encontraba en condici\u00f3n estable, muri\u00f3 m\u00e1s tarde a causa de sus heridas, dijo el portavoz del condado de Pottawattamie, Craig Carlsen.<\/p>\n<p>La gobernadora de Iowa, Kim Reynolds, emiti\u00f3 este s\u00e1bado un anuncio de desastre para el condado de Pottawattamie en respuesta al mal tiempo de este viernes.<\/p>\n<p>Jason Sunday, residente de Omaha, y su familia acababan de ingresar a su nueva casa en Elkhorn hace 30 d\u00edas cuando un tornado azot\u00f3 la zona como un \u201ctren de carga\u201d, le dijo a KETV, afiliada de CNN.<\/p>\n<p>A medida que se acercaba el tornado este viernes, Sunday busc\u00f3 refugio en su casa.<\/p>\n<p>&#171;Est\u00e1bamos en la ba\u00f1era de abajo y era tal como dec\u00eda la pel\u00edcula, era como un tren de carga&#187;, dijo Sunday a KETV. \u201cY sab\u00edas que el techo se estaba cayendo porque se produjo un fuerte estallido y un movimiento de succi\u00f3n. Fue bastante aterrador\u201d.<\/p>\n<p>El tornado caus\u00f3 graves da\u00f1os en el nuevo hogar de la familia y ahora se enfrentan a la necesidad de reconstruirlo.<\/p>\n<p>\u201cEstamos agradecidos de estar vivos. Estamos muy agradecidos\u201d, dijo Sunday.<\/p>\n<p>Muchos residentes de Omaha y Nebraska tambi\u00e9n lidian con intensos da\u00f1os en sus hogares despu\u00e9s de que varios tornados tocaran tierra este viernes.<\/p>\n<p>Elkhorn en Omaha, Nebraska, es una de las comunidades m\u00e1s afectadas. El gobernador de Nebraska, Jim Pillen, dijo a los periodistas este s\u00e1bado que es un milagro que no haya muertes.<\/p>\n<p>\u201cLos habitantes de Nebraska no son ajenos al clima severo y, como lo han hecho en innumerables ocasiones antes, se ayudar\u00e1n entre s\u00ed para reconstruir\u201d, dijo el gobernador en una publicaci\u00f3n en X.<\/p>\n<p>Advierten de da\u00f1os &#171;catastr\u00f3ficos&#187; en Nebraska por tornado que azota el estado<\/p>\n<p>Uno de los tornados que azot\u00f3 el condado de Douglas ten\u00eda una clasificaci\u00f3n preliminar de EF-3 con vientos que superaron los 217 km\/h, seg\u00fan Chris Franks del Servicio Meteorol\u00f3gico Nacional. El otro, que impact\u00f3 en el aeropuerto de Omaha, parec\u00eda ser un EF-2, a\u00f1adi\u00f3.<\/p>\n<p>En las afueras de Lincoln, Nebraska, un tornado arranc\u00f3 los techos de las casas y perfor\u00f3 parte de la I-80 a su paso. Varios vagones de un tren descarrilaron cerca de Waverly despu\u00e9s de ser azotado por un tornado, seg\u00fan un portavoz del ferrocarril.<\/p>\n<p>En el condado de Pottawattamie, Iowa, aproximadamente 120 viviendas y negocios resultaron da\u00f1ados, dijeron funcionarios de gesti\u00f3n de emergencias del condado.<\/p>\n<p>Seg\u00fan el Servicio Meteorol\u00f3gico Nacional, se report\u00f3 un gran tornado en la peque\u00f1a ciudad de Minden en el condado de Pottawattamie. Las im\u00e1genes obtenidas por CNN muestran la devastaci\u00f3n de estructuras destrozadas y escombros esparcidos.<\/p>\n<p>Solo este viernes hubo m\u00e1s de 80 reportes de tornados en al menos cinco estados, muchos de los cuales fueron confirmados por el servicio meteorol\u00f3gico o mediante im\u00e1genes de los detectores de tormentas.<\/p>\n<p>&#8212; Jillian Sykes, Aya Elamroussi, Ray Sanchez, Sara Smart, Mary Gilbert, Sharif Paget, Sarah Dewberry, Jamiel Lynch, Raja Rezek, Colin Jeffrey, Rebekah Riess, Kara Devlin y los meteor\u00f3logos de CNN Sara Tonks, Brandon Miller, Gene Norman y Elisa Raffa de CNN contribuido a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Al menos cuatro personas murieron, entre ellas un beb\u00e9, despu\u00e9s de un tornado que azot\u00f3 Oklahoma durante la noche, mientras fuertes tormentas amenazan con m\u00e1s tornados, fuertes lluvias y granizo desde Missouri hasta Texas este domingo. Seg\u00fan el Servicio Meteorol\u00f3gico Nacional de EE.UU., se reportaron simult\u00e1neamente m\u00faltiples tornados grandes y muy peligrosos en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448641","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Al menos cuatro personas murieron, entre ellas un beb\u00e9, despu\u00e9s de un tornado que azot\u00f3 Oklahoma durante la noche, mientras fuertes tormentas amenazan con m\u00e1s tornados, fuertes lluvias y granizo desde Missouri hasta Texas este domingo. Seg\u00fan el Servicio Meteorol\u00f3gico Nacional de EE.UU., se reportaron simult\u00e1neamente m\u00faltiples tornados grandes y muy peligrosos en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-28T22:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas\",\"datePublished\":\"2024-04-28T22:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/\"},\"wordCount\":1604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/\",\"name\":\"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-28T22:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas - Noticias","og_description":"(CNN) &#8212; Al menos cuatro personas murieron, entre ellas un beb\u00e9, despu\u00e9s de un tornado que azot\u00f3 Oklahoma durante la noche, mientras fuertes tormentas amenazan con m\u00e1s tornados, fuertes lluvias y granizo desde Missouri hasta Texas este domingo. Seg\u00fan el Servicio Meteorol\u00f3gico Nacional de EE.UU., se reportaron simult\u00e1neamente m\u00faltiples tornados grandes y muy peligrosos en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-28T22:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/"},"author":{"name":"","@id":""},"headline":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas","datePublished":"2024-04-28T22:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/"},"wordCount":1604,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","name":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-28T22:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\u00faa la amenaza de tormentas severas desde Missouri hasta Texas","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/28\/4-muertos-ola-tornado-oklahoma-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-28T22:03:44Z","datePublished":"2024-04-28T22:03:44Z","dateModified":"2024-04-28T22:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos 4 muertos por ola de tornados en Oklahoma, mientras contin\\u00faa la amenaza de tormentas severas desde Missouri hasta Texas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/28\\\/4-muertos-ola-tornado-oklahoma-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/28\\\/4-muertos-ola-tornado-oklahoma-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-28T22:03:44Z\",\"datePublished\":\"2024-04-28T22:03:44Z\",\"dateModified\":\"2024-04-28T22:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448626,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/27\/brote-tornados-oklahoma-causa-llamados-mientras-amenaza-fuertes-tormentas-continua-desde-missouri-hasta-texas-trax\/","url_meta":{"origin":1448641,"position":0},"title":"Brote de tornados en Oklahoma causa llamados a resguardarse mientras la amenaza de fuertes tormentas contin\u00faa desde Missouri hasta Texas","author":"","date":"abril 27, 2024","format":false,"excerpt":"(CNN) -- La amenaza de fuertes tormentas que generan tornados contin\u00faa este domingo desde Missouri hasta Texas, donde es posible que se produzcan m\u00e1s tornados, lluvias intensas y granizo grande, mientras las comunidades en Nebraska e Iowa eval\u00faan la destrucci\u00f3n que las tormentas ya han dejado.Un brote de tornados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448694,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/fuertes-tormentas-centro-eeuu-tornados-trax\/","url_meta":{"origin":1448641,"position":1},"title":"Fuertes tormentas amenazan el centro de EE.UU. d\u00edas despu\u00e9s de una serie de poderosos y da\u00f1inos tornados","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN) -- Despu\u00e9s de que una serie de tornados afectara a partes del centro de EE.UU. durante el fin de semana, otra amenaza de tormenta severa afectar\u00e1 a la regi\u00f3n este martes por la tarde y por la noche. M\u00e1s de 15 millones de personas podr\u00edan ver tormentas severas desde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462526,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/19\/tornados-estados-unidos-tormentas-28-muertos-trax\/","url_meta":{"origin":1448641,"position":2},"title":"Fuertes tornados amenazan a millones en EE.UU. tras las tormentas que dejaron 28 muertos","author":"","date":"mayo 19, 2025","format":false,"excerpt":"La racha de d\u00edas de clima severo que dej\u00f3 28 muertos y desat\u00f3 destrucci\u00f3n en el centro y este de Estados Unidos en los \u00faltimos d\u00edas a\u00fan no da tregua, y se pronostica que continuar\u00e1 esta semana.El nivel 4 de 5 de riesgo de tormentas el\u00e9ctricas severas del lunes en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460751,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/04\/02\/pronostico-tormentas-estados-unidos-inundaciones-trax\/","url_meta":{"origin":1448641,"position":3},"title":"Pron\u00f3stico de tormentas en EE.UU.: advierten por una oleada de tornados fuertes e inundaciones sin precedentes","author":"","date":"abril 2, 2025","format":false,"excerpt":"Este mi\u00e9rcoles se espera una oleada potencialmente mortal de tornados fuertes y de larga duraci\u00f3n en partes del centro y este de EE.UU. a ra\u00edz de una poderosa y amplia tormenta de primavera.Tormentas el\u00e9ctricas muy intensas ya estaban atravesando las llanuras el mi\u00e9rcoles por la ma\u00f1ana, antes de la amenaza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448520,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/25\/fuerte-tormenta-centro-de-estados-unidos-trax\/","url_meta":{"origin":1448641,"position":4},"title":"Fuertes tormentas golpear\u00e1n el centro de EE.UU. durante los pr\u00f3ximos 4 d\u00edas","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Peligrosas tormentas descargar\u00e1n a diario tornados, vientos destructivos y granizo de gran tama\u00f1o sobre el centro de Estados Unidos durante el fin de semana. Algunas localidades se enfrentan a una amenaza de tormentas fuertes durante dos o tres d\u00edas consecutivos.Dallas; Kansas City, Missouri; Des Moines, Iowa; y Omaha,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448541,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/fuerte-tormenta-tornado-centro-de-estados-unidos-trax\/","url_meta":{"origin":1448641,"position":5},"title":"Importantes tornados y una amenaza de mal clima est\u00e1n en curso en el centro de EE.UU.","author":"","date":"abril 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Se ha desatado una tormenta el\u00e9ctrica severa que durar\u00e1 varios d\u00edas mientras el centro de EE.UU. sufre r\u00e1fagas de viento da\u00f1inas, granizo de gran tama\u00f1o y tornados. Se espera que el peligro que representan estas feroces tormentas solo aumente durante el fin de semana.Las tormentas da\u00f1inas del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448641"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448641\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}