{"id":1448663,"date":"2024-04-29T09:03:37","date_gmt":"2024-04-29T16:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/"},"modified":"2024-04-29T09:03:37","modified_gmt":"2024-04-29T16:03:37","slug":"don-rodo-mexico-cartel-jalisco-liberan-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/","title":{"rendered":"Liberan en M\u00e9xico a &#171;Don Rodo&#187;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Un juez de Distrito del Centro de Justicia Penal Federal en el Estado de M\u00e9xico dispuso este domingo la libertad de Abraham Oseguera Cervantes, \u201cDon Rodo\u201d, hermano del l\u00edder del Cartel de Jalisco Nueva Generaci\u00f3n, Nemesio Oseguera, inform\u00f3 en un comunicado el Consejo de la Judicatura Federal.<\/p>\n<p>El juez decidi\u00f3 no llevar a juicio a alias &#171;Don Rodo&#187; porque &#171;su forma de detenci\u00f3n result\u00f3 contradictoria a lo expuesto por la autoridad en su Informe policial&#187;, seg\u00fan la nota de prensa.<\/p>\n<p>CNN intenta contactar a la Fiscal\u00eda General de la Rep\u00fablica y a la Secretar\u00eda de Defensa Nacional para obtener su reacci\u00f3n respecto de la resoluci\u00f3n.<\/p>\n<p>CNN intent\u00f3 adem\u00e1s contactar al equipo legal de Oseguera.<\/p>\n<p>El Gobierno de M\u00e9xico inform\u00f3 el 21 de abril en una nota de prensa que alias &#171;Don Rodo&#187; hab\u00eda sido arrestado en Michoac\u00e1n y que se encontraba bajo custodia del Ministerio P\u00fablico por probable participaci\u00f3n en delitos de portaci\u00f3n de arma de fuego de uso exclusivo del Ej\u00e9rcito y posesi\u00f3n de narc\u00f3tico con fines de comercio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Un juez de Distrito del Centro de Justicia Penal Federal en el Estado de M\u00e9xico dispuso este domingo la libertad de Abraham Oseguera Cervantes, \u201cDon Rodo\u201d, hermano del l\u00edder del Cartel de Jalisco Nueva Generaci\u00f3n, Nemesio Oseguera, inform\u00f3 en un comunicado el Consejo de la Judicatura Federal. El juez decidi\u00f3 no llevar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448663","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liberan en M\u00e9xico a &quot;Don Rodo&quot;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liberan en M\u00e9xico a &quot;Don Rodo&quot;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Un juez de Distrito del Centro de Justicia Penal Federal en el Estado de M\u00e9xico dispuso este domingo la libertad de Abraham Oseguera Cervantes, \u201cDon Rodo\u201d, hermano del l\u00edder del Cartel de Jalisco Nueva Generaci\u00f3n, Nemesio Oseguera, inform\u00f3 en un comunicado el Consejo de la Judicatura Federal. El juez decidi\u00f3 no llevar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T16:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Liberan en M\u00e9xico a &#171;Don Rodo&#187;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n\",\"datePublished\":\"2024-04-29T16:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/\",\"name\":\"Liberan en M\u00e9xico a \\\"Don Rodo\\\", hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-29T16:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liberan en M\u00e9xico a &#171;Don Rodo&#187;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liberan en M\u00e9xico a \"Don Rodo\", hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Liberan en M\u00e9xico a \"Don Rodo\", hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Un juez de Distrito del Centro de Justicia Penal Federal en el Estado de M\u00e9xico dispuso este domingo la libertad de Abraham Oseguera Cervantes, \u201cDon Rodo\u201d, hermano del l\u00edder del Cartel de Jalisco Nueva Generaci\u00f3n, Nemesio Oseguera, inform\u00f3 en un comunicado el Consejo de la Judicatura Federal. El juez decidi\u00f3 no llevar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-29T16:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/"},"author":{"name":"","@id":""},"headline":"Liberan en M\u00e9xico a &#171;Don Rodo&#187;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n","datePublished":"2024-04-29T16:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/","name":"Liberan en M\u00e9xico a \"Don Rodo\", hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-29T16:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Liberan en M\u00e9xico a &#171;Don Rodo&#187;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Liberan en M\u00e9xico a &#171;Don Rodo&#187;, hermano del l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/29\/don-rodo-mexico-cartel-jalisco-liberan-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-29T16:03:37Z","datePublished":"2024-04-29T16:03:37Z","dateModified":"2024-04-29T16:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Liberan en M\\u00e9xico a &#171;Don Rodo&#187;, hermano del l\\u00edder del Cartel Jalisco Nueva Generaci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/29\\\/don-rodo-mexico-cartel-jalisco-liberan-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/29\\\/don-rodo-mexico-cartel-jalisco-liberan-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-29T16:03:37Z\",\"datePublished\":\"2024-04-29T16:03:37Z\",\"dateModified\":\"2024-04-29T16:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452903,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/09\/20\/declaran-culpable-menchito-cartel-jalisco-nueva-generacion-orix\/","url_meta":{"origin":1448663,"position":0},"title":"Justicia de EE.UU. declara culpable al Menchito, uno de los l\u00edderes del C\u00e1rtel Jalisco Nueva Generaci\u00f3n","author":"","date":"septiembre 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Rub\u00e9n Oseguera Gonz\u00e1lez, alias \u201cel Menchito\u201d \u2015uno de los l\u00edderes del poderoso Cartel Jalisco Nueva Generaci\u00f3n\u2015, fue declarado este viernes culpable de conspiraci\u00f3n y uso de armas por un jurado federal de Estados Unidos, tras un juicio que dur\u00f3 dos semanas en la corte del Distrito de Columbia,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459649,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/07\/quien-es-ruben-oseguera-gonzalez-alias-el-menchito-orix\/","url_meta":{"origin":1448663,"position":1},"title":"\u00bfQui\u00e9n es Rub\u00e9n Oseguera Gonz\u00e1lez, alias el Menchito?","author":"","date":"marzo 7, 2025","format":false,"excerpt":"Rub\u00e9n Oseguera Gonz\u00e1lez, conocido como el Menchito, uno de los l\u00edderes del poderoso c\u00e1rtel mexicano Jalisco Nueva Generaci\u00f3n, fue condenado este viernes a cadena perpetua por tr\u00e1fico de drogas y armas, inform\u00f3 EFE.La condena fue dictada por la jueza Beryl A. Howell, luego de que Oseguera Gonz\u00e1lez, fuera declarado culpable\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456263,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/04\/ee-uu-usd-15-millones-recompensa-captura-mencho-cjng-orix\/","url_meta":{"origin":1448663,"position":2},"title":"EE.UU. aumenta a US$ 15 millones la recompensa por la captura del &#171;Mencho&#187;, l\u00edder del C\u00e1rtel Jalisco Nueva Generaci\u00f3n","author":"","date":"diciembre 4, 2024","format":false,"excerpt":"El Departamento de Estado de Estados Unidos anunci\u00f3 este mi\u00e9rcoles que aument\u00f3 a US$ 15 millones la recompensa por informaci\u00f3n que conduzca a la captura y condena de Nemesio Rub\u00e9n Oseguera Cervantes, alias \u201cEl Mencho\u201d, presunto cofundador y l\u00edder del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG), banda criminal se\u00f1alada por el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448399,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/5-cosas-23-abril-referendo-ecuador-orix\/","url_meta":{"origin":1448663,"position":3},"title":"Las 5 cosas que debes saber este 23 de abril: \u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo?","author":"","date":"abril 23, 2024","format":false,"excerpt":"Encuentran fosa com\u00fan en un hospital de Gaza. TikTok promete desafiar legalmente su posible prohibici\u00f3n en EE.UU. Momento \"m\u00e1gico\": surfista comparte ola con una manada de delfines. Esto es lo que debes saber para comenzar el d\u00eda.\u00a0Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo1. \u00bfQu\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472595,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/26\/argentina-declara-grupo-terrorista-cartel-jalisco-nueva-generacion-efe\/","url_meta":{"origin":1448663,"position":4},"title":"Gobierno de Argentina declara grupo terrorista al Cartel de Jalisco Nueva Generaci\u00f3n de M\u00e9xico","author":"","date":"marzo 26, 2026","format":false,"excerpt":"El Gobierno de Argentina declar\u00f3 al Cartel Jalisco Nueva Generaci\u00f3n (CJNG) de M\u00e9xico como grupo terrorista, seg\u00fan un comunicado publicado este jueves por la oficina del presidente Javier Milei.\u201cLa Oficina del Presidente informa que el Gobierno Nacional ha declarado al Cartel de Jalisco Nueva Generaci\u00f3n (CING) como organizaci\u00f3n terrorista\u201d, dice\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459305,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/27\/quienes-son-29-narcotraficantes-mexico-extradito-estados-unidos-orix\/","url_meta":{"origin":1448663,"position":5},"title":"Qui\u00e9nes son los 29 narcotraficantes que M\u00e9xico extradit\u00f3 a EE.UU.","author":"","date":"febrero 27, 2025","format":false,"excerpt":"Las autoridades de M\u00e9xico dieron a conocer este jueves que extraditaron a Estados Unidos a 29 miembros de c\u00e1rteles que se encontraban presos en diferentes centros penitenciarios del pa\u00eds.La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) inform\u00f3 en un comunicado que las extradiciones se dieron \u201cen el marco de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448663"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448663\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}