{"id":1448689,"date":"2024-04-30T02:03:41","date_gmt":"2024-04-30T09:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/"},"modified":"2024-04-30T02:03:41","modified_gmt":"2024-04-30T09:03:41","slug":"manifestantes-columbia-irrumpen-edificio-academico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","title":{"rendered":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico"},"content":{"rendered":"<p>(CNN) &#8212; Decenas de estudiantes de la Universidad de Columbia se han atrincherado dentro del Edificio Hamilton, el lugar de la ocupaci\u00f3n universitaria de 1968, seg\u00fan una publicaci\u00f3n en redes sociales de Estudiantes de Columbia por la Justicia en Palestina.<\/p>\n<p>La Universidad de Columbia ha estado en el epicentro de las protestas propalestinas en los campus de todo el pa\u00eds.<\/p>\n<p>Durante la noche, los manifestantes en el campus se trasladaron desde el campamento en el c\u00e9sped oeste hasta el Edificio Hamilton, uno de los principales edificios acad\u00e9micos para estudiantes de pregrado.<\/p>\n<p>La universidad inform\u00f3 horas antes que hab\u00eda comenzado el proceso de suspensi\u00f3n de estudiantes que se negaban a abandonar un campamento en el campus, inform\u00f3 CNN.<\/p>\n<p>CNN se ha puesto en contacto con la Universidad de Columbia y el Departamento de Polic\u00eda de Nueva York para obtener informaci\u00f3n.<\/p>\n<p>Esta es una historia en desarrollo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Decenas de estudiantes de la Universidad de Columbia se han atrincherado dentro del Edificio Hamilton, el lugar de la ocupaci\u00f3n universitaria de 1968, seg\u00fan una publicaci\u00f3n en redes sociales de Estudiantes de Columbia por la Justicia en Palestina. La Universidad de Columbia ha estado en el epicentro de las protestas propalestinas en los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448689","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Decenas de estudiantes de la Universidad de Columbia se han atrincherado dentro del Edificio Hamilton, el lugar de la ocupaci\u00f3n universitaria de 1968, seg\u00fan una publicaci\u00f3n en redes sociales de Estudiantes de Columbia por la Justicia en Palestina. La Universidad de Columbia ha estado en el epicentro de las protestas propalestinas en los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T09:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico\",\"datePublished\":\"2024-04-30T09:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/\"},\"wordCount\":183,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/\",\"name\":\"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-30T09:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico - Noticias","og_description":"(CNN) &#8212; Decenas de estudiantes de la Universidad de Columbia se han atrincherado dentro del Edificio Hamilton, el lugar de la ocupaci\u00f3n universitaria de 1968, seg\u00fan una publicaci\u00f3n en redes sociales de Estudiantes de Columbia por la Justicia en Palestina. La Universidad de Columbia ha estado en el epicentro de las protestas propalestinas en los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-30T09:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/"},"author":{"name":"","@id":""},"headline":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico","datePublished":"2024-04-30T09:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/"},"wordCount":183,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","name":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-30T09:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\u00e9mico","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/manifestantes-columbia-irrumpen-edificio-academico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-30T09:03:41Z","datePublished":"2024-04-30T09:03:41Z","dateModified":"2024-04-30T09:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los manifestantes de la Universidad de Columbia irrumpen en un edificio acad\\u00e9mico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/30\\\/manifestantes-columbia-irrumpen-edificio-academico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/30\\\/manifestantes-columbia-irrumpen-edificio-academico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-30T09:03:41Z\",\"datePublished\":\"2024-04-30T09:03:41Z\",\"dateModified\":\"2024-04-30T09:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448457,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/24\/manifestantes-universidad-columbia-fecha-limite-desmantelar-campamento-trax\/","url_meta":{"origin":1448689,"position":0},"title":"Universidad de Columbia extiende negociaciones con estudiantes que protestan por el campamento despu\u00e9s del &#171;di\u00e1logo constructivo&#187; durante la noche","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN) --La Universidad de Columbia y los estudiantes que protestan continuar\u00e1n las negociaciones sobre el desmantelamiento del campamento propalestino durante las pr\u00f3ximas 48 horas, seg\u00fan un portavoz de la universidad.\"Estamos logrando avances importantes con los representantes del campamento de estudiantes en el c\u00e9sped oeste\", afirm\u00f3 un portavoz de la universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448388,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/22\/tensiones-protestas-propalestina-campus-universidades-columbia-nyu-trax\/","url_meta":{"origin":1448689,"position":1},"title":"Clases del campus principal de la Universidad de Columbia ser\u00e1n h\u00edbridas hasta fin de semestre; estudiantes y profesores de NYU fueron detenidos durante protestas","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia, epicentro de las protestas propalestinas en los campus universitarios estadounidenses en los \u00faltimos d\u00edas, inform\u00f3 que todas las clases en su campus principal ser\u00e1n h\u00edbridas \u2014si la tecnolog\u00eda lo permite\u2014 hasta que finalice el semestre de primavera.\"La seguridad es nuestra m\u00e1xima prioridad mientras nos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448359,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/21\/rabino-recomienda-judios-volver-casa-protestas-universidad-columbia-trax\/","url_meta":{"origin":1448689,"position":2},"title":"La Universidad de Columbia enfrenta una grave crisis mientras un rabino pide a los estudiantes jud\u00edos que \u201cregresen a casa\u201d","author":"","date":"abril 21, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia se enfrenta a una crisis en toda regla de cara a la Pascua, cuando un rabino vinculado a la escuela de la Ivy League inst\u00f3 a los estudiantes jud\u00edos a quedarse en casa y los tensos enfrentamientos en el campus generaron la condena de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448839,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/03\/donde-protestas-universitarias-propalestinas-mundo-trax\/","url_meta":{"origin":1448689,"position":3},"title":"Se realizan protestas universitarias propalestinas alrededor del mundo","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN) -- Las manifestaciones en solidaridad con los palestinos bajo asedio israel\u00ed en Gaza se han extendido por los campus universitarios de Estados Unidos y alrededor del mundo en las \u00faltimas semanas.M\u00e1s de 2.000 personas han sido detenidas en campus estadounidenses desde el 18 de abril, en medio de polarizados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448391,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/columbia-extiende-clases-hibridas-hasta-final-semestre-mientras-protestas-preocupaciones-de-seguridad-trax\/","url_meta":{"origin":1448689,"position":4},"title":"La Universidad de Columbia extiende las clases h\u00edbridas hasta el final del semestre mientras las tensas protestas generan preocupaciones de seguridad","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN) -- La Universidad de Columbia enfrenta un s\u00e9ptimo d\u00eda de tensas manifestaciones pro palestinas mientras las protestas de solidaridad se han extendido a otras universidades y han provocado arrestos en la Universidad de Nueva York y Yale. Cuando la semana de la Pascua comenz\u00f3 este lunes, las crecientes tensiones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448542,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/26\/manifestantes-propalestinos-que-quieren-campus-universitarios-eeeuu-trax\/","url_meta":{"origin":1448689,"position":5},"title":"Lo que realmente quieren los manifestantes propalestinos en los campus universitarios de EE.UU.","author":"","date":"abril 26, 2024","format":false,"excerpt":"(CNN) -- Los campus universitarios de todo Estados Unidos se han visto sacudidos por disturbios que han resultado en enfrentamientos con la polic\u00eda, el cierre de algunas aulas y que han captado la atenci\u00f3n de la naci\u00f3n.Aunque gran parte de la atenci\u00f3n inicial se ha centrado en los incidentes antisemitas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448689"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448689\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}