{"id":1448701,"date":"2024-04-30T11:03:47","date_gmt":"2024-04-30T18:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/"},"modified":"2024-04-30T11:03:47","modified_gmt":"2024-04-30T18:03:47","slug":"camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/","title":{"rendered":"La C\u00e1mara de Diputados de Argentina aprueba la &#171;Ley Bases&#187; de Milei"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Luego de un debate de m\u00e1s de 20 horas, la C\u00e1mara de Diputados de Argentina aprob\u00f3 \u2014primero en general y horas m\u00e1s tarde en particular\u2014 la &#171;Ley de Bases y Puntos de Partida para la Libertad de los Argentinos&#187;, un paquete de reformas tambi\u00e9n conocido como &#171;ley \u00f3mnibus&#187;. Impulsada por el Gobierno de Javier Milei, la ley fue aprobada en general por 142 votos a favor, 106 en contra y 5 abstenciones.<\/p>\n<p>Despu\u00e9s de la votaci\u00f3n en general en el recinto durante la ma\u00f1ana de este martes, el debate sigui\u00f3 para la votaci\u00f3n particular, en el que los diputados decidieron en las primeras horas de la tarde cap\u00edtulo por cap\u00edtulo de esta gran reforma que abarca muchos \u00e1mbitos y busca desregular algunos sectores de la econom\u00eda.<\/p>\n<p>Javier Milei insiste con la Ley \u00d3mnibus, pero reducida y dividida en dos proyectos<\/p>\n<p>&#171;Este es un primer paso fundamental para sacar a Argentina del pantano que ha sido las \u00faltimas d\u00e9cadas. Quiero agradecer la enorme tarea de todos los Diputados que, entendiendo el momento hist\u00f3rico, decidieron acompa\u00f1ar nuestro proyecto&#187;, dijo el presidente Milei en un mensaje en su cuenta en X.<\/p>\n<p>Ya en febrero una primera versi\u00f3n de esta ley, que era m\u00e1s amplia, hab\u00eda conseguido la aprobaci\u00f3n en votaci\u00f3n general en la C\u00e1mara de Diputados, pero no obtuvo los votos en particular y el propio oficialismo dio de baja la sesi\u00f3n.<\/p>\n<p>Ahora, la ley pasa con media sanci\u00f3n a la C\u00e1mara de Senadores. All\u00ed, el oficialismo tambi\u00e9n necesitar\u00e1 del apoyo de aliados y opositores para conseguir su aprobaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Luego de un debate de m\u00e1s de 20 horas, la C\u00e1mara de Diputados de Argentina aprob\u00f3 \u2014primero en general y horas m\u00e1s tarde en particular\u2014 la &#171;Ley de Bases y Puntos de Partida para la Libertad de los Argentinos&#187;, un paquete de reformas tambi\u00e9n conocido como &#171;ley \u00f3mnibus&#187;. Impulsada por el Gobierno [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448701","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La C\u00e1mara de Diputados de Argentina aprueba la &quot;Ley Bases&quot; de Milei - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La C\u00e1mara de Diputados de Argentina aprueba la &quot;Ley Bases&quot; de Milei - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Luego de un debate de m\u00e1s de 20 horas, la C\u00e1mara de Diputados de Argentina aprob\u00f3 \u2014primero en general y horas m\u00e1s tarde en particular\u2014 la &#171;Ley de Bases y Puntos de Partida para la Libertad de los Argentinos&#187;, un paquete de reformas tambi\u00e9n conocido como &#171;ley \u00f3mnibus&#187;. Impulsada por el Gobierno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T18:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La C\u00e1mara de Diputados de Argentina aprueba la &#171;Ley Bases&#187; de Milei\",\"datePublished\":\"2024-04-30T18:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/\"},\"wordCount\":310,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/\",\"name\":\"La C\u00e1mara de Diputados de Argentina aprueba la \\\"Ley Bases\\\" de Milei - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-30T18:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La C\u00e1mara de Diputados de Argentina aprueba la &#171;Ley Bases&#187; de Milei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La C\u00e1mara de Diputados de Argentina aprueba la \"Ley Bases\" de Milei - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La C\u00e1mara de Diputados de Argentina aprueba la \"Ley Bases\" de Milei - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Luego de un debate de m\u00e1s de 20 horas, la C\u00e1mara de Diputados de Argentina aprob\u00f3 \u2014primero en general y horas m\u00e1s tarde en particular\u2014 la &#171;Ley de Bases y Puntos de Partida para la Libertad de los Argentinos&#187;, un paquete de reformas tambi\u00e9n conocido como &#171;ley \u00f3mnibus&#187;. Impulsada por el Gobierno [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-30T18:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/"},"author":{"name":"","@id":""},"headline":"La C\u00e1mara de Diputados de Argentina aprueba la &#171;Ley Bases&#187; de Milei","datePublished":"2024-04-30T18:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/"},"wordCount":310,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/","name":"La C\u00e1mara de Diputados de Argentina aprueba la \"Ley Bases\" de Milei - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-30T18:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La C\u00e1mara de Diputados de Argentina aprueba la &#171;Ley Bases&#187; de Milei"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La C\u00e1mara de Diputados de Argentina aprueba la &#171;Ley Bases&#187; de Milei","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-30T18:03:47Z","datePublished":"2024-04-30T18:03:47Z","dateModified":"2024-04-30T18:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La C\\u00e1mara de Diputados de Argentina aprueba la &#171;Ley Bases&#187; de Milei\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/30\\\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/30\\\/camara-de-diputados-argentina-ley-bases-milei-votacion-general-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-30T18:03:47Z\",\"datePublished\":\"2024-04-30T18:03:47Z\",\"dateModified\":\"2024-04-30T18:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1444824,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/02\/02\/la-camara-de-diputados-de-argentina-aprueba-la-ley-omnibus-en-lo-general-el-debate-en-lo-particular-seguira-el-martes\/","url_meta":{"origin":1448701,"position":0},"title":"La C\u00e1mara de Diputados de Argentina aprueba la \u201cley \u00f3mnibus\u201d en lo general. El debate en lo particular seguir\u00e1 el martes","author":"","date":"febrero 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La C\u00e1mara de Diputados de Argentina aprob\u00f3 este viernes, en lo general, la Ley de Bases y Puntos de Partida para la Libertad de los Argentinos, un paquete de reformas tambi\u00e9n conocido como \u201cley \u00f3mnibus\u201d, que es impulsado por el Gobierno del presidente Javier Milei.La ley avanz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444851,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/02\/03\/asi-se-voto-la-ley-omnibus-de-milei-en-argentina-que-sigue-ahora\/","url_meta":{"origin":1448701,"position":1},"title":"As\u00ed se vot\u00f3 la &#171;ley \u00f3mnibus&#187; de Milei en Argentina: \u00bfQu\u00e9 sigue ahora?","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La aprobaci\u00f3n en general por la C\u00e1mara de Diputados de Argentina del pol\u00e9mico proyecto de Ley de Bases y Condiciones para la Libertad de los Argentinos tras tres d\u00edas de debate, supuso varias modificaciones a la propuesta original del Gobierno de Javier Milei.Pero el debate en la C\u00e1mara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450296,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/06\/12\/senado-argentina-aprueba-general-la-ley-de-bases-milei-orix\/","url_meta":{"origin":1448701,"position":2},"title":"El Senado de Argentina aprueba en lo general la Ley de Bases impulsada por Milei","author":"","date":"junio 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Senado de Argentina aprob\u00f3 en lo general la Ley de Bases y Puntos de Partida para la Libertad de los Argentinos, un proyecto que impulsa el presidente Javier Milei con reformas al Estado y diversas desregulaciones.Despu\u00e9s de una votaci\u00f3n de 36 a favor por 36 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444511,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/27\/gobierno-de-milei-retira-el-polemico-capitulo-fiscal-de-la-ley-omnibus-para-garantizar-su-aprobacion\/","url_meta":{"origin":1448701,"position":3},"title":"Gobierno de Milei retira el pol\u00e9mico cap\u00edtulo fiscal de la &#171;ley \u00f3mnibus&#187; para garantizar su aprobaci\u00f3n","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El ministro de Econom\u00eda de Argentina, Luis Caputo, anunci\u00f3 la exclusi\u00f3n del cap\u00edtulo fiscal del proyecto de Ley de Bases y Puntos de Partida para la Libertad de los Argentinos o \u201cley \u00f3mnibus\u201d para, seg\u00fan dijo, favorecer su aprobaci\u00f3n en el Congreso luego de varias semanas de debate\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444803,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/02\/02\/que-es-la-ley-omnibus-en-argentina-y-que-podria-pasar-en-la-votacion\/","url_meta":{"origin":1448701,"position":4},"title":"\u00bfQu\u00e9 es la \u201cley \u00f3mnibus\u201d en Argentina y qu\u00e9 podr\u00eda pasar en la votaci\u00f3n?","author":"","date":"febrero 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La ley m\u00e1s importante del Gobierno del presidente de Argentina, Javier Milei. 664 art\u00edculos con reformas profundas. Sesiones extraordinarias en el Congreso. Negociaciones pol\u00edticas para favorecer su aprobaci\u00f3n. Rechazo del peronismo. Reuniones con gobernadores. B\u00fasqueda de apoyo en los bloques de la oposici\u00f3n \u201cdialoguista\u201d. Cambios. Qued\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448700,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/que-es-ley-de-bases-congreso-argentino-cambios-orix\/","url_meta":{"origin":1448701,"position":5},"title":"\u00bfQu\u00e9 es el proyecto de Ley de Bases que se debate en el Congreso argentino, qu\u00e9 cambios busca y qu\u00e9 tiene que pasar para que se apruebe?","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN) --\u00a0 Lejos quedaron las sesiones extraordinarias que hab\u00eda convocado el Gobierno entre enero y febrero para tratar la \"Ley de Bases y Puntos de Partida para la Libertad de los argentinos\" que el oficialismo hab\u00eda presentado en los primeros d\u00edas de gesti\u00f3n.Lejos tambi\u00e9n quedaron aquellos 664 art\u00edculos originales. Este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448701"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448701\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}