{"id":1448715,"date":"2024-04-30T19:03:51","date_gmt":"2024-05-01T02:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/"},"modified":"2024-04-30T19:03:51","modified_gmt":"2024-05-01T02:03:51","slug":"mamografias-cancer-mama-pruebas-deteccion-guia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/","title":{"rendered":"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos"},"content":{"rendered":"<p>(CNN) &#8212; Ahora se recomienda a las mujeres que se hagan una mamograf\u00eda cada dos a\u00f1os a partir de los 40 a\u00f1os y hasta los 74 a\u00f1os, seg\u00fan nuevas recomendaciones del Grupo de Trabajo de Servicios Preventivos de EE.UU. (USPSTF, por sus siglas en ingl\u00e9s).<\/p>\n<p>El USPSTF, un panel voluntario de expertos m\u00e9dicos independientes cuyas recomendaciones ayudan a guiar las decisiones de los m\u00e9dicos e influir en los planes de seguro, recomend\u00f3 anteriormente que las mamograf\u00edas bienales comiencen a los 50 a\u00f1os y que la decisi\u00f3n de las mujeres de hacerse las pruebas a los 40 a\u00f1os \u201cdeber\u00eda ser individual\u201d.<\/p>\n<p>Estas nuevas recomendaciones, publicadas el martes en la revista m\u00e9dica JAMA, reemplazan las recomendaciones del grupo de trabajo de 2016. Algunos grupos, como la Sociedad Estadounidense del C\u00e1ncer, ya han recomendado que las mujeres comiencen a hacerse mamograf\u00edas a los 40 a\u00f1os.<\/p>\n<p>Las recomendaciones actualizadas del USPSTF se aplican a todas las mujeres asignadas al nacer, incluidas las mujeres cisg\u00e9nero, los hombres transg\u00e9nero y las personas no binarias con riesgo promedio de c\u00e1ncer de mama, as\u00ed como aquellas con antecedentes familiares de c\u00e1ncer de mama o senos densos.<\/p>\n<p>Estos son los ex\u00e1menes para la detecci\u00f3n temprana del c\u00e1ncer<\/p>\n<p>Las recomendaciones actualizadas no se aplican a personas con antecedentes personales de c\u00e1ncer de mama, un marcador gen\u00e9tico o s\u00edndrome que pueda ponerlas en alto riesgo de c\u00e1ncer de mama, como los genes BRCA1 o BRCA2, o aquellos con antecedentes de dosis altas de radioterapia en el pecho o antecedentes de lesiones mamarias de alto riesgo. Esas pacientes deben seguir el plan descrito por su m\u00e9dico o hablar con su especialista en salud sobre qu\u00e9 es lo mejor para ellas.<\/p>\n<p>&#171;Hacemos esta nueva recomendaci\u00f3n actualizada porque la ciencia m\u00e1s reciente muestra claramente que comenzar a los 40 a\u00f1os y obtener una mamograf\u00eda cada dos a\u00f1os hasta los 74 a\u00f1os puede reducir a\u00fan m\u00e1s las muertes por c\u00e1ncer de mama&#187;, dijo la presidenta del USPSTF, la Dra. Wanda Nicholson, decana asociada principal y profesor de la Escuela de Salud P\u00fablica del Instituto Milken de la Universidad George Washington.<\/p>\n<p>El beneficio de la detecci\u00f3n del c\u00e1ncer de mama es que puede ayudar a diagnosticar los casos de forma temprana, antes de que el c\u00e1ncer se propague, lo que reduce el riesgo de morir a causa de la enfermedad.<\/p>\n<p>El c\u00e1ncer de mama es el segundo c\u00e1ncer m\u00e1s com\u00fan en las mujeres en Estados Unidos, despu\u00e9s del c\u00e1ncer de piel, y es la segunda causa de muerte por c\u00e1ncer, despu\u00e9s del c\u00e1ncer de pulm\u00f3n.<\/p>\n<p>&#171;Podemos salvar a\u00fan m\u00e1s vidas (hasta casi un 20 % m\u00e1s de vidas) con esta estrategia actualizada&#187;, dijo Nicholson sobre las nuevas recomendaciones.<\/p>\n<p>\u00bfPor qu\u00e9 no realizar pruebas todos los a\u00f1os?<\/p>\n<p>Aproximadamente 1 de cada 8 mujeres desarrollar\u00e1 c\u00e1ncer de mama invasivo a lo largo de su vida, seg\u00fan la Sociedad Estadounidense del C\u00e1ncer, y la mamograf\u00eda (tomar una radiograf\u00eda de la mama) sigue siendo la mejor herramienta para detectar y detectar la enfermedad.<\/p>\n<p>El USPSTF ha recibido algunas cr\u00edticas por recomendar realizar pruebas de detecci\u00f3n cada dos a\u00f1os y no anualmente.<\/p>\n<p>&#171;Utilizando la terminolog\u00eda del USPSTF, la detecci\u00f3n anual es tan &#8216;eficiente&#8217; como la detecci\u00f3n bienal, pero produce mayores reducciones generales en la enfermedad en etapa avanzada y muertes por c\u00e1ncer de mama, y mayores ganancias en a\u00f1os de vida salvados&#187;, dijo la Dra. Wendie Berg, del Facultad de Medicina de la Universidad de Pittsburgh, escribi\u00f3 en un editorial publicado el martes en la revista JAMA Oncology. A\u00f1adi\u00f3 que \u201ces sorprendente\u201d que el USPSTF recomiende una evaluaci\u00f3n bienal en lugar de anual.<\/p>\n<p>\u201cLas recomendaciones actualizadas del USPSTF son un importante paso adelante, pero se quedan cortas. La mamograf\u00eda anual es tan eficiente como la mamograf\u00eda bienal pero con mayores ganancias generales en a\u00f1os de vida salvados\u201d, escribi\u00f3 Berg. &#171;La evaluaci\u00f3n anual es particularmente importante para las mujeres premenop\u00e1usicas, especialmente las mujeres de grupos raciales y \u00e9tnicos minoritarios&#187;.<\/p>\n<p>Olivia Munn revela que le diagnosticaron c\u00e1ncer de mama poco despu\u00e9s de una mamograf\u00eda &#171;normal&#187;<\/p>\n<p>Adem\u00e1s de recomendar pruebas de detecci\u00f3n bienales, existen otras preocupaciones sobre c\u00f3mo el USPSTF hace recomendaciones generales para las personas con riesgo promedio, as\u00ed como para aquellas con antecedentes familiares de c\u00e1ncer de mama o senos densos, dijo Molly Guthrie, vicepresidenta de pol\u00edticas y activismo en la fundaci\u00f3n contra el c\u00e1ncer de mama Susan G. Komen.<\/p>\n<p>Aproximadamente la mitad de las mujeres mayores de 40 a\u00f1os en Estados Unidos tienen tejido mamario denso, seg\u00fan la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s), que el a\u00f1o pasado actualiz\u00f3 las regulaciones de mamograf\u00eda para exigir que todos los centros de detecci\u00f3n de Estados Unidos notifiquen a las pacientes sobre la densidad de sus senos con los resultados de sus mamograf\u00edas.<\/p>\n<p>&#171;Nos sorprendi\u00f3 mucho ver c\u00f3mo desglosaron sus audiencias previstas y no refleja lo que es est\u00e1ndar hoy en cuanto a identificar a las personas que tienen un alto riesgo de c\u00e1ncer de mama&#187;, dijo Guthrie. &#171;Me temo que eso solo enturbiar\u00e1 a\u00fan m\u00e1s las aguas sobre lo que se supone que debe hacer la gente&#187;.<\/p>\n<p>Algunos expertos dicen que las personas con antecedentes familiares directos de c\u00e1ncer de mama o con mamas densas deber\u00edan tener diferentes recomendaciones de detecci\u00f3n, ya que ambos factores se han asociado con un mayor riesgo de desarrollar c\u00e1ncer de mama. Por eso, dijo Guthrie, es mejor que las mujeres conversen con sus m\u00e9dicos sobre sus propios antecedentes m\u00e9dicos y familiares y qu\u00e9 podr\u00eda ser mejor para ellas individualmente.<\/p>\n<p>&#171;Se ha prestado mucha atenci\u00f3n a estos sistemas que existen para evaluar el riesgo de las personas, por lo que al tener esa conversaci\u00f3n con su proveedor, podr\u00e1 determinar su riesgo y el tipo y frecuencia de im\u00e1genes mamarias que necesita&#187;, dijo Guthrie.<\/p>\n<p>\u201cLo bueno y lo malo de las pautas del grupo de trabajo es que est\u00e1n directamente relacionadas con que los planes de salud tengan que cubrir esto sin costo alguno\u201d, dijo. Y al no recomendar las pruebas de detecci\u00f3n anuales, \u201cnos preocupa que la recomendaci\u00f3n actualizada reduzca el acceso y la utilizaci\u00f3n de las pruebas de detecci\u00f3n, lo que significa que veremos, probablemente, un resultado de un mayor diagn\u00f3stico en etapa tard\u00eda, y ah\u00ed es cuando el c\u00e1ncer de mama es m\u00e1s dif\u00edcil de tratar y mucho m\u00e1s caro para el sistema sanitario en su conjunto\u201d.<\/p>\n<p>En su revisi\u00f3n de las investigaciones y los datos publicados, los miembros del USPSTF no encontraron evidencia que respalde la detecci\u00f3n anual, dijo Nicholson.<\/p>\n<p>\u201cActualmente no hay ensayos aleatorios que comparen la detecci\u00f3n anual con la detecci\u00f3n cada dos a\u00f1os. Sin embargo, como parte de nuestra revisi\u00f3n sistem\u00e1tica de la evidencia, que es parte de todos nuestros datos de recomendaciones, encontramos evidencia de que si se comparan las pruebas de detecci\u00f3n cada dos a\u00f1os con las anuales, no se observa un aumento en el diagn\u00f3stico de c\u00e1ncer de mama en etapas posteriores\u201c, dijo Nicholson.<\/p>\n<p>&#171;Cuando analizamos nuestros estudios de modelos para evaluar el equilibrio de beneficios y da\u00f1os, hay un equilibrio de beneficios y da\u00f1os mucho m\u00e1s favorable con las pruebas de detecci\u00f3n cada dos a\u00f1os en comparaci\u00f3n con las pruebas anuales&#187;, dijo. &#171;Con las pruebas de detecci\u00f3n anuales, la tasa de resultados falsos positivos era un 50% mayor&#187;.<\/p>\n<p>Los resultados falsos positivos para el c\u00e1ncer de mama significan que una mamograf\u00eda puede haber sido identificada como anormal cuando no hay c\u00e1ncer presente. Eso puede llevar a que los pacientes necesiten biopsias adicionales, pruebas repetidas y estr\u00e9s psicol\u00f3gico duradero.<\/p>\n<p>\u201cHacerse la prueba cada dos a\u00f1os maximiza el beneficio de la prueba y al mismo tiempo minimiza los da\u00f1os relacionados. Estos da\u00f1os pueden incluir que le digan que podr\u00eda tener c\u00e1ncer cuando no lo tiene, o que le digan que no tiene c\u00e1ncer cuando lo tiene, as\u00ed como recibir un tratamiento que no era necesario\u201d, seg\u00fan una hoja informativa para pacientes de la USPSTF.<\/p>\n<p>El cambio del USPSTF de decir que las mujeres deber\u00edan tomar decisiones de detecci\u00f3n individualizadas a los 40 a\u00f1os a que las mujeres deber\u00edan comenzar a hacerse las pruebas a los 40 a\u00f1os parece alinearse m\u00e1s estrechamente con lo que algunas otras organizaciones han recomendado durante alg\u00fan tiempo.<\/p>\n<p>La Sociedad Estadounidense del C\u00e1ncer recomienda que las mujeres de 40 a 44 a\u00f1os tengan la opci\u00f3n de realizarse una mamograf\u00eda cada a\u00f1o, las mujeres de 45 a 55 a\u00f1os deben hacerse mamograf\u00edas cada a\u00f1o y las mujeres de 55 a\u00f1os o m\u00e1s pueden cambiar a un programa de mamograf\u00edas cada dos a\u00f1os.<\/p>\n<p>\u201cLa decisi\u00f3n de hoy del USPSTF es un cambio fundamental en relaci\u00f3n con la salud de las mujeres y la lucha contra el c\u00e1ncer de mama, reconociendo que las mujeres de 40 a\u00f1os se beneficiar\u00e1n de la mamograf\u00eda y enviando un fuerte mensaje a los m\u00e9dicos remitentes y a las mujeres de que las pruebas de detecci\u00f3n del c\u00e1ncer de mama deben comenzar antes de la edad de 50 a\u00f1os\u201d, dijo en parte en un comunicado la Dra. Karen Knudsen, directora ejecutiva de la Sociedad Estadounidense del C\u00e1ncer.<\/p>\n<p>&#171;La mamograf\u00eda es la piedra angular de nuestra estrategia para detectar esta enfermedad potencialmente mortal en sus etapas iniciales, cuando es m\u00e1s f\u00e1cil tratarla con \u00e9xito&#187;, a\u00f1adi\u00f3 Knudsen. \u201cSin embargo, nos decepciona que las recomendaciones actualizadas de detecci\u00f3n del USPSTF no incluyan a las mujeres mayores de 74 a\u00f1os. Millones de mujeres mayores de 75 a\u00f1os gozan de muy buena salud y se espera que vivan muchos m\u00e1s a\u00f1os durante los cuales su riesgo de c\u00e1ncer de mama siga siendo alto\u201d.<\/p>\n<p>El Colegio Estadounidense de Obstetras y Ginec\u00f3logos recomienda que las mujeres con riesgo promedio de c\u00e1ncer de mama se realicen pruebas de detecci\u00f3n cada uno o dos a\u00f1os a partir de los 40 a\u00f1os, a m\u00e1s tardar a los 50 a\u00f1os. Esas recomendaciones dicen que las pruebas de detecci\u00f3n deben continuar hasta al menos los 75 a\u00f1os.<\/p>\n<p>Beneficios y da\u00f1os de la detecci\u00f3n de c\u00e1ncer de mama<\/p>\n<p>Para ayudar a informar las recomendaciones de detecci\u00f3n actualizadas, los miembros del grupo de trabajo analizaron datos de siete ensayos cl\u00ednicos aleatorios y 13 estudios no aleatorios, as\u00ed como un nuevo estudio de modelado.<\/p>\n<p>&#171;Pudimos analizar el equilibrio entre los beneficios y los da\u00f1os con respecto a la detecci\u00f3n a intervalos y la edad para comenzar a realizar la detecci\u00f3n&#187;, dijo Nicholson.<\/p>\n<p>Los miembros del USPSTF descubrieron que la detecci\u00f3n bienal del c\u00e1ncer de mama en mujeres de 40 a 74 a\u00f1os ten\u00eda el beneficio de reducir el riesgo de morir por c\u00e1ncer de mama. Pero la evidencia fue insuficiente para determinar el equilibrio entre los beneficios y los da\u00f1os de la detecci\u00f3n en mujeres de 75 a\u00f1os o m\u00e1s. El grupo de trabajo tambi\u00e9n encontr\u00f3 que la evidencia era insuficiente para evaluar los beneficios y da\u00f1os de la detecci\u00f3n complementaria en mujeres con senos densos.<\/p>\n<p>La recomendaci\u00f3n actualizada incluye tanto la mamograf\u00eda digital tradicional como la tomos\u00edntesis mamaria digital o \u201cmamograf\u00eda 3D\u201d como enfoques de detecci\u00f3n eficaces.<\/p>\n<p>El USPSTF revisa sus recomendaciones cada cinco a\u00f1os para actualizarlas o reafirmarlas, dijo Nicholson, y el grupo de trabajo tambi\u00e9n busca \u201cconsistentemente\u201d nueva evidencia para informar cualquier actualizaci\u00f3n.<\/p>\n<p>Para las nuevas recomendaciones, el USPSTF encontr\u00f3 &#171;evidencia clara&#187; que mostraba que &#171;la incidencia de c\u00e1nceres de mama invasivos en mujeres de 40 a 49 a\u00f1os hab\u00eda aumentado aproximadamente un 2% cada a\u00f1o&#187;, dijo Nicholson.<\/p>\n<p>Sara Sidner, presentadora de CNN, anuncia que tiene c\u00e1ncer de mama<\/p>\n<p>&#171;Cada vez a m\u00e1s mujeres de 40 a\u00f1os se les diagnosticaba c\u00e1ncer de mama invasivo&#187;, dijo. \u201cY por primera vez tambi\u00e9n tuvimos datos sobre las mujeres negras, y sabemos que las mujeres negras tienen casi un 40% m\u00e1s de probabilidades de morir de c\u00e1ncer de mama en comparaci\u00f3n con las mujeres blancas. As\u00ed que estos eran datos de observaci\u00f3n importantes y actualizados que ten\u00edamos y que proporcionaron datos de entrada para nuestros estudios de modelado colaborativo\u201d.<\/p>\n<p>Las recomendaciones actualizadas del USPSTF se\u00f1alan que existen \u201cinequidades pronunciadas\u201d en el c\u00e1ncer de mama, y que las mujeres negras, en comparaci\u00f3n con las mujeres blancas, tienen m\u00e1s probabilidades de ser diagnosticadas en etapas avanzadas y m\u00e1s probabilidades de morir, a pesar de tener menos probabilidades de ser diagnosticadas con la enfermedad en general.<\/p>\n<p>El grupo de trabajo pidi\u00f3 una \u201cinvestigaci\u00f3n rigurosa\u201d para comprender mejor estas desigualdades e identificar formas de abordarlas.<\/p>\n<p>\u201cRealmente necesitamos investigaciones que nos ayuden a comprender mejor la causa subyacente de por qu\u00e9 las mujeres negras pueden tener c\u00e1nceres m\u00e1s agresivos en comparaci\u00f3n con otras mujeres. Puede ser una combinaci\u00f3n de exposici\u00f3n ambiental y determinantes sociales de la salud\u201d, dijo Nicholson.<\/p>\n<p>\u201cEn segundo lugar, necesitamos saber m\u00e1s sobre c\u00f3mo abordar estas disparidades. En otras palabras, lo que est\u00e1 sucediendo dentro de nuestro sistema de atenci\u00f3n m\u00e9dica\u201d, dijo. \u201cEn tercer lugar, necesitamos m\u00e1s estudios sobre cu\u00e1l es el mejor intervalo de detecci\u00f3n para las mujeres negras. La ciencia actual muestra que las mujeres negras tambi\u00e9n deber\u00edan comenzar a los 40 a\u00f1os y continuar cada dos a\u00f1os hasta los 74 a\u00f1os. Pero creo que necesitamos estudios adicionales para determinar si existen diferentes estrategias de detecci\u00f3n que ser\u00edan m\u00e1s \u00fatiles para las mujeres negras\u201d.<\/p>\n<p>Las recomendaciones revisadas del USPSTF arrojan luz sobre dos cuestiones principales: abordar las desigualdades sanitarias en el c\u00e1ncer de mama y garantizar que todas las mujeres puedan beneficiarse de los avances realizados en las tecnolog\u00edas de detecci\u00f3n, afirm\u00f3 la Dra. Joann Elmore, de la Facultad de Medicina David Geffen de la Universidad de California, en Los \u00c1ngeles, y el Dr. Christoph Lee de la Facultad de Medicina de la Universidad de Washington, escribieron en un editorial conjunto publicado el martes en la revista JAMA.<\/p>\n<p>\u201cFomentar la detecci\u00f3n precoz a partir de los 40 a\u00f1os representa solo una faceta del proceso continuo de atenci\u00f3n mamaria. Estos supuestos incluyen que las mujeres accedan a centros de detecci\u00f3n con tecnolog\u00eda actualizada, reciban evaluaciones diagn\u00f3sticas r\u00e1pidas y accedan a tratamientos definitivos de alta calidad, una realidad que no siempre se cumple, en particular para las personas que pertenecen a grupos y comunidades que tradicionalmente carecen de servicios y recursos\u201d, escribieron Elmore y Lee.<\/p>\n<p>&#171;En general, las recomendaciones actualizadas del USPSTF resaltan una intersecci\u00f3n de tecnolog\u00eda y equidad en r\u00e1pida evoluci\u00f3n dentro de un ecosistema de atenci\u00f3n m\u00e9dica ya complejo en el que las disparidades siguen siendo un problema persistente&#187;, escribieron. &#171;Es importante que los m\u00e9dicos contin\u00faen practicando el arte de la medicina para garantizar que las mujeres tomen decisiones informadas y alineadas con sus preferencias&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Ahora se recomienda a las mujeres que se hagan una mamograf\u00eda cada dos a\u00f1os a partir de los 40 a\u00f1os y hasta los 74 a\u00f1os, seg\u00fan nuevas recomendaciones del Grupo de Trabajo de Servicios Preventivos de EE.UU. (USPSTF, por sus siglas en ingl\u00e9s). El USPSTF, un panel voluntario de expertos m\u00e9dicos independientes cuyas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448715","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Ahora se recomienda a las mujeres que se hagan una mamograf\u00eda cada dos a\u00f1os a partir de los 40 a\u00f1os y hasta los 74 a\u00f1os, seg\u00fan nuevas recomendaciones del Grupo de Trabajo de Servicios Preventivos de EE.UU. (USPSTF, por sus siglas en ingl\u00e9s). El USPSTF, un panel voluntario de expertos m\u00e9dicos independientes cuyas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T02:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos\",\"datePublished\":\"2024-05-01T02:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/\"},\"wordCount\":2663,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/\",\"name\":\"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-01T02:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos - Noticias","og_description":"(CNN) &#8212; Ahora se recomienda a las mujeres que se hagan una mamograf\u00eda cada dos a\u00f1os a partir de los 40 a\u00f1os y hasta los 74 a\u00f1os, seg\u00fan nuevas recomendaciones del Grupo de Trabajo de Servicios Preventivos de EE.UU. (USPSTF, por sus siglas en ingl\u00e9s). El USPSTF, un panel voluntario de expertos m\u00e9dicos independientes cuyas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-01T02:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/"},"author":{"name":"","@id":""},"headline":"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos","datePublished":"2024-05-01T02:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/"},"wordCount":2663,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/","name":"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-01T02:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mujeres deber\u00edan comenzar a hacerse mamograf\u00edas a los 40 a\u00f1os, indica gu\u00eda actualizada de expertos","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/30\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-01T02:03:51Z","datePublished":"2024-05-01T02:03:51Z","dateModified":"2024-05-01T02:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mujeres deber\\u00edan comenzar a hacerse mamograf\\u00edas a los 40 a\\u00f1os, indica gu\\u00eda actualizada de expertos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/30\\\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/04\\\/30\\\/mamografias-cancer-mama-pruebas-deteccion-guia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-01T02:03:51Z\",\"datePublished\":\"2024-05-01T02:03:51Z\",\"dateModified\":\"2024-05-01T02:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456450,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/10\/prueba-vph-papanicolaou-deteccion-cancer-trax\/","url_meta":{"origin":1448715,"position":0},"title":"La prueba del VPH es preferible a la de Papanicolaou para la detecci\u00f3n del c\u00e1ncer de cuello uterino, seg\u00fan estudio preliminar","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"Realizarse pruebas de detecci\u00f3n del virus del papiloma humano de alto riesgo cada cinco a\u00f1os \u2014incluso con una muestra recolectada por la propia mujer\u2014 es la \u201cestrategia de detecci\u00f3n preferida\u201d para el c\u00e1ncer de cuello uterino a partir de los 30 a\u00f1os, seg\u00fan un nuevo estudio preliminar de recomendaci\u00f3n del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464876,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/26\/rfk-destituir-panel-expertos-salud-preventiva-trax\/","url_meta":{"origin":1448715,"position":1},"title":"Secretario de Salud de EE.UU. planea destituir al panel de expertos en atenci\u00f3n preventiva, seg\u00fan el Wall Street Journal","author":"","date":"julio 26, 2025","format":false,"excerpt":"El secretario de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy Jr., planea destituir a los asesores expertos que conforman un panel federal sobre atenci\u00f3n preventiva, inform\u00f3 este viernes el Wall Street Journal.El futuro del Grupo de Trabajo de Servicios Preventivos de EE.UU. (USPSTF, por sus siglas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456710,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/18\/vitamina-d-caidas-fracturas-adultos-mayores-que-puede-ayudar-trax\/","url_meta":{"origin":1448715,"position":2},"title":"La popular vitamina D no previene ca\u00eddas ni fracturas en adultos mayores, dicen expertos. \u00bfQu\u00e9 puede ayudar?","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"La vitamina D y el calcio son esenciales para la salud en general, pero no reducen el riesgo de ca\u00eddas o fracturas en adultos mayores generalmente sanos, seg\u00fan un nuevo proyecto de recomendaci\u00f3n del Grupo de Trabajo de Servicios Preventivos de Estados Unidos (USPSTF, por sus siglas en ingl\u00e9s).Cuando se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461427,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/04\/20\/trump-obamacare-corte-suprema-influencia-robert-f-kennedy-trax\/","url_meta":{"origin":1448715,"position":3},"title":"Trump defiende Obamacare en la Corte Suprema; una victoria podr\u00eda aumentar la influencia de Robert F. Kennedy","author":"","date":"abril 20, 2025","format":false,"excerpt":"El Departamento de Justicia del presidente Donald Trump defiende la Ley del cuidado de salud a bajo precio, conocida como Obamacare, ante la Corte Suprema, un notable contraste con su primer mandato, cuando su Gobierno busc\u00f3 derogar la ley en el Congreso y luego se neg\u00f3 a defenderla en un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451533,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/07\/31\/estudio-riesgo-cancer-millennials-generacion-x-trax\/","url_meta":{"origin":1448715,"position":4},"title":"Los millennials y la generaci\u00f3n X corren m\u00e1s riesgo de padecer 17 tipos de c\u00e1ncer que las generaciones anteriores, seg\u00fan un estudio","author":"","date":"julio 31, 2024","format":false,"excerpt":"(CNN) -- A medida que aumentan los casos de c\u00e1ncer entre los adultos j\u00f3venes en Estados Unidos, un nuevo estudio ha identificado 17 tipos de c\u00e1ncer que parecen ser m\u00e1s comunes en la Generaci\u00f3n X y los millennials que en los grupos de mayor edad.Entre los adultos nacidos entre 1920\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462967,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/29\/cambios-politica-vacuna-contra-covid-19-ee-uu-pueden-afectarte-trax\/","url_meta":{"origin":1448715,"position":5},"title":"\u00bfC\u00f3mo pueden afectarte los cambios en la pol\u00edtica de la vacuna contra el covid-19 en EE.UU.?","author":"","date":"mayo 29, 2025","format":false,"excerpt":"El Departamento de Salud y Servicios Humanos de EE.UU., bajo la direcci\u00f3n del secretario Robert F. Kennedy Jr., ha realizado recientemente cambios significativos en la forma en que se aprueban las vacunas contra el covid-19 y los grupos para los cuales se recomiendan.Durante los \u00faltimos a\u00f1os, el Gobierno federal ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448715"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448715\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}