{"id":1448788,"date":"2024-05-02T15:03:42","date_gmt":"2024-05-02T22:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/"},"modified":"2024-05-02T15:03:42","modified_gmt":"2024-05-02T22:03:42","slug":"moon-sniper-japon-modulo-alunizaje-imagenes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/","title":{"rendered":"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &#171;d\u00eda&#187; lunar"},"content":{"rendered":"<p>(CNN) &#8212; El m\u00f3dulo de alunizaje japon\u00e9s &#171;Moon Sniper&#187; volvi\u00f3 a desafiar los pron\u00f3sticos, sobreviviendo a otra larga y g\u00e9lida noche lunar a pesar de no haber sido dise\u00f1ado para soportar condiciones tan duras, seg\u00fan la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n.<\/p>\n<p>Las temperaturas durante la noche lunar pueden descender hasta los 208 \u00b0F bajo cero (133 \u00b0C bajo cero), seg\u00fan la NASA. Y no se esperaba que Moon Sniper resistiera siquiera una noche lunar, que es un periodo de oscuridad en la Luna que dura unas dos semanas.<\/p>\n<p>El veh\u00edculo rob\u00f3tico, tambi\u00e9n conocido como SLIM (Smart Lander for Investigating Moon), aterriz\u00f3 en la superficie lunar el 19 de enero. La hist\u00f3rica haza\u00f1a convirti\u00f3 a Jap\u00f3n en el tercer pa\u00eds de este siglo, y el quinto de la historia, en alunizar. La nave aterriz\u00f3 cerca del cr\u00e1ter Shioli, situado a unos 322 kil\u00f3metros al sur del Mar de la Tranquilidad, una regi\u00f3n cercana al ecuador lunar, donde el Apolo 11 aluniz\u00f3 por primera vez.<\/p>\n<p>Por qu\u00e9 los cient\u00edficos est\u00e1n intrigados por el lugar de alunizaje del Moon Sniper de Jap\u00f3n<\/p>\n<p>Pero las cosas no salieron seg\u00fan lo previsto.<\/p>\n<p>Durante el descenso, la nave experiment\u00f3 una anomal\u00eda y aterriz\u00f3 sobre su parte delantera, lo que significaba que sus paneles solares estaban orientados hacia el oeste en lugar de hacia arriba y no recib\u00edan la luz solar necesaria para generar energ\u00eda. El m\u00f3dulo de aterrizaje solo tuvo energ\u00eda suficiente para enviar un mosaico de im\u00e1genes antes de apagarse. El equipo de la misi\u00f3n en Jap\u00f3n mantiene la esperanza de que, una vez que la luz solar llegue de nuevo a los paneles solares, la nave vuelva a funcionar.<\/p>\n<p>Hasta ahora, el Moon Sniper, que se gan\u00f3 su apodo por la tecnolog\u00eda de precisi\u00f3n que le permiti\u00f3 aterrizar a unos 55 metros de su objetivo, sigue sorprendiendo gratamente al equipo al activarse despu\u00e9s de cada noche lunar, tomando nuevas fotos y transmiti\u00e9ndolas antes de volver a dormirse. La resistencia del veh\u00edculo frente a las condiciones lunares extremas es \u00fanica entre las misiones que han aterrizado en la Luna en el \u00faltimo a\u00f1o, y los expertos tienen un par de ideas de por qu\u00e9 podr\u00eda ser.<\/p>\n<p>Sobrellevar la noche lunar<\/p>\n<p>El equipo de la misi\u00f3n se comunic\u00f3 con el Moon Sniper el 23 de abril, despu\u00e9s de que el m\u00f3dulo superara su tercera noche lunar. La nave pudo transmitir m\u00e1s im\u00e1genes de su lugar de aterrizaje.<\/p>\n<p>&#171;SLIM ha mantenido su funcionalidad principal incluso despu\u00e9s de 3 noches en la Luna, algo que no estaba previsto en el dise\u00f1o&#187;, comparti\u00f3 el equipo en X, antes Twitter.<\/p>\n<p>Moon Sniper tom\u00f3 una nueva imagen de su lugar de aterrizaje, que aparece brillante durante el d\u00eda lunar. Cr\u00e9dito: JAXA<\/p>\n<p>Adem\u00e1s de sobrevivir al fr\u00edo extremo de la noche lunar, Moon Sniper tambi\u00e9n ha soportado las temperaturas abrasadoras del d\u00eda lunar, que pueden alcanzar los 250 \u00b0F (121 \u00b0C), seg\u00fan la NASA.<\/p>\n<p>El equipo se\u00f1al\u00f3 que est\u00e1 supervisando de cerca el estado de SLIM para identificar qu\u00e9 componentes de la nave espacial podr\u00edan deteriorarse con el tiempo a medida que experimenta m\u00e1s el entorno lunar diurno y nocturno.<\/p>\n<p>Los ingenieros de JAXA han tenido mucho cuidado con la forma en que se comunican con SLIM cuando se despierta por primera vez, ya que la nave est\u00e1 funcionando a temperaturas muy altas, lo que podr\u00eda calentar las c\u00e1maras y da\u00f1arlas. Por ello, el equipo de la misi\u00f3n suele esperar aproximadamente un d\u00eda desde que SLIM se despierta antes de ordenarle que env\u00ede im\u00e1genes.<\/p>\n<p>Hasta ahora, una de las c\u00e1maras de navegaci\u00f3n de SLIM y el Star Tracker de la nave han proporcionado im\u00e1genes de la experiencia de Moon Sniper en la superficie lunar. El Star Tracker no es una c\u00e1mara propiamente dicha, sino que se utiliz\u00f3 para medir la direcci\u00f3n de la nave espacial mediante el seguimiento de la alineaci\u00f3n de las estrellas a medida que el m\u00f3dulo de aterrizaje se desplazaba hacia la Luna. Pero el equipo ha tomado medidas inteligentes para sacar el m\u00e1ximo partido del alunizaje de Moon Sniper.<\/p>\n<p>La nave Moon Sniper de Jap\u00f3n revela im\u00e1genes \u00fanicas de la Luna<\/p>\n<p>&#171;Originalmente no estaba previsto que se utilizara en la superficie lunar, pero en principio puede tomar fotos como una c\u00e1mara, lo que llev\u00f3 a su funcionamiento a trav\u00e9s de &#8216;comandos secretos'&#187;, comparti\u00f3 la agencia en X.<\/p>\n<p>La nave cuenta con dos c\u00e1maras de navegaci\u00f3n montadas en distintas direcciones. Teniendo en cuenta c\u00f3mo aterriz\u00f3 Moon Sniper, una de esas c\u00e1maras est\u00e1 orientada hacia el espacio, pero la otra tiene una vista del lugar de aterrizaje desde la perspectiva de la nave.<\/p>\n<p>El Star Tracker de la nave tom\u00f3 una imagen sobreexpuesta de la ladera norte. Cr\u00e9dito: JAXA<\/p>\n<p>El sol ha vuelto a ponerse cerca del cr\u00e1ter Shioli, y Moon Sniper entr\u00f3 de nuevo en hibernaci\u00f3n el 29 de abril, seg\u00fan la agencia.<\/p>\n<p>&#171;Planeamos intentar reanudar la operaci\u00f3n de nuevo a mediados o finales de mayo, cuando las celdas solares de SLIM empiecen a generar electricidad. Apreciamos su continuo apoyo&#187;, comparti\u00f3 la agencia en X mientras Moon Sniper se iba a dormir una vez m\u00e1s.<\/p>\n<p>Los miembros del equipo de la misi\u00f3n compusieron recientemente una canci\u00f3n en honor al inspirador viaje de Moon Sniper a la que llaman &#171;15 Degree Slope&#187;. La canci\u00f3n abarca cada paso de la sorprendente misi\u00f3n, desde el lanzamiento y el viaje a la Luna hasta el inesperado aterrizaje y &#171;el despertar de la resurrecci\u00f3n&#187;, seg\u00fan compartieron los miembros del equipo en X.<\/p>\n<p>La canci\u00f3n toma prestado su nombre de la empinada ladera en la que Moon Sniper deb\u00eda alunizar. Ahora, el equipo de la misi\u00f3n cree que la pendiente en la que aluniz\u00f3 Moon Sniper era de unos 10 grados, lo que sigue siendo &#171;sorprendentemente empinada&#187;.<\/p>\n<p>Historia de dos alunizajes<\/p>\n<p>En febrero, la empresa de exploraci\u00f3n espacial Intuitive Machines, con sede en Houston, aluniz\u00f3 con su misi\u00f3n IM-1, tambi\u00e9n conocida como Odysseus, en el polo sur lunar, convirti\u00e9ndose as\u00ed en la primera nave espacial comercial en alunizar y en el primer veh\u00edculo de fabricaci\u00f3n estadounidense en alcanzar la superficie lunar desde el Apolo 17 en 1972. Pero, al igual que SLIM, la misi\u00f3n &#171;Odie&#187; experiment\u00f3 una especie de monta\u00f1a rusa lunar que incluy\u00f3 tener que depender de tecnolog\u00eda experimental para tocar tierra y, en \u00faltima instancia, aterrizar de lado.<\/p>\n<p>El 29 de febrero, tras siete d\u00edas de funcionamiento, Odie se fue a dormir porque no estaba previsto que sobreviviera a la noche lunar. El equipo de Intuitive Machines estuvo atento por si Odie despertaba en marzo, pero la nave no volvi\u00f3 a comunicarse.<\/p>\n<p>&#171;Odie se dise\u00f1\u00f3 solo para soportar sus cargas \u00fatiles, ninguna de las cuales era capaz de soportar la noche lunar, as\u00ed que no lo dise\u00f1amos para m\u00e1s&#187;, explica Jack Fischer, exastronauta de la NASA y vicepresidente de producci\u00f3n y operaciones de Intuitive Machines. &#171;Hay medidas que podr\u00edamos haber tomado para permitir que potencialmente durara m\u00e1s, pero est\u00e1bamos centrados en el apoyo econ\u00f3mico y r\u00e1pido de nuestras cargas \u00fatiles, en contraposici\u00f3n a una misi\u00f3n patrocinada por un estado-naci\u00f3n&#187;.<\/p>\n<p>&#171;20 minutos de terror&#187;: lo que podemos esperar del hist\u00f3rico intento de alunizaje de Jap\u00f3n con la nave &#171;Moon Sniper&#187;<\/p>\n<p>El hecho de que Odie aterrizara cerca del polo sur de la Luna, mientras que SLIM lo hizo cerca del ecuador, podr\u00eda afectar a su supervivencia de la noche lunar, dijo Fischer.<\/p>\n<p>&#171;Sigue dependiendo del terreno, pero en el ecuador suele haber menos problemas con las sombras y la generaci\u00f3n de energ\u00eda solar es m\u00e1s productiva (debido a los mayores \u00e1ngulos de incidencia) que la que experiment\u00f3 Odie en el Polo Sur&#187;, explic\u00f3.<\/p>\n<p>Otros factores que podr\u00edan aumentar la capacidad de supervivencia son mantener una bater\u00eda qu\u00edmica protegida y funcionando a temperaturas extremas y un dise\u00f1o que pueda alimentar de energ\u00eda solar directamente al sistema de energ\u00eda, dos cosas que podr\u00edan implementarse en el futuro.<\/p>\n<p>&#171;Sobrevivir a la noche es fundamental para cualquier esfuerzo por construir una infraestructura significativa en la Luna, e IM est\u00e1 trabajando en una serie de opciones con experimentos tan pronto como nuestra misi\u00f3n IM-3&#187;, dijo Fischer. &#171;Nuestro objetivo es, en primer lugar, &#8216;sobrevivir&#8217; a la noche, en la que la nave espacial entra en una especie de hibernaci\u00f3n (como ha hecho SLIM) y se despierta al otro lado. En \u00faltima instancia, queremos &#8216;prosperar&#8217; durante la noche, y eso es precisamente lo que estamos haciendo con nuestro programa Veh\u00edculo Lunar Terrestre, en el que el veh\u00edculo puede realizar un trabajo significativo durante la noche lunar&#187;.<\/p>\n<p>Fischer felicit\u00f3 a JAXA por el \u00e9xito de su misi\u00f3n.<\/p>\n<p>&#171;Aunque no soy un experto en el dise\u00f1o de su veh\u00edculo, es toda una haza\u00f1a que su nave espacial haya sobrevivido tres noches lunares, sin importar las circunstancias&#187;, dijo Fischer.<\/p>\n<p>Una carrera hacia la Luna<\/p>\n<p>El \u00e9xito de Jap\u00f3n con Moon Sniper no es m\u00e1s que una entrada en una renovada carrera por alunizar que se ha desarrollado en los \u00faltimos a\u00f1os.<\/p>\n<p>India se convirti\u00f3 en el cuarto pa\u00eds en aterrizar con una misi\u00f3n rob\u00f3tica en la Luna en agosto de 2023, cuando la misi\u00f3n Chandrayaan-3 aterriz\u00f3 cerca del polo sur lunar. El m\u00f3dulo de aterrizaje Vikram y el rover de seis ruedas Pragyan que despleg\u00f3 estudiaron la Luna durante casi dos semanas antes de apagarse durante la noche lunar, pero los intentos de volver a despertarlos fueron infructuosos.<\/p>\n<p>El impulso de la exploraci\u00f3n lunar contin\u00faa, ya que China pretende alunizar una misi\u00f3n de recogida de muestras en la cara oculta de la Luna, es decir, la que da la espalda a la Tierra, y la NASA pretende establecer una presencia humana sostenida en el polo sur lunar a trav\u00e9s de su ambicioso programa Artemis.<\/p>\n<p>Primero en CNN: se espera que la NASA anuncie un &#171;retraso de meses&#187; para la misi\u00f3n lunar tripulada Artemis<\/p>\n<p>El \u00e9xito continuado de Moon Sniper llega durante lo que Noah Petro, cient\u00edfico del proyecto de la NASA tanto para el Lunar Reconnaissance Orbiter como para Artemis III, llama una &#171;gran nueva era de exploraci\u00f3n lunar&#187;.<\/p>\n<p>Seis de las revolucionarias misiones Apolo devolvieron muestras lunares de diferentes lugares de alunizaje, pero todas ellas se encontraban en la cara oculta de la Luna. Explorar nuevas regiones lunares proporciona nuevas ventanas para comprender el sat\u00e9lite de la Tierra.<\/p>\n<p>&#171;Para m\u00ed es una gran alegr\u00eda ver aterrizar misiones en la superficie lunar&#187;, afirma Petro. &#171;Cada vez que aterrizamos en la superficie, aprendemos m\u00e1s sobre este entorno lunar \u00fanico en el que nos estamos metiendo. Construir esta base de datos de conocimientos lunares sobre lo que significa estar y trabajar en la superficie de la Luna nos ayuda a estar mejor preparados para las misiones Artemis&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El m\u00f3dulo de alunizaje japon\u00e9s &#171;Moon Sniper&#187; volvi\u00f3 a desafiar los pron\u00f3sticos, sobreviviendo a otra larga y g\u00e9lida noche lunar a pesar de no haber sido dise\u00f1ado para soportar condiciones tan duras, seg\u00fan la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n. Las temperaturas durante la noche lunar pueden descender hasta los 208 \u00b0F bajo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448788","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &quot;d\u00eda&quot; lunar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &quot;d\u00eda&quot; lunar - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El m\u00f3dulo de alunizaje japon\u00e9s &#171;Moon Sniper&#187; volvi\u00f3 a desafiar los pron\u00f3sticos, sobreviviendo a otra larga y g\u00e9lida noche lunar a pesar de no haber sido dise\u00f1ado para soportar condiciones tan duras, seg\u00fan la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n. Las temperaturas durante la noche lunar pueden descender hasta los 208 \u00b0F bajo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T22:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &#171;d\u00eda&#187; lunar\",\"datePublished\":\"2024-05-02T22:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/\"},\"wordCount\":1938,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/\",\"name\":\"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo \\\"d\u00eda\\\" lunar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-02T22:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &#171;d\u00eda&#187; lunar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo \"d\u00eda\" lunar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo \"d\u00eda\" lunar - Noticias","og_description":"(CNN) &#8212; El m\u00f3dulo de alunizaje japon\u00e9s &#171;Moon Sniper&#187; volvi\u00f3 a desafiar los pron\u00f3sticos, sobreviviendo a otra larga y g\u00e9lida noche lunar a pesar de no haber sido dise\u00f1ado para soportar condiciones tan duras, seg\u00fan la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n. Las temperaturas durante la noche lunar pueden descender hasta los 208 \u00b0F bajo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-02T22:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/"},"author":{"name":"","@id":""},"headline":"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &#171;d\u00eda&#187; lunar","datePublished":"2024-05-02T22:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/"},"wordCount":1938,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/","name":"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo \"d\u00eda\" lunar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-02T22:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &#171;d\u00eda&#187; lunar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Moon Sniper de Jap\u00f3n sigue desconcertando a los expertos. El m\u00f3dulo de alunizaje comparti\u00f3 im\u00e1genes de su \u00faltimo &#171;d\u00eda&#187; lunar","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/02\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-02T22:03:42Z","datePublished":"2024-05-02T22:03:42Z","dateModified":"2024-05-02T22:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Moon Sniper de Jap\\u00f3n sigue desconcertando a los expertos. El m\\u00f3dulo de alunizaje comparti\\u00f3 im\\u00e1genes de su \\u00faltimo &#171;d\\u00eda&#187; lunar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/05\\\/02\\\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/05\\\/02\\\/moon-sniper-japon-modulo-alunizaje-imagenes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-02T22:03:42Z\",\"datePublished\":\"2024-05-02T22:03:42Z\",\"dateModified\":\"2024-05-02T22:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1444074,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/18\/la-agencia-de-exploracion-aeroespacial-de-japon-se-prepara-para-20-minutos-de-terror-por-intento-de-alunizaje-de-su-nave-slim\/","url_meta":{"origin":1448788,"position":0},"title":"La Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n se prepara para &#171;20 minutos de terror&#187; por intento de alunizaje de su nave SLIM","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN) -- Mientras la primera misi\u00f3n estadounidense de alunizaje en d\u00e9cadas finaliza sin alcanzar su objetivo, una nave espacial lanzada por Jap\u00f3n se acerca a la Luna y se prepara para un intento hist\u00f3rico de alunizaje.Se espera que el Smart Lander for Investigating Moon (SLIM) de la Agencia de Exploraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444522,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/27\/por-que-los-cientificos-estan-intrigados-por-el-lugar-de-alunizaje-del-moon-sniper-de-japon-2\/","url_meta":{"origin":1448788,"position":1},"title":"Por qu\u00e9 los cient\u00edficos est\u00e1n intrigados por el lugar de alunizaje del Moon Sniper de Jap\u00f3n","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN) -- El viaje de \"Moon Sniper\", el explorador rob\u00f3tico que ha convertido a Jap\u00f3n en el quinto pa\u00eds en colocar una nave espacial de forma segura en la superficie lunar, no ha ido como se esperaba.Aunque la misi\u00f3n, oficialmente conocida como Smart Lander for Investigating Moon, o SLIM, lleg\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444516,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/27\/por-que-los-cientificos-estan-intrigados-por-el-lugar-de-alunizaje-del-moon-sniper-de-japon\/","url_meta":{"origin":1448788,"position":2},"title":"Por qu\u00e9 los cient\u00edficos est\u00e1n intrigados por el lugar de alunizaje del Moon Sniper de Jap\u00f3n","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN) -- El viaje de \"Moon Sniper\", el explorador rob\u00f3tico que ha convertido a Jap\u00f3n en el quinto pa\u00eds en colocar una nave espacial de forma segura en la superficie lunar, no ha ido como se esperaba.Aunque la misi\u00f3n, oficialmente conocida como Smart Lander for Investigating Moon, o SLIM, lleg\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444146,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/20\/la-carrera-por-llegar-a-la-luna-que-paises-y-misiones-llegaron-y-cuales-lo-intentaron-2\/","url_meta":{"origin":1448788,"position":3},"title":"La carrera por llegar a la Luna: \u00bfqu\u00e9 pa\u00edses y misiones llegaron y cu\u00e1les lo intentaron?","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Jap\u00f3n hizo historia este viernes al convertirse en el quinto pa\u00eds en aterrizar exitosamente en la Luna con el robot \"Moon Sniper\", aunque es posible que la misi\u00f3n termine prematuramente ya que los paneles solares de la nave espacial no generan electricidad, inform\u00f3 la Agencia de Exploraci\u00f3n Aeroespacial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445937,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/02\/22\/india-cuarto-pais-llegar-luna-que-otros-han-llegado-cuales-lo-han-intentado-datos-misiones-orix\/","url_meta":{"origin":1448788,"position":4},"title":"La carrera por llegar a la Luna: \u00bfqu\u00e9 pa\u00edses y misiones llegaron y cu\u00e1les lo intentaron?","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Jap\u00f3n hizo historia este viernes al convertirse en el quinto pa\u00eds en aterrizar exitosamente en la Luna con el robot \"Moon Sniper\", aunque es posible que la misi\u00f3n termine prematuramente ya que los paneles solares de la nave espacial no generan electricidad, inform\u00f3 la Agencia de Exploraci\u00f3n Aeroespacial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460038,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","url_meta":{"origin":1448788,"position":5},"title":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos","author":"","date":"marzo 17, 2025","format":false,"excerpt":"Firefly Aerospace, la compa\u00f1\u00eda con sede en Texas que realiz\u00f3 un alunizaje impecable con su nave espacial Blue Ghost a principios de este mes, declar\u00f3 finalizada la hist\u00f3rica misi\u00f3n tras alcanzar el 100% de sus objetivos. Esta haza\u00f1a marca la primera operaci\u00f3n comercial completamente exitosa en la Luna, seg\u00fan inform\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448788"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448788\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}