{"id":1448894,"date":"2024-05-05T13:03:50","date_gmt":"2024-05-05T20:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/"},"modified":"2024-05-05T13:03:50","modified_gmt":"2024-05-05T20:03:50","slug":"muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/","title":{"rendered":"Muere Bernard Hill, actor de &#171;Titanic&#187; y &#171;El Se\u00f1or de los Anillos&#187;"},"content":{"rendered":"<p>(CNN) &#8212; El actor brit\u00e1nico Bernard Hill, m\u00e1s conocido por sus papeles de reparto en &#171;Titanic&#187; y la trilog\u00eda de &#171;El Se\u00f1or de los Anillos&#187;, muri\u00f3, anunci\u00f3 su familia este domingo.<\/p>\n<p>&#171;Con la mayor tristeza debemos anunciar que Bernard Hill, renombrado actor conocido por sus papeles en &#8216;Titanic&#8217; y &#8216;El Se\u00f1or de los Anillos&#8217;, falleci\u00f3 esta madrugada a la edad de 79 a\u00f1os&#187;, dijo su familia en un comunicado.<\/p>\n<p>&#171;Estaba con su prometida Alison y su hijo Gabriel&#187;.<\/p>\n<p>Hill alcanz\u00f3 la fama en su pa\u00eds natal protagonizando en 1982 &#171;Boys from the Blackstuff&#187;, un descarnado drama sobre hombres desempleados que se convierte en s\u00edmbolo de la era Thatcher.<\/p>\n<p>FOTOS | Los famosos que han muerto en 2024<\/p>\n<p>Sin embargo, el p\u00fablico lo conoce sobre todo por sus papeles m\u00e1s peque\u00f1os, en los que aport\u00f3 su discreta dignidad a algunas de las pel\u00edculas de m\u00e1s \u00e9xito de la historia del cine.<\/p>\n<p>En &#171;Titanic&#187;, de James Cameron, ganadora de varios Oscar en 1997, Hill interpreta al capit\u00e1n del barco, Edward Smith, un hombre atormentado por su papel en la tragedia y, en \u00faltima instancia, resignado a su destino.<\/p>\n<p>La \u00faltima vez que lo vemos es solo, aferrado al tim\u00f3n del barco, antes de que las aguas irrumpan por las ventanas.<\/p>\n<p>Bernard Hill en &#171;El Retorno del Rey&#187;, de 2003. (Cr\u00e9dito: New Line\/Kobal\/Shutterstock)<\/p>\n<p>Hill apareci\u00f3 m\u00e1s tarde en dos partes de la taquillera serie de Peter Jackson &#171;El Se\u00f1or de los Anillos&#187; como Theoden, rey de Rohan, que en &#171;Las Dos Torres&#187; es manipulado por su consejero antes de convertirse en un l\u00edder heroico en &#171;El Retorno del Rey&#187;.<\/p>\n<p>Otros papeles cinematogr\u00e1ficos fueron &#171;Gandhi&#187;, &#171;Shirley Valentine&#187; y &#171;El Rey Escorpi\u00f3n&#187;.<\/p>\n<p>Su agente Lou Coulson dijo a la agencia de noticias PA que muri\u00f3 en las primeras horas de este domingo. CNN se puso en contacto por separado para hacer comentarios.<\/p>\n<p>En su homenaje, la directora de BBC Drama, Lindsay Salt, dijo que Hill &#171;abri\u00f3 un camino a trav\u00e9s de la pantalla, y su larga carrera llena de papeles ic\u00f3nicos y notables es un testimonio de su incre\u00edble talento&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El actor brit\u00e1nico Bernard Hill, m\u00e1s conocido por sus papeles de reparto en &#171;Titanic&#187; y la trilog\u00eda de &#171;El Se\u00f1or de los Anillos&#187;, muri\u00f3, anunci\u00f3 su familia este domingo. &#171;Con la mayor tristeza debemos anunciar que Bernard Hill, renombrado actor conocido por sus papeles en &#8216;Titanic&#8217; y &#8216;El Se\u00f1or de los Anillos&#8217;, falleci\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448894","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere Bernard Hill, actor de &quot;Titanic&quot; y &quot;El Se\u00f1or de los Anillos&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere Bernard Hill, actor de &quot;Titanic&quot; y &quot;El Se\u00f1or de los Anillos&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El actor brit\u00e1nico Bernard Hill, m\u00e1s conocido por sus papeles de reparto en &#171;Titanic&#187; y la trilog\u00eda de &#171;El Se\u00f1or de los Anillos&#187;, muri\u00f3, anunci\u00f3 su familia este domingo. &#171;Con la mayor tristeza debemos anunciar que Bernard Hill, renombrado actor conocido por sus papeles en &#8216;Titanic&#8217; y &#8216;El Se\u00f1or de los Anillos&#8217;, falleci\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T20:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere Bernard Hill, actor de &#171;Titanic&#187; y &#171;El Se\u00f1or de los Anillos&#187;\",\"datePublished\":\"2024-05-05T20:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/\"},\"wordCount\":394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/\",\"name\":\"Muere Bernard Hill, actor de \\\"Titanic\\\" y \\\"El Se\u00f1or de los Anillos\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-05T20:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere Bernard Hill, actor de &#171;Titanic&#187; y &#171;El Se\u00f1or de los Anillos&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere Bernard Hill, actor de \"Titanic\" y \"El Se\u00f1or de los Anillos\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere Bernard Hill, actor de \"Titanic\" y \"El Se\u00f1or de los Anillos\" - Noticias","og_description":"(CNN) &#8212; El actor brit\u00e1nico Bernard Hill, m\u00e1s conocido por sus papeles de reparto en &#171;Titanic&#187; y la trilog\u00eda de &#171;El Se\u00f1or de los Anillos&#187;, muri\u00f3, anunci\u00f3 su familia este domingo. &#171;Con la mayor tristeza debemos anunciar que Bernard Hill, renombrado actor conocido por sus papeles en &#8216;Titanic&#8217; y &#8216;El Se\u00f1or de los Anillos&#8217;, falleci\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-05T20:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/"},"author":{"name":"","@id":""},"headline":"Muere Bernard Hill, actor de &#171;Titanic&#187; y &#171;El Se\u00f1or de los Anillos&#187;","datePublished":"2024-05-05T20:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/"},"wordCount":394,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/","name":"Muere Bernard Hill, actor de \"Titanic\" y \"El Se\u00f1or de los Anillos\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-05T20:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere Bernard Hill, actor de &#171;Titanic&#187; y &#171;El Se\u00f1or de los Anillos&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere Bernard Hill, actor de &#171;Titanic&#187; y &#171;El Se\u00f1or de los Anillos&#187;","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/05\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-05T20:03:50Z","datePublished":"2024-05-05T20:03:50Z","dateModified":"2024-05-05T20:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere Bernard Hill, actor de &#171;Titanic&#187; y &#171;El Se\\u00f1or de los Anillos&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/05\\\/05\\\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/05\\\/05\\\/muere-bernard-hill-actor-titanic-el-senor-de-los-anillos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-05T20:03:50Z\",\"datePublished\":\"2024-05-05T20:03:50Z\",\"dateModified\":\"2024-05-05T20:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472526,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/25\/stephen-colbert-escribira-pelicula-senor-anillos-trax\/","url_meta":{"origin":1448894,"position":0},"title":"Anuncian una nueva pel\u00edcula de &#171;El se\u00f1or de los anillos&#187;, que ser\u00e1 escrita por el presentador Stephen Colbert","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Stephen Colbert ya tiene un nuevo trabajo asegurado para cuando termine su etapa de 11 a\u00f1os como presentador de \u201cThe Late Show\u201d en mayo: el comediante y conocido superf\u00e1n de J. R. R. Tolkien anunci\u00f3 que coescribir\u00e1 y desarrollar\u00e1 una nueva pel\u00edcula de la exitosa franquicia \u201cEl Se\u00f1or de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473194,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/15\/jamie-dornan-aragorn-el-senor-de-los-anillos-orix\/","url_meta":{"origin":1448894,"position":1},"title":"Jamie Dornan ser\u00e1 Aragorn en la nueva pel\u00edcula de &#171;El se\u00f1or de los anillos&#187;","author":"","date":"abril 15, 2026","format":false,"excerpt":"Tras meses de especulaciones, Warner Bros. anunci\u00f3 el martes en redes sociales el elenco principal de la nueva pel\u00edcula de \u201cEl se\u00f1or de los anillos\u201d titulada \u201cThe Hunt for Gollum\u201d, que dirige Andy Serkis bajo la producci\u00f3n de Peter Jackson.La principal revelaci\u00f3n del anuncio \u2013hecho p\u00fablico primero en CinemaCon, convenci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451680,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/08\/08\/cate-blanchett-nadie-cobro-el-senor-de-los-anillos-trax\/","url_meta":{"origin":1448894,"position":2},"title":"Cate Blanchett dice que &#171;nadie cobr\u00f3 nada&#187; por &#171;El Se\u00f1or de los Anillos&#187;","author":"","date":"agosto 8, 2024","format":false,"excerpt":"(CNN) -- Digamos que no fue tan valioso como un tesoro..La actriz Cate Blanchett protagoniz\u00f3 el gran \u00e9xito de taquilla \"El Se\u00f1or de los Anillos: La Comunidad del Anillo\", pero, seg\u00fan ella, el dinero que se recaud\u00f3 producto de ese \u00e9xito nunca lleg\u00f3 al elenco.Durante una aparici\u00f3n en \"Watch What\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471284,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/02\/16\/muere-actor-robert-duvall-95-anos-trax\/","url_meta":{"origin":1448894,"position":3},"title":"Muere el actor ganador del Oscar Robert Duvall a los 95 a\u00f1os","author":"","date":"febrero 16, 2026","format":false,"excerpt":"Robert Duvall, el actor ganador del Oscar m\u00e1s conocido por \u201cThe Godfather\u201d, \u201cApocalypse Now\u201d y muchos otros papeles de hombre duro a lo largo de una aclamada carrera en pantalla que se extendi\u00f3 por seis d\u00e9cadas, muri\u00f3. Ten\u00eda 95 a\u00f1os.Duvall muri\u00f3 \u201cen paz\u201d en su casa en Middleburg, Virginia, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449351,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/09\/senor-anillos-pelicula-lord-rings-trax\/","url_meta":{"origin":1448894,"position":4},"title":"Una nueva pel\u00edcula de &#8216;El se\u00f1or de los anillos&#8217; se estrenar\u00e1 en 2026","author":"","date":"mayo 9, 2024","format":false,"excerpt":"(CNN) -- El equipo ganador del Oscar detr\u00e1s de las exitosas trilog\u00edas de \u201cEl Se\u00f1or de los Anillos\u201d (\"Lord of the Rings) y \u201cEl Hobbit\u201d, valoradas en casi US$ 6.000 millones de d\u00f3lares, se re\u00fane para producir dos nuevas pel\u00edculas.El primero de los nuevos proyectos de sir Peter Jackson, Fran\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451953,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/08\/18\/muere-a-los-88-anos-la-leyenda-del-cine-frances-alain-delon-trax\/","url_meta":{"origin":1448894,"position":5},"title":"Alain Delon, leyenda del cine franc\u00e9s, muere a los 88 a\u00f1os","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) --Alain Delon, el actor, productor y escritor franc\u00e9s cuya belleza fresca y enigm\u00e1tica lo convirti\u00f3 en un s\u00edmbolo sexual internacional, muri\u00f3 a la edad de 88 a\u00f1os.\u201cFalleci\u00f3 en paz en su casa de Douchy, rodeado de sus tres hijos y su familia\u201d, indic\u00f3 un comunicado de la familia difundido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448894"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448894\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}