{"id":1448937,"date":"2024-05-06T13:03:43","date_gmt":"2024-05-06T20:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/"},"modified":"2024-05-06T13:03:43","modified_gmt":"2024-05-06T20:03:43","slug":"armas-nucleares-tacticas-rusia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","title":{"rendered":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una?"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Rusia anunci\u00f3 este lunes que llevar\u00e1 a cabo &#171;en un futuro pr\u00f3ximo&#187; ejercicios con armas nucleares no estrat\u00e9gicas (tambi\u00e9n llamadas &#171;t\u00e1cticas&#187;), luego de que el Kremlin condenara lo que calific\u00f3 de escalada de tensi\u00f3n &#171;sin precedentes&#187; por parte de Occidente.<\/p>\n<p>El Estado Mayor ruso inici\u00f3 los preparativos para realizar los ejercicios &#171;con formaciones de misiles del Distrito Militar Sur que involucran a la aviaci\u00f3n, as\u00ed como a las fuerzas navales&#187;, dijo el Ministerio de Defensa del pa\u00eds en un comunicado &#171;Durante los ejercicios, se llevar\u00e1 a cabo un conjunto de medidas para practicar las cuestiones de preparaci\u00f3n y uso de armas nucleares no estrat\u00e9gicas&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Esta es la ocasi\u00f3n m\u00e1s reciente en la que, en medio de su guerra contra Ucrania, Rusia deja sobre la mesa el tema de las armas nucleares. Previamente, en septiembre de 2022, el presidente Vladimir Putin amenaz\u00f3 con recurrir a ellas.<\/p>\n<p>En ese entonces, Putin advirti\u00f3 que &#171;en caso de una amenaza a la integridad territorial de nuestro pa\u00eds, y para defender a Rusia y a nuestro pueblo, ciertamente haremos uso de todos los sistemas de armas disponibles para nosotros. No estoy fanfarroneando&#187;.<\/p>\n<p>\u00bfCu\u00e1ntas armas nucleares hay en el mundo? Este es un vistazo a los arsenales de cada pa\u00eds<\/p>\n<p>\u00bfQu\u00e9 son las armas nucleares no estrat\u00e9gicas o t\u00e1cticas?<\/p>\n<p>El arsenal de armas ruso incluye un estimado total de 5.580 ojivas nucleares (desplegadas, no desplegadas, almacenadas o esperando desmantelamiento), de las cuales poco m\u00e1s de 1.800 son ojivas &#171;no estrat\u00e9gicas&#187;, tambi\u00e9n conocidas como armas nucleares t\u00e1cticas, seg\u00fan la Nuclear Threat Initiative (NTI).<\/p>\n<p>Con esas m\u00e1s de 1.800 ojivas nucleares no estrat\u00e9gicas, Rusia es el pa\u00eds con la mayor reserva de armas en el mundo en dicha categor\u00eda, agrega la NTI.<\/p>\n<p>Las ojivas t\u00e1cticas se refieren a las dise\u00f1adas para usarse en un campo de batalla limitado, por ejemplo, para destruir una columna de tanques o un grupo de batalla de portaaviones si se usan en el mar. Estas ojivas, con rendimientos explosivos de 10 a 100 kilotones de dinamita, tambi\u00e9n se denominan &#171;de bajo rendimiento&#187;.<\/p>\n<p>Por el contrario, las ojivas nucleares &#171;estrat\u00e9gicas&#187; m\u00e1s poderosas de Rusia tienen potencias explosivas de 500 a 800 kilotones y est\u00e1n dise\u00f1adas para destruir ciudades enteras, y algo m\u00e1s.<\/p>\n<p>La referencia a &#171;bajo rendimiento&#187; para las armas t\u00e1cticas es algo enga\u00f1osa, ya que los rendimientos explosivos de 10 a 100 kilotones de dinamita a\u00fan son suficientes para causar una gran destrucci\u00f3n, como descubri\u00f3 el mundo en 1945 cuando EE.UU. lanz\u00f3 bombas at\u00f3micas sobre Hiroshima y Nagasaki en Jap\u00f3n.<\/p>\n<p>Esas bombas equival\u00edan a unos 15 y 21 kilotones de dinamita, respectivamente, lo que las coloca dentro del rango de las armas nucleares t\u00e1cticas de Rusia.<\/p>\n<p>Y es debido a esta capacidad devastadora que mucha gente dice que realmente no hay diferencia entre un arma estrat\u00e9gica y una t\u00e1ctica cuando se usa en la guerra.<\/p>\n<p>\u201cNo creo que exista tal cosa como un &#8216;arma nuclear t\u00e1ctica'&#187;, dijo el exsecretario de Defensa de EE.UU. James Mattis, durante una audiencia en el Congreso en 2018. \u201cCualquier arma nuclear utilizada en cualquier momento es un cambio de juego estrat\u00e9gico&#187;, dijo Mattis.<\/p>\n<p>\u00bfCu\u00e1l es la estrategia de Putin con sus amenazas nucleares y nuevos reclutamientos? 8:22<\/p>\n<p>\u00bfQu\u00e9 pasar\u00eda si Rusia desplegara un arma nuclear t\u00e1ctica?<\/p>\n<p>Rusia (y antes, la Uni\u00f3n Sovi\u00e9tica) ha fabricado y mantenido una gran reserva de armas nucleares t\u00e1cticas.<\/p>\n<p>El pensamiento inicial fue que usar una bomba nuclear en un campo de batalla les dar\u00eda a los l\u00edderes la opci\u00f3n de perpetrar un ataque decisivo que podr\u00eda evitar la derrota sin recurrir al uso de sus armas nucleares m\u00e1s grandes, las cuales, despu\u00e9s de un contraataque, llevar\u00eda a un &#171;intercambio nuclear que acabar\u00eda con la civilizaci\u00f3n&#187;, seg\u00fan Union of Concerned Scientists (Uni\u00f3n de Cient\u00edficos Preocupados).<\/p>\n<p>En su sitio web, la organizaci\u00f3n llama a ese pensamiento &#171;err\u00f3neo y peligroso&#187;.<\/p>\n<p>EE.UU. advirti\u00f3 a Rusia en privado sobre el uso de armas nucleares contra Ucrania durante varios meses<\/p>\n<p>&#171;Las armas nucleares t\u00e1cticas&#8230; introducen una mayor ambig\u00fcedad, aumentando la posibilidad de que un pa\u00eds piense que puede salirse con la suya con un ataque limitado&#187;, dijo la organizaci\u00f3n.<\/p>\n<p>Algunos an\u00e1lisis respaldan esa teor\u00eda, pero es probable que la realidad diste mucho de eso.<\/p>\n<p>&#171;Los juegos de guerra estadounidenses predicen que un conflicto que involucre el uso de armas nucleares t\u00e1cticas r\u00e1pidamente se saldr\u00e1 de control&#187;, dijo el blog de Union of Concerned Scientists.<\/p>\n<p>&#171;Una simulaci\u00f3n de la Universidad de Princeton de un conflicto entre Estados Unidos y Rusia que comienza con el uso de un arma nuclear t\u00e1ctica predice una escalada r\u00e1pida que dejar\u00eda m\u00e1s de 90 millones de muertos y heridos&#187;, dijo.<\/p>\n<p>En respuesta a la amenaza de Putin de septiembre de 2022, la Campa\u00f1a Internacional para la Abolici\u00f3n de las Armas Nucleares (ICAN) dijo que la Europa de ese a\u00f1o era un lugar mucho m\u00e1s peligroso para usar armas nucleares que el Jap\u00f3n de 1945, que ten\u00eda una poblaci\u00f3n menor y estaba relativamente aislado.<\/p>\n<p>Hoy en Europa, &#171;una sola detonaci\u00f3n nuclear probablemente matar\u00eda a cientos de miles de civiles y lesionar\u00eda a muchos m\u00e1s; la lluvia radiactiva podr\u00eda contaminar grandes \u00e1reas en varios pa\u00edses&#187;, se\u00f1al\u00f3 ICAN en su sitio web.<\/p>\n<p>&#171;Los servicios de emergencia no podr\u00edan responder de manera efectiva y el p\u00e1nico generalizado desencadenar\u00eda movimientos masivos de personas y graves trastornos econ\u00f3micos. Las detonaciones m\u00faltiples, por supuesto, ser\u00edan mucho peores&#187;, agreg\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Rusia anunci\u00f3 este lunes que llevar\u00e1 a cabo &#171;en un futuro pr\u00f3ximo&#187; ejercicios con armas nucleares no estrat\u00e9gicas (tambi\u00e9n llamadas &#171;t\u00e1cticas&#187;), luego de que el Kremlin condenara lo que calific\u00f3 de escalada de tensi\u00f3n &#171;sin precedentes&#187; por parte de Occidente. El Estado Mayor ruso inici\u00f3 los preparativos para realizar los ejercicios &#171;con formaciones de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448937","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Rusia anunci\u00f3 este lunes que llevar\u00e1 a cabo &#171;en un futuro pr\u00f3ximo&#187; ejercicios con armas nucleares no estrat\u00e9gicas (tambi\u00e9n llamadas &#171;t\u00e1cticas&#187;), luego de que el Kremlin condenara lo que calific\u00f3 de escalada de tensi\u00f3n &#171;sin precedentes&#187; por parte de Occidente. El Estado Mayor ruso inici\u00f3 los preparativos para realizar los ejercicios &#171;con formaciones de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T20:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una?\",\"datePublished\":\"2024-05-06T20:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/\"},\"wordCount\":1004,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/\",\"name\":\"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-06T20:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una? - Noticias","og_description":"(CNN) &#8212;\u00a0Rusia anunci\u00f3 este lunes que llevar\u00e1 a cabo &#171;en un futuro pr\u00f3ximo&#187; ejercicios con armas nucleares no estrat\u00e9gicas (tambi\u00e9n llamadas &#171;t\u00e1cticas&#187;), luego de que el Kremlin condenara lo que calific\u00f3 de escalada de tensi\u00f3n &#171;sin precedentes&#187; por parte de Occidente. El Estado Mayor ruso inici\u00f3 los preparativos para realizar los ejercicios &#171;con formaciones de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-06T20:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una?","datePublished":"2024-05-06T20:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/"},"wordCount":1004,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","name":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-06T20:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una?","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-06T20:03:43Z","datePublished":"2024-05-06T20:03:43Z","dateModified":"2024-05-06T20:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 son las armas nucleares t\\u00e1cticas y qu\\u00e9 pasar\\u00eda si Rusia desplegara una?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/05\\\/06\\\/armas-nucleares-tacticas-rusia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2024\\\/05\\\/06\\\/armas-nucleares-tacticas-rusia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-06T20:03:43Z\",\"datePublished\":\"2024-05-06T20:03:43Z\",\"dateModified\":\"2024-05-06T20:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467636,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/10\/22\/putin-ejercicios-militares-nucleares-trax\/","url_meta":{"origin":1448937,"position":0},"title":"Putin supervis\u00f3 ejercicios militares de preparaci\u00f3n de las fuerzas nucleares rusas","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Las fuerzas nucleares estrat\u00e9gicas de Rusia realizaron este mi\u00e9rcoles una prueba de preparaci\u00f3n supervisada por el presidente Vladimir Putin, seg\u00fan inform\u00f3 el Kremlin.\u201cHoy llevamos a cabo un ejercicio planificado \u2014quiero enfatizar, planificado\u2014 de mando y control de las fuerzas nucleares\u201d, declar\u00f3 Putin en una videoconferencia con la c\u00fapula militar.El Ministerio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448500,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","url_meta":{"origin":1448937,"position":1},"title":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Rusia vet\u00f3 este mi\u00e9rcoles una resoluci\u00f3n de las Naciones Unidas que propon\u00eda prohibir el uso de armas nucleares en el espacio exterior en medio de preocupaciones respaldadas por la inteligencia estadounidense de que Mosc\u00fa est\u00e9 tratando de desarrollar un dispositivo nuclear capaz de destruir sat\u00e9lites.El embajador ruso, Vassily\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444157,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/20\/belarus-aliado-de-rusia-adopta-una-nueva-doctrina-militar-que-incluye-armas-nucleares\/","url_meta":{"origin":1448937,"position":2},"title":"Belar\u00fas, aliado de Rusia, adopta una nueva doctrina militar que incluye armas nucleares","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN) -- Belar\u00fas adopt\u00f3 el viernes una nueva doctrina militar que, de ser aprobada, ser\u00eda el primer paso hacia el despliegue de armas nucleares en todo el pa\u00eds.\"El despliegue de armas nucleares t\u00e1cticas en el territorio de la Rep\u00fablica de Belar\u00fas se considera una medida importante de disuasi\u00f3n preventiva para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444158,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/20\/belarus-aliado-de-rusia-adopta-una-nueva-doctrina-militar-que-incluye-armas-nucleares-2\/","url_meta":{"origin":1448937,"position":3},"title":"Belar\u00fas, aliado de Rusia, adopta una nueva doctrina militar que incluye armas nucleares","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN) -- Belar\u00fas adopt\u00f3 el viernes una nueva doctrina militar que, de ser aprobada, ser\u00eda el primer paso hacia el despliegue de armas nucleares en todo el pa\u00eds.\"El despliegue de armas nucleares t\u00e1cticas en el territorio de la Rep\u00fablica de Belar\u00fas se considera una medida importante de disuasi\u00f3n preventiva para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444160,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/01\/20\/belarus-aliado-de-rusia-adopta-una-nueva-doctrina-militar-que-incluye-armas-nucleares-3\/","url_meta":{"origin":1448937,"position":4},"title":"Belar\u00fas, aliado de Rusia, adopta una nueva doctrina militar que incluye armas nucleares","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN) -- Belar\u00fas adopt\u00f3 el viernes una nueva doctrina militar que, de ser aprobada, ser\u00eda el primer paso hacia el despliegue de armas nucleares en todo el pa\u00eds.\"El despliegue de armas nucleares t\u00e1cticas en el territorio de la Rep\u00fablica de Belar\u00fas se considera una medida importante de disuasi\u00f3n preventiva para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470859,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/02\/04\/fin-tratado-new-start-armas-nucleares-rusia-trax\/","url_meta":{"origin":1448937,"position":5},"title":"Un tratado clave sobre armas nucleares llega a su fin. Es un golpe al mito de &#171;superpotencia&#187; de Rusia","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Desde el colapso de la antigua Uni\u00f3n Sovi\u00e9tica, Rusia ha tenido un papel considerablemente disminuido en el escenario internacional.La desintegraci\u00f3n, en 1991, de lo que el presidente estadounidense Ronald Reagan alguna vez llam\u00f3 un \u201cimperio del mal\u201d dej\u00f3 al Kremlin con menos territorio, menos poder financiero y menos influencia en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1448937"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1448937\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1448937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1448937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1448937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}