{"id":1465493,"date":"2025-08-14T04:03:50","date_gmt":"2025-08-14T11:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/"},"modified":"2025-08-14T04:03:50","modified_gmt":"2025-08-14T11:03:50","slug":"asesor-putin-comparte-detalles-cumbre-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/","title":{"rendered":"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta"},"content":{"rendered":"<p>Un alto asesor de Vladimir Putin comparti\u00f3 detalles sobre los planes para la reuni\u00f3n del presidente de Rusia con el presidente de Estados Unidos Donald Trump el viernes en Alaska, y confirm\u00f3 que ambos ofrecer\u00e1n una rueda de prensa conjunta tras sus conversaciones.<\/p>\n<p>Yury Ushakov, asesor de pol\u00edtica exterior de Putin, dijo a los periodistas este jueves que la cumbre se celebrar\u00e1 en la base militar conjunta Elmendorf-Richardson, en Anchorage, Alaska, a las 11:30 a. m. hora local (3:30 p. m. ET) del viernes.<\/p>\n<p>Seg\u00fan Ushakov, los presidentes mantendr\u00e1n primero una conversaci\u00f3n privada, con la ayuda de int\u00e9rpretes, antes de continuar las conversaciones durante un almuerzo de trabajo. No especific\u00f3 cu\u00e1nto durar\u00e1n las conversaciones, diciendo que \u201cdepender\u00e1 de los presidentes\u201d.<\/p>\n<p>Tanto la delegaci\u00f3n rusa como la estadounidense estar\u00e1n compuestas por cinco miembros, con otros grupos de expertos cerca, dijo.<\/p>\n<p>Adem\u00e1s de Ushakov, el equipo ruso est\u00e1 compuesto por el ministro de Asuntos Exteriores, Sergey Lavrov; el ministro de Defensa, Andrey Belousov; el ministro de Finanzas, Anton Siluanov, y Kirill Dmitriev, negociador principal y director del fondo soberano de Rusia.<\/p>\n<p>Ushakov afirm\u00f3 que se espera que los equipos se centren principalmente en la resoluci\u00f3n de la guerra en Ucrania, as\u00ed como en las perspectivas de cooperaci\u00f3n entre Rusia y Estados Unidos en cuestiones comerciales y econ\u00f3micas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un alto asesor de Vladimir Putin comparti\u00f3 detalles sobre los planes para la reuni\u00f3n del presidente de Rusia con el presidente de Estados Unidos Donald Trump el viernes en Alaska, y confirm\u00f3 que ambos ofrecer\u00e1n una rueda de prensa conjunta tras sus conversaciones. Yury Ushakov, asesor de pol\u00edtica exterior de Putin, dijo a los periodistas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465493","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un alto asesor de Vladimir Putin comparti\u00f3 detalles sobre los planes para la reuni\u00f3n del presidente de Rusia con el presidente de Estados Unidos Donald Trump el viernes en Alaska, y confirm\u00f3 que ambos ofrecer\u00e1n una rueda de prensa conjunta tras sus conversaciones. Yury Ushakov, asesor de pol\u00edtica exterior de Putin, dijo a los periodistas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-14T11:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta\",\"datePublished\":\"2025-08-14T11:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/\",\"name\":\"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-14T11:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta - Noticias","og_description":"Un alto asesor de Vladimir Putin comparti\u00f3 detalles sobre los planes para la reuni\u00f3n del presidente de Rusia con el presidente de Estados Unidos Donald Trump el viernes en Alaska, y confirm\u00f3 que ambos ofrecer\u00e1n una rueda de prensa conjunta tras sus conversaciones. Yury Ushakov, asesor de pol\u00edtica exterior de Putin, dijo a los periodistas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-14T11:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta","datePublished":"2025-08-14T11:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/","name":"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-14T11:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\u00e1n una rueda de prensa conjunta","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/asesor-putin-comparte-detalles-cumbre-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-14T11:03:50Z","datePublished":"2025-08-14T11:03:50Z","dateModified":"2025-08-14T11:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Asesor de Putin comparte detalles de la cumbre con Trump y afirma que los presidentes ofrecer\\u00e1n una rueda de prensa conjunta\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/14\\\/asesor-putin-comparte-detalles-cumbre-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/14\\\/asesor-putin-comparte-detalles-cumbre-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-14T11:03:50Z\",\"datePublished\":\"2025-08-14T11:03:50Z\",\"dateModified\":\"2025-08-14T11:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465497,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/putin-ee-uu-rusia-armas-nucleares-paz-trump-trax\/","url_meta":{"origin":1465493,"position":0},"title":"Putin sugiere que EE.UU. y Rusia podr\u00edan alcanzar acuerdo sobre armas nucleares y elogia los esfuerzos de paz de Trump","author":"","date":"agosto 14, 2025","format":false,"excerpt":"El presidente de Rusia, Vladimir Putin, elogi\u00f3 los esfuerzos \u201cen\u00e9rgicos\u201d de la administraci\u00f3n de Trump para detener la guerra en Ucrania e insinu\u00f3 que Mosc\u00fa y Washington podr\u00edan llegar a un acuerdo sobre el control de armas nucleares durante su cumbre del viernes en Alaska.En sus primeros comentarios p\u00fablicos desde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465206,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/07\/kremlin-reunion-trump-putin-trax\/","url_meta":{"origin":1465493,"position":1},"title":"Un alto asesor del Kremlin afirma que acordaron una reuni\u00f3n entre Trump y Putin &#171;en los pr\u00f3ximos d\u00edas&#187;","author":"","date":"agosto 7, 2025","format":false,"excerpt":"El principal asesor del Kremlin, Yuri Ushakov, afirm\u00f3 este jueves que llegaron a un acuerdo para que los presidentes Donald Trump y Vladimir Putin se re\u00fanan \u201cen los pr\u00f3ximos d\u00edas\u201d, y agreg\u00f3 que las partes ya est\u00e1n trabajando en los preparativos.Es \u201cdif\u00edcil decir\u201d cu\u00e1nto tiempo durar\u00e1n estos preparativos, continu\u00f3 Ushakov,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468906,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/12\/02\/negociaciones-paz-kremlin-rusia-ucrania-eeuu-trax\/","url_meta":{"origin":1465493,"position":2},"title":"No se lleg\u00f3 a ning\u00fan compromiso con el plan para Ucrania entre Mosc\u00fa y Washington, dice un asesor del Kremlin","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"No se alcanz\u00f3 ning\u00fan compromiso sobre el plan para Ucrania durante las conversaciones entre el presidente de Rusia, Vladimir Putin, y la delegaci\u00f3n estadounidense, dijo a los periodistas en Mosc\u00fa el asesor del Kremlin, Yuri Ushakov.Ushakov dijo que algunas de las propuestas estadounidenses parecen \u201cm\u00e1s o menos aceptables, aunque necesitan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464188,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/03\/trump-putin-llamada-medio-oriente-ucrania-trax\/","url_meta":{"origin":1465493,"position":3},"title":"Trump y Putin hablaron por tel\u00e9fono sobre Ir\u00e1n, Medio Oriente y la guerra en Ucrania","author":"","date":"julio 3, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, y el presidente de Rusia, Vladimir Putin, mantuvieron una conversaci\u00f3n telef\u00f3nica este jueves, en la que abordaron temas como Ucrania e \u201cIr\u00e1n y Medio Oriente en general\u201d.Seg\u00fan la agencia de noticias estatal rusa TASS, que cit\u00f3 al asesor del Kremlin, Yuri Ushakov, la conversaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463552,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/06\/14\/putin-trump-llamada-medio-oriente-ucrania-trax\/","url_meta":{"origin":1465493,"position":4},"title":"Putin y Trump mantuvieron una llamada de 50 minutos sobre Medio Oriente y Ucrania, seg\u00fan medios estatales rusos","author":"","date":"junio 14, 2025","format":false,"excerpt":"El presidente de Rusia, Vladimir Putin, discuti\u00f3 el conflicto de Ir\u00e1n e Israel, entre otros temas, durante una conversaci\u00f3n telef\u00f3nica de 50 minutos con el presidente de Estados Unidos, Donald Trump, este s\u00e1bado, seg\u00fan inform\u00f3 el principal asesor del Kremlin, Yuri Ushakov, al medio estatal TASS.Ushakov dijo que Putin conden\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465430,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/12\/reunion-trump-putin-alaska-ejercicio-escucha-trax\/","url_meta":{"origin":1465493,"position":5},"title":"La Casa Blanca califica la reuni\u00f3n Trump-Putin en Alaska como un &#171;ejercicio de escucha&#187;","author":"","date":"agosto 12, 2025","format":false,"excerpt":"La Casa Blanca calific\u00f3 este martes los planes del presidente Donald Trump de reunirse con el presidente ruso, Vladimir Putin, como un \u201cejercicio de escucha\u201d, en un aparente intento de moderar las expectativas sobre un posible acuerdo de paz antes de la cumbre de alto nivel que se celebrar\u00e1 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1465493"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465493\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1465493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1465493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1465493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}