{"id":1465505,"date":"2025-08-14T10:04:01","date_gmt":"2025-08-14T17:04:01","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/"},"modified":"2025-08-14T10:04:01","modified_gmt":"2025-08-14T17:04:01","slug":"mexico-reforma-electoral-analisis-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/","title":{"rendered":"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico?"},"content":{"rendered":"<p>El gobierno de la presidenta de M\u00e9xico, Claudia Sheinbaum, anunci\u00f3 el inicio de un nuevo proceso de reforma electoral, el primero bajo su mandato y el segundo de gran calado en la \u00faltima d\u00e9cada.<\/p>\n<p>La propuesta ha generado reacciones encontradas en el \u00e1mbito acad\u00e9mico y pol\u00edtico. Mientras el Ejecutivo promete una transformaci\u00f3n profunda para \u201cponer en el centro la democracia y el pueblo\u201d, varios especialistas entrevistados por CNN advierten de riesgos de retroceso democr\u00e1tico y falta de pluralidad en su construcci\u00f3n.<\/p>\n<p>Desde la Presidencia, se cre\u00f3 la Comisi\u00f3n Presidencial para la Reforma Electoral, encabezada por Pablo G\u00f3mez, e integrada por 6 funcionarios. Ser\u00e1 la encargada de realizar un diagn\u00f3stico del sistema electoral y de partidos para luego elaborar una propuesta legislativa.<\/p>\n<p>El Gobierno asegur\u00f3 en un comunicado que la Comisi\u00f3n trabajar\u00e1 en conjunto con legisladores, expertos, organizaciones y otros ciudadanos. Entre los temas que abordar\u00e1 figuran la representaci\u00f3n popular \u2014incluyendo la posible eliminaci\u00f3n de los diputados y senadores federales <a href=\"https:\/\/cnnespanol.cnn.com\/video\/mexico-congreso-plurinominales-democracia-representacion-politica-cnnee\">plurinominales, legisladores elegidos por representaci\u00f3n proporcional<\/a>, esto es seg\u00fan el n\u00famero de votos que recibe un partido pol\u00edtico\u2014 y los mecanismos de participaci\u00f3n ciudadana.<\/p>\n<p>Para V\u00edctor Alarc\u00f3n Olgu\u00edn, experto en partidos pol\u00edticos y elecciones, el mayor problema es el dise\u00f1o unilateral de la comisi\u00f3n. \u201cNo hay ning\u00fan di\u00e1logo o convocatoria b\u00e1sica hacia partidos opositores, el INE, el Tribunal Electoral ni la sociedad civil. Es un mecanismo muy acotado\u201d, alert\u00f3.<\/p>\n<p>El polit\u00f3logo y especialista en partidos pol\u00edticos, Jos\u00e9 Antonio Carrera Barroso, coincidi\u00f3 en la que, afirma, es falta de garant\u00edas reales de inclusi\u00f3n en el proceso. \u201cCada vez que se nombra a consejeros se conforman comit\u00e9s de expertos que, aunque en teor\u00eda son plurales, han demostrado ser falibles: se han filtrado ex\u00e1menes y hay etapas del proceso que se vuelven cajas negras. No sabemos qu\u00e9 pasa ah\u00ed dentro\u201d, advirti\u00f3.<\/p>\n<p>La presidenta Sheinbaum dijo el martes en su conferencia matutina que se realizar\u00e1n foros y consultas en las que participar\u00e1n ciudadanos, la oposici\u00f3n y exfuncionarios electorales, aunque no dio m\u00e1s detalles.<\/p>\n<p>Si bien dice que la apertura al di\u00e1logo puede parecer alentadora, Carrera cuestion\u00f3 su efectividad: \u201cHe participado en mesas de discusi\u00f3n en las \u00faltimas dos reformas y, aunque se nos invita, eso no significa que seamos escuchados\u201d.<\/p>\n<p>A trav\u00e9s de una carta, varios expresidentes de los \u00f3rganos electorales federales pidieron construir la pr\u00f3xima reforma electoral mediante un amplio di\u00e1logo nacional. En el documento, reconocen la necesidad de una reforma que fortalezca la representaci\u00f3n plural, la equidad en la contienda y la independencia de los \u00f3rganos electorales, y que sea resultado de un amplio consenso.<\/p>\n<p>Para Alarc\u00f3n uno de los riesgos es que la reforma sirva para \u201cconsolidar el predominio\u201d de Morena, m\u00e1s que para fortalecer la democracia. \u201cNo veo intenci\u00f3n de cambiar la f\u00f3rmula electoral que ha beneficiado con sobrerrepresentaci\u00f3n. Al contrario, podr\u00eda afectar a aliados como el Partido Verde o el PT, sostuvo<\/p>\n<p>.<\/p>\n<p>Tambi\u00e9n advirti\u00f3 que se podr\u00eda regresar a propuestas del \u201cPlan A\u201d presentado por el expresidente Andr\u00e9s Manuel L\u00f3pez Obrador el sexenio pasado: desaparecer los \u00f3rganos electorales locales, y concentrarlos en el Instituto Nacional de Elecciones y Consultas (INEC). Pero, aunque el entonces mandatario lo intent\u00f3 dos veces, no cont\u00f3 con los votos suficientes para lograr este cambio en el \u00f3rgano electoral.<\/p>\n<p>Adem\u00e1s, eliminar los legisladores plurinominales, desde su perspectiva, ser\u00eda un grave retroceso democr\u00e1tico. \u201cReducir\u00eda la cantidad de opiniones y de posturas y alternativas (que vienen) desde la propia ciudadan\u00eda\u201d, advirti\u00f3 Alarc\u00f3n.<\/p>\n<p>Record\u00f3 que estas figuras permitieron a las que eran fuerzas minoritarias como los Partidos del Trabajo (PT), Verde Ecologista de M\u00e9xico (PVEM) y Morena \u2014 actualmente el poder\u2014 acceder gradualmente al sistema pol\u00edtico.<\/p>\n<p>Carrera coincide: \u201cque desaparezcan los plurinominales ser\u00eda darnos un balazo en el pie\u201d, pues la representaci\u00f3n proporcional naci\u00f3 como un equilibrio para evitar el abuso de poder.<\/p>\n<p>Enumera varias \u00e1reas que s\u00ed deber\u00eda considerar una nueva reforma: disminuir el presupuesto de los partidos pol\u00edticos, devolver a las entidades federativas las prerrogativas de organizaci\u00f3n de elecciones,<\/p>\n<p>e implementar el voto electr\u00f3nico. Seg\u00fan Carrera, muchas de estas mejoras no son posibles con el modelo actual, ya que \u201cel propio modelo es una camisa de fuerza\u201d \u201c.<\/p>\n<p>Tambi\u00e9n se debe replantear el papel de los \u00f3rganos electorales locales, pues el INE, dice Carrera, ha absorbido atribuciones sin delegar responsabilidades. La reforma de 2014 permite al INE asumir por completo o parcialmente las actividades de un \u00f3rgano electoral local.<\/p>\n<p>Seg\u00fan Carrera, tambi\u00e9n se debe replantear el papel de los \u00f3rganos electorales locales, ya que el INE ha absorbido atribuciones sin delegar responsabilidades. La reforma de 2014, que permite al INE asumir total o parcialmente las actividades de un \u00f3rgano electoral local, ha llevado a un modelo de centralizaci\u00f3n, asegura Carrera.<\/p>\n<p>Aunque existen OPLES, como los de la Ciudad de M\u00e9xico y Nuevo Le\u00f3n, con estructuras desarrolladas y fortalecidas, \u201ceste modelo centralizador, en su af\u00e1n de estandarizar y bajo el argumento de la profesionalizaci\u00f3n, ha provocado la p\u00e9rdida de valiosas experiencias locales\u201d desarrolladas por estos organismos.<\/p>\n<p>Carrera propone instaurar el voto con urnas electr\u00f3nicas. El voto v\u00eda internet solo se ha implementado en elecciones federales para los mexicanos fuera del pa\u00eds. El resto de las boletas sigue cont\u00e1ndose a mano, por lo que su instauraci\u00f3n permitir\u00eda la modernizaci\u00f3n del conteo de resultados.<\/p>\n<p>La \u00faltima reforma estructural ocurri\u00f3 en 2014, cuando el INE sustituy\u00f3 al IFE, creado en 1990, producto de otra reforma de gran calado, que terminaba con la intervenci\u00f3n del Gobierno en las elecciones. En la reforma de hace una d\u00e9cada se introdujo la figura de gobiernos de coalici\u00f3n, en la que el presidente y los partidos pol\u00edticos hacen un acuerdo para construir mayor\u00edas y tratar temas espec\u00edficos.<\/p>\n<p>Sin embargo, para ambos expertos, esta transformaci\u00f3n qued\u00f3 incompleta: se centralizaron funciones en el INE, se mantuvo la captura partidista de \u00f3rganos electorales y no se logr\u00f3 modernizar el modelo de votaci\u00f3n.<\/p>\n<p>En 2021, el entonces presidente del INE, Lorenzo C\u00f3rdova, escribi\u00f3 que la reforma de 2014 \u201cgest\u00f3 la construcci\u00f3n de un nuevo modelo electoral\u201d que, a su juicio, fortaleci\u00f3 el papel del INE en la organizaci\u00f3n de comicios locales, con un sistema de fiscalizaci\u00f3n m\u00e1s s\u00f3lido y eficaz, con mecanismos claros para vigilar el financiamiento pol\u00edtico y sancionar a quienes incumplan las reglas de transparencia y rendici\u00f3n de cuentas.<\/p>\n<p>Para Carrera el pa\u00eds tiene condiciones sociales, institucionales y tecnol\u00f3gicas para una gran reforma electoral, pero la clase pol\u00edtica carece de voluntad. \u201cCuando el poder les llega, se olvidan de sus principios\u201d, pero asegura que es necesaria una reforma electoral \u201cporque el modelo actual ya dio lo que ten\u00eda que dar\u201d.<\/p>\n<p>\u201cNo nos queda m\u00e1s que esperar en t\u00e9rminos de tiempo para saber si es viable, si es correcta y si cumple con los objetivos\u201d, advierte Alarc\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de la presidenta de M\u00e9xico, Claudia Sheinbaum, anunci\u00f3 el inicio de un nuevo proceso de reforma electoral, el primero bajo su mandato y el segundo de gran calado en la \u00faltima d\u00e9cada. La propuesta ha generado reacciones encontradas en el \u00e1mbito acad\u00e9mico y pol\u00edtico. Mientras el Ejecutivo promete una transformaci\u00f3n profunda para \u201cponer [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465505","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El gobierno de la presidenta de M\u00e9xico, Claudia Sheinbaum, anunci\u00f3 el inicio de un nuevo proceso de reforma electoral, el primero bajo su mandato y el segundo de gran calado en la \u00faltima d\u00e9cada. La propuesta ha generado reacciones encontradas en el \u00e1mbito acad\u00e9mico y pol\u00edtico. Mientras el Ejecutivo promete una transformaci\u00f3n profunda para \u201cponer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-14T17:04:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico?\",\"datePublished\":\"2025-08-14T17:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/\"},\"wordCount\":1234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/\",\"name\":\"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-14T17:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico? - Noticias","og_description":"El gobierno de la presidenta de M\u00e9xico, Claudia Sheinbaum, anunci\u00f3 el inicio de un nuevo proceso de reforma electoral, el primero bajo su mandato y el segundo de gran calado en la \u00faltima d\u00e9cada. La propuesta ha generado reacciones encontradas en el \u00e1mbito acad\u00e9mico y pol\u00edtico. Mientras el Ejecutivo promete una transformaci\u00f3n profunda para \u201cponer [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/","og_site_name":"Noticias","article_published_time":"2025-08-14T17:04:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico?","datePublished":"2025-08-14T17:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/"},"wordCount":1234,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/","url":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/","name":"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-14T17:04:01+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 preocupa la pr\u00f3xima reforma electoral de M\u00e9xico?","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/mexico-reforma-electoral-analisis-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-14T17:04:01Z","datePublished":"2025-08-14T17:04:01Z","dateModified":"2025-08-14T17:04:01Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 preocupa la pr\\u00f3xima reforma electoral de M\\u00e9xico?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/14\\\/mexico-reforma-electoral-analisis-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/14\\\/mexico-reforma-electoral-analisis-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-14T17:04:01Z\",\"datePublished\":\"2025-08-14T17:04:01Z\",\"dateModified\":\"2025-08-14T17:04:01Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465074,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/02\/sheinbaum-crea-comision-iniciativa-reforma-electoral-orix\/","url_meta":{"origin":1465505,"position":0},"title":"Sheinbaum crea una comisi\u00f3n que elabore su iniciativa de reforma electoral","author":"","date":"agosto 2, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, cre\u00f3 este s\u00e1bado una comisi\u00f3n que elabore su iniciativa de reforma electoral, en la que plantear\u00e1 cambios en temas como la representaci\u00f3n popular y los mecanismos de participaci\u00f3n ciudadana, inform\u00f3 el Gobierno en un comunicado.Esta comisi\u00f3n tendr\u00e1 como primera tarea realizar un diagn\u00f3stico del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470617,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/01\/29\/reforma-electoral-sheinbaum-mexico-analisis-orix\/","url_meta":{"origin":1465505,"position":1},"title":"La reforma electoral en M\u00e9xico: \u00bfgran legado de Sheinbaum o arma de autodestrucci\u00f3n?","author":"","date":"enero 29, 2026","format":false,"excerpt":"En M\u00e9xico estamos en una batalla pol\u00edtica, por la discusi\u00f3n de una reforma constitucional. Es una esas batallas por cambios electorales que se dan de vez en cuando, como sucedi\u00f3 en los lejanos 1977, 1990 y 2014.El escenario es distinto y las motivaciones tambi\u00e9n: es la primera reforma electoral propuesta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472133,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/12\/derrota-reforma-electoral-sheinbaum-plan-b-orix\/","url_meta":{"origin":1465505,"position":2},"title":"Tras la derrota de su reforma electoral, Sheinbaum anuncia un &#171;plan B&#187;. Esta es su propuesta","author":"","date":"marzo 12, 2026","format":false,"excerpt":"Luego de la derrota sufrida el mi\u00e9rcoles en la C\u00e1mara de Diputados, la presidenta de M\u00e9xico, Claudia Sheinbaum, anunci\u00f3 este jueves el \u201cplan B\u201d de su reforma electoral, con el cual, seg\u00fan la mandataria, buscar\u00e1n disminuir privilegios de los congresos locales y de los municipios del pa\u00eds, as\u00ed como fortalecer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471730,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/02\/27\/sheinbaum-reforma-electoral-que-busca-claves-orix\/","url_meta":{"origin":1465505,"position":3},"title":"Las claves de la reforma electoral de Sheinbaum: qu\u00e9 busca y cu\u00e1les son las cr\u00edticas","author":"","date":"febrero 27, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, present\u00f3 este mi\u00e9rcoles su propuesta de reforma electoral, una iniciativa que ha despertado cr\u00edticas tanto entre la oposici\u00f3n como entre algunos aliados del oficialista Morena.Para elaborar este proyecto, Sheinbaum nombr\u00f3 en agosto una comisi\u00f3n especial con la tarea de trabajar con legisladores, acad\u00e9micos y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448297,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/20\/mexico-propuestas-sistema-de-pensiones-candidatos-orix\/","url_meta":{"origin":1465505,"position":4},"title":"Las propuestas de los candidatos presidenciales de M\u00e9xico para el sistema de pensiones","author":"","date":"abril 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Para 2050 se espera que m\u00e1s del 20% de la poblaci\u00f3n de M\u00e9xico tenga 60 a\u00f1os o m\u00e1s, seg\u00fan el cap\u00edtulo nacional del Fondo de Poblaci\u00f3n de las Naciones Unidas (UNFPA). Este pron\u00f3stico pone el sistema de pensiones en el centro de la discusi\u00f3n pol\u00edtica y electoral.Los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459853,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/12\/analisis-petro-juega-cartas-politica-contienda-electoral-2026-orix\/","url_meta":{"origin":1465505,"position":5},"title":"Petro se juega una de sus \u00faltimas cartas pol\u00edticas rumbo a la contienda electoral de 2026 en Colombia","author":"","date":"marzo 12, 2025","format":false,"excerpt":"El presidente Gustavo Petro no ha ocultado la intenci\u00f3n de que su movimiento pol\u00edtico de izquierda vuelva a ganar las elecciones presidenciales de Colombia el pr\u00f3ximo a\u00f1o.As\u00ed lo ha manifestado p\u00fablicamente en varias ocasiones, incluidos los consejos de ministros televisados y transmitidos tambi\u00e9n en las redes sociales de la Presidencia,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1465505"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465505\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1465505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1465505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1465505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}