{"id":1465564,"date":"2025-08-16T17:03:47","date_gmt":"2025-08-17T00:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/"},"modified":"2025-08-16T17:03:47","modified_gmt":"2025-08-17T00:03:47","slug":"bebes-prematuros-mueren-italia-contaminacion-detergente-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","title":{"rendered":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos"},"content":{"rendered":"<p>Se abri\u00f3 una investigaci\u00f3n penal despu\u00e9s de que dos beb\u00e9s prematuros murieran con pocas horas de diferencia durante la noche del 12 al 13 de agosto en el Hospital San Maurizio, en la ciudad de Bolzano, en el norte de Italia, informaron las autoridades.<\/p>\n<p>Ambos beb\u00e9s, que nacieron hace tres semanas \u2014uno en la semana 23 de gestaci\u00f3n y el otro en la semana 27\u2014, fueron diagnosticados con una infecci\u00f3n causada por la bacteria Serratia marcescens, un microbio com\u00fan que solo es peligroso para personas con condiciones de salud comprometidas. Los reci\u00e9n nacidos pesaban alrededor de 700 gramos cada uno.<\/p>\n<p>Seg\u00fan Josef Widmann, director m\u00e9dico de la Autoridad Sanitaria del Tirol del Sur, la bacteria ha sido vinculada al detergente para lavar platos utilizado en el hospital. Widmann inform\u00f3 en una conferencia de prensa el jueves que se ha retirado todo el detergente industrial utilizado en el sistema hospitalario de Bolzano.<\/p>\n<p>\u201cAdem\u00e1s de los graves problemas derivados de su extrema prematuridad, a ambos ni\u00f1os se les diagnostic\u00f3 una infecci\u00f3n por Serratia marcescens, una bacteria ampliamente presente en el ambiente, en el agua, el suelo, las plantas, los animales y los humanos, entre otros\u201d, dijo Widmann. \u201cEsta bacteria es generalmente inofensiva para personas sanas; sin embargo, para beb\u00e9s muy prematuros, la infecci\u00f3n es potencialmente letal\u201d.<\/p>\n<p>La doctora Monika Zaebisch, directora m\u00e9dica del hospital, se\u00f1al\u00f3 que la instituci\u00f3n ha dejado de aceptar beb\u00e9s prematuros de alto riesgo en su unidad neonatal durante la investigaci\u00f3n. El hospital est\u00e1 trasladando a 10 beb\u00e9s de alto riesgo que estaban en la misma sala que los reci\u00e9n nacidos fallecidos a otra sala para asegurar que no est\u00e9n expuestos a materiales contaminados.<\/p>\n<p>\u201cEn el hospital de Bolzano hemos implementado todas las medidas preventivas para evitar la transmisi\u00f3n de bacterias\u201d, dijo Zaebisch el jueves. \u201cEl personal de la sala sigue estrictamente las medidas de higiene. Lamentablemente, estos dos casos no pudieron evitarse. El 12 de agosto decidimos no aceptar m\u00e1s partos de alto riesgo. Hemos acordado con el hospital de Trento que ellos recibir\u00e1n a los beb\u00e9s prematuros para que ning\u00fan ni\u00f1o est\u00e9 expuesto a riesgos\u201d.<\/p>\n<p>El director del hospital, Pierpaolo Bertoli, indic\u00f3 que la infecci\u00f3n fue identificada en ambos beb\u00e9s cuando comenzaron a mostrar s\u00edntomas.<\/p>\n<p>\u201cLamentablemente, los beb\u00e9s desarrollaron sepsis, que result\u00f3 ser mortal\u201d, dijo el jueves. \u201cLa presencia de esta bacteria no es inusual, ya que representa un riesgo constante para las unidades de cuidados intensivos neonatales, no tanto por el tipo de bacteria, sino por la particular vulnerabilidad de estos peque\u00f1os pacientes debido a su sistema inmunol\u00f3gico inmaduro\u201d.<\/p>\n<p>La Unidad Nacional Anticorrupci\u00f3n de los Carabinieri (NAS, por sus siglas en ingl\u00e9s) est\u00e1 investigando el caso y la Fiscal\u00eda de Bolzano determinar\u00e1 si ordena autopsias a los beb\u00e9s para decidir si corresponde presentar cargos por negligencia m\u00e9dica u homicidio involuntario.<\/p>\n<p>La tragedia ocurre semanas despu\u00e9s de que tres personas murieran por presunto envenenamiento por <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/12\/01\/botulismo-enfermedad-mortal-ninos-sintomas-tratamiento\">botulismo <\/a>en el sur del pa\u00eds.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se abri\u00f3 una investigaci\u00f3n penal despu\u00e9s de que dos beb\u00e9s prematuros murieran con pocas horas de diferencia durante la noche del 12 al 13 de agosto en el Hospital San Maurizio, en la ciudad de Bolzano, en el norte de Italia, informaron las autoridades. Ambos beb\u00e9s, que nacieron hace tres semanas \u2014uno en la semana [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465564","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se abri\u00f3 una investigaci\u00f3n penal despu\u00e9s de que dos beb\u00e9s prematuros murieran con pocas horas de diferencia durante la noche del 12 al 13 de agosto en el Hospital San Maurizio, en la ciudad de Bolzano, en el norte de Italia, informaron las autoridades. Ambos beb\u00e9s, que nacieron hace tres semanas \u2014uno en la semana [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-17T00:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos\",\"datePublished\":\"2025-08-17T00:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/\"},\"wordCount\":550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/\",\"name\":\"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-17T00:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos - Noticias","og_description":"Se abri\u00f3 una investigaci\u00f3n penal despu\u00e9s de que dos beb\u00e9s prematuros murieran con pocas horas de diferencia durante la noche del 12 al 13 de agosto en el Hospital San Maurizio, en la ciudad de Bolzano, en el norte de Italia, informaron las autoridades. Ambos beb\u00e9s, que nacieron hace tres semanas \u2014uno en la semana [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-17T00:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/"},"author":{"name":"","@id":""},"headline":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos","datePublished":"2025-08-17T00:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/"},"wordCount":550,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","name":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-17T00:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Dos beb\u00e9s prematuros mueren en Italia por presunta contaminaci\u00f3n con detergente para platos","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/16\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-17T00:03:47Z","datePublished":"2025-08-17T00:03:47Z","dateModified":"2025-08-17T00:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Dos beb\\u00e9s prematuros mueren en Italia por presunta contaminaci\\u00f3n con detergente para platos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/16\\\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/16\\\/bebes-prematuros-mueren-italia-contaminacion-detergente-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-17T00:03:47Z\",\"datePublished\":\"2025-08-17T00:03:47Z\",\"dateModified\":\"2025-08-17T00:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472720,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/31\/prematuros-muerte-recien-nacidos-quimicos-plastico-trax\/","url_meta":{"origin":1465564,"position":0},"title":"Millones de nacimientos prematuros y miles de muertes de reci\u00e9n nacidos est\u00e1n vinculadas a un qu\u00edmico del pl\u00e1stico","author":"","date":"marzo 31, 2026","format":false,"excerpt":"Dos sustancias qu\u00edmicas utilizadas para hacer el pl\u00e1stico m\u00e1s flexible est\u00e1n vinculadas a casi 2 millones de nacimientos prematuros y la muerte de 74.000 reci\u00e9n nacidos en todo el mundo en 2018, seg\u00fan un nuevo estudio.Se considera que un beb\u00e9 es prematuro cuando nace antes de la semana 37 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459787,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/11\/romina-moya-enfermera-del-hospital-penna-relato-como-fue-la-evacuacion-durante-la-inundacion\/","url_meta":{"origin":1465564,"position":1},"title":"Romina Moya, enfermera del Hospital Penna, relat\u00f3 c\u00f3mo fue la evacuaci\u00f3n durante la inundaci\u00f3n","author":"","date":"marzo 11, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Romina Moya, enfermera del servicio de neonatolog\u00eda del Hospital Penna de Bah\u00eda Blanca, relat\u00f3 este martes en Regreso CNN con Mariana Arias y Pepe Gil Vidal c\u00f3mo fue la situaci\u00f3n en el hospital durante la inundaci\u00f3n.\u201cNunca nos imaginamos inundarnos. Nosotras tenemos una residencia de madres, as\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456429,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/10\/klebsiella-oxytoca-enterobacter-cloacae-menores-muertos-mexico-orix\/","url_meta":{"origin":1465564,"position":2},"title":"Infecciones de bacterias \u2018Klebsiella oxytoca\u2019 y \u2018Enterobacter cloacae\u2019 dejan al menos 17 menores muertos en M\u00e9xico","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"El secretario de Salud de M\u00e9xico, David Kershenobich, inform\u00f3 este martes que se reportan 17 ni\u00f1os fallecidos tras infectarse con dos bacterias, la Klebsiella oxytoca y la Enterobacter cloacae.Kershenobich inform\u00f3 que se notific\u00f3 a la Secretaria de Salud sobre un posible brote de dos enterobacterias en unidades de terapia intensiva.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464369,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/09\/medicos-gaza-bebes-incubadora-crisis-combustible-trax\/","url_meta":{"origin":1465564,"position":3},"title":"M\u00e9dicos desesperados meten varios beb\u00e9s en una incubadora, mientras la crisis de combustible en Gaza alcanza un punto cr\u00edtico","author":"","date":"julio 9, 2025","format":false,"excerpt":"M\u00e9dicos en Gaza dicen que se vieron obligados a meter a varios beb\u00e9s en una sola incubadora, mientras los hospitales advirtieron que la escasez de combustible los est\u00e1 obligando a cerrar servicios vitales, poniendo en riesgo la vida de los pacientes.La ONU ha advertido que la crisis del combustible est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456956,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/25\/bebes-palestinos-muertos-invierno-gaza-trax\/","url_meta":{"origin":1465564,"position":4},"title":"Tres beb\u00e9s palestinos mueren congelados en Gaza a medida que llega el invierno","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"Una beb\u00e9 reci\u00e9n nacida muri\u00f3 congelado en un campamento de tiendas de campa\u00f1a en Al-Mawasi, en el sur de Gaza, el mi\u00e9rcoles, lo que pone de relieve los graves desaf\u00edos para la supervivencia que enfrentan los ni\u00f1os palestinos desplazados de sus hogares en medio del ataque continuo de Israel al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459254,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/26\/siete-bebes-mueren-hipotermia-gaza-trax\/","url_meta":{"origin":1465564,"position":5},"title":"Siete beb\u00e9s mueren de hipotermia en Gaza, seg\u00fan las autoridades sanitarias","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Siete beb\u00e9s han muerto de hipotermia en Gaza desde el domingo, seg\u00fan los responsables sanitarios del enclave, quienes advierten que habr\u00e1 m\u00e1s muertes de este tipo a menos que entre m\u00e1s ayuda a la zona.El Dr. Saeed Salah, director m\u00e9dico del Hospital de la Sociedad Ben\u00e9vola de Amigos del Paciente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1465564"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465564\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1465564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1465564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1465564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}