{"id":1465685,"date":"2025-08-20T05:03:42","date_gmt":"2025-08-20T12:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/"},"modified":"2025-08-20T05:03:42","modified_gmt":"2025-08-20T12:03:42","slug":"muro-fronterizo-sur-pintado-negro-noem-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","title":{"rendered":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido"},"content":{"rendered":"<p>El muro a lo largo de la frontera sur ser\u00e1 pintado de negro en un esfuerzo por hacer que la estructura sea demasiado caliente para escalarla, anunci\u00f3 este martes la secretaria del Departamento de Seguridad Nacional, Kristi Noem, diciendo que la sugerencia vino del presidente Donald Trump.<\/p>\n<p>\u201cEs alto, lo que lo hace muy, muy dif\u00edcil de escalar, casi imposible. Adem\u00e1s, se hunde profundamente, lo que dificultar\u00eda mucho, si no es imposible, excavar debajo. Y hoy tambi\u00e9n lo pintaremos de negro\u201d, dijo Noem durante una conferencia de prensa este martes en Santa Teresa, Nuevo M\u00e9xico, mientras se encontraba frente a la estructura de acero de listones.<\/p>\n<p>\u201cEso es espec\u00edficamente a petici\u00f3n del presidente, quien entiende que con las altas temperaturas de aqu\u00ed, cuando algo se pinta de negro, se calienta a\u00fan m\u00e1s y ser\u00e1 a\u00fan m\u00e1s dif\u00edcil para la gente escalar\u201d, dijo.<\/p>\n<p>\u201cLa pintura negra tambi\u00e9n evitar\u00e1 la oxidaci\u00f3n del acero\u201d, dijo el jefe de la Patrulla Fronteriza de Estados Unidos, Michael Banks.<\/p>\n<p>La decisi\u00f3n de pintar el muro ocurre mientras la administraci\u00f3n Trump afirma que hubo poco m\u00e1s de 6.000 <a href=\"https:\/\/www.cbp.gov\/newsroom\/national-media-release\/most-secure-border-history-cbp-reports-major-enforcement-wins-june\">detenciones<\/a> en la frontera sur en junio, un 15 % menos que un r\u00e9cord anterior en marzo.<\/p>\n<p>El muro fronterizo sur fue un elemento central de la l\u00ednea dura de Trump contra la inmigraci\u00f3n durante su primer mandato. Ahora, en su segundo mandato, el enfoque de Trump se ha centrado principalmente en las deportaciones y el aumento de la aplicaci\u00f3n de la ley en Estados Unidos.<\/p>\n<p>Noem no dijo cu\u00e1nto costar\u00eda pintar el muro, pero la administraci\u00f3n consigui\u00f3 <a href=\"https:\/\/www.cnn.com\/2025\/05\/02\/politics\/what-is-in-trump-tax-spending-cuts-package\">alrededor de US$ 46.500 millones<\/a> en fondos a trav\u00e9s de la \u201cgran y hermosa ley\u201d respaldada por Trump para modernizar el sistema de barreras fronterizas, incluida la finalizaci\u00f3n de la construcci\u00f3n de 1.127 km (700 millas) de muro principal.<\/p>\n<p>El gobierno est\u00e1 construyendo aproximadamente<strong> <\/strong>800 metros (media milla) de barrera cada d\u00eda, dijo Noem este martes.<\/p>\n<p>\u201cEl muro fronterizo tendr\u00e1 un aspecto muy diferente dependiendo de la topograf\u00eda y la geograf\u00eda del lugar donde se construya\u201d, explic\u00f3.<\/p>\n<p>Noem tambi\u00e9n destac\u00f3 el despliegue de \u201cinfraestructura acu\u00e1tica\u201d y tecnolog\u00eda avanzada por parte del departamento, como c\u00e1maras y sensores.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El muro a lo largo de la frontera sur ser\u00e1 pintado de negro en un esfuerzo por hacer que la estructura sea demasiado caliente para escalarla, anunci\u00f3 este martes la secretaria del Departamento de Seguridad Nacional, Kristi Noem, diciendo que la sugerencia vino del presidente Donald Trump. \u201cEs alto, lo que lo hace muy, muy [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465685","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido - Noticias\" \/>\n<meta property=\"og:description\" content=\"El muro a lo largo de la frontera sur ser\u00e1 pintado de negro en un esfuerzo por hacer que la estructura sea demasiado caliente para escalarla, anunci\u00f3 este martes la secretaria del Departamento de Seguridad Nacional, Kristi Noem, diciendo que la sugerencia vino del presidente Donald Trump. \u201cEs alto, lo que lo hace muy, muy [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-20T12:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido\",\"datePublished\":\"2025-08-20T12:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/\",\"name\":\"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-20T12:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido - Noticias","og_description":"El muro a lo largo de la frontera sur ser\u00e1 pintado de negro en un esfuerzo por hacer que la estructura sea demasiado caliente para escalarla, anunci\u00f3 este martes la secretaria del Departamento de Seguridad Nacional, Kristi Noem, diciendo que la sugerencia vino del presidente Donald Trump. \u201cEs alto, lo que lo hace muy, muy [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","og_site_name":"Noticias","article_published_time":"2025-08-20T12:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/"},"author":{"name":"","@id":""},"headline":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido","datePublished":"2025-08-20T12:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","url":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","name":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-20T12:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El muro fronterizo sur se pintar\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\u00e1lido","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/20\/muro-fronterizo-sur-pintado-negro-noem-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-20T12:03:42Z","datePublished":"2025-08-20T12:03:42Z","dateModified":"2025-08-20T12:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El muro fronterizo sur se pintar\\u00e1 de negro para disuadir a la gente de escalarlo durante el clima c\\u00e1lido\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/20\\\/muro-fronterizo-sur-pintado-negro-noem-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/08\\\/20\\\/muro-fronterizo-sur-pintado-negro-noem-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-20T12:03:42Z\",\"datePublished\":\"2025-08-20T12:03:42Z\",\"dateModified\":\"2025-08-20T12:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471961,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/06\/despedida-trump-noem-insinuacion-mintio-trax\/","url_meta":{"origin":1465685,"position":0},"title":"El regalo de despedida de Trump a Noem: insinuar que minti\u00f3 bajo juramento","author":"","date":"marzo 6, 2026","format":false,"excerpt":"O el presidente Donald Trump no dice la verdad, o Kristi Noem parece haber cometido perjurio.En este punto, no hay una tercera alternativa.El jueves, Trump podr\u00eda haber relevado a Noem de sus funciones, como lo hizo. Pero no se detuvo all\u00ed; tambi\u00e9n pareci\u00f3 negar repetidamente partes de su testimonio \u2014que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457870,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/01\/25\/senado-confirma-kristi-noem-secretaria-seguridad-nacional-trax\/","url_meta":{"origin":1465685,"position":1},"title":"El Senado confirma a Kristi Noem como secretaria de Seguridad Nacional, un papel clave contra la inmigraci\u00f3n","author":"","date":"enero 25, 2025","format":false,"excerpt":"El Senado vot\u00f3 en la ma\u00f1ana de este s\u00e1bado para confirmar a Kristi Noem como la secretaria de Seguridad Nacional, instalando a una aliada de larga data de Donald Trump al frente de una agencia que desempe\u00f1ar\u00e1 un papel central en la prometida ofensiva contra la inmigraci\u00f3n del presidente.La votaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464330,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/08\/secretaria-agricultura-amnistia-inmigrantes-reemplazados-trax\/","url_meta":{"origin":1465685,"position":2},"title":"No habr\u00e1 &#171;amnist\u00eda&#187; para inmigrantes para buscar una fuerza laboral &#171;100 % estadounidense&#187;, dice secretaria de Agricultura","author":"","date":"julio 8, 2025","format":false,"excerpt":"La secretaria de Agricultura, Brooke Rollins, declar\u00f3 este martes durante una conferencia de prensa que no habr\u00e1 \u201camnist\u00eda\u201d para los inmigrantes y que las deportaciones masivas continuar\u00e1n para lograr una fuerza laboral 100 % estadounidense. Rollins mencion\u00f3 el n\u00famero de adultos en el programa de Medicaid y afirm\u00f3 que hay\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447296,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/03\/24\/amlo-trump-no-construira-muro-porque-nos-entendemos-muy-bien-orix\/","url_meta":{"origin":1465685,"position":3},"title":"AMLO: Trump no construir\u00e1 el muro &#171;porque nos entendemos muy bien&#187;","author":"","date":"marzo 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo que el expresidente de Estados Unidos Donald Trump no construir\u00e1 el muro en caso de ganar un segundo mandato en las elecciones de noviembre.En una entrevista con el programa \"60 Minutes\" de CBS, que se emite la noche\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464464,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/12\/noem-promete-aumentar-deportaciones-impulso-fondos-trax\/","url_meta":{"origin":1465685,"position":4},"title":"Noem promete aumentar las deportaciones con el impulso de fondos de la &#171;gran y hermosa ley&#187; de pol\u00edtica interna de Trump","author":"","date":"julio 12, 2025","format":false,"excerpt":"La secretaria de Seguridad Nacional, Kristi Noem, prometi\u00f3 este s\u00e1bado que su departamento reforzar\u00e1 sus esfuerzos para combatir la inmigraci\u00f3n, gracias a un aumento de fondos proveniente de la ley de pol\u00edtica interna del presidente Donald Trump, que firm\u00f3 la semana pasada.\u201cAhora que se aprob\u00f3 el proyecto de ley de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470539,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/01\/27\/stephen-miller-asesor-casa-blanca-violacion-protocolo-tiroteo-alex-pretti-trax\/","url_meta":{"origin":1465685,"position":5},"title":"Stephen Miller, asesor de la Casa Blanca, reconoce posible violaci\u00f3n del protocolo antes del tiroteo de Alex Pretti","author":"","date":"enero 27, 2026","format":false,"excerpt":"El principal asesor de la Casa Blanca, Stephen Miller, dijo el martes que los funcionarios estaban evaluando por qu\u00e9 los agentes de la Oficina de Aduanas y Protecci\u00f3n Fronteriza en Minneapolis \u201cpuede que no hayan estado siguiendo\u201d el protocolo adecuado antes del tiroteo mortal de Alex Pretti, lo que implica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1465685"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1465685\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1465685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1465685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1465685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}