{"id":1466350,"date":"2025-09-10T19:03:56","date_gmt":"2025-09-11T02:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/"},"modified":"2025-09-10T19:03:56","modified_gmt":"2025-09-11T02:03:56","slug":"charlie-kirk-admiracion-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/","title":{"rendered":"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump"},"content":{"rendered":"<p>Charlie Kirk era un orgulloso desertor universitario con una l\u00ednea directa al presidente Donald Trump como pocos.<\/p>\n<p>Visitante frecuente de la Casa Blanca, Kirk era mucho m\u00e1s que un aficionado leal y admirador del presidente; ten\u00eda el pulso de la base MAGA y se aseguraba de que sus opiniones fueran conocidas, incluso en las raras ocasiones en que no estaba de acuerdo, como con la decisi\u00f3n de Trump en junio de atacar sitios nucleares en Ir\u00e1n.<\/p>\n<p>En ese momento, Kirk dijo que advirti\u00f3 sobre las posibles consecuencias con los seguidores m\u00e1s j\u00f3venes, muchos de los cuales se sintieron atra\u00eddos por Trump debido a su promesa de campa\u00f1a de poner fin a las guerras en el extranjero.<\/p>\n<p>La mera noci\u00f3n de que Kirk ofreci\u00f3 una cr\u00edtica \u2014y Trump la acept\u00f3 sin contraatacar\u2014 subraya cu\u00e1nto admiraba el presidente al activista conservador y respetaba la fortaleza de su organizaci\u00f3n Turning Point USA. Personas cercanas a \u00e9l dijeron que Kirk se ve\u00eda a s\u00ed mismo como un verdadero creyente en los valores conservadores y en Trump, y que estaba decidido a fortalecer su movimiento en el segundo mandato del presidente.<\/p>\n<p>\u201cNadie entend\u00eda ni ten\u00eda el coraz\u00f3n de la juventud en Estados Unidos mejor que Charlie\u201d, escribi\u00f3 Trump en las redes sociales este mi\u00e9rcoles en una publicaci\u00f3n anunciando la muerte de Kirk, subrayando su estrecha relaci\u00f3n. \u201cTodos lo amaban y admiraban, especialmente yo\u201d.<\/p>\n<p>El homicidio de Kirk sorprendi\u00f3 a la Casa Blanca y caus\u00f3 conmoci\u00f3n en todo el Partido Republicano, y representa una p\u00e9rdida personal para la primera familia de Estados Unidos.<\/p>\n<p>Trump le atribuy\u00f3 a Kirk, de 31 a\u00f1os, haber movilizado el voto joven que lo llev\u00f3 a la victoria en 2024. Pero antes de eso, se hab\u00eda convertido en un amigo y asesor valioso y de confianza para el presidente y su familia.<\/p>\n<p>Trump consideraba a Kirk como parte de su familia extendida, dijo a CNN una fuente familiarizada con la relaci\u00f3n, y su muerte ha sido recibida con horror, conmoci\u00f3n y dolor en el c\u00edrculo \u00edntimo de Trump. El hijo mayor del presidente, Donald Trump Jr., era especialmente cercano a Kirk, con quien hab\u00eda viajado y aparecido p\u00fablicamente en numerosas ocasiones a medida que crec\u00eda el movimiento MAGA, la m\u00e1s reciente en la cumbre de Turning Point USA en Florida en julio.<\/p>\n<p>\u201cTe quiero, hermano. Le diste a tanta gente el valor de alzar la voz y nunca seremos silenciados\u201d, escribi\u00f3 Trump Jr. en X.<\/p>\n<p>Jared Kushner, yerno del presidente y alto asesor durante su primer mandato, destac\u00f3 el papel de Kirk en la campa\u00f1a de 2016 y el desarrollo del movimiento MAGA.<\/p>\n<p>\u201cCuando estaba en la Casa Blanca, las organizaciones establecidas a menudo se quejaban de que segu\u00edamos haciendo eventos con Charlie, a lo que yo respond\u00eda: \u2018\u00c9l viene con grandes ideas, es f\u00e1cil trabajar con \u00e9l y siempre supera las expectativas\u2019\u201d, public\u00f3 Kushner en X, llamando a Kirk \u201clo mejor de MAGA\u201d.<\/p>\n<p>Donald Trump fue solo el cuarto presidente en la vida de Kirk. Nacido en 1993, creci\u00f3 en los suburbios del noroeste de Chicago. A menudo hablaba de sus primeras se\u00f1ales de conciencia pol\u00edtica y activismo a los 15 a\u00f1os, cuando el senador de su estado natal, Barack Obama, gan\u00f3 la presidencia.<\/p>\n<p>Kirk no celebr\u00f3 la hist\u00f3rica victoria de Obama en 2008. Su propio ascenso pol\u00edtico sigui\u00f3 el crecimiento del movimiento Tea Party. Asisti\u00f3 brevemente a Harper College en Palatine, Illinois, pero abandon\u00f3 los estudios para seguir su activismo conservador, una decisi\u00f3n que m\u00e1s tarde se convirti\u00f3 en motivo de orgullo.<\/p>\n<p>\u201cSi quieres sobresalir, no vayas a la universidad\u201d, dec\u00eda Kirk en los m\u00edtines. \u201cA m\u00ed me funcion\u00f3\u201d.<\/p>\n<p>Un poco m\u00e1s de una d\u00e9cada despu\u00e9s, Kirk ya era una estrella conservadora, primero como confidente cercano de Trump Jr., quien finalmente se gan\u00f3 la confianza de su padre. Kirk era excepcionalmente cercano a J. D. Vance, desempe\u00f1ando un papel clave en su carrera por el Senado de Ohio en 2022 y presionando a Trump para seleccionarlo como vicepresidente en 2024.<\/p>\n<p>\u201cRecen por Charlie Kirk\u201d, escribi\u00f3 Vance este mi\u00e9rcoles. \u201cUn tipo genuinamente bueno y un joven padre\u201d.<\/p>\n<p>Kirk y su organizaci\u00f3n pol\u00edtica afiliada, Turning Point Action, fueron fundamentales para asegurar el regreso de Trump a la Casa Blanca.<\/p>\n<p>Por ejemplo, el grupo invirti\u00f3 millones de d\u00f3lares en un programa para movilizar votantes en Arizona, un estado clave en disputa que Trump recuper\u00f3 de manos del presidente Joe Biden.<\/p>\n<p>Como parte de su iniciativa \u201cChase the Vote\u201d, los empleados del grupo cultivaron relaciones con votantes espec\u00edficos a lo largo de la campa\u00f1a para ayudar a asegurar que votaran en las elecciones. Esos esfuerzos incluyeron fomentar la votaci\u00f3n anticipada, llevar a los votantes a las urnas y ayudarlos a enviar sus boletas por correo, todo con el objetivo de asegurar que los votantes poco frecuentes que estaban inclinados a apoyar a Trump realmente cumplieran con emitir su voto.<\/p>\n<p>CNN inform\u00f3 el a\u00f1o pasado que el esfuerzo de Turning Point ayud\u00f3 a asegurar votos de m\u00e1s de 125.000 votantes irregulares que hab\u00eda identificado en Arizona, seg\u00fan una persona con conocimiento de la operaci\u00f3n del grupo. Trump gan\u00f3 el estado por aproximadamente 187.000 votos.<\/p>\n<p>Trump se ha jactado de su desempe\u00f1o con los votantes j\u00f3venes en 2024: redujo su derrota entre los j\u00f3venes de 18 a 29 a\u00f1os a 11 puntos desde 24 puntos en 2020, y le atribuy\u00f3 en parte a Kirk su atractivo entre esos votantes.<\/p>\n<p>\u201cY Charlie Kirk te lo dir\u00e1, TikTok ayud\u00f3, pero Charlie Kirk tambi\u00e9n ayud\u00f3\u201d, dijo Trump durante una ceremonia de juramento en la Oficina Oval para la jueza Jeanine Pirro, a la que Kirk asisti\u00f3 en mayo.<\/p>\n<p>Despu\u00e9s de las elecciones, hubo discusiones sobre un papel para Kirk dentro del Gobierno, dijeron varias fuentes a CNN en ese momento. Finalmente, se decidi\u00f3 que pod\u00eda ser m\u00e1s influyente y tener m\u00e1s poder fuera del Gobierno federal. Sin embargo, fue enormemente influyente con aquellos que s\u00ed terminaron en el gabinete de Trump, ayudando a evaluar y entrevistar a los candidatos.<\/p>\n<p>Kirk se traslad\u00f3 temporalmente a Palm Beach durante la transici\u00f3n presidencial y luego pas\u00f3 una cantidad significativa de tiempo en Washington despu\u00e9s de que el presidente regres\u00f3 al cargo, asistiendo a las ceremonias de juramento de numerosos funcionarios con los que ten\u00eda una relaci\u00f3n cercana. Las fuentes describieron a Kirk como alguien con una habilidad \u00fanica para construir y mantener amistades, incluso con funcionarios que estaban en desacuerdo entre s\u00ed.<\/p>\n<p>La relaci\u00f3n de Kirk con Trump creci\u00f3 durante el segundo mandato, pero la gratitud del presidente ya era evidente desde hace tiempo.<\/p>\n<p>\u201cCharlie es fant\u00e1stico. Quiero decir, este tipo, no crean lo que dicen cuando escuchan que los j\u00f3venes son liberales\u201d, dijo Trump en la v\u00edspera de su investidura. \u201cNo lo son. Quiz\u00e1s sol\u00edan serlo, pero ya no lo son\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlie Kirk era un orgulloso desertor universitario con una l\u00ednea directa al presidente Donald Trump como pocos. Visitante frecuente de la Casa Blanca, Kirk era mucho m\u00e1s que un aficionado leal y admirador del presidente; ten\u00eda el pulso de la base MAGA y se aseguraba de que sus opiniones fueran conocidas, incluso en las raras [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466350","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Charlie Kirk era un orgulloso desertor universitario con una l\u00ednea directa al presidente Donald Trump como pocos. Visitante frecuente de la Casa Blanca, Kirk era mucho m\u00e1s que un aficionado leal y admirador del presidente; ten\u00eda el pulso de la base MAGA y se aseguraba de que sus opiniones fueran conocidas, incluso en las raras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T02:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump\",\"datePublished\":\"2025-09-11T02:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/\"},\"wordCount\":1211,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/\",\"name\":\"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-11T02:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump - Noticias","og_description":"Charlie Kirk era un orgulloso desertor universitario con una l\u00ednea directa al presidente Donald Trump como pocos. Visitante frecuente de la Casa Blanca, Kirk era mucho m\u00e1s que un aficionado leal y admirador del presidente; ten\u00eda el pulso de la base MAGA y se aseguraba de que sus opiniones fueran conocidas, incluso en las raras [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-11T02:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump","datePublished":"2025-09-11T02:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/"},"wordCount":1211,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/","name":"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-11T02:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo Charlie Kirk lleg\u00f3 a ganarse la admiraci\u00f3n de Trump","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/10\/charlie-kirk-admiracion-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-11T02:03:56Z","datePublished":"2025-09-11T02:03:56Z","dateModified":"2025-09-11T02:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo Charlie Kirk lleg\\u00f3 a ganarse la admiraci\\u00f3n de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/10\\\/charlie-kirk-admiracion-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/10\\\/charlie-kirk-admiracion-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-11T02:03:56Z\",\"datePublished\":\"2025-09-11T02:03:56Z\",\"dateModified\":\"2025-09-11T02:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466388,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/12\/sospechoso-asesinato-charlie-kirk-custodia-detenido-trump-trax\/","url_meta":{"origin":1466350,"position":0},"title":"Trump dice que el sospechoso de asesinar a Charlie Kirk est\u00e1 &#171;bajo custodia&#187;","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, sugiri\u00f3 el viernes que el sospechoso del tiroteo de Charlie Kirk est\u00e1 \u201cbajo custodia\u201d.\u201cCreo que con un alto grado de certeza lo tenemos bajo custodia\u201d, declar\u00f3 Trump durante una aparici\u00f3n en Fox News.Trump afirm\u00f3 que alguien \u201cmuy cercano a \u00e9l lo delat\u00f3\u201d y que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466343,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/10\/quien-es-charlie-kirk-disparo-utah-activista-conservador-trax\/","url_meta":{"origin":1466350,"position":1},"title":"\u00bfQui\u00e9n era Charlie Kirk, el activista pro-Trump que muri\u00f3 baleado en una universidad de Utah?","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Charlie Kirk, quien muri\u00f3 tras ser herido de bala durante un evento en la Universidad del Valle de Utah, fue fundador del grupo conservador juvenil Turning Point USA y una voz influyente en el universo MAGA.Kirk emergi\u00f3 durante la primera campa\u00f1a presidencial del presidente Donald Trump como una voz definitoria\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466679,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/22\/analisis-trump-muerte-kirk-camino-futuro-maga-trax\/","url_meta":{"origin":1466350,"position":2},"title":"Trump nunca cambiar\u00e1, pero la muerte de Kirk ilumina el camino hacia el futuro de MAGA","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"El presidente Donald Trump quiere que el mundo entienda que el asesinato de Charlie Kirk no lo moderar\u00e1 ni lo inducir\u00e1 a reparar las divisiones del pa\u00eds.El homenaje f\u00fanebre en Arizona el domingo fue un notable elogio de varias horas por una vida que termin\u00f3 cruelmente demasiado joven, una mirada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466662,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/21\/charlie-kirk-duelo-recriminaciones-movimiento-conservador-trax\/","url_meta":{"origin":1466350,"position":3},"title":"Duelo, recriminaciones y un momento decisivo para el movimiento conservador que fund\u00f3 Charlie Kirk","author":"","date":"septiembre 21, 2025","format":false,"excerpt":"El funeral de Charlie Kirk aqu\u00ed este domingo marcar\u00e1 un momento decisivo para el movimiento conservador de base que fund\u00f3 cuando era adolescente y que segu\u00eda impulsando a principios de este mes, cuando un hombre armado lo mat\u00f3 a tiros.Para los seguidores de Kirk, los d\u00edas desde el asesinato han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466560,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/17\/retiran-programa-jimmy-kimmel-comentarios-charlie-kirk-trax\/","url_meta":{"origin":1466350,"position":4},"title":"Retiran &#171;indefinidamente&#187; del aire el programa de Jimmy Kimmel tras comentarios sobre Charlie Kirk","author":"","date":"septiembre 17, 2025","format":false,"excerpt":"La cadena de televisi\u00f3n ABC de Disney est\u00e1 retirando del aire indefinidamente el programa de entrevistas nocturno de Jimmy Kimmel en medio de una controversia por sus recientes comentarios sobre el presunto asesino de Charlie Kirk.\u201cJimmy Kimmel Live ser\u00e1 suspendido indefinidamente\u201d, dijo un portavoz de ABC, neg\u00e1ndose a compartir m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466644,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/20\/servicio-conmemorativo-charlie-kirk-trax\/","url_meta":{"origin":1466350,"position":5},"title":"As\u00ed ser\u00e1 la ceremonia en memoria de Charlie Kirk","author":"","date":"septiembre 20, 2025","format":false,"excerpt":"Miles de personas se reunir\u00e1n el domingo para honrar la vida del activista conservador asesinado Charlie Kirk en una ceremonia conmemorativa que se espera ponga de manifiesto su indeleble influencia en la pol\u00edtica estadounidense.Con una lista de oradores de los m\u00e1s altos niveles del Gobierno de Estados Unidos, incluido el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1466350"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466350\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1466350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1466350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1466350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}