{"id":1466417,"date":"2025-09-13T04:03:42","date_gmt":"2025-09-13T11:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/"},"modified":"2025-09-13T04:03:42","modified_gmt":"2025-09-13T11:03:42","slug":"estudiantes-internacionales-chinos-atrapados-limbo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/","title":{"rendered":"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo"},"content":{"rendered":"<p>Para los estudiantes chinos, un t\u00edtulo universitario estadounidense antes era considerado un \u201cboleto dorado\u201d para acceder a empleos codiciados en su pa\u00eds. Pero muchos ahora descubren que la geopol\u00edtica est\u00e1 frenando sus ambiciones.<\/p>\n<p> La amenaza de cancelaci\u00f3n de visas por parte de la administraci\u00f3n Trump \u2013posteriormente archivada tras una llamada telef\u00f3nica de tregua comercial entre el presidente de EE.UU. y el l\u00edder de China, Xi Jinping, a principios de junio\u2013 ha agravado la ya creciente incertidumbre para los estudiantes chinos en Estados Unidos.<\/p>\n<p>Y en su pa\u00eds, algunos graduados descubren que su experiencia en el extranjero est\u00e1 levantando se\u00f1ales de alerta entre los empleadores, que cada vez miran con m\u00e1s recelo a los profesionales formados en universidades de todo el mundo.<\/p>\n<p>Con sus padres pagando la costosa factura, algunos estudiantes chinos se preguntan si vale la pena estudiar en el extranjero, especialmente cuando el mercado laboral interno parece favorecer al talento local.<\/p>\n<p>Barry Lian, un graduado de maestr\u00eda de 24 a\u00f1os del sudeste de China que pas\u00f3 tres a\u00f1os estudiando en Estados Unidos, ten\u00eda sue\u00f1os de trabajar en Wall Street, hasta que su visa de estudiante fue revocada abruptamente en julio pasado.<\/p>\n<p>Lian, quien estudi\u00f3 Estad\u00edstica Econ\u00f3mica en una universidad china, perdi\u00f3 su visa debido a una prohibici\u00f3n heredada del primer mandato del presidente Donald Trump, que efectivamente niega visas estadounidenses a estudiantes e investigadores chinos de universidades que se cree que est\u00e1n vinculadas al ej\u00e9rcito chino.<\/p>\n<p>La modificaci\u00f3n dej\u00f3 a Lian varado en China durante su pasant\u00eda de verano, lo que lo oblig\u00f3 a sumergirse en la \u201ccarrera de ratas\u201d del mercado laboral interno.<\/p>\n<p>Ninguna de sus m\u00e1s de 70 solicitudes a bancos y empresas financieras respaldadas por el Estado le consigui\u00f3 un puesto, y la mayor\u00eda ni siquiera pas\u00f3 las evaluaciones iniciales de CV, se\u00f1al\u00f3 Lian.<\/p>\n<p>\u201cEs probable que haya sensibilidades pol\u00edticas en juego\u201d, dijo, y pidi\u00f3 a CNN que no revelara en qu\u00e9 universidad china estudi\u00f3 debido a la sensibilidad del tema.<\/p>\n<p>Lian cree que su experiencia en EE.UU. obstaculiz\u00f3 su ingreso al sector p\u00fablico y convirti\u00f3 su postulaci\u00f3n a un puesto en una empresa privada en un desaf\u00edo inesperado.<\/p>\n<p>\u201cQuedarse atrapado en la disputa entre los dos pa\u00edses te deja simplemente indefenso\u201d, dijo Lian, cuya b\u00fasqueda de empleo finalmente dio sus frutos en marzo con una oferta de una firma de inversi\u00f3n privada en Shangh\u00e1i.<\/p>\n<p>El mercado laboral de China, tanto en el sector privado como en el p\u00fablico, no excluye espec\u00edficamente solo a los graduados estadounidenses, sino a un grupo m\u00e1s amplio de titulados extranjeros, aunque estos eligen cada vez m\u00e1s regresar.<\/p>\n<p>Desde que Xi asumi\u00f3 el cargo en 2013, el n\u00famero anual de retornados del extranjero ha aumentado de manera constante de aproximadamente 350.000 a 580.000 en 2019, antes de superar el mill\u00f3n en 2021, seg\u00fan datos del Ministerio de Educaci\u00f3n y el Centro para China y la Globalizaci\u00f3n, un grupo de expertos con sede en Beijing.<\/p>\n<p>Pero no todas las empresas chinas les dieron una recepci\u00f3n entusiasta en un momento de intenso nacionalismo y sospechas de seguridad nacional bajo el gobierno de Xi.<\/p>\n<p>A fines de abril, Dong Mingzhu, presidente del gigante chino de electrodom\u00e9sticos Gree Electric, dijo en una reuni\u00f3n de accionistas que la compa\u00f1\u00eda \u201cnunca contratar\u00e1 a ning\u00fan repatriado porque podr\u00eda haber esp\u00edas entre ellos\u201d, un comentario criticado en las redes sociales y <a href=\"https:\/\/www.bjnews.com.cn\/detail\/1745388998168042.html\">los medios estatales<\/a> por \u201cestigmatizar\u201d y \u201cestereotipar\u201d a la cohorte que regresa.<\/p>\n<p>La \u201csospecha de espionaje\u201d \u2014una paranoia habitual en empresas estatales\u2014 resulta especialmente alarmante viniendo de un destacado l\u00edder empresarial privado.<\/p>\n<p>Y agrava la situaci\u00f3n de graduados chinos en el extranjero como Lian, quienes afirman que ya se sienten mal recibidos en el sector p\u00fablico chino.<\/p>\n<p>Desde 2023, varias provincias, incluida posiblemente la m\u00e1s liberal de Guangdong en el sudeste de China y grandes ciudades como Beijing, han prohibido a los titulados extranjeros inscribirse en el programa \u201cXuandiaosheng\u201d, una iniciativa de reclutamiento del Gobierno que selecciona a graduados de \u00e9lite para prepararlos como futuros cuadros superiores del Gobierno y del gobernante Partido Comunista.<\/p>\n<p>Ese mismo a\u00f1o, casi la mitad de todos los estudiantes chinos en el extranjero buscaron ingresar a empresas o entidades gubernamentales respaldadas por el Estado, lugares que ofrec\u00edan empleos de \u201cgran calidad\u201d, codiciados por su seguridad percibida en una econom\u00eda en crisis, seg\u00fan un <a href=\"https:\/\/www.fhyanbao.com\/article\/vlZ6djTn\">informe anual<\/a> publicado conjuntamente por la Cumbre Mundial de la Juventud China y Liepin, una importante plataforma de reclutamiento en l\u00ednea en China.<\/p>\n<p>\u201cEl sector p\u00fablico se est\u00e1 volviendo menos receptivo a los graduados extranjeros\u201d, afirm\u00f3 Alfred Wu, profesor asociado de la Escuela de Pol\u00edticas P\u00fablicas Lee Kuan Yew de la Universidad Nacional de Singapur. Se\u00f1al\u00f3 la preocupaci\u00f3n generalizada por la seguridad nacional como un factor clave.<\/p>\n<p>Wu explic\u00f3 que un clima de paranoia en torno al espionaje se ha convertido en una \u201cnorma social\u201d en China, en gran parte gracias a una campa\u00f1a en las redes sociales del Ministerio de Seguridad del Estado (MSS), la poderosa agencia de espionaje civil de China, que peri\u00f3dicamente les dice a los ciudadanos que hay esp\u00edas extranjeros en todas partes.<\/p>\n<p>Los graduados extranjeros, en particular, han sido vistos durante mucho tiempo por el MSS como \u201cblancos f\u00e1ciles\u201d para ser reclutados por agencias de espionaje for\u00e1neas, dijeron los medios estatales.<\/p>\n<p>Una serie reciente de videos de propaganda publicados por la cuenta de redes sociales de la autoridad incluye <a href=\"https:\/\/mp.weixin.qq.com\/s\/ganFmWNjBD11HDAtZq1qhQ\">uno<\/a> que detalla c\u00f3mo un hombre chino fue atra\u00eddo por un esp\u00eda extranjero durante sus estudios de doctorado en el extranjero y termin\u00f3 ayud\u00e1ndolos a recopilar secretos nacionales clasificados.<\/p>\n<p>Para algunos empleadores chinos, contratar graduados nacionales no solo significa menos preocupaciones de seguridad: tambi\u00e9n son m\u00e1s baratos y se adaptan mejor a la cultura y el mercado locales.<\/p>\n<p>Yuan Xin, consultor de desarrollo profesional en Shangh\u00e1i, dijo que algunas empresas chinas prefieren a los estudiantes nacionales m\u00e1s rentables, considerados por tener una \u00e9tica de trabajo m\u00e1s fuerte y un mejor conocimiento del mercado local.<\/p>\n<p>\u201cPor lo que hemos visto, la mayor\u00eda de los estudiantes que regresan despu\u00e9s de un programa de maestr\u00eda de un a\u00f1o de hecho no tienen fuertes habilidades de estudio y sus habilidades laborales son exactamente as\u00ed\u201d, dijo Yuan, argumentando que el \u201cmecanismo de selecci\u00f3n\u201d para los programas de posgrado nacionales es m\u00e1s riguroso que los utilizados en el extranjero.<\/p>\n<p>En China, los estudiantes deben aprobar un examen de ingreso a estudios de posgrado nacional altamente competitivo y luego estudiar durante al menos dos a\u00f1os antes de obtener un t\u00edtulo de maestr\u00eda.<\/p>\n<p>Los poseedores de t\u00edtulos de maestr\u00eda han dominado durante mucho tiempo el panorama de los retornados, representando casi el 80 % de todos los retornados el a\u00f1o pasado, seg\u00fan una encuesta anual de Zhilian Zhaopin, una plataforma de reclutamiento l\u00edder en China.<\/p>\n<p>Yuan dijo que los graduados de pa\u00edses occidentales, donde el equilibrio entre vida laboral y personal es muy valorado, \u201cpueden no encajar del todo\u201d en la cultura laboral dom\u00e9stica, donde los horarios \u201c996\u201d \u2013de 9:00 a.m. a 9:00 p.m., seis d\u00edas a la semana\u2013 son comunes.<\/p>\n<p>La creencia generalizada de que los graduados extranjeros no son tan comprometidos ni capaces como los locales le parece a Ezio Duan un \u201cestereotipo\u201d, lo que seg\u00fan \u00e9l tuvo un \u201cimpacto real\u201d en su b\u00fasqueda de empleo en octubre pasado.<\/p>\n<p>Duan estudi\u00f3 comunicaci\u00f3n en Estados Unidos, tanto para su licenciatura como para su maestr\u00eda, y afirm\u00f3 que solo recibi\u00f3 tres ofertas de unas 400 solicitudes de empleo formales.<\/p>\n<p>Otros posgraduados que han regresado comparten en l\u00ednea quejas similares sobre la generalizaci\u00f3n excesiva.<\/p>\n<p>Duan, quien estudi\u00f3 en Estados Unidos durante cinco a\u00f1os y se centra en empresas privadas en China, considera la \u201cpresi\u00f3n generalizada de las largas jornadas laborales\u201d en su pa\u00eds como \u201cun verdadero problema\u201d. Sin embargo, Lian, quien se mostr\u00f3 abierto a trabajar en empresas estatales tras tres a\u00f1os en Estados Unidos, afirm\u00f3 que \u201cno se resistir\u00e1 mucho\u201d a la cultura laboral en su pa\u00eds.<\/p>\n<p>Pero incluso a los graduados chinos en el extranjero que m\u00e1s trabajan puede resultarles dif\u00edcil superar el cambio de actitud de los empleadores nacionales.<\/p>\n<p>Wu, un estudioso de pol\u00edticas p\u00fablicas chinas, dice que los empleadores se han vuelto m\u00e1s reacios a contratar a graduados extranjeros como Duan y Lian debido a las pol\u00edticas \u201cintrospectivas\u201d de Xi.<\/p>\n<p>\u201c(Xi) pretende construir un sistema relativamente cerrado ya que existe una narrativa importante que \u00e9l ve como una dura realidad: la rivalidad entre China y Estados Unidos\u201d, dijo Wu.<\/p>\n<p>Wu dijo que la tendencia \u201cintrospectiva\u201d se ha vuelto m\u00e1s clara para el p\u00fablico desde 2018, cuando Xi elimin\u00f3 los l\u00edmites al mandato presidencial, y desde entonces ha reforzado la \u201cautosuficiencia y seguridad\u201d internas en medio de una guerra comercial entre China y Estados Unidos.<\/p>\n<p>\u201cEl \u00e9nfasis en la estabilidad y el control internos ha, en muchos sentidos, prevalecido sobre los compromisos previos de reforma y apertura\u201d, dijo Wu y se\u00f1al\u00f3 que los estudiantes extranjeros son una encarnaci\u00f3n clave de la pol\u00edtica de \u201cpuertas abiertas\u201d de China.<\/p>\n<p>\u201cEsas ventajas que cre\u00edamos tener hace seis a\u00f1os se han erosionado por completo en los \u00faltimos tiempos\u201d, coment\u00f3 Duan, licenciado en comunicaciones.<\/p>\n<p>\u201cEso es algo que realmente no esperaba\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para los estudiantes chinos, un t\u00edtulo universitario estadounidense antes era considerado un \u201cboleto dorado\u201d para acceder a empleos codiciados en su pa\u00eds. Pero muchos ahora descubren que la geopol\u00edtica est\u00e1 frenando sus ambiciones. La amenaza de cancelaci\u00f3n de visas por parte de la administraci\u00f3n Trump \u2013posteriormente archivada tras una llamada telef\u00f3nica de tregua comercial entre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466417","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Para los estudiantes chinos, un t\u00edtulo universitario estadounidense antes era considerado un \u201cboleto dorado\u201d para acceder a empleos codiciados en su pa\u00eds. Pero muchos ahora descubren que la geopol\u00edtica est\u00e1 frenando sus ambiciones. La amenaza de cancelaci\u00f3n de visas por parte de la administraci\u00f3n Trump \u2013posteriormente archivada tras una llamada telef\u00f3nica de tregua comercial entre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-13T11:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo\",\"datePublished\":\"2025-09-13T11:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/\"},\"wordCount\":1645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/\",\"name\":\"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-13T11:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo - Noticias","og_description":"Para los estudiantes chinos, un t\u00edtulo universitario estadounidense antes era considerado un \u201cboleto dorado\u201d para acceder a empleos codiciados en su pa\u00eds. Pero muchos ahora descubren que la geopol\u00edtica est\u00e1 frenando sus ambiciones. La amenaza de cancelaci\u00f3n de visas por parte de la administraci\u00f3n Trump \u2013posteriormente archivada tras una llamada telef\u00f3nica de tregua comercial entre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-13T11:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/"},"author":{"name":"","@id":""},"headline":"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo","datePublished":"2025-09-13T11:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/"},"wordCount":1645,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/","name":"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-13T11:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/estudiantes-internacionales-chinos-atrapados-limbo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-13T11:03:42Z","datePublished":"2025-09-13T11:03:42Z","dateModified":"2025-09-13T11:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se\\u00f1alados en el extranjero y rechazados en casa: los estudiantes internacionales chinos atrapados en el limbo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/13\\\/estudiantes-internacionales-chinos-atrapados-limbo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/13\\\/estudiantes-internacionales-chinos-atrapados-limbo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-13T11:03:42Z\",\"datePublished\":\"2025-09-13T11:03:42Z\",\"dateModified\":\"2025-09-13T11:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462940,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/29\/visa-estudiante-china-revocar-rubio-trax\/","url_meta":{"origin":1466417,"position":0},"title":"La administraci\u00f3n Trump revocar\u00e1 agresivamente las visas de estudiantes chinos en una importante escalada con Beijing","author":"","date":"mayo 29, 2025","format":false,"excerpt":"Estados Unidos revocar\u00e1 agresivamente las visas de estudiantes chinos, anunci\u00f3 este mi\u00e9rcoles el secretario de Estado, Marco Rubio, en una importante escalada de tensiones con Beijing y un nuevo rev\u00e9s para las instituciones de educaci\u00f3n superior estadounidenses.El alto diplom\u00e1tico estadounidense dijo que el Departamento de Estado colaborar\u00e1 con el Departamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462944,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/29\/china-eeuu-tregua-chips-visa-estudiante-trax\/","url_meta":{"origin":1466417,"position":1},"title":"China cre\u00eda haber llegado a una tregua con EE.UU. pero Trump lanz\u00f3 dos ofensivas","author":"","date":"mayo 29, 2025","format":false,"excerpt":"Un doble golpe de Estados Unidos corre el riesgo de romper la ya fr\u00e1gil tregua de la guerra comercial entre Washington y Beijing, ya que tanto empresas tecnol\u00f3gicas como estudiantes chinos recibieron golpes impactantes por parte de la administraci\u00f3n Trump este mi\u00e9rcoles por la noche.Visto desde dentro de China, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465950,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/28\/carteles-mexicanos-redes-chinas-lavado-venta-drogas-tesoro-orix\/","url_meta":{"origin":1466417,"position":2},"title":"El Tesoro de EE.UU. dice que c\u00e1rteles mexicanos est\u00e1n usando redes chinas para blanquear ganancias por venta de drogas","author":"","date":"agosto 28, 2025","format":false,"excerpt":"El Departamento del Tesoro de EE.UU. alert\u00f3 que c\u00e1rteles mexicanos han estado utilizando redes chinas de lavado de dinero para obtener ganancias por la venta de drogas en Estados Unidos.Seg\u00fan un aviso emitido este jueves por la Red de Control de Delitos Financieros (FinCEN, por sus siglas en ingl\u00e9s) \u2014adscrita\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462987,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/29\/trump-medidas-contra-china-frustracion-negociaciones-trax\/","url_meta":{"origin":1466417,"position":3},"title":"El Gobierno de Trump tom\u00f3 medidas contra China debido a la frustraci\u00f3n en las negociaciones comerciales, dicen funcionarios","author":"","date":"mayo 29, 2025","format":false,"excerpt":"La oleada de medidas punitivas tomadas contra China por parte de la administraci\u00f3n Trump en los \u00faltimos d\u00edas fue motivada por la creencia, entre funcionarios estadounidenses, de que China no cumpli\u00f3 los compromisos asumidos en las negociaciones comerciales a principios de este mes, dijeron tres funcionarios de la administraci\u00f3n a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462942,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/29\/estudiantes-titulares-visas-departamento-estado-harvard-trax\/","url_meta":{"origin":1466417,"position":4},"title":"El Departamento de Estado revisa a todos los titulares de visas afiliadas a Harvard, seg\u00fan funcionarios","author":"","date":"mayo 29, 2025","format":false,"excerpt":"El Departamento de Estado de EE.UU. est\u00e1 revisando a todos los titulares de visas afiliadas a la Universidad de Harvard, no solo a los estudiantes, seg\u00fan informaron a CNN este mi\u00e9rcoles tres altos funcionarios del Departamento de Estado.Esta medida supone una notable escalada de la disputa de la administraci\u00f3n Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463202,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/06\/04\/investigadores-chinos-contrabandear-patogenos-biologicos-michigan-trax\/","url_meta":{"origin":1466417,"position":5},"title":"Acusan a investigadores chinos de contrabandear pat\u00f3genos biol\u00f3gicos para estudios en laboratorio de Universidad de Michigan","author":"","date":"junio 4, 2025","format":false,"excerpt":"Dos investigadores chinos fueron acusados de contrabandear un pat\u00f3geno biol\u00f3gico que planeaban estudiar en un laboratorio de la Universidad de Michigan el verano pasado, seg\u00fan una denuncia presentada el martes.Yunqing Jian, de 33 a\u00f1os, y Zunyong Liu, de 34, fueron acusados de conspiraci\u00f3n para cometer un delito o defraudar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1466417"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466417\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1466417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1466417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1466417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}