{"id":1466431,"date":"2025-09-13T16:03:38","date_gmt":"2025-09-13T23:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/"},"modified":"2025-09-13T16:03:38","modified_gmt":"2025-09-13T23:03:38","slug":"netanyahu-ataque-qatar-rehenes-sabotaje-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/","title":{"rendered":"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &#171;sabotaje&#187;"},"content":{"rendered":"<p>El primer ministro de Israel, Benjamin Netanyahu, redobl\u00f3 su ofensiva contra los negociadores de Hamas en Qatar a principios de esta semana, justificando el ataque en una publicaci\u00f3n en redes sociales este s\u00e1bado, afirmando que matarlos habr\u00eda \u201celiminado el principal obst\u00e1culo para liberar a todos nuestros rehenes y poner fin a la guerra\u201d.<\/p>\n<p>Sin embargo, un importante grupo de familiares de los rehenes rechaz\u00f3 la afirmaci\u00f3n del primer ministro, acusando a Netanyahu de \u201csabotaje\u201d y de ser un \u201cobst\u00e1culo\u201d para terminar con la guerra en Gaza.<\/p>\n<p>\u201cLa operaci\u00f3n dirigida en Qatar demostr\u00f3, sin lugar a dudas, que existe un obst\u00e1culo para el regreso de los 48 rehenes y el fin de la guerra: el primer ministro Netanyahu\u201d, dijo el Foro de Familias de Rehenes y Desaparecidos en un comunicado este s\u00e1bado. \u201cCada vez que se acerca un acuerdo, Netanyahu lo sabotea\u201d.<\/p>\n<p>Cuando Israel atac\u00f3 un edificio que albergaba al equipo negociador de Hamas en Doha el 9 de septiembre, Hamas hab\u00eda declarado d\u00edas antes que estaba revisando las \u201cideas\u201d de cese del fuego por Estados Unidos, principios que el propio Netanyahu afirm\u00f3 posteriormente que Israel hab\u00eda aceptado.<\/p>\n<p>Ese intento de homicidio finalmente fracas\u00f3, y Hamas afirm\u00f3 que mat\u00f3 a cinco miembros de menor rango del grupo y a un funcionario de seguridad catar\u00ed.<\/p>\n<p>Qatar, por su parte, ha calificado el ataque como \u201cterrorismo de Estado\u201d y prometi\u00f3 responder con la ayuda de sus socios regionales.<\/p>\n<p>El primer ministro de Qatar, el jeque Mohammed bin Abdulrahman bin Jassim Al-Thani, dijo el mi\u00e9rcoles en una <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/10\/mundo\/ministro-qatar-netanyahu-esperanza-rehenes-trax\">entrevista exclusiva a CNN<\/a>, que Netanyahu \u201cmat\u00f3 cualquier esperanza\u201d para los rehenes que permanecen en Gaza, luego del <a href=\"https:\/\/cnnespanol.cnn.com\/mundo\/live-news\/israel-ataque-lideres-hamas-doha-ii-trax\">intento de Israel de matar <\/a>a los l\u00edderes de Hamas en Doha.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer ministro de Israel, Benjamin Netanyahu, redobl\u00f3 su ofensiva contra los negociadores de Hamas en Qatar a principios de esta semana, justificando el ataque en una publicaci\u00f3n en redes sociales este s\u00e1bado, afirmando que matarlos habr\u00eda \u201celiminado el principal obst\u00e1culo para liberar a todos nuestros rehenes y poner fin a la guerra\u201d. Sin embargo, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466431","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &quot;sabotaje&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &quot;sabotaje&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El primer ministro de Israel, Benjamin Netanyahu, redobl\u00f3 su ofensiva contra los negociadores de Hamas en Qatar a principios de esta semana, justificando el ataque en una publicaci\u00f3n en redes sociales este s\u00e1bado, afirmando que matarlos habr\u00eda \u201celiminado el principal obst\u00e1culo para liberar a todos nuestros rehenes y poner fin a la guerra\u201d. Sin embargo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-13T23:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &#171;sabotaje&#187;\",\"datePublished\":\"2025-09-13T23:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/\"},\"wordCount\":327,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/\",\"name\":\"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de \\\"sabotaje\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-13T23:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &#171;sabotaje&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de \"sabotaje\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de \"sabotaje\" - Noticias","og_description":"El primer ministro de Israel, Benjamin Netanyahu, redobl\u00f3 su ofensiva contra los negociadores de Hamas en Qatar a principios de esta semana, justificando el ataque en una publicaci\u00f3n en redes sociales este s\u00e1bado, afirmando que matarlos habr\u00eda \u201celiminado el principal obst\u00e1culo para liberar a todos nuestros rehenes y poner fin a la guerra\u201d. Sin embargo, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-13T23:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/"},"author":{"name":"","@id":""},"headline":"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &#171;sabotaje&#187;","datePublished":"2025-09-13T23:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/"},"wordCount":327,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/","name":"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de \"sabotaje\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-13T23:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &#171;sabotaje&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &#171;sabotaje&#187;","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/13\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-13T23:03:38Z","datePublished":"2025-09-13T23:03:38Z","dateModified":"2025-09-13T23:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mientras Netanyahu redobla su ataque contra Qatar, las familias de los rehenes lo acusan de &#171;sabotaje&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/13\\\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/13\\\/netanyahu-ataque-qatar-rehenes-sabotaje-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-13T23:03:38Z\",\"datePublished\":\"2025-09-13T23:03:38Z\",\"dateModified\":\"2025-09-13T23:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461833,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/01\/netanyahu-rehenes-guerra-gaza-objetivo-supremo-trax\/","url_meta":{"origin":1466431,"position":0},"title":"Netanyahu dice que derrotar a enemigos de Israel es m\u00e1s importante que liberar rehenes; expandir\u00e1 la guerra en Gaza","author":"","date":"mayo 1, 2025","format":false,"excerpt":"El primer ministro de Israel, Benjam\u00edn Netanyahu, se reunir\u00e1 el viernes con altos funcionarios de defensa mientras Israel se prepara para expandir su guerra en Gaza, seg\u00fan dijo este jueves una fuente familiarizada con el asunto.El ministro de Defensa, Israel Katz, y el jefe de Estado Mayor de las Fuerzas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466354,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/10\/ministro-qatar-netanyahu-esperanza-rehenes-trax\/","url_meta":{"origin":1466431,"position":1},"title":"Exclusivo CNN: primer ministro de Qatar dice que Netanyahu &#171;mat\u00f3 cualquier esperanza&#187; para los rehenes israel\u00edes","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"El primer ministro de Qatar critic\u00f3 duramente al primer ministro de Israel, Benjamin Netanyahu, en una entrevista exclusiva con CNN este mi\u00e9rcoles, calificando de \u201cb\u00e1rbaro\u201d el intento de homicidio por parte de Israel de los l\u00edderes de Hamas en Doha.\u201cPens\u00e1bamos que est\u00e1bamos tratando con gente civilizada\u201d, dijo el primer ministro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465827,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/25\/netanyahu-estrategia-alto-el-fuego-hamas-trax\/","url_meta":{"origin":1466431,"position":2},"title":"Siguiendo el ejemplo de Trump, Netanyahu cambia su estrategia sobre el alto el fuego incluso despu\u00e9s de que Hamas lo aceptara","author":"","date":"agosto 25, 2025","format":false,"excerpt":"Casi una semana despu\u00e9s de que Hamas aceptara la \u00faltima propuesta de cese del fuego en Gaza de los mediadores qatar\u00edes y egipcios, Israel a\u00fan no ha respondido, incluso cuando el primer ministro Benjamin Netanyahu afirma que est\u00e1 iniciando \u201cinmediatamente\u201d negociaciones para liberar a todos los rehenes y poner fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462042,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/06\/netanyahu-elige-guerra-israel-en-gaza-analisis-trax\/","url_meta":{"origin":1466431,"position":3},"title":"Netanyahu elige la guerra y su supervivencia pol\u00edtica mientras los israel\u00edes exigen un acuerdo sobre la liberaci\u00f3n de rehenes","author":"","date":"mayo 6, 2025","format":false,"excerpt":"El primer ministro de Israel Benjamin Netanyahu mantuvo las apariencias durante casi 19 meses: la liberaci\u00f3n de los rehenes y la derrota de Hamas, insisti\u00f3, ocupaban la cima de la pir\u00e1mide de los objetivos b\u00e9licos de Israel.Incluso cuando miembros de su coalici\u00f3n gobernante de derecha amenazaban con derrocar a su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464466,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/12\/israel-hamas-acusan-estancamiento-negociaciones-gaza-trax\/","url_meta":{"origin":1466431,"position":4},"title":"Israel y Hamas se acusan mutuamente del estancamiento en las negociaciones para un alto el fuego en Gaza","author":"","date":"julio 12, 2025","format":false,"excerpt":"Israel y Hamas se acusan mutuamente del estancamiento en las negociaciones de un alto el fuego en Gaza. El grupo palestino atribuye la falta de avances a nuevas condiciones impuestas por el primer ministro de Israel, Benjamin Netanyahu, mientras que una fuente pol\u00edtica de Israel asegura que Hamas rechaz\u00f3 una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466929,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/28\/reservas-netanyahu-plan-trump-gaza-trax\/","url_meta":{"origin":1466431,"position":5},"title":"Trump promete &#171;algo especial&#187; sobre Gaza, pero funcionarios israel\u00edes dicen que Netanyahu tiene reservas sobre ese plan","author":"","date":"septiembre 28, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump ha prometido que \u201calgo especial\u201d est\u00e1 por venir sobre Gaza, mientras funcionarios israel\u00edes afirman que el primer ministro de Israel Benjamin Netanyahu tiene reservas respecto al plan de 21 puntos de la Casa Blanca para el cese del fuego y la gobernanza posterior en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1466431"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466431\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1466431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1466431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1466431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}