{"id":1466491,"date":"2025-09-15T18:03:45","date_gmt":"2025-09-16T01:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/"},"modified":"2025-09-15T18:03:45","modified_gmt":"2025-09-16T01:03:45","slug":"milei-presupuesto-argentina-efe","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/15\/milei-presupuesto-argentina-efe\/","title":{"rendered":"Tras derrota en elecciones provinciales, Milei dice que &#171;lo peor ya pas\u00f3&#187; y env\u00eda presupuesto al Congreso de Argentina"},"content":{"rendered":"<p>El presidente de Argentina, Javier Milei, asegur\u00f3 este lunes, al anunciar el env\u00edo al Congreso del proyecto de Presupuesto 2026, que el equilibrio fiscal no es un \u201ccapricho\u201d sino un principio \u201cno negociable\u201d de su Gobierno.<\/p>\n<p>\u201cEl equilibrio fiscal es la piedra angular de nuestro Gobierno y es un principio no negociable\u201d, afirm\u00f3 Milei este lunes, en un mensaje grabado, emitido en directo a todo el pa\u00eds. \u201cEs la soluci\u00f3n definitiva a los problemas que azotan desde hace d\u00e9cadas a la Argentina\u201d, agreg\u00f3.<\/p>\n<p>Milei no precis\u00f3 durante su mensaje cu\u00e1l es la proyecci\u00f3n de super\u00e1vit fiscal para el a\u00f1o pr\u00f3ximo, ni la meta de crecimiento econ\u00f3mico ni la de inflaci\u00f3n<\/p>\n<p>El mandatario pidi\u00f3 tambi\u00e9n a los argentinos \u201cno aflojar\u201d, reconoci\u00f3 que \u201cel camino es arduo\u201d y enfatiz\u00f3 que \u201clo peor ya pas\u00f3\u201d.<\/p>\n<p>\u201cQuisiera destacar que, por como fue configurado el plan de gobierno, los a\u00f1os m\u00e1s duros de afrontar fueron los primeros. Y por eso podemos afirmar, como hemos hecho en tantas otras veces y pese a las turbulencias coyunturales, que lo peor ya pas\u00f3\u201d, se\u00f1al\u00f3 Meli, en un contexto de inestabilidad pol\u00edtica y econ\u00f3mica en el pa\u00eds tras la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/07\/argentina\/peronismo-aplasta-partido-milei-elecciones-buenos-aires-efe\">reciente derrota del Gobierno en las elecciones legislativas en la provincia de Buenos Aires.<\/a><\/p>\n<p>Al respecto, Milei adelant\u00f3 que el proyecto propone un aumento de las partidas para <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/27\/argentina\/jubilarse-medida-milei-recorto-esperanzas-orix\">pensionados <\/a>del 5 % mientras que se incrementar\u00e1 el gasto en <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/05\/argentina\/milei-retira-oms-orix\">salud <\/a>en 17 %, dos \u00e1reas en las que su Gobierno hab\u00eda sido criticado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Argentina, Javier Milei, asegur\u00f3 este lunes, al anunciar el env\u00edo al Congreso del proyecto de Presupuesto 2026, que el equilibrio fiscal no es un \u201ccapricho\u201d sino un principio \u201cno negociable\u201d de su Gobierno. \u201cEl equilibrio fiscal es la piedra angular de nuestro Gobierno y es un principio no negociable\u201d, afirm\u00f3 Milei este [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466491","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tras derrota en elecciones provinciales, Milei dice que &quot;lo peor ya pas\u00f3&quot; y env\u00eda presupuesto al Congreso de Argentina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras derrota en elecciones provinciales, Milei dice que &quot;lo peor ya pas\u00f3&quot; y env\u00eda presupuesto al Congreso de Argentina - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Argentina, Javier Milei, asegur\u00f3 este lunes, al anunciar el env\u00edo al Congreso del proyecto de Presupuesto 2026, que el equilibrio fiscal no es un \u201ccapricho\u201d sino un principio \u201cno negociable\u201d de su Gobierno. \u201cEl equilibrio fiscal es la piedra angular de nuestro Gobierno y es un principio no negociable\u201d, afirm\u00f3 Milei este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T01:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tras derrota en elecciones provinciales, Milei dice que &#171;lo peor ya pas\u00f3&#187; y env\u00eda presupuesto al Congreso de Argentina\",\"datePublished\":\"2025-09-16T01:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/\"},\"wordCount\":293,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/\",\"name\":\"Tras derrota en elecciones provinciales, Milei dice que \\\"lo peor ya pas\u00f3\\\" y env\u00eda presupuesto al Congreso de Argentina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-16T01:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras derrota en elecciones provinciales, Milei dice que &#171;lo peor ya pas\u00f3&#187; y env\u00eda presupuesto al Congreso de Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras derrota en elecciones provinciales, Milei dice que \"lo peor ya pas\u00f3\" y env\u00eda presupuesto al Congreso de Argentina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/","og_locale":"es_ES","og_type":"article","og_title":"Tras derrota en elecciones provinciales, Milei dice que \"lo peor ya pas\u00f3\" y env\u00eda presupuesto al Congreso de Argentina - Noticias","og_description":"El presidente de Argentina, Javier Milei, asegur\u00f3 este lunes, al anunciar el env\u00edo al Congreso del proyecto de Presupuesto 2026, que el equilibrio fiscal no es un \u201ccapricho\u201d sino un principio \u201cno negociable\u201d de su Gobierno. \u201cEl equilibrio fiscal es la piedra angular de nuestro Gobierno y es un principio no negociable\u201d, afirm\u00f3 Milei este [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/","og_site_name":"Noticias","article_published_time":"2025-09-16T01:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/"},"author":{"name":"","@id":""},"headline":"Tras derrota en elecciones provinciales, Milei dice que &#171;lo peor ya pas\u00f3&#187; y env\u00eda presupuesto al Congreso de Argentina","datePublished":"2025-09-16T01:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/"},"wordCount":293,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/","url":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/","name":"Tras derrota en elecciones provinciales, Milei dice que \"lo peor ya pas\u00f3\" y env\u00eda presupuesto al Congreso de Argentina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-16T01:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/15\/milei-presupuesto-argentina-efe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tras derrota en elecciones provinciales, Milei dice que &#171;lo peor ya pas\u00f3&#187; y env\u00eda presupuesto al Congreso de Argentina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/15\/milei-presupuesto-argentina-efe\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tras derrota en elecciones provinciales, Milei dice que &#171;lo peor ya pas\u00f3&#187; y env\u00eda presupuesto al Congreso de Argentina","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/15\/milei-presupuesto-argentina-efe\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/15\/milei-presupuesto-argentina-efe\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-16T01:03:45Z","datePublished":"2025-09-16T01:03:45Z","dateModified":"2025-09-16T01:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tras derrota en elecciones provinciales, Milei dice que &#171;lo peor ya pas\\u00f3&#187; y env\\u00eda presupuesto al Congreso de Argentina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/15\\\/milei-presupuesto-argentina-efe\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/15\\\/milei-presupuesto-argentina-efe\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-16T01:03:45Z\",\"datePublished\":\"2025-09-16T01:03:45Z\",\"dateModified\":\"2025-09-16T01:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452758,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/09\/17\/milei-presupuesto-2025-inflacion-dolar-argentina-orix\/","url_meta":{"origin":1466491,"position":0},"title":"Milei presenta el presupuesto 2025: proyecta inflaci\u00f3n de 18% y d\u00f3lar a 1.207 pesos","author":"","date":"septiembre 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente de Argentina, Javier Milei, present\u00f3 este domingo el presupuesto para 2025 en un mensaje ofrecido desde el Congreso, que ahora deber\u00e1 discutir y \u2015en su caso\u2015 aprobarlo.En un hecho inusual, ya que esta presentaci\u00f3n suele ser realizada por el ministro de Econom\u00eda frente a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459773,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/11\/martin-yeza-no-es-bueno-que-el-acuerdo-con-el-fmi-sea-por-dnu\/","url_meta":{"origin":1466491,"position":1},"title":"Mart\u00edn Yeza: &#171;No es bueno que el acuerdo con el FMI sea por DNU&#187;","author":"","date":"marzo 11, 2025","format":false,"excerpt":"Mart\u00edn Yeza, diputado nacional por el PRO, visit\u00f3 el piso de La Ma\u00f1ana de CNN para conversar con Nacho Gir\u00f3n y equipo sobre su espacio pol\u00edtico, los dichos de Mauricio Macri respecto al decreto del acuerdo con el FMI y el Presupuesto 2025, Javier Milei y el v\u00ednculo LLA-PRO\u201cEl decreto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448489,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/24\/analisis-impacto-marcha-universitaria-argentina-gobierno-milei-orix\/","url_meta":{"origin":1466491,"position":2},"title":"An\u00e1lisis | El impacto de la masiva marcha universitaria en Argentina para el gobierno de Milei","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Llegar a la hist\u00f3rica Plaza de Mayo, en el centro de Buenos Aires, fue una tarea casi imposible. Cuadras y cuadras de manifestantes, entre ellos estudiantes, profesores y egresados, se sumaron a una protesta que denunci\u00f3 el ajuste presupuestario en las universidades p\u00fablicas de Argentina.Una multitud llen\u00f3 Avenida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448401,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/04\/23\/milei-cadena-nacional-superavit-financiero-orix\/","url_meta":{"origin":1466491,"position":3},"title":"Javier Milei habl\u00f3 en cadena nacional y dijo que el super\u00e1vit financiero alcanzado por su Gobierno en el primer trimestre es &#171;un hito&#187;","author":"","date":"abril 23, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) --El presidente de Argentina, Javier Milei, habl\u00f3 en cadena nacional para hacer un balance de los tres primeros meses de su gesti\u00f3n.Rodeado por su equipo econ\u00f3mico -encabezado por el ministro de Econom\u00eda, Luis Caputo-, el mandatario inform\u00f3 en su discurso que \u201cel sector p\u00fablico nacional registr\u00f3 durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449758,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/25\/milei-pacto-de-mayo-sin-firma-cordoba-orix\/","url_meta":{"origin":1466491,"position":4},"title":"Sin la firma del Pacto de Mayo \u00bfQu\u00e9 har\u00e1 Javier Milei este s\u00e1bado en C\u00f3rdoba?","author":"","date":"mayo 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, participar\u00e1 este s\u00e1bado de un acto en la provincia de C\u00f3rdoba para celebrar un nuevo aniversario de la Revoluci\u00f3n de Mayo, en la que se conmemora el inicio del proceso que culmin\u00f3 en la independencia argentina. Finalmente, el evento no contar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446556,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/03\/06\/pacto-de-mayo-milei-apuesta-gobierno-orix\/","url_meta":{"origin":1466491,"position":5},"title":"Qu\u00e9 es el Pacto de Mayo de Milei y por qu\u00e9 es una gran apuesta del Gobierno","author":"","date":"marzo 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \"Un nuevo contrato social\". As\u00ed defini\u00f3 el presidente de Argentina, Javier Milei, al Pacto de Mayo. Convoc\u00f3 a gobernadores, expresidentes y l\u00edderes de partidos pol\u00edticos a firmar un consenso de 10 puntos que, seg\u00fan el jefe de Estado, establecer\u00edan \"los principios del nuevo orden econ\u00f3mico argentino\".Puede sonar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1466491"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466491\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1466491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1466491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1466491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}