{"id":1466509,"date":"2025-09-16T08:03:48","date_gmt":"2025-09-16T15:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/"},"modified":"2025-09-16T08:03:48","modified_gmt":"2025-09-16T15:03:48","slug":"brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/","title":{"rendered":"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &#171;medida pol\u00edtica&#187;"},"content":{"rendered":"<p>El canciller de Brasil, Mauro Vieira, calific\u00f3 como una \u201cinterferencia en asuntos internos\u201d las solicitudes y presiones internacionales \u2014incluidas las del Gobierno de Estados Unidos\u2014 para liberar al expresidente Jair Bolsonaro, condenado a m\u00e1s de 27 a\u00f1os de prisi\u00f3n por intento de golpe de Estado, durante una entrevista con CNN.<\/p>\n<p>Vieira se\u00f1al\u00f3 que el presidente Lula da Silva no tiene autoridad alguna para intervenir en decisiones del Poder Judicial, que, record\u00f3, es totalmente independiente. \u201cHablar del juicio al expresidente y pedir su liberaci\u00f3n por cualquier motivo es una interferencia en asuntos internos. Es imposible para el presidente Lula hacer algo al respecto, porque los tres poderes del Gobierno brasile\u00f1o son independientes\u201d, dijo.<\/p>\n<p>Mientras tanto, la defensa de Bolsonaro ya <a href=\"https:\/\/cnnespanol.cnn.com\/latinoamerica\/live-news\/fallo-juicio-bolsonaro-brasil-condena-golpe-estado-orix\">adelant<\/a>\u00f3 que apelar\u00e1 la decisi\u00f3n del Tribunal Federal Supremo, incluso ante instancias internacionales. En un comunicado, los abogados calificaron la sentencia como \u201cabsurdamente excesiva y desproporcionada\u201d, y aseguraron que presentar\u00e1n un recurso tras revisar el fallo.<\/p>\n<p>Las declaraciones de Vieira llegan en un contexto de creciente tensi\u00f3n diplom\u00e1tica, marcado por los comentarios del presidente Donald Trump, quien adopt\u00f3 una postura abiertamente cr\u00edtica frente al juicio de Bolsonaro, al calificarlo como una \u201ccacer\u00eda de brujas\u201d, y lleg\u00f3 incluso a imponer un arancel del 50 % a Brasil como medida de presi\u00f3n para que se pusiera fin al proceso judicial.<\/p>\n<p>Tras conocerse la sentencia del expresidente de 70 a\u00f1os, Trump <a href=\"https:\/\/cnnespanol.cnn.com\/latinoamerica\/live-news\/fallo-juicio-bolsonaro-brasil-condena-golpe-estado-orix#cmfg38pz30000356nucz8m9me\">compar\u00f3 <\/a>su situaci\u00f3n con los procesos judiciales que \u00e9l mismo enfrenta en Estados Unidos, al afirmar que ambos son v\u00edctimas de persecuci\u00f3n pol\u00edtica. Lula respondi\u00f3 con firmeza: \u201cEste pa\u00eds es un ejemplo de c\u00f3mo se practica la democracia\u201d.<\/p>\n<p>El secretario de Estado de EE.UU., Marco Rubio, <a href=\"https:\/\/cnnespanol.cnn.com\/latinoamerica\/live-news\/fallo-juicio-bolsonaro-brasil-condena-golpe-estado-orix#cmffzzc32001o356nhiui7ijb\">calific\u00f3 <\/a>en X el veredicto de \u201cinjusto\u201d y afirm\u00f3 que Estados Unidos \u201cresponder\u00e1 en consecuencia a esta cacer\u00eda de brujas\u201d.<\/p>\n<p>Mientras sectores de la derecha tanto en Brasil como en Estados Unidos insisten en la necesidad de una amnist\u00eda para Bolsonaro. En contraste, en varias ciudades brasile\u00f1as, las calles se han dividido entre simpatizantes que exigen su liberaci\u00f3n y manifestantes que rechazan cualquier posibilidad de indulto.<\/p>\n<p>Vieira tambi\u00e9n se refiri\u00f3 al reciente aumento de aranceles impuestos por Estados Unidos a productos brasile\u00f1os, que calific\u00f3 como una decisi\u00f3n \u201cclaramente pol\u00edtica\u201d.<\/p>\n<p>Seg\u00fan el canciller, un alto funcionario del Departamento de Estado habr\u00eda reconocido ante empresarios brasile\u00f1os que las medidas no respond\u00edan a motivos comerciales, y los inst\u00f3 a hacer lobby dentro de Brasil.<\/p>\n<p>\u201cNo hay un motivo, una base comercial para los aranceles\u201d, dijo Vieira, se\u00f1alando que Brasil tiene un d\u00e9ficit comercial con EE.UU. de US$ 25.000 millones anuales, y, adem\u00e1s, aplica aranceles m\u00e1s bajos a productos estadounidenses que los que EE.UU. impone a las exportaciones brasile\u00f1as.<\/p>\n<p>\u201cDe los diez principales productos de exportaci\u00f3n de Estados Unidos a Brasil, ocho ingresan sin ning\u00fan arancel, y el arancel promedio que aplicamos es de solo 0,7%, frente al 3,4% que EE.UU. aplica a los productos brasile\u00f1os\u201d, explic\u00f3.<\/p>\n<p>Vieira enfatiz\u00f3 que Brasil est\u00e1 abierto al di\u00e1logo y a la negociaci\u00f3n en materia comercial, pero advirti\u00f3 que, ante posibles nuevas sanciones econ\u00f3micas bajo el Gobierno de Trump, el pa\u00eds podr\u00eda aplicar su nueva Ley de Reciprocidad Comercial.<\/p>\n<p>Seg\u00fan el canciller, la normativa, aprobada recientemente, autoriza al Ejecutivo a imponer aranceles a pa\u00edses que utilicen medidas comerciales \u201ccomo instrumento de comercio o de cualquier otra naturaleza\u201d.<\/p>\n<p>\u201cSomos un pa\u00eds de di\u00e1logo y queremos mantener el dialogo con Estados Unidos y \u00e9l (Bolsonaro) est\u00e1 condenado y va a cumplir la sentencia, sobre eso nadie puede negociar, est\u00e1 en manos de la justicia y no hay nada que se pueda hacer\u201d, reiter\u00f3 el canciller.<\/p>\n<p>Adem\u00e1s, dijo que una carta enviada por el presidente Trump interrumpi\u00f3 las negociaciones t\u00e9cnicas que estaban en curso entre ambos gobiernos, aunque asegur\u00f3 que Brasil est\u00e1 dispuesto a reanudarlas.<\/p>\n<p>Como reflejo de la creciente preocupaci\u00f3n por el impacto econ\u00f3mico de esta tensi\u00f3n comercial, el Gobierno de Brasil <a href=\"https:\/\/cnnespanol.cnn.com\/latinoamerica\/live-news\/fallo-juicio-bolsonaro-brasil-condena-golpe-estado-orix#cmffuy5hz0005356ntupaxtp6\">redujo <\/a>su previsi\u00f3n de crecimiento para 2025 del 2,5 % al 2,3 %, citando como factores los altos tipos de inter\u00e9s y los posibles efectos negativos de los aranceles impuestos por Estados Unidos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El canciller de Brasil, Mauro Vieira, calific\u00f3 como una \u201cinterferencia en asuntos internos\u201d las solicitudes y presiones internacionales \u2014incluidas las del Gobierno de Estados Unidos\u2014 para liberar al expresidente Jair Bolsonaro, condenado a m\u00e1s de 27 a\u00f1os de prisi\u00f3n por intento de golpe de Estado, durante una entrevista con CNN. Vieira se\u00f1al\u00f3 que el presidente [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466509","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &quot;medida pol\u00edtica&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &quot;medida pol\u00edtica&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El canciller de Brasil, Mauro Vieira, calific\u00f3 como una \u201cinterferencia en asuntos internos\u201d las solicitudes y presiones internacionales \u2014incluidas las del Gobierno de Estados Unidos\u2014 para liberar al expresidente Jair Bolsonaro, condenado a m\u00e1s de 27 a\u00f1os de prisi\u00f3n por intento de golpe de Estado, durante una entrevista con CNN. Vieira se\u00f1al\u00f3 que el presidente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T15:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &#171;medida pol\u00edtica&#187;\",\"datePublished\":\"2025-09-16T15:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/\"},\"wordCount\":752,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/\",\"name\":\"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como \\\"medida pol\u00edtica\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-16T15:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &#171;medida pol\u00edtica&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como \"medida pol\u00edtica\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como \"medida pol\u00edtica\" - Noticias","og_description":"El canciller de Brasil, Mauro Vieira, calific\u00f3 como una \u201cinterferencia en asuntos internos\u201d las solicitudes y presiones internacionales \u2014incluidas las del Gobierno de Estados Unidos\u2014 para liberar al expresidente Jair Bolsonaro, condenado a m\u00e1s de 27 a\u00f1os de prisi\u00f3n por intento de golpe de Estado, durante una entrevista con CNN. Vieira se\u00f1al\u00f3 que el presidente [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-16T15:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/"},"author":{"name":"","@id":""},"headline":"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &#171;medida pol\u00edtica&#187;","datePublished":"2025-09-16T15:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/"},"wordCount":752,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/","name":"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como \"medida pol\u00edtica\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-16T15:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &#171;medida pol\u00edtica&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &#171;medida pol\u00edtica&#187;","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-16T15:03:48Z","datePublished":"2025-09-16T15:03:48Z","dateModified":"2025-09-16T15:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Brasil rechaza las presiones de EE.UU. por la condena a Bolsonaro y califica los aranceles como &#171;medida pol\\u00edtica&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/16\\\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/16\\\/brasil-rechaza-presiones-estados-unidos-condena-bolsonaro-medida-politica-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-16T15:03:48Z\",\"datePublished\":\"2025-09-16T15:03:48Z\",\"dateModified\":\"2025-09-16T15:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464674,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/19\/lula-revocacion-visa-eeuu-juez-bolsonaro-orix\/","url_meta":{"origin":1466509,"position":0},"title":"Lula critica revocaci\u00f3n de visa de EE.UU. a juez de Brasil por el caso Bolsonaro","author":"","date":"julio 19, 2025","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, critic\u00f3 este s\u00e1bado la decisi\u00f3n del Gobierno de Estados Unidos de revocar la visa del juez del Supremo Tribunal Federal brasile\u00f1o Alexandre de Moraes, as\u00ed como de algunos de sus colaboradores y familiares, en represalia por las acciones que el magistrado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466374,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/11\/brasil-tribunal-mayoria-condena-jair-bolsonaro-orix\/","url_meta":{"origin":1466509,"position":1},"title":"La Justicia de Brasil condena a Jair Bolsonaro a 27 a\u00f1os de prisi\u00f3n por tentativa de golpe de Estado","author":"","date":"septiembre 11, 2025","format":false,"excerpt":"El Supremo Tribunal de Brasil alcanz\u00f3 este jueves una mayor\u00eda de cuatro votos para condenar al expresidente Jair Bolsonaro por liderar un intento de golpe de Estado tras las elecciones de 2022, en un panel de cinco miembros. La Justicia conden\u00f3 al exmandatario a 27 a\u00f1os con tres meses de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469224,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/12\/12\/eeuu-levanta-sanciones-alexandre-moraes-brasil-orix\/","url_meta":{"origin":1466509,"position":2},"title":"EE.UU. levanta las sanciones financieras que hab\u00eda impuesto al juez del Tribunal Supremo de Brasil Alexandre de Moraes","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"El Departamento del Tesoro de Estados Unidos levant\u00f3 este viernes las sanciones financieras que impuso en julio al juez brasile\u00f1o Alexandre de Moraes, integrante del Supremo Tribunal Federal de Brasil (STF), en una medida que representa un giro respecto de la ofensiva que Washington llevaba a cabo contra el jurista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465543,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/15\/juicio-bolsonaro-fase-final-trump-ejecucion-politica-orix\/","url_meta":{"origin":1466509,"position":3},"title":"El juicio contra Bolsonaro entra en su fase final. Trump lo llama una &#171;ejecuci\u00f3n pol\u00edtica&#187;","author":"","date":"agosto 15, 2025","format":false,"excerpt":"\u201cCreo que es un hombre honesto\u2026 Esto que intentan hacer con Bolsonaro es realmente una ejecuci\u00f3n pol\u00edtica\u201d. De esta manera el presidente de Estados Unidos Donald Trump defendi\u00f3 el jueves ante la prensa presente en la Casa Blanca al expresidente de Brasil, Jair Bolsonaro, quien enfrenta un juicio por un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466351,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/10\/juicio-votacion-brasil-jair-bolsonaro-orix\/","url_meta":{"origin":1466509,"position":4},"title":"Inesperado voto en contra de condenar a Bolsonaro sorprende a Brasil y deja abierta la intriga sobre el veredicto","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"El juez del Supremo Tribunal de Brasil Luiz Fux vot\u00f3 este mi\u00e9rcoles en contra de los cargos presentados contra el exmandatraio Jair Bolsonaro, acusado de presunto intento de golpe de Estado, un pronunciamiento que pod\u00eda ser decisivo para confirmar una mayor\u00eda condenatoria en el panel de cinco magistrados y en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465187,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/06\/lula-trump-aranceles-humillacion-reuters\/","url_meta":{"origin":1466509,"position":5},"title":"Lula dice que hablar con Trump sobre los aranceles de EE.UU. a Brasil ser\u00eda una &#171;humillaci\u00f3n&#187;","author":"","date":"agosto 6, 2025","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, dijo este mi\u00e9rcoles a Reuters que no ve\u00eda espacio para conversaciones directas con el presidente de Estados Unidos, Donald Trump, lo cual cree que se convertir\u00eda en una \u201chumillaci\u00f3n\u201d para \u00e9l.En la entrevista a\u00f1adi\u00f3 que Brasil no va a anunciar aranceles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1466509"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466509\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1466509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1466509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1466509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}