{"id":1466519,"date":"2025-09-16T12:03:38","date_gmt":"2025-09-16T19:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/"},"modified":"2025-09-16T12:03:38","modified_gmt":"2025-09-16T19:03:38","slug":"usain-bolt-retiro-escaleras-aliento-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","title":{"rendered":"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo"},"content":{"rendered":"<p>El ocho veces campe\u00f3n ol\u00edmpico Usain Bolt es humano como todos nosotros, y admite que, tras su retiro, se queda sin aliento al subir las escaleras.<\/p>\n<p>Considerado ampliamente como el mejor velocista de todos los tiempos, este atleta de 39 a\u00f1os, quien a\u00fan ostenta los r\u00e9cords mundiales de los 100 y 200 metros y el relevo 4&#215;100 metros, declar\u00f3 a la prensa en el Campeonato Mundial de Atletismo que, debido a una rotura del tend\u00f3n de Aquiles, ya no corre.<\/p>\n<p>\u201cNo, principalmente entreno en el gimnasio. No me encanta, pero creo que ahora que llevo un tiempo sin correr, tengo que empezar a correr de verdad porque, cuando subo las escaleras, me quedo sin aliento\u201d, declar\u00f3 a los medios de comunicaci\u00f3n reunidos en Tokio, incluyendo a The Guardian y The Telegraph.<\/p>\n<p>\u201cCreo que cuando vuelva a entrenar a fondo, probablemente tendr\u00e9 que dar algunas vueltas solo para poder respirar adecuadamente\u201d.<\/p>\n<p>El jamaicano anunci\u00f3 su retiro del sprint de \u00e9lite en 2017. Al preguntarle sobre su rutina diaria actual, coment\u00f3 que pasa gran parte del tiempo con sus hijos.<\/p>\n<p>\u201cBueno, normalmente me despierto justo a tiempo para despedir a los ni\u00f1os rumbo al colegio, y luego depende de lo que tenga que hacer. Si no tengo nada que hacer, simplemente me relajo. A veces hago ejercicio si estoy de buen humor. Veo series y me relajo hasta que los ni\u00f1os llegan a casa\u201d.<\/p>\n<p>\u201cPaso tiempo con ellos, paso el rato, hasta que empiezan a molestarme y entonces me voy. Y despu\u00e9s, me quedo en casa viendo pel\u00edculas o como ahora me gusta el Lego, juego con Lego\u201d.<\/p>\n<p>Cuando le preguntaron por qu\u00e9 la generaci\u00f3n actual de corredores a\u00fan no se ha puesto al d\u00eda con su generaci\u00f3n, a pesar de los avances tecnol\u00f3gicos, como las zapatillas de clavos, respondi\u00f3: \u201c\u00bfQuieres la verdadera respuesta? Simplemente tenemos m\u00e1s talento\u201d.<\/p>\n<p>\u201cEso es todo lo que digo. Claro, es algo que se nota en los hombres. Se puede ver que con las mujeres es diferente. Cada vez corren m\u00e1s r\u00e1pido. As\u00ed que eso lo demuestra: tiene que ser el talento\u201d.<\/p>\n<p>Hizo un gesto con la cabeza hacia los tiempos de su compatriota jamaiquina, la leyenda del sprint, Shelly-Ann Fraser-Pryce, despu\u00e9s de las zapatillas de clavos.<\/p>\n<p>\u201cTienes a Shelly, que tiene las nuevas zapatillas de clavos, y corri\u00f3 m\u00e1s r\u00e1pido. As\u00ed que es simplemente el talento. Simplemente \u00e9ramos mucho m\u00e1s talentosos en ese tiempo. Se nota si te fijas\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ocho veces campe\u00f3n ol\u00edmpico Usain Bolt es humano como todos nosotros, y admite que, tras su retiro, se queda sin aliento al subir las escaleras. Considerado ampliamente como el mejor velocista de todos los tiempos, este atleta de 39 a\u00f1os, quien a\u00fan ostenta los r\u00e9cords mundiales de los 100 y 200 metros y el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466519","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Cuando subo las escaleras, me quedo sin aliento&quot;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Cuando subo las escaleras, me quedo sin aliento&quot;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ocho veces campe\u00f3n ol\u00edmpico Usain Bolt es humano como todos nosotros, y admite que, tras su retiro, se queda sin aliento al subir las escaleras. Considerado ampliamente como el mejor velocista de todos los tiempos, este atleta de 39 a\u00f1os, quien a\u00fan ostenta los r\u00e9cords mundiales de los 100 y 200 metros y el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T19:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo\",\"datePublished\":\"2025-09-16T19:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/\",\"name\":\"\\\"Cuando subo las escaleras, me quedo sin aliento\\\": Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-16T19:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Cuando subo las escaleras, me quedo sin aliento\": Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"Cuando subo las escaleras, me quedo sin aliento\": Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo - Noticias","og_description":"El ocho veces campe\u00f3n ol\u00edmpico Usain Bolt es humano como todos nosotros, y admite que, tras su retiro, se queda sin aliento al subir las escaleras. Considerado ampliamente como el mejor velocista de todos los tiempos, este atleta de 39 a\u00f1os, quien a\u00fan ostenta los r\u00e9cords mundiales de los 100 y 200 metros y el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-16T19:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo","datePublished":"2025-09-16T19:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","name":"\"Cuando subo las escaleras, me quedo sin aliento\": Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-16T19:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\u00f3mo el retiro lo hizo sentir humano de nuevo","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/16\/usain-bolt-retiro-escaleras-aliento-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-16T19:03:38Z","datePublished":"2025-09-16T19:03:38Z","dateModified":"2025-09-16T19:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Cuando subo las escaleras, me quedo sin aliento&#187;: Usain Bolt habla de c\\u00f3mo el retiro lo hizo sentir humano de nuevo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/16\\\/usain-bolt-retiro-escaleras-aliento-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2025\\\/09\\\/16\\\/usain-bolt-retiro-escaleras-aliento-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-16T19:03:38Z\",\"datePublished\":\"2025-09-16T19:03:38Z\",\"dateModified\":\"2025-09-16T19:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466542,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/17\/5-cosas-17-septiembre-orix\/","url_meta":{"origin":1466519,"position":0},"title":"Las 5 cosas que debes saber este 17 de septiembre: asesinato de Kirk, guerra en Gaza y muerte de Robert Redford","author":"","date":"septiembre 17, 2025","format":false,"excerpt":"Palestinos huyen de la Ciudad de Gaza en medio del ataque terrestre de Israel. Petro critic\u00f3 la descertificaci\u00f3n de EE.UU. Astr\u00f3nomos descubren una cuasiluna cerca de la Tierra. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.\ufeffSuscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473328,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/20\/gout-gout-rompe-record-usain-bolt-trax\/","url_meta":{"origin":1466519,"position":1},"title":"Gout Gout, la joven promesa del sprint, rompi\u00f3 uno de los r\u00e9cords de Usain Bolt y recibi\u00f3 un consejo del jamaicano","author":"","date":"abril 20, 2026","format":false,"excerpt":"La leyenda del atletismo Usain Bolt declar\u00f3 a CNN Sports que espera que el joven prodigio Gout Gout \u201cencuentre a las personas adecuadas\u201d a su alrededor, mientras el joven de 18 a\u00f1os contin\u00faa su mete\u00f3rico ascenso en el mundo del atletismo.El australiano ha revolucionado el deporte con una serie de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473213,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/15\/ejercicio-puede-reducirl-riesgo-enfermedades-trax\/","url_meta":{"origin":1466519,"position":2},"title":"Un tipo de ejercicio puede reducir el riesgo de desarrollar ocho enfermedades","author":"","date":"abril 15, 2026","format":false,"excerpt":"Mu\u00e9vete m\u00e1s. Si\u00e9ntate menos. Durante a\u00f1os, ese ha sido el consejo aceptado para quienes buscan mejorar su salud.Ahora ese mensaje se est\u00e1 afinando. Un creciente cuerpo de investigaciones sugiere que ciertos tipos de movimiento pueden ser m\u00e1s beneficiosos que otros cuando se trata de obtener ventajas para la salud.La intensidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446503,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/03\/04\/opinion-viajes-historia-mari-rodriguez-orix\/","url_meta":{"origin":1466519,"position":3},"title":"OPINI\u00d3N | \u00bfPor qu\u00e9 viajamos? \u00bfPara encontrar una nueva realidad? \u00a1Yo busco caminar sobre la historia!","author":"","date":"marzo 4, 2024","format":false,"excerpt":"Nota del editor: Mari Rodr\u00edguez Ichaso ha sido colaboradora de la revista Vanidades durante varias d\u00e9cadas. Especialista en moda, viajes, gastronom\u00eda, arte, arquitectura y entretenimiento. Productora de cine. Columnista de estilo de CNN en Espa\u00f1ol. Las opiniones expresadas en esta columna son exclusivamente suyas. Lee m\u00e1s art\u00edculos de opini\u00f3n en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1436649,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2023\/01\/26\/entrevista-con-mariangela-melancolia-para-sobrevivir-el-cambio\/","url_meta":{"origin":1466519,"position":4},"title":"Entrevista con Mariangela: Melancol\u00eda para sobrevivir el cambio","author":"Eduardo Salinas","date":"enero 26, 2023","format":"video","excerpt":"\u00bfQu\u00e9 pasa cuando das todo sin esperar nada a cambio? Cuando el coraz\u00f3n manda y la creatividad rebasa todo l\u00edmite de tu ADN. Ese es el feeling que representa a Mariangela, la cantautora mexicana que est\u00e1 apoder\u00e1ndose de los charts y que ha trabajado casi artesanalmente una carrera que de\u2026","rel":"","context":"In &quot;Entretenimiento&quot;","block_context":{"text":"Entretenimiento","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/entretenimiento"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/DSC02136-Edit-e1674774813494.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/DSC02136-Edit-e1674774813494.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/DSC02136-Edit-e1674774813494.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/elboton.com\/wp-content\/uploads\/sites\/6\/2023\/01\/DSC02136-Edit-e1674774813494.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1464526,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/15\/muere-corredor-mas-anciano-mundo-maraton-india-trax\/","url_meta":{"origin":1466519,"position":5},"title":"El maratonista m\u00e1s longevo del mundo muere atropellado a los 114 a\u00f1os","author":"","date":"julio 15, 2025","format":false,"excerpt":"Fauja Singh, reconocido como el maratonista m\u00e1s longevo del mundo y c\u00e9lebre por seguir compitiendo tras cumplir 100 a\u00f1os, falleci\u00f3 este lunes a los 114 a\u00f1os tras ser atropellado en India. El conductor se dio a la fuga, seg\u00fan inform\u00f3 a la polic\u00eda india.Nacido en la India rural en 1911\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1466519"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1466519\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1466519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1466519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1466519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}