{"id":1472732,"date":"2026-03-31T10:03:45","date_gmt":"2026-03-31T17:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/"},"modified":"2026-03-31T10:03:45","modified_gmt":"2026-03-31T17:03:45","slug":"mercado-laboral-febrero-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/31\/mercado-laboral-febrero-trax\/","title":{"rendered":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia"},"content":{"rendered":"<p>Las empresas estadounidenses est\u00e1n incorporando trabajadores al ritmo m\u00e1s d\u00e9bil en 15 a\u00f1os, excluyendo el inicio de la pandemia, seg\u00fan nuevos datos el martes, una se\u00f1al de que un enfriamiento a\u00fan m\u00e1s profundo ya estaba atravesando el <a href=\"https:\/\/www.cnn.com\/2026\/03\/29\/economy\/us-job-market-thaw-middle-east-war\">mercado laboral<\/a> antes de que el conflicto en el Medio Oriente amenazara con sacudir la econom\u00eda de EE.UU.<\/p>\n<p>Las contrataciones como porcentaje del <a href=\"https:\/\/cnnespanol.cnn.com\/economia\/empleo\">empleo<\/a> total bajaron a 3,1 % a finales de febrero, la tasa m\u00e1s baja desde abril de 2020 y, antes de eso, 2011, seg\u00fan la m\u00e1s reciente Encuesta de Ofertas de Empleo y Rotaci\u00f3n Laboral de la Oficina de Estad\u00edsticas Laborales.<\/p>\n<p>La tasa de contrataci\u00f3n cay\u00f3 desde 3,4 % en enero, marcando la ca\u00edda mensual m\u00e1s pronunciada fuera de la pandemia desde 2016, se\u00f1al\u00f3 Laura Ullrich, directora de investigaci\u00f3n econ\u00f3mica en Norteam\u00e9rica en el Indeed Hiring Lab.<\/p>\n<p>\u201cLo cual es preocupante dado el impacto continuo del conflicto en Ir\u00e1n\u201d, escribi\u00f3 en una nota el martes.<\/p>\n<p>Los retrocesos m\u00e1s pronunciados en la contrataci\u00f3n se observaron en los sectores de la construcci\u00f3n y de servicios profesionales y empresariales.<\/p>\n<p>La tasa de contrataci\u00f3n m\u00e1s baja registrada fue de 2,9 % en 2009, durante la Gran Recesi\u00f3n.<\/p>\n<p>El informe del martes tambi\u00e9n mostr\u00f3 una disminuci\u00f3n en el n\u00famero de vacantes laborales, una medici\u00f3n muy seguida de la demanda de trabajo. Bajaron a un estimado de 6,88 millones desde 7,24 millones en enero.<\/p>\n<p>Los despidos aumentaron a 1,72 millones desde 1,66 millones, pero la tasa de despidos sobre el empleo total se mantiene en l\u00ednea con los promedios observados en los \u00faltimos a\u00f1os. Las renuncias voluntarias, que sirven como un indicador de la confianza de los trabajadores, cayeron en febrero a 2,97 millones, marcando el nivel m\u00e1s bajo desde 2020.<\/p>\n<p>La contrataci\u00f3n apagada y la retenci\u00f3n de mano de obra significan que el important\u00edsimo \u201crecambio\u201d necesario para un mercado laboral sano y una econom\u00eda saludable se ha frenado hasta casi detenerse.<\/p>\n<p>El <a href=\"https:\/\/www.cnn.com\/2026\/03\/06\/economy\/us-jobs-report-february\">informe de empleo de febrero<\/a>, que mostr\u00f3 que la econom\u00eda de EE.UU. perdi\u00f3 un estimado de 92.000 empleos ese mes, aument\u00f3 a\u00fan m\u00e1s las preocupaciones de que el mercado laboral no solo estuviera estancado, sino fisur\u00e1ndose.<\/p>\n<p>El conflicto mortal iniciado por EE.UU. e Israel y en escalada de varias semanas en el Medio Oriente ha amplificado esos temores.<\/p>\n<p>Adem\u00e1s de la creciente incertidumbre, el shock energ\u00e9tico y otras escaseces de insumos est\u00e1n obligando a las empresas a lidiar con efectos inmediatos y tangibles, como el <a href=\"https:\/\/www.cnn.com\/2026\/03\/09\/business\/prices-oil-iran-war-affordability\">mayor costo de vida<\/a> para los trabajadores y los clientes, se\u00f1al\u00f3 Elizabeth Renter, economista s\u00e9nior de NerdWallet.<\/p>\n<p>\u201cSi aumentan sus costos de insumos, podr\u00edan verse obligadas a enfrentar decisiones dif\u00edciles como subir precios o reducir horas y plantilla\u201d, escribi\u00f3 el martes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las empresas estadounidenses est\u00e1n incorporando trabajadores al ritmo m\u00e1s d\u00e9bil en 15 a\u00f1os, excluyendo el inicio de la pandemia, seg\u00fan nuevos datos el martes, una se\u00f1al de que un enfriamiento a\u00fan m\u00e1s profundo ya estaba atravesando el mercado laboral antes de que el conflicto en el Medio Oriente amenazara con sacudir la econom\u00eda de EE.UU. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472732","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las empresas estadounidenses est\u00e1n incorporando trabajadores al ritmo m\u00e1s d\u00e9bil en 15 a\u00f1os, excluyendo el inicio de la pandemia, seg\u00fan nuevos datos el martes, una se\u00f1al de que un enfriamiento a\u00fan m\u00e1s profundo ya estaba atravesando el mercado laboral antes de que el conflicto en el Medio Oriente amenazara con sacudir la econom\u00eda de EE.UU. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T17:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia\",\"datePublished\":\"2026-03-31T17:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/\"},\"wordCount\":515,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/\",\"name\":\"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-31T17:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia - Noticias","og_description":"Las empresas estadounidenses est\u00e1n incorporando trabajadores al ritmo m\u00e1s d\u00e9bil en 15 a\u00f1os, excluyendo el inicio de la pandemia, seg\u00fan nuevos datos el martes, una se\u00f1al de que un enfriamiento a\u00fan m\u00e1s profundo ya estaba atravesando el mercado laboral antes de que el conflicto en el Medio Oriente amenazara con sacudir la econom\u00eda de EE.UU. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-31T17:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/"},"author":{"name":"","@id":""},"headline":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia","datePublished":"2026-03-31T17:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/"},"wordCount":515,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/","name":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-31T17:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/mercado-laboral-febrero-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/31\/mercado-laboral-febrero-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/31\/mercado-laboral-febrero-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/31\/mercado-laboral-febrero-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-31T17:03:45Z","datePublished":"2026-03-31T17:03:45Z","dateModified":"2026-03-31T17:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El ritmo de contrataci\\u00f3n en EE.UU. acaba de caer al nivel m\\u00e1s bajo desde 2011, sin contar la pandemia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/03\\\/31\\\/mercado-laboral-febrero-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/03\\\/31\\\/mercado-laboral-febrero-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-31T17:03:45Z\",\"datePublished\":\"2026-03-31T17:03:45Z\",\"dateModified\":\"2026-03-31T17:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464141,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/02\/politicas-trump-afectando-mercado-laboral-trax\/","url_meta":{"origin":1472732,"position":0},"title":"El efecto de las pol\u00edticas de Trump sobre el sector privado: se perdieron 33.000 empleos en junio","author":"","date":"julio 2, 2025","format":false,"excerpt":"El sector privado estadounidense perdi\u00f3 empleos en el mes de junio, el primer mes negativo en m\u00e1s de dos a\u00f1os, seg\u00fan nuevos datos publicados este mi\u00e9rcoles por la empresa de n\u00f3minas ADP.Puntualmente, el sector privado estadounidense perdi\u00f3 33.000 empleos en junio, incumpliendo las expectativas de un aumento de 115.000.Los economistas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466205,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","url_meta":{"origin":1472732,"position":1},"title":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"Tras a\u00f1os de abundantes oportunidades de empleo, importantes aumentos salariales y un gasto desenfrenado impulsado por el ahorro acumulado durante la pandemia, los trabajadores estadounidenses se enfrentan ahora a una realidad econ\u00f3mica preocupante: cada vez es m\u00e1s dif\u00edcil encontrar trabajo, y cada vez m\u00e1s sectores est\u00e1n eliminando puestos.El \u00faltimo informe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450965,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/07\/08\/estadounidenses-dificil-conseguir-trabajo-conservarlo-trax\/","url_meta":{"origin":1472732,"position":2},"title":"A los estadounidenses les resulta m\u00e1s dif\u00edcil tanto conseguir un trabajo como conservarlo","author":"","date":"julio 8, 2024","format":false,"excerpt":"(CNN) -- Los solicitantes de empleo fueron quienes tomaron las decisiones durante casi cuatro a\u00f1os mientras los empleadores luchaban por llenar millones de vacantes para satisfacer la avalancha de demanda derivada de la pandemia.Muchos empleadores ni siquiera pod\u00edan exigir a los trabajadores que regresaran a las oficinas por temor a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458431,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/07\/datos-mercado-laboral-saludable-trump-no-de-acuerdo-trax\/","url_meta":{"origin":1472732,"position":3},"title":"Los datos muestran un mercado laboral saludable en EE.UU, pero Trump no est\u00e1 de acuerdo y culpa a Biden","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Por muchas medidas, el mercado laboral de Estados Unidos parece estar en buena forma: en enero, el desempleo estaba en un hist\u00f3ricamente bajo 4% mientras los empleadores continuaban con la segunda racha m\u00e1s larga de crecimiento de empleo en la historia de EE.UU., seg\u00fan nuevos datos del Gobierno publicados este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470860,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/02\/04\/empleo-sector-privado-desplome-enero-trax\/","url_meta":{"origin":1472732,"position":4},"title":"La contrataci\u00f3n del sector privado se desplom\u00f3 en enero: se crearon solo 22.000 empleos","author":"","date":"febrero 4, 2026","format":false,"excerpt":"El breve cierre del Gobierno de EE.UU. ha retrasado el informe oficial de empleo de enero (los datos se publicar\u00e1n el 11 de febrero en lugar del pr\u00f3ximo viernes). Sin embargo, un primer an\u00e1lisis de la actividad de contrataci\u00f3n en el sector privado mostr\u00f3 que el crecimiento del empleo se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466180,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/09\/05\/estancamiento-empleo-ee-uu-trax\/","url_meta":{"origin":1472732,"position":5},"title":"Estancamiento del empleo en EE.UU.: se suman solo 22.000 empleos en agosto y el desempleo est\u00e1 en su nivel m\u00e1s alto en a\u00f1os","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"El crecimiento del empleo se desaceler\u00f3 dr\u00e1sticamente en agosto, y la tasa de desempleo subi\u00f3 a su nivel m\u00e1s alto en casi cuatro a\u00f1os, lo que indica que el mercado laboral estadounidense se est\u00e1 estancando.La econom\u00eda sum\u00f3 solo 22.000 empleos el mes pasado y la tasa de desempleo subi\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1472732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1472732"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1472732\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1472732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1472732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1472732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}