{"id":1472870,"date":"2026-04-04T18:03:50","date_gmt":"2026-04-05T01:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/"},"modified":"2026-04-04T18:03:50","modified_gmt":"2026-04-05T01:03:50","slug":"laliga-jornada-30-barcelona-real-madrid-atletico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/","title":{"rendered":"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid"},"content":{"rendered":"<p>Contin\u00faa la jornada 30 del f\u00fatbol espa\u00f1ol, una fecha que dej\u00f3 resultados que podr\u00edan ser determinantes en la temporada hacia el rumbo definitivo, tanto en la lucha por el t\u00edtulo como en la pelea por puestos europeos y la permanencia.<\/p>\n<p>El golpe m\u00e1s sorpresivo lo protagoniz\u00f3 el Mallorca, que consigui\u00f3 una victoria de enorme valor al imponerse de local 2-1 al Real Madrid. El conjunto merengue no solo dej\u00f3 escapar tres puntos fundamentales, sino que tambi\u00e9n sufri\u00f3 ante un rival que, hasta antes de este compromiso, se encontraba en zona de descenso.<\/p>\n<p>Con este triunfo, el equipo ahora dirigido por Mart\u00edn Demichelis logr\u00f3 salir moment\u00e1neamente del fondo de la tabla, ubic\u00e1ndose en el puesto 17 y tomando un respiro importante en su ardua lucha por mantenerse en la categor\u00eda.<\/p>\n<p>Para el Real Madrid, la derrota representa mucho m\u00e1s que un tropiezo aislado. El equipo blanco ve c\u00f3mo se le escapan unidades clave en un momento cr\u00edtico del campeonato, lo que se traduce en una desventaja de siete puntos respecto al liderato. La presi\u00f3n aumenta considerablemente, especialmente porque su principal competidor no dej\u00f3 pasar la oportunidad de ampliar la diferencia.<\/p>\n<p>El Barcelona fue el gran beneficiado de la jornada al conseguir una victoria como visitante 2-1 frente al Atl\u00e9tico de Madrid. En un duelo complicado, los blaugranas supieron aprovechar las circunstancias de su rival, que lleg\u00f3 con varias ausencias importantes en el mediocampo. Esta situaci\u00f3n abri\u00f3 la puerta para que el mexicano Obed Vargas tuviera la oportunidad de iniciar como titular, respondiendo con una actuaci\u00f3n s\u00f3lida en la que cumpli\u00f3 con las exigencias del partido, aunque sin un rol protag\u00f3nico.<\/p>\n<p>El encuentro tambi\u00e9n estuvo condicionado por la expulsi\u00f3n de Nico Gonz\u00e1lez antes del descanso, una acci\u00f3n que termin\u00f3 por complicar a\u00fan m\u00e1s el panorama para los colchoneros. Con un hombre menos durante gran parte del partido, el Atl\u00e9tico de Madrid no logr\u00f3 sostener el ritmo competitivo y el Barcelona, en los \u00faltimos minutos del partido, marc\u00f3 el tanto de la ventaja con anotaci\u00f3n de Robert Lewandowski para asegurar tres puntos clave en su aspiraci\u00f3n al t\u00edtulo.<\/p>\n<p>En la parte alta de la clasificaci\u00f3n, el Real Betis dej\u00f3 escapar una oportunidad importante al empatar sin goles frente al Espanyol. Aunque el conjunto verdiblanco contin\u00faa en la quinta posici\u00f3n, estos resultados podr\u00edan pesar en la recta final del torneo.<\/p>\n<p>Por su parte, la Real Sociedad firm\u00f3 una victoria contundente de 2-0 sobre el Levante, resultado que le permite escalar hasta la sexta posici\u00f3n de la tabla. Este triunfo no solo refuerza su buen momento, sino que tambi\u00e9n le permite superar al Celta de Vigo, con quien est\u00e1 empatado con 41 puntos, pero al que aventaja gracias a una mejor diferencia de goles. Sin embargo, los de Vigo a\u00fan tienen pendiente su partido de esta jornada.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contin\u00faa la jornada 30 del f\u00fatbol espa\u00f1ol, una fecha que dej\u00f3 resultados que podr\u00edan ser determinantes en la temporada hacia el rumbo definitivo, tanto en la lucha por el t\u00edtulo como en la pelea por puestos europeos y la permanencia. El golpe m\u00e1s sorpresivo lo protagoniz\u00f3 el Mallorca, que consigui\u00f3 una victoria de enorme valor [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472870","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid - Noticias\" \/>\n<meta property=\"og:description\" content=\"Contin\u00faa la jornada 30 del f\u00fatbol espa\u00f1ol, una fecha que dej\u00f3 resultados que podr\u00edan ser determinantes en la temporada hacia el rumbo definitivo, tanto en la lucha por el t\u00edtulo como en la pelea por puestos europeos y la permanencia. El golpe m\u00e1s sorpresivo lo protagoniz\u00f3 el Mallorca, que consigui\u00f3 una victoria de enorme valor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-05T01:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid\",\"datePublished\":\"2026-04-05T01:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/\"},\"wordCount\":535,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/\",\"name\":\"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-05T01:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid - Noticias","og_description":"Contin\u00faa la jornada 30 del f\u00fatbol espa\u00f1ol, una fecha que dej\u00f3 resultados que podr\u00edan ser determinantes en la temporada hacia el rumbo definitivo, tanto en la lucha por el t\u00edtulo como en la pelea por puestos europeos y la permanencia. El golpe m\u00e1s sorpresivo lo protagoniz\u00f3 el Mallorca, que consigui\u00f3 una victoria de enorme valor [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-05T01:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/"},"author":{"name":"","@id":""},"headline":"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid","datePublished":"2026-04-05T01:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/"},"wordCount":535,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/","name":"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-05T01:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\u00e9tico de Madrid","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/04\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-05T01:03:50Z","datePublished":"2026-04-05T01:03:50Z","dateModified":"2026-04-05T01:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Real Madrid cae ante el Mallorca y el Barcelona aprovecha para alejarse en el liderato tras vencer al Atl\\u00e9tico de Madrid\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/04\\\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/04\\\/laliga-jornada-30-barcelona-real-madrid-atletico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-05T01:03:50Z\",\"datePublished\":\"2026-04-05T01:03:50Z\",\"dateModified\":\"2026-04-05T01:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1462338,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/14\/cuentas-barcelona-real-madrid-laliga-orix\/","url_meta":{"origin":1472870,"position":0},"title":"Las cuentas del Barcelona y el Real Madrid para ganar LaLiga 2024\/2025","author":"","date":"mayo 14, 2025","format":false,"excerpt":"Con la salida de Carlo Ancelotti, el Real Madrid reacomoda su vestuario y este remate de temporada lo est\u00e1 pasando de forma amarga, no solo porque el t\u00e9cnico m\u00e1s ganador de su historia se marcha, sino por los t\u00edtulos que se le escapan de las manos, mientras su ac\u00e9rrimo rival,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462144,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/08\/clasico-definir-laliga-barcelona-real-madrid-orix\/","url_meta":{"origin":1472870,"position":1},"title":"El cl\u00e1sico que puede definir el rumbo de LaLiga: Barcelona y Real Madrid se enfrentan con el t\u00edtulo en juego","author":"","date":"mayo 8, 2025","format":false,"excerpt":"El f\u00fatbol espa\u00f1ol vivir\u00e1 este domingo 11 de mayo una de sus jornadas m\u00e1s electrizantes. El FC Barcelona y el Real Madrid se enfrentar\u00e1n en un duelo que podr\u00eda ser decisivo para el desenlace de torneo de primera divisi\u00f3n.El partido se disputar\u00e1 en el Estadio Ol\u00edmpico Llu\u00eds Companys y corresponde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472362,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/19\/thibaut-courtois-real-madrid-mundial-2026-orix\/","url_meta":{"origin":1472870,"position":2},"title":"Thibaut Courtois, lesionado: \u00bfcorre riesgo el portero del Real Madrid de perderse el Mundial 2026?","author":"","date":"marzo 19, 2026","format":false,"excerpt":"Poco menos de tres meses faltan para que ruede la pelota en el Mundial de 2026 y una lesi\u00f3n en este punto de la temporada puede resultar catastr\u00f3fica para cualquier jugador que aspire a representar a su selecci\u00f3n en la cita de Canad\u00e1, Estados Unidos y M\u00e9xico.Ya varias figuras, como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451880,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/08\/15\/kylian-mbappe-primer-gol-real-madrid-supercopa-trax\/","url_meta":{"origin":1472870,"position":3},"title":"&#171;Una noche m\u00e1gica&#187;: Kylian Mbapp\u00e9 anota su primer gol con el Real Madrid que suma su sexta Supercopa de Europa tras ganarle al Atalanta","author":"","date":"agosto 15, 2024","format":false,"excerpt":"(CNN) -- Kylian Mbapp\u00e9 tard\u00f3 solo 68 minutos para iniciar su cuenta con el Real Madrid, ya que la superestrella francesa ayud\u00f3 a los merengues a imponerse 2-0 ante el Atalanta en la final de la Supercopa de la UEFA Champions League (Liga de Campeones).La Supercopa se disputa entre los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472912,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/06\/real-madrid-bayern-cuartos-ida-champions-orix\/","url_meta":{"origin":1472870,"position":4},"title":"Real Madrid vs. Bayern Munich, por los cuartos de la Champions League 2025\/2026: previa, alineaciones, hora y c\u00f3mo ver","author":"","date":"abril 6, 2026","format":false,"excerpt":"Un verdadero choque de gal\u00e1cticos es lo que tiene preparado la UEFA Champions League para este martes, cuando se abran dos de las llaves de cuartos de final del torneo.De un lado, el Real Madrid, el club m\u00e1s laureado de Europa, y del otro, el Bayern Munich, el tercero m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465521,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/14\/resultados-laliga-barcelona-real-madrid-jornada-1-orix\/","url_meta":{"origin":1472870,"position":5},"title":"Comienza LaLiga en Espa\u00f1a: partidos de la jornada 1, resultados y m\u00e1s","author":"","date":"agosto 14, 2025","format":false,"excerpt":"El tiempo de las palabras se termina. La temporada 2025\/2026 de la liga espa\u00f1ola de f\u00fatbol comienza este viernes con dos encuentros: Girona FC vs. Rayo Vallecano, y Villarreal vs. Real Oviedo, uno de los tres reci\u00e9n ascendidos a la \u00e9lite.El campe\u00f3n defensor, el FC Barcelona, empezar\u00e1 su camino el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1472870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1472870"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1472870\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1472870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1472870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1472870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}