{"id":1473434,"date":"2026-04-23T08:03:45","date_gmt":"2026-04-23T15:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/"},"modified":"2026-04-23T08:03:45","modified_gmt":"2026-04-23T15:03:45","slug":"reclasifica-marihuana-droga-menos-peligrosa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","title":{"rendered":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa"},"content":{"rendered":"<p>El secretario de Justicia interino de EE.UU., Todd Blanche, firm\u00f3 este jueves una orden que reclasifica la marihuana medicinal autorizada por el estado como una droga menos peligrosa. Esta decisi\u00f3n cambia una pol\u00edtica que durante d\u00e9cadas ha dificultado la investigaci\u00f3n de los posibles beneficios medicinales de la droga.<\/p>\n<p>La orden de Blanche no legaliza el uso recreativo bajo la ley federal. En cambio, traslada la marihuana medicinal autorizada de la Lista I \u2014que incluye las drogas m\u00e1s restringidas, como la hero\u00edna y el \u00e9xtasis\u2014 a la Lista III, la misma categor\u00eda que algunos medicamentos recetados como la ketamina y el Tylenol con code\u00edna.<\/p>\n<p>Tambi\u00e9n ofrece una exenci\u00f3n fiscal a los distribuidores autorizados de marihuana medicinal y flexibiliza algunas restricciones para la investigaci\u00f3n de sus efectos.<\/p>\n<p>\u201cEstas medidas permitir\u00e1n una investigaci\u00f3n m\u00e1s espec\u00edfica y rigurosa sobre la seguridad y la eficacia de la marihuana, ampliando el acceso de los pacientes a los tratamientos y capacitando a los m\u00e9dicos para tomar decisiones sanitarias mejor fundamentadas\u201d, escribi\u00f3 Blanche en una publicaci\u00f3n <a href=\"https:\/\/x.com\/DAGToddBlanche\/status\/2047291538653241488\">en X<\/a>.<\/p>\n<p>La Administraci\u00f3n para el Control de Drogas de EE.UU. (DEA, por sus siglas en ingl\u00e9s) celebrar\u00e1 audiencias administrativas ante un juez sobre el cambio de normativa, dijo Blanche.<\/p>\n<p>Ya ha habido varios intentos para reclasificar la marihuana como sustancia nociva y, aunque siempre ha sido objeto de debate, ninguna administraci\u00f3n logr\u00f3 aprobar una normativa definitiva. El expresidente Joe Biden inici\u00f3 un nuevo intento durante el \u00faltimo a\u00f1o de su mandato, pero no se concret\u00f3 antes de que dejara el cargo.<\/p>\n<p>Los cr\u00edticos atribuyeron la lentitud del proceso a la reticencia de la entonces administradora de la DEA, Anne Milgram. La norma tambi\u00e9n estaba programada para ser sometida a audiencias administrativas antes del final del mandato de Biden, pero el juez principal de la DEA la suspendi\u00f3 indefinidamente.<\/p>\n<p>En un decreto <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/12\/increasing-medical-marijuana-and-cannabidiol-research\/\">emitido<\/a> el pasado mes de diciembre, el presidente Donald Trump orden\u00f3 al Departamento de Justicia que acelerara el proceso e impulsara el cambio de normativa propuesto por Biden.<\/p>\n<p>Pero en los meses siguientes hubo poca movilizaci\u00f3n p\u00fablica, y los defensores de la flexibilizaci\u00f3n de las regulaciones se sintieron cada vez m\u00e1s frustrados.<\/p>\n<p>El propio Trump pareci\u00f3 expresar su frustraci\u00f3n por la demora durante el fin de semana cuando le dijo al presentador de podcasts Joe Rogan, partidario de la reclasificaci\u00f3n de la marihuana, en un evento en la Oficina Oval: \u201cMe est\u00e1n tomando el pelo\u201d.<\/p>\n<p>Fuentes consultadas por CNN indicaron que tanto la Casa Blanca como el Departamento de Justicia se han enfrentado a una creciente presi\u00f3n por parte de la industria del cannabis para que se apruebe el cambio de clasificaci\u00f3n.<\/p>\n<p>Mientras se ultimaba un plan para seguir adelante, algunos miembros del Departamento esperaban dar a conocer sus decisiones el 20 de abril, un d\u00eda de celebraci\u00f3n para los entusiastas de la marihuana, pero se les dijo que ser\u00eda inapropiado, seg\u00fan dos fuentes familiarizadas con las conversaciones.<\/p>\n<p>Ahora, es probable que este esfuerzo revitalizado se enfrente r\u00e1pidamente a impugnaciones legales por parte de los cr\u00edticos, quienes afirman que la rebaja de la calificaci\u00f3n podr\u00eda fomentar el uso recreativo de una droga da\u00f1ina.<\/p>\n<p>Sin embargo, la flexibilizaci\u00f3n de las restricciones en torno a la marihuana goza de amplio apoyo. Una <a href=\"https:\/\/www.pewresearch.org\/politics\/2024\/03\/26\/most-americans-favor-legalizing-marijuana-for-medical-recreational-use\/\">encuesta del Pew Research Center<\/a> de 2024 revel\u00f3 que casi seis de cada diez estadounidenses apoyan la legalizaci\u00f3n del cannabis recreativo.<\/p>\n<p>Kim Rivers, CEO de la empresa de marihuana Trulieve, le agradeci\u00f3 tanto a Trump como a Blanche por \u201ccumplir\u201d su promesa de reclasificar la marihuana.<\/p>\n<p>\u201cEl doble enfoque de utilizar la v\u00eda del tratado y el proceso de elaboraci\u00f3n de normas garantiza que la reclasificaci\u00f3n de la marihuana medicinal se produzca de forma r\u00e1pida y completa, y es una declaraci\u00f3n inequ\u00edvoca del compromiso del presidente de cumplir su promesa de campa\u00f1a\u201d, dijo.<\/p>\n<p>El hecho de que el Gobierno federal reconozca el valor medicinal de la marihuana no solo es simb\u00f3licamente poderoso, sino que tambi\u00e9n podr\u00eda servir como una se\u00f1al permisiva para los legisladores estatales que actualmente sopesan la legislaci\u00f3n sobre el cannabis, dijo Brian Vicente, socio fundador de Vicente LLP, un bufete de abogados especializado en cannabis con sede en Denver.<\/p>\n<p>Seg\u00fan explic\u00f3, una reclasificaci\u00f3n tambi\u00e9n tendr\u00eda implicaciones pr\u00e1cticas, y se\u00f1al\u00f3 que una de las m\u00e1s significativas es que las empresas de cannabis podr\u00edan dejar de estar sujetas a la Secci\u00f3n 280E del C\u00f3digo de Rentas Internas, una disposici\u00f3n fiscal de principios de la d\u00e9cada de 1980 que proh\u00edbe a las empresas dedicadas al \u201ctr\u00e1fico\u201d de sustancias de la Lista I o II deducir gastos comerciales ordinarios o reclamar cr\u00e9ditos fiscales.<\/p>\n<p>\u201cEstamos hablando de miles de millones de d\u00f3lares en nueva actividad econ\u00f3mica, decenas de miles de nuevos empleos o, simplemente, un impulso para esta industria que ha soportado una carga impositiva muy elevada durante a\u00f1os\u201d, dijo Vicente. \u201cEso supondr\u00eda un cambio radical para much\u00edsimas empresas de cannabis legal a nivel estatal\u201d.<\/p>\n<p>Desde 2018, las empresas de cannabis han pagado aproximadamente US$ 15.000 millones en impuestos adicionales relacionados con la Secci\u00f3n 280E, seg\u00fan un an\u00e1lisis publicado a principios de este mes por Whitney Economics. Sujetas a la Secci\u00f3n 280E, algunas empresas de cannabis tienen una tasa impositiva efectiva del 70 % o m\u00e1s, seg\u00fan la consultora de cannabis y c\u00e1\u00f1amo con sede en Portland, Oregon, especializada en investigaci\u00f3n econ\u00f3mica.<\/p>\n<p>\u201cAl eliminar esta carga impositiva, se lograr\u00e1 un impacto positivo sustancial en estas empresas, en su capacidad para contratar personal, pagar salarios m\u00e1s altos y aumentar su rentabilidad\u201d, afirm\u00f3 Vicente. \u201cEn una econom\u00eda que atraviesa momentos dif\u00edciles, esto podr\u00eda representar un verdadero triunfo para los estados que albergan estas empresas\u201d.<\/p>\n<p>Vicente afirm\u00f3 que probablemente el Servicio de Impuestos Internos tendr\u00eda que emitir directrices sobre la reclasificaci\u00f3n de la marihuana a la Lista III.<\/p>\n<p>Otra consecuencia pr\u00e1ctica de la reclasificaci\u00f3n ser\u00eda la aceleraci\u00f3n de la investigaci\u00f3n m\u00e9dica sobre el cannabis, afirm\u00f3.<\/p>\n<p>\u201cDurante a\u00f1os, en Colorado y en todo el pa\u00eds, he hablado con universidades y hospitales que desean permitir la investigaci\u00f3n, pero temen la ilegalidad federal y la p\u00e9rdida de fondos federales\u201d, dijo. \u201cSi bien esto no cambiar\u00eda el estatus de legalidad del cannabis, lo reclasificar\u00eda a la Lista III, lo que ayudar\u00eda a acelerar la investigaci\u00f3n y sin duda reducir\u00eda parte del estigma asociado a esta medicina\u201d.<\/p>\n<p>Seg\u00fan coment\u00f3, no se espera que cambien las leyes y regulaciones estatales relativas al cannabis recreativo y medicinal.<\/p>\n<p>La reclasificaci\u00f3n de la marihuana no resolver\u00e1 el conflicto de larga data entre el Gobierno federal y los estados: el cultivo, la fabricaci\u00f3n, la venta y la posesi\u00f3n de marihuana para uso recreativo seguir\u00edan siendo ilegales, seg\u00fan la ley federal y potencialmente sujetas a la aplicaci\u00f3n de la ley y al enjuiciamiento.<\/p>\n<p>Actualmente, las empresas estatales que venden marihuana medicinal legalmente cuentan con algunas protecciones federales a trav\u00e9s de la legislaci\u00f3n de asignaciones presupuestarias, que restringe la interferencia del Departamento de Justicia en estos programas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Justicia interino de EE.UU., Todd Blanche, firm\u00f3 este jueves una orden que reclasifica la marihuana medicinal autorizada por el estado como una droga menos peligrosa. Esta decisi\u00f3n cambia una pol\u00edtica que durante d\u00e9cadas ha dificultado la investigaci\u00f3n de los posibles beneficios medicinales de la droga. La orden de Blanche no legaliza el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473434","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa - Noticias\" \/>\n<meta property=\"og:description\" content=\"El secretario de Justicia interino de EE.UU., Todd Blanche, firm\u00f3 este jueves una orden que reclasifica la marihuana medicinal autorizada por el estado como una droga menos peligrosa. Esta decisi\u00f3n cambia una pol\u00edtica que durante d\u00e9cadas ha dificultado la investigaci\u00f3n de los posibles beneficios medicinales de la droga. La orden de Blanche no legaliza el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-23T15:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa\",\"datePublished\":\"2026-04-23T15:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/\"},\"wordCount\":1274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/\",\"name\":\"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-23T15:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa - Noticias","og_description":"El secretario de Justicia interino de EE.UU., Todd Blanche, firm\u00f3 este jueves una orden que reclasifica la marihuana medicinal autorizada por el estado como una droga menos peligrosa. Esta decisi\u00f3n cambia una pol\u00edtica que durante d\u00e9cadas ha dificultado la investigaci\u00f3n de los posibles beneficios medicinales de la droga. La orden de Blanche no legaliza el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-23T15:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/"},"author":{"name":"","@id":""},"headline":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa","datePublished":"2026-04-23T15:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/"},"wordCount":1274,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","name":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-23T15:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/23\/reclasifica-marihuana-droga-menos-peligrosa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-23T15:03:45Z","datePublished":"2026-04-23T15:03:45Z","dateModified":"2026-04-23T15:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Departamento de Justicia de EE.UU. reclasifica la marihuana medicinal con licencia estatal como una droga menos peligrosa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/23\\\/reclasifica-marihuana-droga-menos-peligrosa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/23\\\/reclasifica-marihuana-droga-menos-peligrosa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-23T15:03:45Z\",\"datePublished\":\"2026-04-23T15:03:45Z\",\"dateModified\":\"2026-04-23T15:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465274,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/09\/trump-marihuana-droga-menos-peligrosa-trax\/","url_meta":{"origin":1473434,"position":0},"title":"Trump est\u00e1 considerando en privado c\u00f3mo declarar la marihuana una droga menos peligrosa","author":"","date":"agosto 9, 2025","format":false,"excerpt":"Durante una cena reciente en su club privado de Bedminster, Nueva Jersey, mientras el presidente Donald Trump relataba su acci\u00f3n contra el principal estad\u00edstico econ\u00f3mico del pa\u00eds y hac\u00eda alusiones a la pol\u00edtica de la ciudad de Nueva York, la conversaci\u00f3n gir\u00f3 hacia un tema pol\u00edticamente potente que todav\u00eda est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469340,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/12\/17\/trump-decreto-marihuana-restricciones-droga-trax\/","url_meta":{"origin":1473434,"position":1},"title":"Se espera que Trump firme un decreto que reclasifica la marihuana y alivia las restricciones sobre la droga","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Se espera que el presidente de EE.UU., Donald Trump, firme el jueves un decreto que reclasificar\u00eda la marihuana a una clasificaci\u00f3n de droga m\u00e1s baja, una medida que aliviar\u00eda las restricciones federales, aunque no significar\u00eda una legalizaci\u00f3n total, seg\u00fan una fuente familiarizada con la planificaci\u00f3n y un alto funcionario de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449660,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/21\/intoxicaciones-marihuana-adultos-mayores-triplicaron-estudio-trax\/","url_meta":{"origin":1473434,"position":2},"title":"Las intoxicaciones por marihuana entre los adultos mayores se triplicaron, seg\u00fan un estudio","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- Uno puede pensar que los j\u00f3venes son el principal grupo que disfruta de la libertad de la marihuana legal, pero en Canad\u00e1, el mayor aumento de usuarios despu\u00e9s de la legalizaci\u00f3n se produjo entre los adultos mayores, y a veces los env\u00eda al hospital, seg\u00fan una nueva investigaci\u00f3n.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452549,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/09\/09\/trump-votara-legalizar-uso-recreativo-marihuana-adultos-florida-trax\/","url_meta":{"origin":1473434,"position":3},"title":"Trump dice que votar\u00e1 para legalizar el uso recreativo de marihuana para adultos en Florida","author":"","date":"septiembre 9, 2024","format":false,"excerpt":"(CNN) -- Donald Trump, expresidente de Estados Unidos y actual candidato presidencial republicano, dijo el domingo que votar\u00eda a favor de una medida en la boleta electoral en Florida que legalizar\u00eda el uso recreativo de la marihuana para adultos, una posici\u00f3n que lo pone en desacuerdo con el gobernador Ron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1427161,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2022\/09\/19\/este-lunes-votan-cambios-que-facilitaran-venta-de-cannabis-en-denver\/","url_meta":{"origin":1473434,"position":4},"title":"Este lunes votan cambios que facilitar\u00e1n venta de cannabis en Denver","author":"agomez","date":"septiembre 19, 2022","format":false,"excerpt":"La venta de este producto se redujo el a\u00f1o pasado, por lo que buscan darle un impulso.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473315,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/19\/mujeres-recurriendo-cannabis-ayuda-trax\/","url_meta":{"origin":1473434,"position":5},"title":"Lo intentaron todo, y nada funcion\u00f3. Ahora, las mujeres est\u00e1n recurriendo al cannabis en busca de ayuda","author":"agomez","date":"abril 19, 2026","format":false,"excerpt":"Cuando comenc\u00e9 a filmar el primer documental sobre la marihuana, en 2012, no podr\u00eda haber predicho ad\u00f3nde me llevar\u00eda este viaje, ni las historias que seguir\u00edan desarroll\u00e1ndose mucho despu\u00e9s de esa exploraci\u00f3n inicial del mundo del cannabis.En aquel momento, pens\u00e9 que estaba haciendo un \u00fanico documental sobre una planta controversial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473434"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473434\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}