{"id":1473459,"date":"2026-04-24T02:03:38","date_gmt":"2026-04-24T09:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/"},"modified":"2026-04-24T02:03:38","modified_gmt":"2026-04-24T09:03:38","slug":"plan-tiroteo-masivo-nueva-orleans-frustrado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/","title":{"rendered":"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso"},"content":{"rendered":"<p>Las fuerzas del orden de tres estados <a href=\"https:\/\/www.cnn.com\/2026\/04\/23\/us\/new-orleans-mass-shooting-planning-arrest\">frustraron los planes<\/a> de un expolic\u00eda con experiencia que, seg\u00fan afirman, expres\u00f3 su deseo de hacer da\u00f1o a personas negras y amenaz\u00f3 con perpetrar un tiroteo masivo en un festival de Nueva Orleans.<\/p>\n<p>Christopher Gillum, de 45 a\u00f1os y residente de Carolina del Norte, fue reportado como desaparecido el martes por su familia, y la polic\u00eda r\u00e1pidamente descubri\u00f3 que estaba armado y representaba un posible riesgo para s\u00ed mismo y para los dem\u00e1s, seg\u00fan inform\u00f3 el Departamento de Polic\u00eda de Burlington.<\/p>\n<p>Al d\u00eda siguiente, Gillum fue arrestado a m\u00e1s de 960 kil\u00f3metros de distancia, en Florida, acusado por la polic\u00eda de Louisiana de proferir amenazas terroristas.<\/p>\n<p>\u201cLas autoridades obtuvieron informaci\u00f3n de que Gillum planeaba viajar a un festival en Nueva Orleans para perpetrar un tiroteo masivo y luego morir a manos de la polic\u00eda\u201d, inform\u00f3 la Oficina del Sheriff del Condado de Okaloosa, que arrest\u00f3 a Gillum.<\/p>\n<p>Todav\u00eda no est\u00e1 claro c\u00f3mo las autoridades se enteraron del supuesto complot, los detalles de la amenaza y qu\u00e9 pudo haber motivado al veterano agente de la ley con m\u00e1s de una d\u00e9cada de experiencia policial.<\/p>\n<p>Si bien las autoridades no han confirmado a qu\u00e9 festival apuntaba Gillum, su arresto se produjo justo un d\u00eda antes de que la ciudad de Nueva Orleans diera comienzo a su Festival Anual de Jazz y Patrimonio, que atrae a unos 400.000 asistentes cada a\u00f1o.<\/p>\n<p>La Polic\u00eda Estatal de Louisiana ha declarado no tener conocimiento de otras amenazas cre\u00edbles, pero la ciudad de Nueva Orleans y sus residentes son plenamente conscientes de la realidad de los ataques p\u00fablicos.<\/p>\n<p>Otro atentado planeado contra la ciudad fue <a href=\"https:\/\/www.cnn.com\/2025\/12\/17\/us\/new-orleans-attack-thwarted\">frustrado<\/a> en diciembre, casi un a\u00f1o despu\u00e9s de una <a href=\"https:\/\/www.cnn.com\/2025\/01\/03\/us\/bourbon-street-narrative-new-orleans-truck-attack\">agresi\u00f3n mortal<\/a> que dej\u00f3 14 muertos en el Barrio Franc\u00e9s.<\/p>\n<p>Gillum ahora espera ser extraditado de Florida a Louisiana. Esto es lo que sabemos:<\/p>\n<p>La familia de Gillum lo report\u00f3 como desaparecido el martes, <a href=\"https:\/\/apnews.com\/article\/new-orleans-festival-mass-shooting-arrest-f2b60f1e8415c9177c04c230ce930c76\">seg\u00fan inform\u00f3 a The Associated Press<\/a> el teniente Clint Lyons de la Oficina del Sheriff del Condado de Alamance en Carolina del Norte. Lyons se\u00f1al\u00f3 que Gillum tiene antecedentes de autolesiones.<\/p>\n<p>Seg\u00fan declar\u00f3 un agente de la ley a CNN, su familia indic\u00f3 que pose\u00eda una pistola Glock y que hab\u00eda expresado inter\u00e9s en hacer da\u00f1o a personas negras.<\/p>\n<p>A pesar de sus comentarios sobre las personas negras, Lyons declar\u00f3 a la AP que no exist\u00edan motivos penales para detener a Gillum en ese momento \u201cporque no hab\u00eda ninguna v\u00edctima\u201d.<\/p>\n<p>Seg\u00fan Lyons, Gillum hab\u00eda abandonado el estado antes de que la polic\u00eda pudiera redactar la documentaci\u00f3n necesaria para internarlo involuntariamente en un centro psiqui\u00e1trico.<\/p>\n<p>Los investigadores del condado de Alamance contactaron el martes a la polic\u00eda de la ciudad de Burlington para alertarlos sobre el caso.<\/p>\n<p>A medida que avanzaba la investigaci\u00f3n, las autoridades \u201cencontraron motivos para creer que Christopher Gillum representaba un peligro para s\u00ed mismo y para los dem\u00e1s\u201d, indic\u00f3 el Departamento de Polic\u00eda de Burlington en un comunicado.<\/p>\n<p>Seg\u00fan la polic\u00eda de Burlington, los investigadores utilizaron lectores de matr\u00edculas para determinar que Gillum se dirig\u00eda a Florida y comenzaron a contactar con otros organismos policiales para intentar localizarlo.<\/p>\n<p>Posteriormente, enviaron un bolet\u00edn de inteligencia a agencias como la Polic\u00eda Estatal de Louisiana y el Departamento de Polic\u00eda de Nueva Orleans.<\/p>\n<p>Seg\u00fan informaron los investigadores, estos utilizaron una extensa red de <a href=\"https:\/\/www.cnn.com\/2025\/03\/02\/us\/mardi-gras-surveillance-project-nola\">lectores de matr\u00edculas FLOCK<\/a> para localizar a Gillum en un hotel de Destin, Florida, donde fue arrestado el mi\u00e9rcoles por la noche.<\/p>\n<p>Tras su detenci\u00f3n, los agentes descubrieron una pistola y unos 200 cartuchos de munici\u00f3n en la habitaci\u00f3n de hotel de Gillum, seg\u00fan la Oficina del Sheriff del Condado de Okaloosa, que supervisa Destin.<\/p>\n<p>No est\u00e1 claro en qu\u00e9 momento las autoridades de Louisiana tuvieron conocimiento del posible complot para un tiroteo masivo ni cu\u00e1ndo se presentaron los cargos en su contra. CNN no ha podido determinar si Gillum cuenta con un abogado.<\/p>\n<p>La polic\u00eda estatal de Louisiana indic\u00f3 que la investigaci\u00f3n a\u00fan se encuentra en sus primeras etapas y se llevar\u00e1 a cabo en coordinaci\u00f3n con el FBI. La agencia estatal se neg\u00f3 a brindar m\u00e1s detalles \u201cpara no comprometer la investigaci\u00f3n\u201d.<\/p>\n<p>\u201cHasta el momento, no se conocen amenazas directas contra ning\u00fan festival en Louisiana\u201d, declar\u00f3 el sargento Ross Brennan de la Polic\u00eda Estatal de Louisiana. \u201cLa investigaci\u00f3n contin\u00faa en curso y la credibilidad de cualquier amenaza potencial, pasada o presente, forma parte del proceso de investigaci\u00f3n\u201d.<\/p>\n<p>Seg\u00fan sus empleadores, Gillum trabaj\u00f3 para al menos tres agencias policiales en Carolina del Norte entre 2004 y 2025.<\/p>\n<p>La mayor parte de su carrera la pas\u00f3 como agente de polic\u00eda en Chapel Hill, desde 2004 hasta 2019, a\u00f1o en que renunci\u00f3 y acept\u00f3 un puesto como agente en el Departamento de Polic\u00eda de Carolina Beach, a unas tres horas de distancia. Trabaj\u00f3 para el departamento de Carolina Beach durante un a\u00f1o.<\/p>\n<p>No est\u00e1 claro d\u00f3nde trabaj\u00f3 Gillum durante los a\u00f1os siguientes, ni si trabaj\u00f3, pero a finales de 2023 se uni\u00f3 a la Oficina del Sheriff del Condado de Orange como agente de detenci\u00f3n y dej\u00f3 el puesto en julio de 2024, seg\u00fan Alicia Stemper, portavoz de la oficina del sheriff.<\/p>\n<p> Posteriormente, Gillum regres\u00f3 al departamento de polic\u00eda de Chapel Hill como empleado no juramentado antes de irse a otro trabajo a finales de ese a\u00f1o, seg\u00fan declar\u00f3 a CNN Alex Carrasquillo, gerente de comunicaciones del municipio de Chapel Hill.<\/p>\n<p>Gillum fue contratado nuevamente por la Oficina del Sheriff del Condado de Orange en enero del a\u00f1o pasado, esta vez como ayudante del sheriff, pero renunci\u00f3 en septiembre, dijo Stemper.<\/p>\n<p>Nueva Orleans ha reforzado las medidas de seguridad p\u00fablica durante el \u00faltimo a\u00f1o, especialmente en lo que respecta a grandes concentraciones p\u00fablicas, desde que un atropello mortal con un cami\u00f3n acab\u00f3 con la vida de 14 personas durante una celebraci\u00f3n de A\u00f1o Nuevo.<\/p>\n<p>El atentado terrorista tuvo lugar en la concurrida calle Bourbon de la ciudad y suscit\u00f3 interrogantes sobre c\u00f3mo la ciudad hab\u00eda asegurado la popular zona y c\u00f3mo un cami\u00f3n de grandes dimensiones pudo circular por el distrito, tan transitado por peatones, en una de las noches m\u00e1s importantes del a\u00f1o.<\/p>\n<p>Un informe publicado por la Fundaci\u00f3n de la Polic\u00eda y la Justicia de Nueva Orleans recomend\u00f3 que la mayor parte de la calle Bourbon se <a href=\"https:\/\/www.cnn.com\/2025\/04\/08\/us\/bourbon-street-new-orleans-closed-cars\">cerrara al tr\u00e1fico vehicular<\/a>, creando una plaza peatonal permanente.<\/p>\n<p>Las fuerzas del orden no han confirmado a qu\u00e9 festival supuestamente pretend\u00eda atacar Gillum, pero Matthew Goldman, director de prensa y publicidad del Jazz Fest, declar\u00f3 a la <a href=\"https:\/\/www.fox8live.com\/2026\/04\/23\/man-arrested-destin-after-federal-tip-about-louisiana-festival-mass-shooting-threat-sheriff-says\/\">filial de CNN, WVUE,<\/a> tras la detenci\u00f3n de Gillum, que los organizadores estaban \u201cagradecidos a todos los agentes del orden por su dedicaci\u00f3n y servicio excepcional en la protecci\u00f3n de nuestra comunidad\u201d.<\/p>\n<p>El Festival de Jazz de este fin de semana se celebrar\u00e1 en el hip\u00f3dromo y sala de m\u00e1quinas tragamonedas Fair Grounds, a unos 4 kil\u00f3metros de Bourbon Street y del Barrio Franc\u00e9s de la ciudad.<\/p>\n<p>Hace apenas cuatro meses, otro plan para atacar a los residentes de Nueva Orleans fue frustrado por las fuerzas del orden.<\/p>\n<p>Un exinfante de marina fue <a href=\"https:\/\/www.cnn.com\/2025\/12\/17\/us\/new-orleans-attack-thwarted\">arrestado en diciembre<\/a> cuando se dirig\u00eda a perpetrar un ataque en la ciudad, seg\u00fan consta en los documentos judiciales de la \u00e9poca.<\/p>\n<p>El sospechoso estaba vinculado a un grupo antigubernamental y cre\u00eda que era el momento de \u201crecrear\u201d Waco, seg\u00fan informaron las autoridades.<\/p>\n<p>El gobernador de Luisiana, Jeff Landry, declar\u00f3 a <a href=\"https:\/\/x.com\/wdsu\/status\/2047359376332116079\">WDSU, filial de CNN,<\/a> que su administraci\u00f3n ha considerado la \u201cprotecci\u00f3n\u201d en torno a la ciudad de Nueva Orleans como \u201cextremadamente importante\u201d desde el ataque terrorista de A\u00f1o Nuevo.<\/p>\n<p>El atentado frustrado, declar\u00f3 Landry el jueves, demuestra que las autoridades \u201ctienen los recursos necesarios para asegurarse de que recibimos informaci\u00f3n precisa y luego actuamos en consecuencia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las fuerzas del orden de tres estados frustraron los planes de un expolic\u00eda con experiencia que, seg\u00fan afirman, expres\u00f3 su deseo de hacer da\u00f1o a personas negras y amenaz\u00f3 con perpetrar un tiroteo masivo en un festival de Nueva Orleans. Christopher Gillum, de 45 a\u00f1os y residente de Carolina del Norte, fue reportado como desaparecido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473459","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las fuerzas del orden de tres estados frustraron los planes de un expolic\u00eda con experiencia que, seg\u00fan afirman, expres\u00f3 su deseo de hacer da\u00f1o a personas negras y amenaz\u00f3 con perpetrar un tiroteo masivo en un festival de Nueva Orleans. Christopher Gillum, de 45 a\u00f1os y residente de Carolina del Norte, fue reportado como desaparecido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-24T09:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso\",\"datePublished\":\"2026-04-24T09:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/\"},\"wordCount\":1417,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/\",\"name\":\"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-24T09:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso - Noticias","og_description":"Las fuerzas del orden de tres estados frustraron los planes de un expolic\u00eda con experiencia que, seg\u00fan afirman, expres\u00f3 su deseo de hacer da\u00f1o a personas negras y amenaz\u00f3 con perpetrar un tiroteo masivo en un festival de Nueva Orleans. Christopher Gillum, de 45 a\u00f1os y residente de Carolina del Norte, fue reportado como desaparecido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-24T09:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/"},"author":{"name":"","@id":""},"headline":"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso","datePublished":"2026-04-24T09:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/"},"wordCount":1417,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/","name":"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-24T09:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/24\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-24T09:03:38Z","datePublished":"2026-04-24T09:03:38Z","dateModified":"2026-04-24T09:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Plan para perpetrar un tiroteo masivo en Nueva Orleans fue frustrado por una red de fuerzas del orden. Claves del caso\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/24\\\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/24\\\/plan-tiroteo-masivo-nueva-orleans-frustrado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-24T09:03:38Z\",\"datePublished\":\"2026-04-24T09:03:38Z\",\"dateModified\":\"2026-04-24T09:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473438,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/23\/exagente-plan-tiroteo-nueva-orleans-trax\/","url_meta":{"origin":1473459,"position":0},"title":"Exagente de Polic\u00eda fue arrestado por presuntamente planear un tiroteo masivo en un festival de Nueva Orleans","author":"","date":"abril 23, 2026","format":false,"excerpt":"Un exagente de Polic\u00eda fue arrestado el mi\u00e9rcoles en Florida despu\u00e9s de que las autoridades encontraran informaci\u00f3n que sugiere que planeaba un tiroteo masivo en un festival de Nueva Orleans, seg\u00fan la oficina del sheriff del condado de Okaloosa.Christopher Gillum, de Chapel Hill, Carolina del Norte, era buscado en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471820,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/03\/declaran-culpable-homicidio-padre-autor-tiroteo-escuela-georgia-trax\/","url_meta":{"origin":1473459,"position":1},"title":"Declaran culpable de homicidio al padre del autor de un tiroteo masivo en una escuela de Georgia que dej\u00f3 cuatro muertos","author":"","date":"marzo 3, 2026","format":false,"excerpt":"Colin Gray, padre de Colt Gray, autor de un tiroteo escolar en Georgia, fue declarado culpable el martes de homicidio en un caso que puso a prueba los l\u00edmites de qui\u00e9n es responsable ante un tiroteo masivo.El jurado deliber\u00f3 durante menos de dos horas antes de condenarlo por los 27\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464931,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/07\/28\/tiroteo-nueva-york-manhattan-trax\/","url_meta":{"origin":1473459,"position":2},"title":"Se cree que el sospechoso muri\u00f3 tras tiroteo que dej\u00f3 heridos a un polic\u00eda de Nueva York y a dos civiles, seg\u00fan fuentes","author":"","date":"julio 28, 2025","format":false,"excerpt":"Se cree que un hombre armado muri\u00f3 despu\u00e9s de disparar a un agente del Departamento de Polic\u00eda de Nueva York (NYPD) y al menos a dos civiles cerca de un edificio de oficinas corporativas en el centro de Manhattan este lunes por la tarde, seg\u00fan dijeron a CNN varias fuentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456322,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/12\/06\/pistas-asesinato-ceo-unitedhealthcare-trax\/","url_meta":{"origin":1473459,"position":3},"title":"Un coqueteo, municiones escritas y una botella ofrecen pistas sobre el atacante del CEO de UnitedHealthcare","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"Una foto que muestra a un hombre encapuchado sonriendo puede proporcionar pistas importantes que podr\u00edan ayudar a conducir al sospechoso en el tiroteo mortal del CEO de UnitedHealthcare, Brian Thompson.Una imagen publicada por el Departamento de Polic\u00eda de Nueva York muestra a un hombre al que las autoridades califican de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450933,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/07\/07\/arrestan-a-tercer-sospechoso-de-tiroteo-masivo-en-celebracion-del-juneteenth-en-texas-que-dejo-2-muertos-y-14-heridos\/","url_meta":{"origin":1473459,"position":4},"title":"Arrestan a tercer sospechoso de tiroteo masivo en celebraci\u00f3n del Juneteenth en Texas que dej\u00f3 2 muertos y 14 heridos","author":"","date":"julio 7, 2024","format":false,"excerpt":"(CNN) -- Un tercer sospechoso fue\u00a0 arrestado en relaci\u00f3n con un tiroteo masivo en una celebraci\u00f3n del Juneteenth que dej\u00f3 dos personas muertas y otras 14 heridas en Round Rock, Texas, seg\u00fan la Polic\u00eda.Keshawn Dixon, de 18 a\u00f1os, fue arrestado este s\u00e1bado en Killeen, Texas, y llevado a la c\u00e1rcel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450623,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/06\/23\/muere-cuarta-victima-tiroteo-masivo-tienda-comestibles-de-arkansas-trax\/","url_meta":{"origin":1473459,"position":5},"title":"Muere la cuarta v\u00edctima del tiroteo masivo en una tienda de comestibles de Arkansas mientras contin\u00faa la investigaci\u00f3n policial","author":"","date":"junio 23, 2024","format":false,"excerpt":"(CNN) -- Una cuarta v\u00edctima muri\u00f3 este s\u00e1bado por la noche tras un tiroteo en una tienda de comestibles en Fordyce, Arkansas , dijeron las autoridades, mientras la Polic\u00eda continuaba investigando el ataque.Un hombre abri\u00f3 fuego en Mad Butcher en Fordyce este viernes, matando a cuatro personas de edades comprendidas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473459"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473459\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}