{"id":1473513,"date":"2026-04-26T01:03:39","date_gmt":"2026-04-26T08:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/"},"modified":"2026-04-26T01:03:39","modified_gmt":"2026-04-26T08:03:39","slug":"cena-anual-washington-caos-crimen-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","title":{"rendered":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen"},"content":{"rendered":"<p>El presidente Donald Trump y la primera dama Melania Trump estaban sentados en el escenario del enorme sal\u00f3n de baile del Washington Hilton poco despu\u00e9s de las 8:30 p.m. (hora de Miami) del s\u00e1bado por la noche, interactuando de manera juguetona con el artista de la velada, el mentalista Oz Pearlman.<\/p>\n<p>Justo afuera, un hombre corri\u00f3 a trav\u00e9s de un punto de control de seguridad con una escopeta en la mano, intercambiando disparos con agentes del Servicio Secreto que lo persegu\u00edan, seg\u00fan im\u00e1genes de seguridad del incidente que fueron difundidas.<\/p>\n<p>En cuesti\u00f3n de segundos, el hombre armado fue reducido por el Servicio Secreto, antes de que pudiera llegar al sal\u00f3n de baile donde el presidente, funcionarios de la administraci\u00f3n Trump, miembros del Congreso y algunos de los reporteros y editores m\u00e1s destacados del pa\u00eds asist\u00edan a la Cena anual de la Asociaci\u00f3n de Corresponsales de la Casa Blanca.<\/p>\n<p>Dentro del abarrotado sal\u00f3n de baile, los invitados ya estaban sentados y picoteaban ensaladas de burrata y pepino cuando qued\u00f3 claro que la noche hab\u00eda dado un giro aterrador. Sonidos secos, uno tras otro, provenientes del exterior de las puertas del sal\u00f3n hicieron que el fuerte murmullo de conversaci\u00f3n se apagara r\u00e1pidamente.<\/p>\n<p>Para quienes estaban dentro de la sala \u2014ubicada un nivel por debajo de donde ocurri\u00f3 el incidente\u2014 no era evidente qu\u00e9 eran esos sonidos. Incluso el propio presidente no estuvo seguro de inmediato de lo que hab\u00eda pasado. El primer pensamiento de Trump fue que se trataba de una bandeja llena de platos de la cena que se hab\u00eda estrellado contra el suelo: \u201cHe escuchado eso muchas veces\u201d, dir\u00eda m\u00e1s tarde desde la Casa Blanca, a\u00fan con el esmoquin del evento.<\/p>\n<p>Pero cuando agentes de las fuerzas del orden, muchos armados, se desplegaron por la sala desde todas las entradas, qued\u00f3 claro que hab\u00eda ocurrido un incidente grave. Gritos de \u201cal suelo\u201d se extendieron por el sal\u00f3n mientras los invitados y el personal del hotel se lanzaban debajo de sillas y mesas para cubrirse.<\/p>\n<p>La mesa principal se despej\u00f3 casi de inmediato. El vicepresidente J. D. Vance fue apartado de la mesa y llevado hacia la izquierda del escenario. Mientras agentes con rifles corr\u00edan hacia el frente del escenario, el equipo del Servicio Secreto del presidente lo rode\u00f3, seg\u00fan un <a href=\"https:\/\/x.com\/GettyImagesNews\/status\/2048228852128952654?s=20\">video<\/a> grabado desde un costado del escenario. Mientras era evacuado, el presidente pareci\u00f3 caer brevemente al suelo antes de que \u00e9l y la primera dama fueran llevados r\u00e1pidamente a una sala segura del hotel. Quienes estaban sentados a su lado fueron trasladados a una sala distinta al final del pasillo.<\/p>\n<p>Los asistentes a la cena que eligieron ese momento para salir del sal\u00f3n de baile antes de que se sirviera el plato principal, incluido Wolf Blitzer de CNN, lamentablemente se pusieron en peligro. Blitzer acababa de salir de un ba\u00f1o fuera del sal\u00f3n cuando vio al hombre armado a solo unos pocos pies de distancia.<\/p>\n<p>\u201cEmpec\u00e9 a escuchar disparos en el pasillo, justo cerca de m\u00ed, y lo siguiente que supe fue que un agente de polic\u00eda me tir\u00f3 al suelo y se puso encima de m\u00ed\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/26\/eeuu\/wolf-blitzer-cnn-cena-corresponsales-trax\">dijo Blitzer<\/a>. \u201cLos disparos fueron tan fuertes, tan aterradores, que nos asust\u00f3 a todos. No ten\u00edamos idea de qu\u00e9 estaba pasando\u201d.<\/p>\n<p>El presentador de CNN fue llevado de vuelta al ba\u00f1o de hombres, donde \u00e9l y m\u00e1s de una decena de personas se refugiaron en el lugar, dijo.<\/p>\n<p>Perdi\u00f3 un zapato en medio del alboroto.<\/p>\n<p>Cuando el hombre armado arremeti\u00f3 contra el punto de control, llevaba una escopeta, una pistola y varios cuchillos, seg\u00fan funcionarios de las fuerzas del orden. Un agente del Servicio Secreto recibi\u00f3 un disparo en el pecho durante el intercambio de disparos y estaba bien despu\u00e9s de ser trasladado a un hospital gracias al chaleco antibalas que llevaba puesto, dijo Trump m\u00e1s tarde a los periodistas.<\/p>\n<p>Las fuerzas del orden identificaron al presunto hombre armado como <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/26\/eeuu\/sospechoso-tiroteo-cena-corresponsales-casa-blanca-profesor-california-trax\">Cole Tomas Allen<\/a>, un hombre de 31 a\u00f1os de un suburbio de Los \u00c1ngeles que trabajaba como profesor y desarrollador de videojuegos, seg\u00fan registros p\u00fablicos. Los funcionarios dijeron que era un hu\u00e9sped registrado del hotel y que parec\u00eda haber actuado solo.<\/p>\n<p>El sospechoso no fue alcanzado por disparos, pero estaba recibiendo tratamiento en un hospital local, seg\u00fan la alcaldesa de la ciudad de Washington, Muriel Bowser.<\/p>\n<p>M\u00e1s tarde, Trump difundi\u00f3 en redes sociales las im\u00e1genes de seguridad del hombre armado corriendo a trav\u00e9s del punto de control, as\u00ed como una foto del sospechoso reducido por las fuerzas del orden en el suelo.<\/p>\n<p>De vuelta en el sal\u00f3n de baile, se impuso el silencio, interrumpido por jadeos ocasionales. Algunos asistentes a la cena se agacharon detr\u00e1s de sillas y mesas, mientras que muchos \u2014entre ellos reporteros\u2014 sacaron sus tel\u00e9fonos para capturar el momento hist\u00f3rico.<\/p>\n<p>Los miembros del gabinete que asistieron como invitados de organizaciones de noticias \u2014lo que significa que estaban repartidos en mesas por todo el sal\u00f3n, abarrotado\u2014 fueron sacados apresuradamente de la sala por sus propios equipos de seguridad, que hablaban a gritos en sus dispositivos de comunicaci\u00f3n mientras se apresuraban a salir del sal\u00f3n de banquetes. Se pudo escuchar a uno declarar \u201cdisparos efectuados\u201d por su radio.<\/p>\n<p>Los agentes revisaron la sala, en algunos casos subi\u00e9ndose a sillas para gritar los nombres de los funcionarios que buscaban evacuar, hasta encontrarlos y sacarlos de entre la multitud. La cantidad de altos funcionarios que estaban siendo evacuados a toda prisa ilustr\u00f3 cu\u00e1ntas personas en la l\u00ednea de sucesi\u00f3n presidencial, junto con Trump y Vance, estaban reunidas en un mismo lugar abarrotado.<\/p>\n<p>Mientras los invitados se tiraban al suelo, una voz grit\u00f3: \u201cDios bendiga a Estados Unidos\u201d.<\/p>\n<p>La funcionaria del Departamento de Justicia Harmeet Dhillon <a href=\"https:\/\/x.com\/AAGDhillon\/status\/2048226278801625193\">dijo en X<\/a> que ten\u00eda un moret\u00f3n en la cabeza porque un agente del Servicio Secreto pas\u00f3 corriendo por encima de su mesa, y agradeci\u00f3 al Servicio de alguaciles de EE.UU. por llevarla a casa sana y salva.<\/p>\n<p>Con el tiempo, cuando los agentes salieron de la sala, los invitados comenzaron a levantarse del suelo. Bajo tierra y abarrotado, el servicio de telefon\u00eda m\u00f3vil en el evento era notoriamente malo (el hotel s\u00ed proporcion\u00f3 Wi\u2011Fi; en parte para que los asistentes pudieran conectarse y comprar m\u00e1s vino para sus mesas). Pero muchos intentaron hacer llamadas a las redacciones o a familiares para dar actualizaciones.<\/p>\n<p>El evento anual se celebra en el Washington Hilton, ubicado a poco m\u00e1s de 1,6 km al noroeste de la Casa Blanca. El presidente Ronald Reagan recibi\u00f3 un disparo afuera del hotel en un intento de magnicidio en 1981.<\/p>\n<p>A medida que avanzaba la noche, no estaba claro dentro de la sala si el programa continuar\u00eda. En un momento, un presentador anim\u00f3 a los invitados a mantenerse a la espera, incluso sugiriendo que el plato de bistec y langosta a\u00fan se servir\u00eda.<\/p>\n<p>Tanto Trump como la presidenta de la Asociaci\u00f3n de Corresponsales de la Casa Blanca, la corresponsal de CBS en la Casa Blanca Weijia Jiang, inicialmente quer\u00edan continuar con el programa. Jiang dijo a quienes a\u00fan estaban en el sal\u00f3n de baile que el programa se reanudar\u00eda en breve. Trump, por su parte, estaba resguardado en un lugar seguro dentro del hotel y quer\u00eda regresar al recinto, seg\u00fan un funcionario de la administraci\u00f3n.<\/p>\n<p>Pero el Servicio Secreto no quer\u00eda que lo hiciera; y, al final, se impuso la postura de las fuerzas del orden.<\/p>\n<p>\u201cLuch\u00e9 como un demonio para quedarme\u201d, dijo Trump en su conferencia de prensa. \u201cPero es el protocolo\u201d.<\/p>\n<p>Para cuando Trump anunci\u00f3 que regresar\u00eda a la Casa Blanca para ofrecer una conferencia de prensa \u2014casi exactamente una hora despu\u00e9s de que el tirador arremetiera contra el punto de control de seguridad\u2014 ya hab\u00edan empezado a formarse filas para salir del hotel. Un per\u00edmetro de seguridad de varias manzanas de ancho dificultaba la salida.<\/p>\n<p>Reporteros de la Casa Blanca, vestidos de gala, se apresuraron afuera para intentar detener taxis, recorriendo a toda prisa los 2 km de regreso por Connecticut Avenue hasta la residencia presidencial.<\/p>\n<p>Cuando Trump apareci\u00f3 en la sala de prensa James S. Brady \u2014nombrada en honor al secretario de Prensa de Reagan que result\u00f3 herido en aquel intento de magnicidio de 1981 en el Hilton\u2014 estaba flanqueado por Vance y sus principales funcionarios de las fuerzas del orden. Trump agradeci\u00f3 a Jiang por su trabajo y dijo que toda la experiencia, por extra\u00f1o que parezca, hab\u00eda hecho que la sala llena de adversarios pol\u00edticos y la prensa quedara \u201ctotalmente unificada\u201d.<\/p>\n<p>\u201cFue muy inesperado, pero el Servicio Secreto y las fuerzas del orden actuaron de manera incre\u00edble\u201d, dijo Trump.<\/p>\n<p>A un lado, otra persona escuchaba en silencio: la primera dama, que al igual que su esposo hab\u00eda sido llevada r\u00e1pidamente a la sala segura en el s\u00f3tano del hotel.<\/p>\n<p>\u201cFue una experiencia bastante traum\u00e1tica para ella\u201d, reconoci\u00f3 Trump. \u201cHubo mucha acci\u00f3n all\u00e1 arriba muy r\u00e1pidamente\u201d.<\/p>\n<p>Melania Trump no estuvo al lado de su esposo durante dos intentos de magnicidio anteriores, en Butler, Pensilvania, y en West Palm Beach, Florida. Desde hace tiempo ha expresado preocupaci\u00f3n por la seguridad de su familia. Para ella, el incidente del s\u00e1bado puso en un primer plano los riesgos de seguridad de su posici\u00f3n.<\/p>\n<p>\u201cMe lo ha dicho muchas veces; me dijo: \u2018Tienes un trabajo peligroso\u2019, pero eso tambi\u00e9n va con ella. Quiero decir, tambi\u00e9n es peligroso para ella\u201d, dijo Trump.<\/p>\n<p>M\u00e1s tarde, cuando un reportero le pregunt\u00f3 si ella podr\u00eda ofrecer sus propias reflexiones sobre la noche, ella declin\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump y la primera dama Melania Trump estaban sentados en el escenario del enorme sal\u00f3n de baile del Washington Hilton poco despu\u00e9s de las 8:30 p.m. (hora de Miami) del s\u00e1bado por la noche, interactuando de manera juguetona con el artista de la velada, el mentalista Oz Pearlman. Justo afuera, un hombre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473513","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump y la primera dama Melania Trump estaban sentados en el escenario del enorme sal\u00f3n de baile del Washington Hilton poco despu\u00e9s de las 8:30 p.m. (hora de Miami) del s\u00e1bado por la noche, interactuando de manera juguetona con el artista de la velada, el mentalista Oz Pearlman. Justo afuera, un hombre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-26T08:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen\",\"datePublished\":\"2026-04-26T08:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/\"},\"wordCount\":1696,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/\",\"name\":\"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-26T08:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen - Noticias","og_description":"El presidente Donald Trump y la primera dama Melania Trump estaban sentados en el escenario del enorme sal\u00f3n de baile del Washington Hilton poco despu\u00e9s de las 8:30 p.m. (hora de Miami) del s\u00e1bado por la noche, interactuando de manera juguetona con el artista de la velada, el mentalista Oz Pearlman. Justo afuera, un hombre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-26T08:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen","datePublished":"2026-04-26T08:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/"},"wordCount":1696,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","name":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-26T08:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-26T08:03:39Z","datePublished":"2026-04-26T08:03:39Z","dateModified":"2026-04-26T08:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo la cena anual m\\u00e1s importante de Washington se transform\\u00f3 en caos\\u2026 y en una escena del crimen\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/26\\\/cena-anual-washington-caos-crimen-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/26\\\/cena-anual-washington-caos-crimen-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-26T08:03:39Z\",\"datePublished\":\"2026-04-26T08:03:39Z\",\"dateModified\":\"2026-04-26T08:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473807,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/05\/ice-senado-trump-salon-baile-trax\/","url_meta":{"origin":1473513,"position":0},"title":"Republicanos del Senado contemplan destinar US$ 1.000 millones para la seguridad del sal\u00f3n de baile de Trump","author":"","date":"mayo 5, 2026","format":false,"excerpt":"Los republicanos del Senado buscan otorgar al Servicio Secreto de EE.UU. US$ 1.000 millones para reforzar la seguridad del futuro sal\u00f3n de baile de la Casa Blanca del presidente Donald Trump, como parte de un paquete m\u00e1s amplio de aplicaci\u00f3n de leyes migratorias.Dos comisiones del Senado lideradas por republicanos presentaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473512,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/25\/wolf-blitzer-cnn-cena-corresponsales-trax\/","url_meta":{"origin":1473513,"position":1},"title":"Wolf Blitzer, de CNN, vive una &#171;terrible&#187; experiencia cuando un hombre armado abre fuego cerca de la Cena de Corresponsales","author":"","date":"abril 25, 2026","format":false,"excerpt":"Wolf Blitzer, de CNN, estaba a solo unos pocos pies de un hombre armado cuando se realizaron disparos afuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca.Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, afuera del sal\u00f3n de baile en el Washington\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473624,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/29\/escrutinio-servicio-secreto-ataque-cena-corresponsales-trax\/","url_meta":{"origin":1473513,"position":2},"title":"&#171;Al l\u00edmite de su capacidad&#187;: nuevo escrutinio al Servicio Secreto tras ataque en la cena de corresponsales de la Casa Blanca","author":"","date":"abril 29, 2026","format":false,"excerpt":"El presidente Donald Trump, el secretario de Justicia interino y otros altos funcionarios de la administraci\u00f3n afirman p\u00fablicamente que el Servicio Secreto respondi\u00f3 seg\u00fan lo previsto cuando un hombre armado intent\u00f3 irrumpir en la cena de la Asociaci\u00f3n de Corresponsales de la Casa Blanca.Pero entre bastidores, el incidente del s\u00e1bado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473515,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","url_meta":{"origin":1473513,"position":3},"title":"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca","author":"","date":"abril 26, 2026","format":false,"excerpt":"Wolf Blitzer, de CNN, estaba a solo unos pocos metros de un hombre armado cuando se efectuaron disparos fuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca.Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, fuera del sal\u00f3n de baile del Washington Hilton,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473524,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/27\/presunto-atacante-cena-corresponsales-seguridad-trax\/","url_meta":{"origin":1473513,"position":4},"title":"El presunto atacante en la cena de corresponsales plantea interrogantes sobre el protocolo de seguridad del evento","author":"","date":"abril 27, 2026","format":false,"excerpt":"El presunto atacante que el s\u00e1bado se abri\u00f3 paso m\u00e1s all\u00e1 de un puesto de control de seguridad en la cena de la Asociaci\u00f3n de Corresponsales de la Casa Blanca reaviv\u00f3 las preguntas sobre los protocolos del Servicio Secreto y sobre si deber\u00edan hacerse cambios al ya estricto cord\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470229,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","url_meta":{"origin":1473513,"position":5},"title":"As\u00ed son los planes para reconstruir el b\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca","author":"","date":"enero 19, 2026","format":false,"excerpt":"El presidente de Estados Unidos orden\u00f3 la construcci\u00f3n secreta de una instalaci\u00f3n subterr\u00e1nea segura en la Casa Blanca y construy\u00f3 una nueva extensi\u00f3n del ala este encima.Corr\u00eda el a\u00f1o 1941, y Franklin D. Roosevelt hab\u00eda sido alentado a construir un refugio antia\u00e9reo en la Casa Blanca tras el ataque a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473513"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473513\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}