{"id":1473661,"date":"2026-04-30T01:03:48","date_gmt":"2026-04-30T08:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/"},"modified":"2026-04-30T01:03:48","modified_gmt":"2026-04-30T08:03:48","slug":"estimacion-pentagono-millones-guerra-iran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/","title":{"rendered":"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes"},"content":{"rendered":"<p>La <a href=\"https:\/\/www.cnn.com\/2026\/04\/29\/world\/live-news\/iran-war-peace-proposal-trump#cmok6srly0000356ujewjiyvc\">estimaci\u00f3n de US$ 25.000 millones<\/a> que un alto funcionario del Pent\u00e1gono present\u00f3 el mi\u00e9rcoles a los legisladores sobre el coste total hasta la fecha de la guerra con Ir\u00e1n es una cifra muy baja que no incluye el coste de reparar los extensos da\u00f1os sufridos por las bases estadounidenses en la regi\u00f3n, informaron a CNN tres personas familiarizadas con el asunto.<\/p>\n<p>Una de las fuentes indic\u00f3 que el costo real estimado se acerca m\u00e1s a los US$ 40.000 o US$ 50.000 millones si se tienen en cuenta los costos de reconstrucci\u00f3n de las instalaciones militares estadounidenses y la sustituci\u00f3n de los bienes destruidos.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/shorts\/g05X8Xe3cU8\">Seg\u00fan ha informado<\/a> CNN, los ataques iran\u00edes en el golfo P\u00e9rsico durante los primeros d\u00edas de la guerra da\u00f1aron significativamente al menos nueve instalaciones militares estadounidenses en tan solo 48 horas, alcanzando emplazamientos en Bahrein, Kuwait, Iraq, los Emiratos \u00c1rabes Unidos y Qatar.<\/p>\n<p>Varios sistemas de radar estadounidenses cr\u00edticos y otros equipos en Medio Oriente tambi\u00e9n fueron destruidos por ataques iran\u00edes, incluido el sistema de radar de una bater\u00eda de misiles THAAD estadounidense en Jordania y edificios que albergaban sistemas de radar similares en dos ubicaciones de los Emiratos \u00c1rabes Unidos, <a href=\"https:\/\/www.cnn.com\/2026\/03\/05\/middleeast\/radar-bases-us-missile-defense-iran-war-intl-invs\">tambi\u00e9n divulg\u00f3 CNN.<\/a><\/p>\n<p>Un avi\u00f3n E-3 Sentry de la Fuerza A\u00e9rea de EE.UU. <a href=\"https:\/\/www.cnn.com\/2026\/03\/30\/middleeast\/us-air-force-awacs-jet-destroyed-saudi-arabia-intl-hnk-ml\">tambi\u00e9n fue destruido<\/a> en un ataque iran\u00ed contra una base a\u00e9rea en Arabia Saud\u00ed.<\/p>\n<p>Jules \u201cJay\u201d Hurst III, el funcionario del Pent\u00e1gono que actualmente se desempe\u00f1a como contralor de la agencia, declar\u00f3 el mi\u00e9rcoles ante la Comisi\u00f3n de Servicios Armados de la C\u00e1mara de Representantes que \u201cla mayor parte\u201d de los US$ 25.000 millones que mencion\u00f3 se han gastado en municiones.<\/p>\n<p>El secretario de Defensa, Pete Hegseth, se neg\u00f3 a decir si esa cifra inclu\u00eda la reparaci\u00f3n de los da\u00f1os a las bases estadounidenses.<\/p>\n<p>CNN ha solicitado comentarios al Pent\u00e1gono.<\/p>\n<p>El representante dem\u00f3crata Ro Khanna se mostr\u00f3 esc\u00e9ptico ante la estimaci\u00f3n de US$ 25.000 millones, calific\u00e1ndola de \u201ctotalmente err\u00f3nea\u201d durante la audiencia del mi\u00e9rcoles.<\/p>\n<p>Funcionarios del Pent\u00e1gono hab\u00edan informado previamente al Congreso que la guerra cost\u00f3 aproximadamente US$ 11.000 millones solo en los primeros seis d\u00edas, y el departamento solicit\u00f3 a la Casa Blanca el mes pasado que aprobara una petici\u00f3n al Congreso de m\u00e1s de US$ 200.000 millones en fondos militares adicionales para la guerra en curso, <a href=\"https:\/\/www.cnn.com\/2026\/03\/19\/politics\/iran-war-cost-republicans-congress\">inform\u00f3 CNN.<\/a><\/p>\n<p>Trump habla de mantener el bloqueo de los puertos iran\u00edes durante meses.<\/p>\n<p>Durante las reuniones informativas sobre el presupuesto con los periodistas la semana pasada, Hurst declar\u00f3 que el Pent\u00e1gono no tiene \u201cuna cifra definitiva sobre los da\u00f1os sufridos por nuestras instalaciones en el extranjero\u201d y que depende \u201cde c\u00f3mo decidamos reconstruirlas, o si lo hacemos\u201d.<\/p>\n<p>Se\u00f1al\u00f3 que el precio de reparar esas instalaciones \u201cno se refleja\u201d en la solicitud presupuestaria del Pent\u00e1gono de US$ 1,5 billones para el a\u00f1o fiscal 2027, en parte porque el departamento todav\u00eda est\u00e1 evaluando \u201cqu\u00e9 queremos construir en el futuro\u201d.<\/p>\n<p>\u201cNuestros socios tambi\u00e9n podr\u00edan aportar una parte para esa construcci\u00f3n\u201d, indic\u00f3 Hurst. \u201cAs\u00ed que no tenemos una estimaci\u00f3n precisa de lo que costar\u00eda reconstruir esas instalaciones\u201d.<\/p>\n<p>Seg\u00fan informaron funcionarios la semana pasada, el presupuesto solicitado de US$ 1,5 billones para 2027 supondr\u00eda un aumento del 42 % en la financiaci\u00f3n del Departamento de Defensa.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estimaci\u00f3n de US$ 25.000 millones que un alto funcionario del Pent\u00e1gono present\u00f3 el mi\u00e9rcoles a los legisladores sobre el coste total hasta la fecha de la guerra con Ir\u00e1n es una cifra muy baja que no incluye el coste de reparar los extensos da\u00f1os sufridos por las bases estadounidenses en la regi\u00f3n, informaron a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473661","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes - Noticias\" \/>\n<meta property=\"og:description\" content=\"La estimaci\u00f3n de US$ 25.000 millones que un alto funcionario del Pent\u00e1gono present\u00f3 el mi\u00e9rcoles a los legisladores sobre el coste total hasta la fecha de la guerra con Ir\u00e1n es una cifra muy baja que no incluye el coste de reparar los extensos da\u00f1os sufridos por las bases estadounidenses en la regi\u00f3n, informaron a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T08:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes\",\"datePublished\":\"2026-04-30T08:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/\"},\"wordCount\":615,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/\",\"name\":\"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-30T08:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes - Noticias","og_description":"La estimaci\u00f3n de US$ 25.000 millones que un alto funcionario del Pent\u00e1gono present\u00f3 el mi\u00e9rcoles a los legisladores sobre el coste total hasta la fecha de la guerra con Ir\u00e1n es una cifra muy baja que no incluye el coste de reparar los extensos da\u00f1os sufridos por las bases estadounidenses en la regi\u00f3n, informaron a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-30T08:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/"},"author":{"name":"","@id":""},"headline":"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes","datePublished":"2026-04-30T08:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/"},"wordCount":615,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/","name":"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-30T08:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La estimaci\u00f3n del Pent\u00e1gono de US$ 25.000 millones de la guerra con Ir\u00e1n es baja y no incluye otros costos, seg\u00fan fuentes","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/estimacion-pentagono-millones-guerra-iran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-30T08:03:48Z","datePublished":"2026-04-30T08:03:48Z","dateModified":"2026-04-30T08:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La estimaci\\u00f3n del Pent\\u00e1gono de US$ 25.000 millones de la guerra con Ir\\u00e1n es baja y no incluye otros costos, seg\\u00fan fuentes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/30\\\/estimacion-pentagono-millones-guerra-iran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/30\\\/estimacion-pentagono-millones-guerra-iran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-30T08:03:48Z\",\"datePublished\":\"2026-04-30T08:03:48Z\",\"dateModified\":\"2026-04-30T08:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471940,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/06\/espera-cueste-contribuyentes-ee-uu-guerra-iran-trax\/","url_meta":{"origin":1473661,"position":0},"title":"Esto es lo que se espera que cueste cada d\u00eda a los contribuyentes de EE.UU. la guerra con Ir\u00e1n","author":"","date":"marzo 6, 2026","format":false,"excerpt":"Transcurridos unos d\u00edas desde el inicio de la guerra con Ir\u00e1n y sin un final claro a la vista, han surgido preguntas sobre cu\u00e1nto costar\u00e1 la Operaci\u00f3n Furia \u00c9pica a los contribuyentes estadounidenses.El Pent\u00e1gono no ha compartido una estimaci\u00f3n y a\u00fan no ha pedido al Congreso un proyecto de ley\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462615,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/21\/trump-escudo-antimisiles-domo-dorado-trax\/","url_meta":{"origin":1473661,"position":1},"title":"Trump detalla su plan para construir el escudo antimisiles &#171;Domo Dorado&#187; para finales de su mandato","author":"","date":"mayo 21, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, present\u00f3 nuevos detalles de su ambicioso plan para un sistema multimillonario de defensa antimisiles \u201cDomo Dorado\u201d que proteger\u00e1 a EE.UU. de ataques extranjeros, afirmando que deber\u00eda estar listo antes de que deje el cargo.\u201cLo tendremos listo en tres a\u00f1os\u201d, declar\u00f3 Trump a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462514,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/19\/escudo-antimisiles-cupula-dorada-trump-millones-trax\/","url_meta":{"origin":1473661,"position":2},"title":"El escudo antimisiles &#171;C\u00fapula Dorada&#187; de Trump podr\u00eda costar cientos de miles de millones","author":"","date":"mayo 19, 2025","format":false,"excerpt":"El Pent\u00e1gono ha presentado a la Casa Blanca opciones de tama\u00f1o peque\u00f1o, mediano y grande para el desarrollo de la \u201cC\u00fapula Dorada\u201d, la visi\u00f3n del presidente Donald Trump de un escudo antimisiles de vanguardia que pueda proteger a Estados Unidos de ataques de largo alcance que probablemente costar\u00e1 cientos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460583,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/03\/29\/mision-militar-trump-frontera-sur-millones-trax\/","url_meta":{"origin":1473661,"position":3},"title":"La misi\u00f3n militar de Trump en la frontera sur cost\u00f3 m\u00e1s de US$ 300 millones en las primeras seis semanas","author":"","date":"marzo 29, 2025","format":false,"excerpt":"La amplia misi\u00f3n militar de la administraci\u00f3n Trump en la frontera sur de EE.UU. centrada en reducir la inmigraci\u00f3n y los flujos de drogas ya ha costado a los contribuyentes m\u00e1s de US$ 300 millones, seg\u00fan fuentes informadas sobre los datos del contralor del Departamento de Defensa, incluso cuando la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472733,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/31\/hegseth-porrista-fuerzas-armadas-iran-trax\/","url_meta":{"origin":1473661,"position":4},"title":"Tras bambalinas y frente a las c\u00e1maras, Hegseth act\u00faa como el porrista del poder de las Fuerzas Armadas en la guerra con Ir\u00e1n","author":"","date":"marzo 31, 2026","format":false,"excerpt":"En los d\u00edas previos al lanzamiento de las primeras bombas sobre Ir\u00e1n el mes pasado, el presidente de Estados Unidos, Donald Trump, se reuni\u00f3 con un peque\u00f1o grupo de asesores para discutir opciones. All\u00ed dej\u00f3 claro que quer\u00eda lanzar una campa\u00f1a militar junto a Israel, dijeron a CNN m\u00faltiples fuentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473386,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/21\/reserva-misiles-guerra-iran-trax\/","url_meta":{"origin":1473661,"position":5},"title":"EE.UU. agota su reserva de misiles clave en Ir\u00e1n y corre el riesgo de quedarse sin provisiones si estalla otra guerra","author":"","date":"abril 21, 2026","format":false,"excerpt":"Las Fuerzas Armadas de EE.UU. han agotado de forma significativa sus reservas de misiles clave durante la guerra con Ir\u00e1n y han creado un \u201criesgo a corto plazo\u201d de quedarse sin provisiones si surgiera otro conflicto en los pr\u00f3ximos a\u00f1os, seg\u00fan expertos y tres personas familiarizadas con evaluaciones internas recientes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473661"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473661\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}