{"id":1473686,"date":"2026-04-30T14:03:41","date_gmt":"2026-04-30T21:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/"},"modified":"2026-04-30T14:03:41","modified_gmt":"2026-04-30T21:03:41","slug":"cruzada-trump-jerome-powell-contraproducente-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/","title":{"rendered":"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente"},"content":{"rendered":"<p>Una de las preguntas m\u00e1s grandes sobre la cruzada de represalias del Presidente Donald Trump es cu\u00e1nto de esto est\u00e1 impulsado por estrategia, es decir, convirtiendo en ejemplos de precauci\u00f3n a sus enemigos, y cu\u00e1nto de esto est\u00e1 impulsado por agravio personal y rencor.<\/p>\n<p>El caso del Presidente de la Reserva Federal (Fed) Jerome Powell parece sugerir que es en gran parte lo \u00faltimo.<\/p>\n<p>Porque ahora ha resultado contraproducente gracias a la incapacidad de Trump de dejarlo pasar.<\/p>\n<p>El presidente continu\u00f3 su campa\u00f1a contra Powell mucho despu\u00e9s de que comenzara a verse pol\u00edticamente poco sensato. Y ahora, Powell, cuyo mandato como presidente termina el 15 de mayo, <a href=\"https:\/\/www.cnn.com\/2026\/04\/29\/business\/live-news\/federal-reserve-interest-rate\">decidi\u00f3 quedarse<\/a> en la Junta de Gobernadores de la Reserva Federal por eso.<\/p>\n<p>En resumen: Powell se convirti\u00f3 el mi\u00e9rcoles en el primer presidente desde 1948 en optar por quedarse en la junta de la Fed despu\u00e9s de que su mandato como presidente expire. Su mandato como gobernador termina en 2028, por lo que tiene todo el derecho de hacerlo. Pero es inusual.<\/p>\n<p>Su decisi\u00f3n <a href=\"https:\/\/www.wsj.com\/livecoverage\/fed-interest-rate-decision-earnings-04-29-2026\/card\/if-powell-leaves-trump-would-get-a-majority-on-the-fed-board-M3sgxniCgINc3wVtEVMz\">priva a Trump de una mayor\u00eda <\/a>en la junta de la Fed compuesta por sus propios nombramientos, al menos por ahora. (Powell fue nobrado como presidente por Trump pero inicialmente nominado por Barack Obama.)<\/p>\n<p>Y Powell dej\u00f3 en claro que su motivaci\u00f3n eran los intentos de Trump de atacarlo legalmente a \u00e9l y a la Fed (<a href=\"https:\/\/www.cnn.com\/2026\/03\/24\/business\/powell-doj-fed-renovations-judge\">basado en evidencia notablemente d\u00e9bil<\/a>). El presidente ha atacado y apuntado a Powell durante a\u00f1os por que la Fed no baja las tasas de inter\u00e9s como \u00e9l quiere.<\/p>\n<p>\u201cMi preocupaci\u00f3n es realmente sobre la serie de ataques legales a la Fed que amenazan nuestra capacidad de llevar a cabo la pol\u00edtica monetaria sin considerar factores pol\u00edticos\u201d, dijo Powell este mi\u00e9rcoles. Llam\u00f3 a los ataques legales \u201csin precedentes en nuestra historia de 113 a\u00f1os\u201d y cit\u00f3 \u201camenazas continuas de acciones adicionales similares\u201d.<\/p>\n<p>Powell a\u00f1adi\u00f3: \u201cLiteralmente me estoy quedando por las acciones que se han tomado. Hace mucho tiempo que planeaba retirarme. Y, ya sabes, las cosas que han sucedido, realmente, en los \u00faltimos tres meses, creo que no me han dejado otra opci\u00f3n\u201d.<\/p>\n<p>Aunque Powell no lo dijo directamente, parece posible que pueda querer quedarse para protegerse a s\u00ed mismo.<\/p>\n<p>El Departamento de Justicia de Trump recientemente <a href=\"https:\/\/www.cnn.com\/2026\/04\/24\/business\/doj-criminal-probe-of-powell\">cerr\u00f3 la investigaci\u00f3n criminal<\/a> y dej\u00f3 el asunto a un inspector general, despu\u00e9s de que el senador republicano Thom Tillis de Carolina del Norte exigiera que la investigaci\u00f3n se cerrara antes de votar para confirmar a Kevin Warsh \u2014elegido por Trump\u2014, como el nuevo presidente de la Fed.<\/p>\n<p>Pero se podr\u00eda entender si Powell est\u00e1 preocupado de que alg\u00fan d\u00eda el Departamento de Justicia (DOJ, por sus siglas en ingl\u00e9s) vuelva a abrir el caso. Renunciar le privar\u00eda de poder en esa circunstancia.<\/p>\n<p>Tillis ha dicho que el DOJ le inform\u00f3 que el caso no se reavivar\u00eda <a href=\"https:\/\/www.cnn.com\/2026\/04\/26\/business\/tillis-warsh-fed-nominee\">sin una referencia penal <\/a>del inspector general. Pero Trump la semana pasada insisti\u00f3 en que el asunto no se hab\u00eda \u201cdesechado\u201d y <a href=\"https:\/\/x.com\/kaitlancollins\/status\/2048113893487054921\">continu\u00f3 atacando a Powell <\/a>por el costo de las renovaciones del edificio de la Fed.<\/p>\n<p>Fue un comentario revelador del presidente. El Gobierno intentaba dejar atr\u00e1s el problema y conseguir que Warsh fuera confirmado, pero Trump no lo dejaba pasar.<\/p>\n<p>Eso ha sido un tema.<\/p>\n<p>Durante a\u00f1os, desde el primer mandato de Trump, Powell ha dejado en claro que no ceder\u00eda a la presi\u00f3n del presidente.<\/p>\n<p>Eso fue evidente cuando Powell <a href=\"https:\/\/www.cnn.com\/2025\/07\/24\/politics\/video\/president-trump-jerome-powell-renovation-exchange-digvid\">corrigi\u00f3 en tiempo real <\/a>las afirmaciones falsas de Trump sobre las renovaciones de la Fed el a\u00f1o pasado mientras estaba a su lado. Fue evidente cuando Powell asisti\u00f3 a argumentos orales ante la Corte Suprema sobre el intento de Trump de destituir a su compa\u00f1era gobernadora de la Fed, Lisa Cook, bas\u00e1ndose en acusaciones igualmente infundadas. Y fue quiz\u00e1s m\u00e1s evidente en el <a href=\"https:\/\/www.cnn.com\/2018\/12\/20\/business\/powell-fed-trump-markets\">desafiante video <\/a>que Powell public\u00f3 poco despu\u00e9s de que se hiciera p\u00fablico su investigaci\u00f3n criminal en diciembre.<\/p>\n<p>Pero incluso a medida que su mandato como presidente llegaba a su fin y la utilidad de presionarlo se volv\u00eda menos y menos, Trump segu\u00eda presionando.<\/p>\n<p>Hasta el 15 de abril, exactamente un mes antes de que caducara la presidencia de Powell, Trump estaba amenazando con despedirlo si se quedaba en la junta de la Fed en Fox Business Network. (No est\u00e1 claro si Trump tiene este poder.)<\/p>\n<p>Durante <a href=\"https:\/\/www.cnbc.com\/video\/2026\/04\/21\/watch-cnbcs-full-interview-with-president-donald-trump.html\">una aparici\u00f3n la semana pasada en CNBC,<\/a> el presentador af\u00edn a Trump Joe Kernen asumi\u00f3 un papel que a menudo desempe\u00f1a <a href=\"https:\/\/www.washingtonpost.com\/politics\/2024\/06\/06\/trump-hannity-retribution\/\">Sean Hannity de Fox News.<\/a> Sutilmente sugiri\u00f3 que tal vez Trump deber\u00eda tomar un rumbo pol\u00edticamente m\u00e1s conveniente al dejar ir a Powell para que Warsh pudiera ser confirmado.<\/p>\n<p>En un intercambio de cinco minutos, Kernen plante\u00f3 repetidamente la idea, solo para que Trump la rechazara.<\/p>\n<p>\u201cY de alguna manera \u2014no\u201d, dijo Trump mientras hablaba por encima de Kernen. \u201cPero, Joe, de alguna manera tenemos que averiguar c\u00f3mo puede suceder esto\u201d.<\/p>\n<p>Finalmente, Kernen dijo: \u201cSolo estoy buscando una salida para ti\u201d<\/p>\n<p>Trump respondi\u00f3: \u201cBueno, s\u00ed y no, Joe. Tienes que descubrir por qu\u00e9 puede suceder algo as\u00ed\u201d. Y continu\u00f3 adelante.<\/p>\n<p>Luego de que el Departamento de Justicia pareci\u00f3 seguir el consejo de Kernen unos d\u00edas despu\u00e9s y termin\u00f3 su investigaci\u00f3n sobre Powell, Trump insisti\u00f3 en que el asunto no hab\u00eda terminado.<\/p>\n<p>Sus intentos de venganza contra sus enemigos han <a href=\"https:\/\/www.cnn.com\/2026\/04\/02\/politics\/fired-pam-bondi-trump-why\">tenido poco \u00e9xito<\/a> en su mayor\u00eda. Las acusaciones iniciales contra el exdirector del FBI James Comey y la fiscal general de Nueva York Letitia James fueron anuladas. Comey ha sido acusado de nuevo, pero por algo que pocos esperan que se <a href=\"https:\/\/www.cnn.com\/2026\/04\/29\/politics\/comey-kimmel-trump-free-speech\">sostenga en el tribunal.<\/a> El DOJ ha fallado repetidamente en volver a acusar a James. Fracas\u00f3 en acusar a seis legisladores dem\u00f3cratas por decir a los miembros del servicio que desobedecieran \u00f3rdenes ilegales. Otros esfuerzos por investigar a figuras como el senador dem\u00f3crata Adam Schiff de California no han dado frutos.<\/p>\n<p>Pero incluso si ninguno de estos intentos de venganza resulta en una condena, vale la pena simplemente hacer la vida de las personas miserable. Otros que pudieran denunciar o interponerse en tu camino ver\u00e1n eso y tal vez reconsideren sus decisiones.<\/p>\n<p>Al mismo tiempo, si los esfuerzos de Trump contin\u00faan fracasando, eso podr\u00eda perjudicarlo pol\u00edticamente, dado que las personas nunca estuvieron muy entusiasmadas con su cruzada de venganza en primer lugar.<\/p>\n<p>(Las encuestas han mostrado que los estadounidenses vieron las acusaciones iniciales contra Comey y James como <a href=\"https:\/\/www.cnn.com\/2025\/09\/27\/politics\/indictment-comey-trump-difference\">menos leg\u00edtimas <\/a>que las acusaciones contra Trump, lo cual -a pesar de las quejas de MAGA- mayor\u00edas de estadounidenses generalmente aprobaron).<\/p>\n<p>Y cuando se trata de ciertos objetivos de Trump, los esfuerzos del presidente aparentemente pueden fortalecer su determinaci\u00f3n y convertirlos en un dolor de cabeza a\u00fan mayor para \u00e9l.<\/p>\n<p>Eso parece estar ocurriendo con Powell. La presi\u00f3n de Trump no funcion\u00f3, y ahora tendr\u00e1 que lidiar con Powell incluso m\u00e1s tiempo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las preguntas m\u00e1s grandes sobre la cruzada de represalias del Presidente Donald Trump es cu\u00e1nto de esto est\u00e1 impulsado por estrategia, es decir, convirtiendo en ejemplos de precauci\u00f3n a sus enemigos, y cu\u00e1nto de esto est\u00e1 impulsado por agravio personal y rencor. El caso del Presidente de la Reserva Federal (Fed) Jerome Powell [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473686","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una de las preguntas m\u00e1s grandes sobre la cruzada de represalias del Presidente Donald Trump es cu\u00e1nto de esto est\u00e1 impulsado por estrategia, es decir, convirtiendo en ejemplos de precauci\u00f3n a sus enemigos, y cu\u00e1nto de esto est\u00e1 impulsado por agravio personal y rencor. El caso del Presidente de la Reserva Federal (Fed) Jerome Powell [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T21:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente\",\"datePublished\":\"2026-04-30T21:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/\"},\"wordCount\":1216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/\",\"name\":\"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-30T21:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente - Noticias","og_description":"Una de las preguntas m\u00e1s grandes sobre la cruzada de represalias del Presidente Donald Trump es cu\u00e1nto de esto est\u00e1 impulsado por estrategia, es decir, convirtiendo en ejemplos de precauci\u00f3n a sus enemigos, y cu\u00e1nto de esto est\u00e1 impulsado por agravio personal y rencor. El caso del Presidente de la Reserva Federal (Fed) Jerome Powell [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-30T21:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente","datePublished":"2026-04-30T21:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/"},"wordCount":1216,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/","name":"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-30T21:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo la cruzada de Trump contra Powell le result\u00f3 contraproducente","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/cruzada-trump-jerome-powell-contraproducente-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-30T21:03:41Z","datePublished":"2026-04-30T21:03:41Z","dateModified":"2026-04-30T21:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo la cruzada de Trump contra Powell le result\\u00f3 contraproducente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/30\\\/cruzada-trump-jerome-powell-contraproducente-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/30\\\/cruzada-trump-jerome-powell-contraproducente-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-30T21:03:41Z\",\"datePublished\":\"2026-04-30T21:03:41Z\",\"dateModified\":\"2026-04-30T21:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470593,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/01\/29\/independencia-reserva-federal-trump-trax\/","url_meta":{"origin":1473686,"position":0},"title":"El notable consejo de Jerome Powell a su sucesor dice mucho sobre su batalla con Trump","author":"","date":"enero 29, 2026","format":false,"excerpt":"El presidente de la Reserva Federal, Jerome Powell, se neg\u00f3 a responder tres preguntas seguidas sobre pol\u00edtica durante su conferencia de prensa del mi\u00e9rcoles. Esto es t\u00edpico de la imagen de \u201csimplemente los hechos\u201d que se ha forjado a lo largo de los a\u00f1os. Pero casi al final de su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461554,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/04\/23\/trump-ataque-jerome-powell-reserva-federal-trax\/","url_meta":{"origin":1473686,"position":1},"title":"Trump ataca nuevamente al presidente de la Reserva Federal","author":"","date":"abril 23, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, dijo este mi\u00e9rcoles que el presidente de la Reserva Federal, Jerome Powell, ha mantenido las tasas de inter\u00e9s demasiado altas, por lo que \u201cpodr\u00eda llamarlo\u201d.\u201cNo lo he llamado. Podr\u00eda llamarlo\u201d, dijo Trump en una ceremonia de firma de acci\u00f3n ejecutiva en la Oficina Oval\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470033,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/01\/13\/analisis-powell-trump-economia-estadounidense-trax\/","url_meta":{"origin":1473686,"position":2},"title":"Por qu\u00e9 Powell contraataca a Trump: porque la econom\u00eda estadounidense est\u00e1 en juego","author":"","date":"enero 13, 2026","format":false,"excerpt":"El acalorado enfrentamiento entre el presidente de la Reserva Federal, Jerome Powell, y el presidente Donald Trump ha dejado de lado la tensi\u00f3n. Por extraordinaria que sea una investigaci\u00f3n criminal contra un presidente de la Fed en funciones, la reprimenda de Powell a Trump fue, en cierto modo, a\u00fan m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473633,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/29\/jerome-powell-reserva-federal-trax\/","url_meta":{"origin":1473686,"position":3},"title":"\u00bfSeguir\u00e1 Jerome Powell en la Reserva Federal? Esto es lo que nos contaron fuentes internas","author":"","date":"abril 29, 2026","format":false,"excerpt":"El presidente de la Reserva Federal, Jerome Powell, no es ajeno a las decisiones dif\u00edciles. Sin embargo, ahora se enfrenta a una de sus disyuntivas m\u00e1s arduas y personales hasta la fecha: abandonar el escenario o permanecer en un papel secundario una vez que su sucesor asuma el tim\u00f3n del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462977,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/05\/29\/trump-reunion-powell-tasas-de-interes-trax\/","url_meta":{"origin":1473686,"position":4},"title":"Trump se reuni\u00f3 con Jerome Powell y volvi\u00f3 a criticarlo por las tasas de inter\u00e9s de la Fed","author":"","date":"mayo 29, 2025","format":false,"excerpt":"El presidente Donald Trump se reuni\u00f3 este jueves con el presidente de la Reserva Federal (Fed), Jerome Powell. Es la primera vez que Trump se re\u00fane en con Powell en lo que va de su segundo mandato, y aprovech\u00f3 la ocasi\u00f3n para reprenderlo por no reducir el costo de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461339,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/04\/18\/powell-trump-aranceles-reserva-federal-trax\/","url_meta":{"origin":1473686,"position":5},"title":"Mientras los aranceles ensombrecen el panorama econ\u00f3mico, Trump considera al presidente de la Fed como chivo expiatorio","author":"","date":"abril 18, 2025","format":false,"excerpt":"Donald Trump est\u00e1 demostrando por qu\u00e9 los bancos centrales independientes son una buena idea.La doble diatriba de Trump contra el presidente de la Reserva Federal, Jerome Powell, este jueves evoc\u00f3 otra nube oscura sobre los mercados financieros y una econom\u00eda repetidamente traumatizada por el caos de sus aranceles y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473686"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473686\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}