{"id":1473687,"date":"2026-04-30T15:03:52","date_gmt":"2026-04-30T22:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/"},"modified":"2026-04-30T15:03:52","modified_gmt":"2026-04-30T22:03:52","slug":"juicio-elon-musk-sam-altman-openai-conclusiones-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/","title":{"rendered":"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI"},"content":{"rendered":"<p>Elon Musk pas\u00f3 la mayor parte de tres d\u00edas en el estrado, acusando a OpenAI y a sus ejecutivos de enga\u00f1arlo para que donara dinero con el fin de ayudar a fundar lo que ahora es una de las mayores empresas de inteligencia artificial del mundo.<\/p>\n<p>La demanda enfrenta a Musk contra sus antiguos colaboradores convertidos en competidores, el CEO de OpenAI Sam Altman y el presidente Greg Brockman, de quienes Musk alega que se enriquecieron injustamente cuando se desviaron de la misi\u00f3n fundacional de OpenAI como organizaci\u00f3n sin fines de lucro para convertirse en una empresa con fines de lucro. Musk tambi\u00e9n nombr\u00f3 a Microsoft como codemandado en el caso, acusando a la compa\u00f1\u00eda de ayudar e instigar el incumplimiento por parte de OpenAI de un fideicomiso ben\u00e9fico.<\/p>\n<p>Las grandes personalidades y las altas apuestas del juicio quedaron plenamente en evidencia en la sala, ya que Musk choc\u00f3 regularmente con el abogado de OpenAI, acus\u00e1ndolo de intentar \u201cenga\u00f1arlo\u201d. La jueza ocasionalmente reprendi\u00f3 a las partes involucradas, llegando en un momento a decirle a Musk que realmente respondiera las preguntas que se le estaban haciendo y advirti\u00e9ndoles que dejaran de hablar sobre si la IA causar\u00e1 la extinci\u00f3n humana.<\/p>\n<p>OpenAI y Microsoft han argumentado que Musk apoyaba la creaci\u00f3n de un brazo con fines de lucro de la compa\u00f1\u00eda. Dicen que solo est\u00e1 presentando la demanda porque no pudo tomar el control total de OpenAI y ahora quiere derribar a un competidor.<\/p>\n<p>William Savitt, el abogado de OpenAI, sugiri\u00f3 que Musk renunci\u00f3 a la junta directiva de OpenAI en febrero de 2018 porque se le impidi\u00f3 tomar el control unilateral de la compa\u00f1\u00eda. Musk, sin embargo, dijo que renunci\u00f3 a la junta para centrarse en sus otras empresas, incluidas SpaceX y Tesla.<\/p>\n<p>Savitt sugiri\u00f3 que en los a\u00f1os posteriores a que Musk dej\u00f3 la junta, tom\u00f3 medidas para obstaculizar a OpenAI, especialmente despu\u00e9s de formar una empresa competidora, xAI.<\/p>\n<p>Durante el interrogatorio, Savitt pregunt\u00f3 si Musk revel\u00f3 que hab\u00eda iniciado su propia empresa de IA cuando firm\u00f3 una carta p\u00fablica en 2023 en la que abogaba por pausar el desarrollo de sistemas de IA m\u00e1s potentes que el GPT-4 de OpenAI. Savitt tambi\u00e9n mencion\u00f3 el intento que Musk lider\u00f3 el a\u00f1o pasado de comprar OpenAI con un grupo de inversores con fines de lucro, a lo que Musk respondi\u00f3: \u201cNo hay nada malo en tener una organizaci\u00f3n con fines de lucro, simplemente no puedes robar a una organizaci\u00f3n ben\u00e9fica\u201d.<\/p>\n<p>Savitt tambi\u00e9n cuestion\u00f3 a Musk sobre por qu\u00e9 no ha creado una organizaci\u00f3n sin fines de lucro de IA desde que dej\u00f3 la junta de OpenAI. Musk dijo que no cre\u00f3 una nueva porque \u00e9l hab\u00eda iniciado OpenAI.<\/p>\n<p>\u201c\u00bfPor qu\u00e9 iniciar\u00eda otra organizaci\u00f3n sin fines de lucro cuando ya inici\u00e9 una organizaci\u00f3n sin fines de lucro? Eso no tiene ning\u00fan sentido\u201d, dijo Musk.<\/p>\n<p>El debate en la sala del tribunal se extendi\u00f3 m\u00e1s all\u00e1 de la fundaci\u00f3n de OpenAI hacia los riesgos de seguridad planteados por la IA justo antes de que comenzara el interrogatorio el jueves.<\/p>\n<p>\u201cTodos podr\u00edamos morir\u201d por culpa de la IA, dijo Steven Molo, el abogado de Musk, al abogado de OpenAI y a la jueza Yvonne Gonzales Rogers antes de que el jurado y Musk se sentaran el jueves. Pero la jueza Gonzales Rogers dijo que tales declaraciones tan alarmantes no se permitir\u00edan frente al jurado, especialmente dado que Musk hab\u00eda fundado xAI, su propia empresa de IA con fines de lucro.<\/p>\n<p>\u201cSospecho que hay muchas personas que no quieren poner el futuro de la humanidad en manos del Sr. Musk, pero no importa, no vamos a entrar en esos temas\u201d, dijo Rogers, se\u00f1alando que el juicio no trata sobre si la IA ha da\u00f1ado o no a la humanidad.<\/p>\n<p>La pregunta en el centro del caso es si OpenAI y sus ejecutivos convirtieron injustamente a la compa\u00f1\u00eda en una empresa orientada al lucro, incumpliendo su misi\u00f3n original y enga\u00f1ando a Musk.<\/p>\n<p>Musk fue uno de los cofundadores de la compa\u00f1\u00eda y aport\u00f3 US$ 38 millones a OpenAI. Sin embargo, se fue en 2018 y dej\u00f3 de realizar todos los pagos para 2020.<\/p>\n<p>\u201cLes di financiamiento gratuito para crear una startup\u201d, testific\u00f3 Musk, diciendo que pensaba que estaba donando a una organizaci\u00f3n sin fines de lucro que buscaba hacer la IA \u201cpara el bien de la humanidad\u201d.<\/p>\n<p>Pero ya en 2015, antes de que OpenAI se anunciara oficialmente, Musk hab\u00eda propuesto que OpenAI incluyera una entidad con fines de lucro, seg\u00fan correos electr\u00f3nicos mostrados al jurado. En 2017, indic\u00f3 a sus asesores principales que registraran una corporaci\u00f3n con fines de lucro a nombre de OpenAI, dijo el abogado de OpenAI, se\u00f1alando notas de reuniones y los documentos de registro.<\/p>\n<p>Musk testific\u00f3 esta semana que le parec\u00eda bien que OpenAI tuviera una subsidiaria con fines de lucro siempre y cuando no \u201csuperara\u201d a la organizaci\u00f3n sin fines de lucro, lo cual, seg\u00fan argument\u00f3, es lo que finalmente ocurri\u00f3.<\/p>\n<p>El mi\u00e9rcoles, Savitt le mostr\u00f3 a Musk correos electr\u00f3nicos y mensajes de texto de 2018 en los que Altman intent\u00f3 contarle a Musk sobre los planes de OpenAI para asegurar financiamiento adicional de Microsoft. (Musk no respondi\u00f3 a todos los mensajes.)<\/p>\n<p>Un correo electr\u00f3nico de la \u00e9poca inclu\u00eda una hoja de t\u00e9rminos para una estructura corporativa propuesta que dec\u00eda expl\u00edcitamente que OpenAI pretend\u00eda recaudar US$ 10.000 millones en el futuro, pero Musk testific\u00f3 que \u201cno ley\u00f3 las letras peque\u00f1as\u201d.<\/p>\n<p>\u201cEs un documento de cuatro p\u00e1ginas\u201d, respondi\u00f3 Savitt.<\/p>\n<p>Pero Musk testific\u00f3 que su confianza en los l\u00edderes de OpenAI comenz\u00f3 a flaquear. Musk le dijo a Altman en 2022 que la valoraci\u00f3n de US$ 20.000 millones de OpenAI tras la inversi\u00f3n de US$ 10.000 millones de Microsoft se sinti\u00f3 como un \u201ccambio de reglas a mitad del juego\u201d.<\/p>\n<p>\u201cEstoy de acuerdo en que se siente mal\u201d, respondi\u00f3 Altman, antes de se\u00f1alar que Musk rechaz\u00f3 la participaci\u00f3n accionaria que OpenAI le ofreci\u00f3.<\/p>\n<p>La carrera de Musk por construir una IA mejor que la de Google fue un factor motivador en su financiamiento de OpenAI, testific\u00f3. El laboratorio DeepMind de Google, por ejemplo, ha producido investigaciones significativas durante a\u00f1os.<\/p>\n<p>\u201cDeepMind se est\u00e1 moviendo muy r\u00e1pido. Me preocupa que OpenAI no se est\u00e9 moviendo lo suficientemente r\u00e1pido para alcanzarlo. Haberlo configurado como una organizaci\u00f3n sin fines de lucro podr\u00eda, en retrospectiva, haber sido un movimiento equivocado\u201d, dijo Musk en un correo electr\u00f3nico de 2016 a uno de sus colegas en Neuralink, otra de las empresas de Musk.<\/p>\n<p>Musk testific\u00f3 el martes que le preocupaba que el enfoque de Google hacia la IA no fuera lo suficientemente seguro. Se necesitaba \u201calg\u00fan tipo de contrapeso\u201d a Google, \u201cuna organizaci\u00f3n sin fines de lucro de c\u00f3digo abierto en lugar de una con fines de lucro de c\u00f3digo cerrado\u201d, dijo Musk.<\/p>\n<p>El abogado de OpenAI, Savitt, interrog\u00f3 a Musk durante dos d\u00edas, el mi\u00e9rcoles y el jueves. En ocasiones, sus intercambios se volvieron tensos.<\/p>\n<p>Savitt le pidi\u00f3 a Musk que se limitara a respuestas de \u201cs\u00ed\u201d o \u201cno\u201d, y en un momento Musk pregunt\u00f3 si Savitt dejar\u00eda de interrumpirlo.<\/p>\n<p>\u201cSus preguntas no son simples. Est\u00e1n dise\u00f1adas para enga\u00f1arme\u201d, le dijo Musk a Savitt temprano el mi\u00e9rcoles, antes de comparar la pregunta con la falacia cl\u00e1sica de \u201c\u00bfhas dejado de golpear a tu esposa?\u201d. La jueza interrumpi\u00f3 a Musk, dici\u00e9ndole que no iban a \u201centrar en eso\u201d.<\/p>\n<p>Despu\u00e9s de que el jurado y Musk abandonaran la sala del tribunal por el d\u00eda el mi\u00e9rcoles, la jueza Gonzales Rogers concedi\u00f3 a los abogados de OpenAI que Musk \u201cfue, en ocasiones, dif\u00edcil\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elon Musk pas\u00f3 la mayor parte de tres d\u00edas en el estrado, acusando a OpenAI y a sus ejecutivos de enga\u00f1arlo para que donara dinero con el fin de ayudar a fundar lo que ahora es una de las mayores empresas de inteligencia artificial del mundo. La demanda enfrenta a Musk contra sus antiguos colaboradores [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473687","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI - Noticias\" \/>\n<meta property=\"og:description\" content=\"Elon Musk pas\u00f3 la mayor parte de tres d\u00edas en el estrado, acusando a OpenAI y a sus ejecutivos de enga\u00f1arlo para que donara dinero con el fin de ayudar a fundar lo que ahora es una de las mayores empresas de inteligencia artificial del mundo. La demanda enfrenta a Musk contra sus antiguos colaboradores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T22:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI\",\"datePublished\":\"2026-04-30T22:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/\"},\"wordCount\":1360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/\",\"name\":\"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-30T22:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI - Noticias","og_description":"Elon Musk pas\u00f3 la mayor parte de tres d\u00edas en el estrado, acusando a OpenAI y a sus ejecutivos de enga\u00f1arlo para que donara dinero con el fin de ayudar a fundar lo que ahora es una de las mayores empresas de inteligencia artificial del mundo. La demanda enfrenta a Musk contra sus antiguos colaboradores [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-30T22:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/"},"author":{"name":"","@id":""},"headline":"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI","datePublished":"2026-04-30T22:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/"},"wordCount":1360,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/","name":"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-30T22:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-30T22:03:52Z","datePublished":"2026-04-30T22:03:52Z","dateModified":"2026-04-30T22:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Conclusiones de la primera semana del enfrentamiento judicial de Elon Musk y Sam Altman por OpenAI\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/30\\\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/04\\\/30\\\/juicio-elon-musk-sam-altman-openai-conclusiones-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-30T22:03:52Z\",\"datePublished\":\"2026-04-30T22:03:52Z\",\"dateModified\":\"2026-04-30T22:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458569,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/11\/altman-ataca-musk-compra-openai-trax\/","url_meta":{"origin":1473687,"position":0},"title":"Sam Altman contraataca a Elon Musk: &#171;No creo que sea una persona feliz. Lo siento por \u00e9l&#187;","author":"","date":"febrero 11, 2025","format":false,"excerpt":"La batalla por el futuro de la IA se ha vuelto extremadamente costosa y muy personal.El CEO de OpenAI, Sam Altman, se pronunci\u00f3 en contra de su rival Elon Musk un d\u00eda despu\u00e9s de rechazar un acuerdo potencialmente trascendental que podr\u00eda dar forma al futuro de la inteligencia artificial. Le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473531,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/27\/elon-musk-y-sam-altman-enfrentamiento-juicio-openai-trax\/","url_meta":{"origin":1473687,"position":1},"title":"Elon Musk y Sam Altman est\u00e1n a punto de enfrentarse en los tribunales. \u00bfEs siquiera posible un jurado imparcial?","author":"","date":"abril 27, 2026","format":false,"excerpt":"Un grupo de personas comunes y corrientes, que tal vez ni siquiera sepan mucho sobre inteligencia artificial, podr\u00eda determinar pronto el futuro de OpenAI.La demanda de Elon Musk contra el creador de ChatGPT, OpenAI, y sus directivos \u2014incluido su CEO, Sam Altman\u2014 llegar\u00e1 a los tribunales este lunes. Se espera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458690,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/13\/elon-musk-retirara-oferta-us-100-000-millones-openai-sin-animo-lucro-trax\/","url_meta":{"origin":1473687,"position":2},"title":"Elon Musk retirar\u00e1 su oferta de casi US$ 100.000 millones por OpenAI si se mantiene como una organizaci\u00f3n sin fines de lucro","author":"","date":"febrero 13, 2025","format":false,"excerpt":"Elon Musk dice que est\u00e1 dispuesto a abandonar su intento de comprar OpenAI si el creador de ChatGPT mantiene su inusual estructura actual, en la que la empresa de inteligencia artificial (IA) m\u00e1s importante y valiosa del mundo est\u00e1 gestionada por una organizaci\u00f3n sin fines de lucro.La batalla por OpenAI\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458761,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/14\/openai-rechaza-oferta-compra-elon-musk-trax\/","url_meta":{"origin":1473687,"position":3},"title":"La junta de OpenAI rechaza la oferta de compra de US $97.400 millones liderada por Elon Musk","author":"","date":"febrero 14, 2025","format":false,"excerpt":"La junta directiva de OpenAI ha rechazado formalmente una oferta de US$ 97.400 millones por parte de Elon Musk y otros inversores para comprar la empresa.\u201cOpenAI no est\u00e1 en venta, y la junta ha rechazado un\u00e1nimemente el \u00faltimo intento del Sr. Musk de interrumpir a su competencia\u201d, dijo el presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473569,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/28\/elon-musk-caso-rumbo-ia-trax\/","url_meta":{"origin":1473687,"position":4},"title":"Elon Musk testificar\u00e1 en un caso que podr\u00eda cambiar el futuro de la IA","author":"","date":"abril 28, 2026","format":false,"excerpt":"Este lunes, Elon Musk public\u00f3 en su plataforma de redes sociales X informaci\u00f3n sobre su demanda contra OpenAI, su CEO, Sam Altman, y su presidente Greg Brockman. Musk alega que el creador de ChatGPT lo enga\u00f1\u00f3 y traicion\u00f3 su misi\u00f3n original.\u201cScam Altman y Greg Stockman robaron una organizaci\u00f3n ben\u00e9fica. Punto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458539,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/02\/10\/elon-musk-oferta-comprar-matriz-chatgpt-us-millones-trax\/","url_meta":{"origin":1473687,"position":5},"title":"Elon Musk lidera una oferta para comprar la matriz de ChatGPT por casi US$ 100.000 millones","author":"","date":"febrero 10, 2025","format":false,"excerpt":"En una oferta de alto riesgo que podr\u00eda remodelar el futuro de la inteligencia artificial, Elon Musk lidera un grupo de inversores que ofrecieron comprar OpenAI, la empresa matriz de ChatGPT, por US$ 97.400 millones.Musk est\u00e1 enemistado desde hace tiempo con Sam Altman, CEO de OpenAI, y ha presentado varias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473687"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473687\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}