{"id":1473721,"date":"2026-05-01T18:03:38","date_gmt":"2026-05-02T01:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/"},"modified":"2026-05-01T18:03:38","modified_gmt":"2026-05-02T01:03:38","slug":"eeuu-retirara-5000-soldados-alemania-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","title":{"rendered":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n"},"content":{"rendered":"<p>El Pent\u00e1gono dijo este viernes que EE.UU. retirar\u00e1 aproximadamente 5.000 soldados de Alemania durante el pr\u00f3ximo a\u00f1o.<\/p>\n<p>La medida, que se produce despu\u00e9s de que el presidente Donald Trump arremetiera contra el canciller alem\u00e1n por sus cr\u00edticas a la guerra de EE.UU. con Ir\u00e1n, a\u00fan dejar\u00eda a m\u00e1s de 30.000 efectivos estadounidenses en el pa\u00eds.<\/p>\n<p>\u201cEl secretario de Guerra ha ordenado la retirada de aproximadamente 5.000 tropas de Alemania\u201d, dijo en un comunicado el portavoz principal del Pent\u00e1gono, Sean Parnell. \u201cEsta decisi\u00f3n sigue a una revisi\u00f3n exhaustiva de la postura de fuerzas del Departamento en Europa y reconoce los requisitos del teatro de operaciones y las condiciones sobre el terreno. Esperamos que la retirada se complete en los pr\u00f3ximos seis a doce meses\u201d.<\/p>\n<p>Trump anticip\u00f3 los recortes a principios de esta semana despu\u00e9s de que el canciller alem\u00e1n, Friedrich Merz, dijera que EE.UU. estaba siendo \u201chumillado\u201d por Ir\u00e1n.<\/p>\n<p>Durante su visita a una escuela en el centro de Alemania el lunes, Merz acus\u00f3 a funcionarios estadounidenses de entrar en una guerra sin una estrategia clara, diciendo que \u201ctodo el asunto es, como m\u00ednimo, mal concebido\u201d.<\/p>\n<p>\u201cLos iran\u00edes son obviamente muy h\u00e1biles negociando, o m\u00e1s bien, muy h\u00e1biles en no negociar, dejando que los estadounidenses viajen a Islamabad y luego se marchen de nuevo sin ning\u00fan resultado\u201d, dijo Merz. \u201cUna naci\u00f3n entera est\u00e1 siendo humillada por el liderazgo iran\u00ed, especialmente por estos llamados Guardianes Revolucionarios. Y por eso espero que esto termine lo antes posible\u201d.<\/p>\n<p>Trump dijo el martes que Merz \u201cno sabe de lo que est\u00e1 hablando\u201d sobre Ir\u00e1n y al d\u00eda siguiente anunci\u00f3 que EE.UU. estaba \u201cestudiando y revisando\u201d una posible reducci\u00f3n de tropas.<\/p>\n<p>Antes de la amenaza de Trump de retirar algunos soldados de Alemania, Merz hab\u00eda dicho que su relaci\u00f3n con el presidente de EE.UU. segu\u00eda siendo \u201cbuena\u201d.<\/p>\n<p>Trump ya hab\u00eda amenazado con reducir el n\u00famero de efectivos en el pa\u00eds en 2020, durante su primer mandato en el cargo y mientras Angela Merkel ocupaba la canciller\u00eda alemana.<\/p>\n<p>Alemania alberga la Base A\u00e9rea de Ramstein, que es el cuartel general de las Fuerzas A\u00e9reas de EE.UU. en Europa \u2014incluida la unidad que realiza \u201coperaciones de transporte a\u00e9reo, lanzamiento a\u00e9reo y evacuaci\u00f3n aerom\u00e9dica\u201d\u2014 y una instalaci\u00f3n de la Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte, seg\u00fan su sitio web.<\/p>\n<p>A diciembre de 2025, hab\u00eda 36.436 efectivos militares estadounidenses en servicio activo estacionados permanentemente en Alemania, seg\u00fan datos del Centro de Datos de Personal de Defensa de EE.UU.<\/p>\n<p>La fricci\u00f3n entre los l\u00edderes europeos y el Gobierno de Trump se ha intensificado debido a la guerra con Ir\u00e1n, que EE.UU. inici\u00f3 sin notificar a la mayor\u00eda de los aliados de la OTAN. El presidente tambi\u00e9n ha arremetido contra los aliados por lo que considera una ayuda insuficiente en el conflicto, amenazando tambi\u00e9n el jueves con recortar los niveles de efectivos en Italia y Espa\u00f1a.<\/p>\n<p>\u201cQuiero decir, no han estado exactamente de acuerdo\u201d, respondi\u00f3, cuando se le pregunt\u00f3 sobre la posibilidad. \u201cS\u00ed, probablemente lo har\u00e9\u201d, a\u00f1adi\u00f3, \u201c\u00bfPor qu\u00e9 no habr\u00eda de hacerlo? Italia no ha sido de ninguna ayuda. Espa\u00f1a ha sido horrible. Absolutamente.\u201d<\/p>\n<p>Alemania, al igual que algunos otros pa\u00edses europeos, ha ofrecido un apoyo militar limitado a EE.UU., de forma m\u00e1s notable permitiendo el uso de su infraestructura militar, como bases a\u00e9reas, para operaciones relacionadas con el conflicto, aunque no ha permitido que estas se utilicen como plataformas de lanzamiento para ataques ofensivos directos.<\/p>\n<p>Merz tambi\u00e9n ha prometido m\u00e1s ayuda alemana con la condici\u00f3n de que el conflicto pase a una fase de posguerra, lo que podr\u00eda incluir participar en una posible misi\u00f3n internacional de estabilizaci\u00f3n.<\/p>\n<p>En ese sentido, Berl\u00edn anunci\u00f3 recientemente que se desplegar\u00e1 un dragaminas naval en el mar Mediterr\u00e1neo en preparaci\u00f3n para los esfuerzos de reabrir el estrecho de Ormuz, una vez que se alcance un fin duradero de las hostilidades. Sin embargo, estas acciones no han logrado satisfacer a Trump.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Pent\u00e1gono dijo este viernes que EE.UU. retirar\u00e1 aproximadamente 5.000 soldados de Alemania durante el pr\u00f3ximo a\u00f1o. La medida, que se produce despu\u00e9s de que el presidente Donald Trump arremetiera contra el canciller alem\u00e1n por sus cr\u00edticas a la guerra de EE.UU. con Ir\u00e1n, a\u00fan dejar\u00eda a m\u00e1s de 30.000 efectivos estadounidenses en el pa\u00eds. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473721","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Pent\u00e1gono dijo este viernes que EE.UU. retirar\u00e1 aproximadamente 5.000 soldados de Alemania durante el pr\u00f3ximo a\u00f1o. La medida, que se produce despu\u00e9s de que el presidente Donald Trump arremetiera contra el canciller alem\u00e1n por sus cr\u00edticas a la guerra de EE.UU. con Ir\u00e1n, a\u00fan dejar\u00eda a m\u00e1s de 30.000 efectivos estadounidenses en el pa\u00eds. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-02T01:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n\",\"datePublished\":\"2026-05-02T01:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/\",\"name\":\"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-02T01:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n - Noticias","og_description":"El Pent\u00e1gono dijo este viernes que EE.UU. retirar\u00e1 aproximadamente 5.000 soldados de Alemania durante el pr\u00f3ximo a\u00f1o. La medida, que se produce despu\u00e9s de que el presidente Donald Trump arremetiera contra el canciller alem\u00e1n por sus cr\u00edticas a la guerra de EE.UU. con Ir\u00e1n, a\u00fan dejar\u00eda a m\u00e1s de 30.000 efectivos estadounidenses en el pa\u00eds. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-02T01:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n","datePublished":"2026-05-02T01:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","name":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-02T01:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. retirar\u00e1 5.000 soldados de Alemania despu\u00e9s de que el canciller criticara la guerra con Ir\u00e1n","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/01\/eeuu-retirara-5000-soldados-alemania-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-02T01:03:38Z","datePublished":"2026-05-02T01:03:38Z","dateModified":"2026-05-02T01:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. retirar\\u00e1 5.000 soldados de Alemania despu\\u00e9s de que el canciller criticara la guerra con Ir\\u00e1n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/01\\\/eeuu-retirara-5000-soldados-alemania-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/01\\\/eeuu-retirara-5000-soldados-alemania-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-02T01:03:38Z\",\"datePublished\":\"2026-05-02T01:03:38Z\",\"dateModified\":\"2026-05-02T01:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473756,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/trump-soldados-alemania-europa-crisis-trax\/","url_meta":{"origin":1473721,"position":0},"title":"La p\u00e9rdida de 5.000 soldados estadounidenses en Alemania es solo la punta del iceberg del desaf\u00edo al que se enfrenta Europa","author":"","date":"mayo 3, 2026","format":false,"excerpt":"Pr\u00e1cticamente no pasa una semana sin que surja alguna nueva disputa entre la administraci\u00f3n de Trump y Europa.Pero en un a\u00f1o marcado por una importante disputa sobre aranceles, la amenaza del presidente de Estados Unidos, Donald Trump, de anexionarse Groenlandia y desacuerdos sobre la ayuda a Ucrania, la amenaza m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467847,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/10\/29\/retiran-soldados-rumania-defensa-america-latina-trax\/","url_meta":{"origin":1473721,"position":1},"title":"EE.UU. retirar\u00e1 algunos soldados de Europa del Este y le apuesta a un enfoque hacia Am\u00e9rica Latina","author":"","date":"octubre 29, 2025","format":false,"excerpt":"EE.UU. retirar\u00e1 algunos soldados de Rumania, en el flanco oriental de la OTAN, mientras el Pent\u00e1gono trabaja para cambiar su enfoque de Europa hacia la defensa nacional y Am\u00e9rica Latina, dijeron el mi\u00e9rcoles funcionarios estadounidenses y europeos.Estados Unidos enviar\u00e1 de regreso a Kentucky al 2\u00ba Equipo de Combate de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473682,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/30\/trump-amenaza-retirar-soldados-alemania-trax\/","url_meta":{"origin":1473721,"position":2},"title":"Trump amenaza con retirar soldados estadounidenses de Alemania en medio de una disputa por la guerra con Ir\u00e1n","author":"","date":"abril 30, 2026","format":false,"excerpt":"Una disputa entre Estados Unidos y Alemania ha alcanzado nuevos niveles, con el presidente de EE.UU., Donald Trump, amenazando con retirar algunos soldados estadounidenses del pa\u00eds en medio de desacuerdos sobre la campa\u00f1a liderada por Estados Unidos en Ir\u00e1n.\u201cEstados Unidos est\u00e1 estudiando y revisando la posible reducci\u00f3n de efectivos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473769,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/04\/5-cosas-4-mayo-2026-orix\/","url_meta":{"origin":1473721,"position":3},"title":"Las 5 cosas que debes saber este 4 de mayo: estrecho de Ormuz, la CIA en M\u00e9xico, cierre de Spirit Airlines y m\u00e1s","author":"","date":"mayo 4, 2026","format":false,"excerpt":"La controversia por la presencia de la CIA en M\u00e9xico. Investigan brote de hantavirus en un crucero. El Kremlin refuerza la seguridad en torno a Putin ante temores de asesinatos. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471881,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/04\/porque-congreso-no-declara-guerra-iran-trax\/","url_meta":{"origin":1473721,"position":4},"title":"\u00bfPor qu\u00e9 el Congreso de EE.UU. no declara la guerra a Ir\u00e1n?","author":"","date":"marzo 4, 2026","format":false,"excerpt":"Desde luego que se trata de una \u201cguerra\u201d cuando dos pa\u00edses atacan a un tercero, matan a su l\u00edder y tratan de destruir su ej\u00e9rcito, como han hecho Estados Unidos e Israel con Ir\u00e1n.Pero, en la extra\u00f1a manera en que los l\u00edderes estadounidenses modernos danzan alrededor de la Constituci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473386,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/21\/reserva-misiles-guerra-iran-trax\/","url_meta":{"origin":1473721,"position":5},"title":"EE.UU. agota su reserva de misiles clave en Ir\u00e1n y corre el riesgo de quedarse sin provisiones si estalla otra guerra","author":"","date":"abril 21, 2026","format":false,"excerpt":"Las Fuerzas Armadas de EE.UU. han agotado de forma significativa sus reservas de misiles clave durante la guerra con Ir\u00e1n y han creado un \u201criesgo a corto plazo\u201d de quedarse sin provisiones si surgiera otro conflicto en los pr\u00f3ximos a\u00f1os, seg\u00fan expertos y tres personas familiarizadas con evaluaciones internas recientes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473721"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473721\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}