{"id":1473750,"date":"2026-05-03T05:03:49","date_gmt":"2026-05-03T12:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/"},"modified":"2026-05-03T05:03:49","modified_gmt":"2026-05-03T12:03:49","slug":"agentes-muertos-renuncia-tensiones-controversia-cia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/","title":{"rendered":"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico"},"content":{"rendered":"<p>Hace dos semanas, un operativo de seguridad para desmantelar laboratorios clandestinos para fabricar drogas sint\u00e9ticas en el estado de Chihuahua, ubicado en el norte de M\u00e9xico y fronterizo con Estados Unidos, deriv\u00f3 en una controversia que hasta ahora a\u00fan no tiene un final a la vista.<\/p>\n<p>La revelaci\u00f3n de que dos agentes de la Agencia Central de Inteligencia de Estados Unidos (CIA, por sus siglas en ingl\u00e9s) estuvieron en esa operaci\u00f3n, y despu\u00e9s murieron en un accidente automovil\u00edstico, ha hecho que el Gobierno de M\u00e9xico pida explicaciones tanto al Gobierno de Chihuahua como al de Estados Unidos, al tiempo que el fiscal de Chihuahua renunci\u00f3 al cargo y muchos especialistas se preguntan de qu\u00e9 tama\u00f1o es la presencia de agencias extranjeras en territorio mexicano.<\/p>\n<p>As\u00ed es como llegamos hasta aqu\u00ed.<\/p>\n<p>Entre el viernes 17 y el domingo 19 de abril, elementos de la Fiscal\u00eda de Chihuahua e integrantes del Ej\u00e9rcito participaron en un operativo para desmantelar laboratorios clandestinos para fabricar drogas en el municipio de Morelos, ubicado en la zona serrana del estado.<\/p>\n<p>La noche del 19 de abril, el entonces fiscal de Chihuahua, C\u00e9sar J\u00e1uregui, inform\u00f3 en una rueda de prensa que, durante la madrugada de ese d\u00eda, cuando el convoy viajaba de regreso a Chihuahua capital, un veh\u00edculo se volc\u00f3.<\/p>\n<p>En ese accidente, dijo, murieron el director de la Agencia Estatal de Investigaci\u00f3n (AEI), Pedro Rom\u00e1n Oseguera Cervantes, su escolta Manuel Genaro M\u00e9ndez Montes <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/19\/mexico\/mueren-instructores-embajada-eeuu-agentes-mexicanos-accidente-operativo-antidrogas-chihuahua-orix\" rel=\"noopener noreferrer\" target=\"_blank\">y dos funcionarios estadounidenses<\/a>, a quienes identific\u00f3 como instructores de la Embajada de Estados Unidos.<\/p>\n<p>El embajador de Estados Unidos, Ronald Johnson, lament\u00f3 lo sucedido. \u201cEsta tragedia es un solemne recordatorio de los riesgos que enfrentan los funcionarios mexicanos y estadounidenses dedicados a proteger a nuestras comunidades, y fortalece nuestra determinaci\u00f3n de continuar su misi\u00f3n y avanzar en nuestro compromiso compartido con la seguridad y la justicia, para proteger a nuestra gente\u201d, <a href=\"https:\/\/x.com\/USAmbMex\/status\/2045966644187722038\">public\u00f3 en X<\/a>.<\/p>\n<p>El lunes 20 de abril, en su conferencia de prensa ma\u00f1anera, la presidenta de M\u00e9xico, Claudia Sheinbaum, lament\u00f3 la muerte de los estadounidenses, pero tambi\u00e9n <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/20\/mexico\/sheinbaum-operativo-chihuahua-muerte-agentes-eeuu-orix\">asegur\u00f3 que su Gobierno no estaba enterado<\/a> sobre su presencia en Chihuahua.<\/p>\n<p>Por esta raz\u00f3n, dijo, pidi\u00f3 informaci\u00f3n tanto al Gobierno de Chihuahua como al de Estados Unidos, con el prop\u00f3sito de aclarar si hubo una posible violaci\u00f3n a la Constituci\u00f3n de M\u00e9xico y a Ley de Seguridad Nacional, que establecen l\u00edmites a la cooperaci\u00f3n que autoridades mexicanas pueden tener con agencias extranjeras.<\/p>\n<p>Entre otros puntos, esta legislaci\u00f3n se\u00f1ala que los agentes extranjeros deben recibir una acreditaci\u00f3n del Gobierno federal para permanecer en el pa\u00eds de forma temporal, deben enfocarse en labores de intercambio de informaci\u00f3n y deben reportar mensualmente las gestiones que realicen. En tanto, la Constituci\u00f3n establece que M\u00e9xico no permitir\u00e1 que instituciones extranjeras realicen \u201cinvestigaci\u00f3n y persecuci\u00f3n\u201d de delitos sin que haya \u201cautorizaci\u00f3n y colaboraci\u00f3n expresa\u201d.<\/p>\n<p>El martes 21 de abril, CNN y otros medios reportaron que los dos estadounidenses que murieron en Chihuahua <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/eeuu\/estadounidenses-muertos-chihuahua-mexico-cia-orix\">eran agentes de la CIA<\/a>. Fuentes con conocimiento del caso dijeron a CNN que se trataba de personas que trabajaban con autoridades mexicanas en la ampliaci\u00f3n de operaciones antidrogas en M\u00e9xico.<\/p>\n<p>La revelaci\u00f3n gener\u00f3 numerosas reacciones en M\u00e9xico, incluyendo cuestionamientos a la gobernadora de Chihuahua, Mar\u00eda Eugenia Campos, quien milita en el opositor Partido Acci\u00f3n Nacional (PAN).<\/p>\n<p>Al d\u00eda siguiente, la Comisi\u00f3n de Puntos Constitucionales del Senado, una c\u00e1mara donde el oficialista partido Morena es mayor\u00eda, <a href=\"https:\/\/comunicacionsocial.senado.gob.mx\/informacion\/comunicados\/15121-aprueba-comision-acuerdo-para-invitar-a-reunion-de-trabajo-a-la-gobernadora-de-chihuahua-maria-eugenia-campos\">acord\u00f3 invitar a Campos y al fiscal J\u00e1uregui<\/a> a una reuni\u00f3n para dar informaci\u00f3n sobre el caso.<\/p>\n<p>El jueves 23 de abril, mientras la presidenta continuaba con su llamado a investigar y esclarecer los hechos, Campos se reuni\u00f3 en privado con el secretario de Seguridad federal, Omar Garc\u00eda Harfuch, seg\u00fan reportaron medios locales. Autoridades en ese momento no dieron m\u00e1s informaci\u00f3n sobre el encuentro.<\/p>\n<p>Al d\u00eda siguiente, Campos public\u00f3 una foto suya junto con Garc\u00eda Harfuch y dijo <a href=\"https:\/\/chihuahua.gob.mx\/prensa\/reconocemos-y-acompanamos-el-llamado-de-la-presidenta-claudia-sheinbaum-para-trabajar-juntos\">en un comunicado<\/a> que coincide con Sheinbaum en que \u201clos gobiernos, independientemente de su filiaci\u00f3n partidista, deben trabajar juntos por la seguridad de las familias mexicanas y la integridad soberana de nuestro pa\u00eds, en el marco de nuestras leyes y en un ambiente de confianza y coordinaci\u00f3n institucional\u201d.<\/p>\n<p>Por la noche, adem\u00e1s, Campos anunci\u00f3 <a href=\"https:\/\/x.com\/MaruCampos_G\/status\/2047860801021612532\">la creaci\u00f3n de una unidad especial de la Fiscal\u00eda de Chihuahua<\/a> para investigar c\u00f3mo se dio la presencia de los agentes de la CIA en el estado. Al frente de este organismo nombr\u00f3 a la fiscal Wendy Ch\u00e1vez.<\/p>\n<p>El s\u00e1bado 25 de abril, el gabinete de seguridad del Gobierno federal <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/25\/mexico\/agentes-eeuu-chihuahua-visitante-diplomatico-orix\">inform\u00f3 que<\/a>, seg\u00fan los registros migratorios, uno de los agentes estadounidenses fallecidos entr\u00f3 a M\u00e9xico como visitante sin permiso para realizar actividades remuneradas, mientras que el otro lo hizo con un pasaporte diplom\u00e1tico. El gabinete enfatiz\u00f3 que ninguno estaba acreditado para participar en tareas operativas en territorio mexicano.<\/p>\n<p>\u201cLa legislaci\u00f3n mexicana es clara: no permite la participaci\u00f3n de agentes extranjeros en operaciones dentro del territorio nacional. La cooperaci\u00f3n internacional en materia de seguridad se desarrolla mediante mecanismos de intercambio de informaci\u00f3n, coordinaci\u00f3n institucional y colaboraci\u00f3n t\u00e9cnica, siempre con respeto absoluto a la soberan\u00eda nacional, la reciprocidad, la confianza mutua y sin subordinaci\u00f3n\u201d, dijo entonces.<\/p>\n<p>El lunes 27 de abril, en medio de la controversia por el caso, J\u00e1uregui <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/27\/mexico\/renuncia-fiscal-chihuahua-jauregui-orix\">renunci\u00f3 a su cargo como fiscal de Chihuahua<\/a>. Reconoci\u00f3 que hubo \u201comisiones\u201d en la informaci\u00f3n sobre c\u00f3mo se gestion\u00f3 el contacto con los agentes estadounidenses y dijo que asum\u00eda esa \u201cresponsabilidad pol\u00edtica\u201d.<\/p>\n<p>A la par, la unidad especial de la Fiscal\u00eda de Chihuahua <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/28\/mexico\/chihuahua-agentes-cia-informe-oficial-orix\">dio su primer informe<\/a> sobre lo ocurrido.<\/p>\n<p>En un mensaje a los medios, la fiscal Ch\u00e1vez se\u00f1al\u00f3 que, seg\u00fan las primeras indagatorias, cuatro personas ajenas a la Fiscal\u00eda se sumaron al convoy que viaj\u00f3 al municipio de Morelos para el operativo contra los laboratorios clandestinos. Dos de ellas eran los agentes de la CIA que murieron. No dio detalles sobre los otros dos, pero la Fiscal\u00eda dijo despu\u00e9s a CNN que presumiblemente tambi\u00e9n eran ciudadanos estadounidenses.<\/p>\n<p>Ch\u00e1vez tambi\u00e9n inform\u00f3 que estos hombres iban vestidos de civil, no tra\u00edan placas de alguna instituci\u00f3n de seguridad ni armas y llevaron el rostro cubierto la mayor parte del tiempo. Agreg\u00f3 que, de acuerdo con testimonios recabados, no participaron en reuniones con mandos militares, su trato directo era con el fallecido director de Investigaci\u00f3n y posiblemente ten\u00edan una colaboraci\u00f3n \u201cde car\u00e1cter extraoficial\u201d.<\/p>\n<p>El martes 28 de abril, la presidenta Sheinbaum dijo en su conferencia matutina que envi\u00f3 una nota diplom\u00e1tica a la Embajada de Estados Unidos \u201cpidiendo explicaci\u00f3n sobre este caso y diciendo que el Gobierno federal no estaba informado, y tambi\u00e9n diciendo que esto no puede ocurrir\u201d.<\/p>\n<p>A la par, la gobernadora Campos declin\u00f3 acudir a la reuni\u00f3n a la que la hab\u00eda invitado el Senado y a la que legalmente no estaba obligada a presentarse.<\/p>\n<p>Mediante <a href=\"https:\/\/chihuahua.gob.mx\/prensa\/maru-campos-declina-participar-en-reunion-de-trabajo-en-el-senado-para-no-comprometer\">un comunicado<\/a>, el Gobierno de Chihuahua dijo que la decisi\u00f3n \u201cresponde a la necesidad de salvaguardar el adecuado desarrollo de las investigaciones que se llevan a cabo, evitando comprometer informaci\u00f3n de car\u00e1cter confidencial, o clasificada, as\u00ed como garantizar la debida conducci\u00f3n institucional de la informaci\u00f3n y el respeto a la seguridad nacional\u201d.<\/p>\n<p>Horas m\u00e1s tarde, la Fiscal\u00eda General de la Rep\u00fablica (FGR) inform\u00f3 que <a href=\"https:\/\/www.fgr.org.mx\/en\/FGR\/Nacional\/_rid\/61\/_mod\/story?p=1&#038;ord=desc&#038;f=0&#038;categoria=Nacional&#038;suri=http%3A%2F%2Fwww.FGR.swb%23fgr_Boletin%3A25497\">abri\u00f3 dos investigaciones por este caso<\/a>: una por el hallazgo de los laboratorios clandestinos y otra por la presencia de los agentes de la CIA.<\/p>\n<p>\u201cEsta instituci\u00f3n establece que, a partir de lo ocurrido, se investiga la comisi\u00f3n de posibles delitos de competencia de la FGR, con el fin de esclarecer los hechos y, en su caso, deslindar responsabilidades de cualquier persona que haya participado. Los avances y resultados de las indagatorias se comunicar\u00e1n de manera transparente y oportuna, observando las implicaciones del debido proceso\u201d, dijo en un comunicado.<\/p>\n<p>A dos semanas de que la controversia comenzara, a\u00fan hay que esperar respuestas sobre lo ocurrido.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace dos semanas, un operativo de seguridad para desmantelar laboratorios clandestinos para fabricar drogas sint\u00e9ticas en el estado de Chihuahua, ubicado en el norte de M\u00e9xico y fronterizo con Estados Unidos, deriv\u00f3 en una controversia que hasta ahora a\u00fan no tiene un final a la vista. La revelaci\u00f3n de que dos agentes de la Agencia [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473750","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hace dos semanas, un operativo de seguridad para desmantelar laboratorios clandestinos para fabricar drogas sint\u00e9ticas en el estado de Chihuahua, ubicado en el norte de M\u00e9xico y fronterizo con Estados Unidos, deriv\u00f3 en una controversia que hasta ahora a\u00fan no tiene un final a la vista. La revelaci\u00f3n de que dos agentes de la Agencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-03T12:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico\",\"datePublished\":\"2026-05-03T12:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/\"},\"wordCount\":1435,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/\",\"name\":\"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-03T12:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico - Noticias","og_description":"Hace dos semanas, un operativo de seguridad para desmantelar laboratorios clandestinos para fabricar drogas sint\u00e9ticas en el estado de Chihuahua, ubicado en el norte de M\u00e9xico y fronterizo con Estados Unidos, deriv\u00f3 en una controversia que hasta ahora a\u00fan no tiene un final a la vista. La revelaci\u00f3n de que dos agentes de la Agencia [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/","og_site_name":"Noticias","article_published_time":"2026-05-03T12:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/"},"author":{"name":"","@id":""},"headline":"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico","datePublished":"2026-05-03T12:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/"},"wordCount":1435,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/","url":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/","name":"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-03T12:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\u00ed ha sido la controversia por presencia de la CIA en M\u00e9xico","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-03T12:03:49Z","datePublished":"2026-05-03T12:03:49Z","dateModified":"2026-05-03T12:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Dos agentes muertos, una renuncia y tensiones entre gobiernos: as\\u00ed ha sido la controversia por presencia de la CIA en M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/03\\\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/03\\\/agentes-muertos-renuncia-tensiones-controversia-cia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-03T12:03:49Z\",\"datePublished\":\"2026-05-03T12:03:49Z\",\"dateModified\":\"2026-05-03T12:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473614,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/28\/chihuahua-agentes-cia-informe-oficial-orix\/","url_meta":{"origin":1473750,"position":0},"title":"\u00bfQu\u00e9 hac\u00edan en Chihuahua los agentes de la CIA que murieron en un accidente? Esto dice el primer informe oficial","author":"","date":"abril 28, 2026","format":false,"excerpt":"La Fiscal\u00eda de Chihuahua, en el norte de M\u00e9xico, present\u00f3 este lunes un primer informe sobre las investigaciones realizadas luego de la controversia que ha generado la presencia en el estado de dos agentes de la Agencia Central de Inteligencia de Estados Unidos (CIA, por sus siglas en ingl\u00e9s) que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473367,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/21\/estadounidenses-muertos-chihuahua-mexico-cia-orix\/","url_meta":{"origin":1473750,"position":1},"title":"Estadounidenses muertos en accidente automovil\u00edstico en M\u00e9xico tras redada antidrogas trabajaban para la CIA, seg\u00fan fuentes","author":"","date":"abril 21, 2026","format":false,"excerpt":"Dos funcionarios de la embajada estadounidense que murieron en un accidente automovil\u00edstico en M\u00e9xico el domingo trabajaban para la CIA y colaboraban con funcionarios mexicanos en la ampliaci\u00f3n de las operaciones antidrogas en el pa\u00eds, seg\u00fan confirmaron a CNN dos personas con conocimiento del caso.Dos funcionarios mexicanos, pertenecientes a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473388,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/21\/sheinbaum-gobierno-investiga-funcionarios-eeuu-fallecidos-orix\/","url_meta":{"origin":1473750,"position":2},"title":"Sheinbaum dice que su Gobierno est\u00e1 investigando qu\u00e9 hac\u00edan en M\u00e9xico los funcionarios de EE.UU. que murieron en un accidente","author":"","date":"abril 21, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este martes que su Gobierno est\u00e1 investigando qu\u00e9 hac\u00edan en M\u00e9xico los dos funcionarios de Estados Unidos que murieron el domingo en un accidente automovil\u00edstico en Chihuahua, en el norte del pa\u00eds.Sheinbaum volvi\u00f3 a hablar del tema durante su conferencia de prensa diaria,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473708,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","url_meta":{"origin":1473750,"position":3},"title":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa","author":"","date":"mayo 1, 2026","format":false,"excerpt":"Con la renegociaci\u00f3n del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 en puerta, el Gobierno de la presidenta mexicana, Claudia Sheinbaum, ya ten\u00eda un desaf\u00edo este a\u00f1o en su relaci\u00f3n con la administraci\u00f3n de su hom\u00f3logo estadounidense, Donald Trump. Sin embargo, el panorama se le ha complicado m\u00e1s en solo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473499,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","url_meta":{"origin":1473750,"position":4},"title":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump","author":"","date":"abril 25, 2026","format":false,"excerpt":"Hace 43 a\u00f1os, el periodista Manuel Buend\u00eda public\u00f3 el libro \u201cLa CIA en M\u00e9xico\u201d, que cimbr\u00f3 a la sociedad mexicana y sus c\u00edrculos pol\u00edticos. En el libro, Buend\u00eda expone la forma en que operaba la agencia de inteligencia estadounidense en territorio mexicano en labores contrainsurgentes, estableciendo alianzas con actores pol\u00edticos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473446,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/04\/23\/chihuahua-agentes-eeuu-accidente-sheinbaum-orix\/","url_meta":{"origin":1473750,"position":5},"title":"Sheinbaum se enfrenta a gobernadora por presencia de agentes de la CIA: &#171;Lo que hubo fue una falta de una autoridad estatal&#187;","author":"","date":"abril 23, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo que autoridades de Chihuahua cometieron \u201cuna falta\u201d al permitir la presencia de agentes de Estados Unidos en el pa\u00eds para una colaboraci\u00f3n en materia antidrogas sin antes haberlo coordinado con el Gobierno federal.La mandataria hizo esta declaraci\u00f3n luego del operativo realizado el domingo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473750"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473750\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}