{"id":1473758,"date":"2026-05-03T14:03:44","date_gmt":"2026-05-03T21:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/"},"modified":"2026-05-03T14:03:44","modified_gmt":"2026-05-03T21:03:44","slug":"antonelli-gran-premio-miami-f1-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","title":{"rendered":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde"},"content":{"rendered":"<p>La F\u00f3rmula 1 regres\u00f3 a la actividad con una gran carrera en Miami. En lo que fue apenas el cuarto Gran Premio de la temporada (suspendidos los de Medio Oriente por la guerra entre Estados Unidos e Israel con Ir\u00e1n), Mercedes demostr\u00f3 que, a pesar de las mejoras que otras escuder\u00edas llevaron al circuito floridense, es el gran rival a vencer, ya que el italiano Andrea Kimi Antonelli se impuso por tercera vez consecutiva para ampliar a\u00fan m\u00e1s su ventaja en el campeonato de pilotos, donde es l\u00edder absoluto.<\/p>\n<p>Adelantada por la amenaza de fuertes tormentas para la tarde, la carrera tuvo emoci\u00f3n desde el comienzo hasta el final. La largada fue ca\u00f3tica (algo que los aficionados de la F1 saben apreciar muy bien), debido a que el tetracampe\u00f3n Max Verstappen casi se queda afuera con un trompo en una curva que pudo resultar en un accidente masivo. El neerland\u00e9s, que part\u00eda segundo, peleaba mano a mano por el liderato con el monegasco Charles Leclerc, pero el incidente lo mand\u00f3 atr\u00e1s. En apenas unos segundos la carrera ya ten\u00eda nuevo l\u00edder, ya que Antonelli hab\u00eda salido en la pole position.<\/p>\n<p>En el sexto giro varios contuvieron el aliento porque se produjo el accidente del d\u00eda, cuando en la entrada a una curva el neozeland\u00e9s Liam Lawson (de RB) toc\u00f3 una rueda trasera del Alpine de Pierre Gasly, haci\u00e9ndole perder el control del monoplaza, que volc\u00f3, quedando un instante de cabeza, antes de completar la pirueta y quedar inutilizable a un costado.<\/p>\n<p>El que aprovech\u00f3 los incidentes fue el argentino Franco Colapinto, de muy buen fin de semana, que tras largar octavo lleg\u00f3 a estar cuarto (sexto tras el incidente de Verstappen) gracias a la estrategia de neum\u00e1ticos y paradas. El pilarense se mantuvo siempre en los puntos (entre los primeros 10) y logr\u00f3 finalizar en la misma posici\u00f3n de largada, 8\u00b0. Eso iguala su mejor rendimiento en su corta trayectoria en la F\u00f3rmula 1.<\/p>\n<p>Promet\u00eda ser un gran fin de semana para Leclerc, puntero ya en la primera vuelta, pero su Ferrari no tuvo mucho que hacer contra el rendimiento superior del Mercedes de Antonelli y el McLaren de Lando Norris, vigente campe\u00f3n. La cosa empeor\u00f3 en el final, cuando el asedio de Oscar Piastri (McLaren) dio frutos y logr\u00f3 el sobrepaso. El monegasco intent\u00f3 recuperar el \u00faltimo lugar del podio, pero fue para peor: perdi\u00f3 el control del auto, dio un trompo y rompi\u00f3 su aler\u00f3n delantero. Da\u00f1ado, no pudo impedir que Russell y Verstappen lo dejaran atr\u00e1s.<\/p>\n<p>El mexicano Sergio \u201cCheco\u201d P\u00e9rez (16\u00b0) no tuvo mucho que hacer en Miami. El rendimiento de los Cadillac sigue dejando mucho que desear, y junto a su compa\u00f1ero de equipo, Valtteri Bottas (18\u00b0), y los dos Aston Martin de Fernando Alonso (15\u00b0) y Lance Stroll (17\u00b0), se repartieron los \u00faltimos cuatro lugares entre los que pudieron terminar el Gran Premio. Estos cuatro pilotos y Nico Hulkenberg, de Audi, son los \u00fanicos que no han logrado sumar ning\u00fan punto en lo que va del a\u00f1o.<\/p>\n<p>La pr\u00f3xima parada ser\u00e1 el circuito Gilles Villeneuve en el Gran Premio de Canad\u00e1, pero para eso habr\u00e1 que esperar hasta el 24 de mayo. Antonelli llegar\u00e1 a la quinta carrera con 20 puntos de ventaja sobre su compa\u00f1ero, George Russell, ambos de Mercedes.<\/p>\n<ol>\n<li><strong>Kimi Antonelli &#8211; Mercedes<\/strong><\/li>\n<li>Lando Norris &#8211; McLaren<\/li>\n<li>Oscar Piastri &#8211; McLaren<\/li>\n<li>George Russell &#8211; Mercedes<\/li>\n<li>Max Verstappen &#8211; Red Bull<\/li>\n<li>Charles Leclerc &#8211; Ferrari<\/li>\n<li>Lewis Hamilton &#8211; Ferrari<\/li>\n<li>Franco Colapinto &#8211; Alpine<\/li>\n<li>Carlos Sainz &#8211; Williams<\/li>\n<li>Alex Albon &#8211; Williams<\/li>\n<li>Ollie Bearman &#8211; Haas<\/li>\n<li>Gabriel Bortoleto &#8211; Audi<\/li>\n<li>Esteban Ocon &#8211; Haas<\/li>\n<li>Arvid Lindblad &#8211; RB<\/li>\n<li>Fernando Alonso &#8211; Aston Martin<\/li>\n<li>Sergio P\u00e9rez &#8211; Cadillac<\/li>\n<li>Lance Stroll &#8211; Aston Martin<\/li>\n<li>Valtteri Bottas &#8211; Cadillac<\/li>\n<\/ol>\n<ul>\n<li><strong>Kimi Antonelli &#8211; 100 puntos<\/strong><\/li>\n<li>George Russell &#8211; 80<\/li>\n<li>Charles Leclerc &#8211; 63<\/li>\n<li>Lando Norris &#8211; 51<\/li>\n<li>Lewis Hamilton &#8211; 49<\/li>\n<li>Oscar Piastri &#8211; 43<\/li>\n<li>Max Verstappen &#8211; 26<\/li>\n<\/ul>\n<ul>\n<li><strong>Mercedes &#8211; 180 puntos<\/strong><\/li>\n<li>Ferrari &#8211; 112<\/li>\n<li>McLaren &#8211; 94<\/li>\n<li>Red Bull Racing &#8211; 30<\/li>\n<li>Alpine &#8211; 21<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La F\u00f3rmula 1 regres\u00f3 a la actividad con una gran carrera en Miami. En lo que fue apenas el cuarto Gran Premio de la temporada (suspendidos los de Medio Oriente por la guerra entre Estados Unidos e Israel con Ir\u00e1n), Mercedes demostr\u00f3 que, a pesar de las mejoras que otras escuder\u00edas llevaron al circuito floridense, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473758","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde - Noticias\" \/>\n<meta property=\"og:description\" content=\"La F\u00f3rmula 1 regres\u00f3 a la actividad con una gran carrera en Miami. En lo que fue apenas el cuarto Gran Premio de la temporada (suspendidos los de Medio Oriente por la guerra entre Estados Unidos e Israel con Ir\u00e1n), Mercedes demostr\u00f3 que, a pesar de las mejoras que otras escuder\u00edas llevaron al circuito floridense, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-03T21:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde\",\"datePublished\":\"2026-05-03T21:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/\"},\"wordCount\":719,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/\",\"name\":\"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-03T21:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde - Noticias","og_description":"La F\u00f3rmula 1 regres\u00f3 a la actividad con una gran carrera en Miami. En lo que fue apenas el cuarto Gran Premio de la temporada (suspendidos los de Medio Oriente por la guerra entre Estados Unidos e Israel con Ir\u00e1n), Mercedes demostr\u00f3 que, a pesar de las mejoras que otras escuder\u00edas llevaron al circuito floridense, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","og_site_name":"Noticias","article_published_time":"2026-05-03T21:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/"},"author":{"name":"","@id":""},"headline":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde","datePublished":"2026-05-03T21:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/"},"wordCount":719,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","url":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","name":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-03T21:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde","url":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/nuevo-mexico\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-03T21:03:44Z","datePublished":"2026-05-03T21:03:44Z","dateModified":"2026-05-03T21:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\\u00f3 su mejor resultado y Checo P\\u00e9rez tuvo una mala tarde\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/03\\\/antonelli-gran-premio-miami-f1-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/nuevo-mexico\\\/2026\\\/05\\\/03\\\/antonelli-gran-premio-miami-f1-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-03T21:03:44Z\",\"datePublished\":\"2026-05-03T21:03:44Z\",\"dateModified\":\"2026-05-03T21:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452319,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/08\/31\/mercedes-sustituira-lewis-hamilton-andrea-kimi-antonelli-trax\/","url_meta":{"origin":1473758,"position":0},"title":"Mercedes confirm\u00f3 que sustituir\u00e1 a Lewis Hamilton con el corredor de 18 a\u00f1os Andrea Kimi Antonelli","author":"","date":"agosto 31, 2024","format":false,"excerpt":"(CNN) -- Mercedes anunci\u00f3 que el joven italiano Andrea Kimi Antonelli sustituir\u00e1 a Lewis Hamilton, que se marchar\u00e1 a Ferrari la pr\u00f3xima temporada.Antonelli, de 18 a\u00f1os, graduado del programa j\u00fanior del equipo, se asociar\u00e1 con George Russell en Mercedes tras la marcha del siete veces campe\u00f3n de F1, Hamilton.\"Kimi ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448907,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/05\/05\/lando-norris-gana-gran-premio-de-miami-primera-victoria-en-formula-1-trax\/","url_meta":{"origin":1473758,"position":1},"title":"Lando Norris sorprende y gana el Gran Premio de Miami, su primera victoria en F\u00f3rmula 1","author":"","date":"mayo 5, 2024","format":false,"excerpt":"(CNN) -- Lando Norris sorprendi\u00f3 a los competidores y gan\u00f3 el Gran Premio de Miami mientras las celebridades acudieron en masa a Florida para la tercera edici\u00f3n de la carrera este domingo. El piloto de McLaren termin\u00f3 7,6 segundos por delante de Max Verstappen de Red Bull en segundo lugar.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472688,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2026\/03\/30\/max-verstappen-retiro-f1-trax\/","url_meta":{"origin":1473758,"position":2},"title":"\u00bfPor qu\u00e9 el tetracampe\u00f3n mundial Max Verstappen considera retirarse de la F1?","author":"","date":"marzo 30, 2026","format":false,"excerpt":"Puede que sea cuatro veces campe\u00f3n del mundo y una de las figuras m\u00e1s emblem\u00e1ticas de la F\u00f3rmula 1, pero Max Verstappen no est\u00e1 disfrutando de su carrera en el deporte que tanto am\u00f3.Desde hace un tiempo, el neerland\u00e9s se muestra inquieto e insatisfecho con el rumbo que est\u00e1 tomando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465876,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/08\/26\/cadillac-checo-perez-valtteri-bottas-formula-1-orix\/","url_meta":{"origin":1473758,"position":3},"title":"Cadillac apuesta por la experiencia: \u00bfqu\u00e9 pueden darle Sergio &#171;Checo&#187; P\u00e9rez y Valtteri Bottas en sus regresos a la F\u00f3rmula 1?","author":"","date":"agosto 26, 2025","format":false,"excerpt":"Lo que era un secreto a voces finalmente se confirm\u00f3 este martes: la escuder\u00eda estadounidense Cadillac, que debutar\u00e1 en la F\u00f3rmula 1 en 2026, opt\u00f3 por una dupla de experiencia para comandar sus b\u00f3lidos.La llave Sergio \u201cCheco\u201d P\u00e9rez y Valtteri Bottas es la apuesta de un equipo que por primera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468843,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2025\/11\/30\/verstappen-gp-qatar-mclaren-norris-piastri-f1-orix\/","url_meta":{"origin":1473758,"position":4},"title":"McLaren arruina su fin de semana y deja m\u00e1s vivo que nunca a Verstappen: sorpresivo tercer puesto de Sainz en el GP de Qatar","author":"","date":"noviembre 30, 2025","format":false,"excerpt":"Siete vueltas. Eso fue todo lo que dur\u00f3 la carrera en el GP de Qatar este fin de semana, gracias a una estrategia casi de principiantes de McLaren con las paradas en boxes, que le facilit\u00f3 todo al tetracampe\u00f3n del mundo Max Verstappen, que ahora tiene claras chances de quedarse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446207,"url":"https:\/\/noticiasya.com\/nuevo-mexico\/2024\/03\/02\/max-verstappen-gran-premio-de-bahrein-carrera-inaugural-f1-trax\/","url_meta":{"origin":1473758,"position":5},"title":"Max Verstappen gana el Gran Premio de Bahrein y marca una gran diferencia con el resto en la carrera inaugural de la temporada de F1","author":"","date":"marzo 2, 2024","format":false,"excerpt":"(CNN) -- Max Verstappen logr\u00f3 la victoria del Gran Premio de Bahrein este s\u00e1bado, dejando un tiempo siniestro para el resto del pelot\u00f3n en la carrera inaugural de esta temporada de F\u00f3rmula 1 (F1).Su victoria disip\u00f3 cualquier idea de que el dominio de Red Bull podr\u00eda haber disminuido durante el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/nuevo-mexico\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/comments?post=1473758"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/posts\/1473758\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/media?parent=1473758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/categories?post=1473758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/nuevo-mexico\/wp-json\/wp\/v2\/tags?post=1473758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}